{"id":99242,"date":"2018-06-29T10:17:16","date_gmt":"2018-06-29T10:17:16","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=99242"},"modified":"2018-06-29T10:17:16","modified_gmt":"2018-06-29T10:17:16","slug":"vettel-asume-su-error-en-francia-lo-tengo-superado","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/vettel-asume-su-error-en-francia-lo-tengo-superado\/","title":{"rendered":"Vettel asume su error en Francia: \u00abLo tengo superado\u00bb"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-91805\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/formula-1-630147_1280-360x239.jpg\" alt=\"\" width=\"360\" height=\"239\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/formula-1-630147_1280-360x239.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/formula-1-630147_1280-696x463.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/formula-1-630147_1280-1068x710.jpg 1068w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/formula-1-630147_1280-632x420.jpg 632w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/formula-1-630147_1280-768x511.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/formula-1-630147_1280-655x435.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/formula-1-630147_1280.jpg 1280w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Spielberg (Austria), 28 jun (dpa) &#8211; El alem\u00e1n Sebastian Vettel asegur\u00f3 hoy tener superado el error que le llev\u00f3 a perder el liderato de la F\u00f3rmula 1 el domingo en el Gran Premio de Francia.<\/p>\n<p>\u00abEn un primer momento le das vueltas, normalmente por la noche\u00bb, cont\u00f3 el piloto de Ferrari en el circuito de Spielberg, donde este fin de semana se corre el Gran Premio de Austria.<\/p>\n<p>\u00abEn alg\u00fan momento se me cierran los ojos y al d\u00eda siente el tema est\u00e1 superado\u00bb, agreg\u00f3 el tetracampe\u00f3n mundial. \u00abLo he asumido como un error m\u00edo. Lo que la gente no ve es que a este nivel muchos detalles pueden hacer la diferencia\u00bb.<\/p>\n<p>Para el alem\u00e1n de 30 a\u00f1os ser\u00eda aburrido incluso para \u00e9l si todo fuera previsible. \u00abPienso que la cuesti\u00f3n es c\u00f3mo se reacciona cuando el plan cambia\u00bb, se\u00f1al\u00f3.<\/p>\n<p>Tras su choque con el piloto de Mercedes Valtteri Bottas en la primera curva, Vettel no pudo entrar en el podio y se encuentra a 14 puntos del nuevo l\u00edder, el brit\u00e1nico Lewis Hamilton.<\/p>\n<p>\u00abCreo que tenemos una buena oportunidad de pelear por el t\u00edtulo\u00bb, dijo el alem\u00e1n.<\/p>\n<p>Su principal rival se mostr\u00f3 contento por ello. \u00abCuantos m\u00e1s rivales y m\u00e1s ajustado est\u00e9 todo, mejor\u00bb, dijo Hamilton. \u00abPara eso estoy yo en este mundo de las carreras\u00bb, a\u00f1adi\u00f3 el l\u00edder de Mercedes.<\/p>\n<p>Vettel tuvo que responder tambi\u00e9n a una pregunta sobre el Mundial de f\u00fatbol cuando un periodista le pregunt\u00f3 si tras la eliminaci\u00f3n germana era ahora su turno de mantener el honor del deporte alem\u00e1n en alto.<\/p>\n<p>\u00abEso es una tonter\u00eda\u00bb, dijo. \u00abLa F\u00f3rmula 1 y el f\u00fatbol no tienen nada que ver. Y creo que hay muchos, muchos otros deportistas alemanes de los que podemos estar orgullosos y pelean por el Mundial en otras disciplinas\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Spielberg (Austria), 28 jun (dpa) &#8211; El alem\u00e1n Sebastian Vettel asegur\u00f3 hoy tener superado el error que le llev\u00f3 a perder el liderato de la F\u00f3rmula 1 el domingo en el Gran Premio de Francia. \u00abEn un primer momento le das vueltas, normalmente por la noche\u00bb, cont\u00f3 el piloto de Ferrari en el circuito de<\/p>\n","protected":false},"author":1,"featured_media":91805,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[319],"tags":[],"class_list":{"0":"post-99242","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-deporte"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7 - aioseo.com -->\n\t<meta name=\"description\" content=\"Spielberg (Austria), 28 jun (dpa) - El alem\u00e1n Sebastian Vettel asegur\u00f3 hoy tener superado el error que le llev\u00f3 a perder el liderato de la F\u00f3rmula 1 el domingo en el Gran Premio de Francia. &quot;En un primer momento le das vueltas, normalmente por la noche&quot;, cont\u00f3 el piloto de Ferrari en el circuito de\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"deporte\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/vettel-asume-su-error-en-francia-lo-tengo-superado\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Vettel asume su error en Francia: \u00abLo tengo superado\u00bb | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Spielberg (Austria), 28 jun (dpa) - El alem\u00e1n Sebastian Vettel asegur\u00f3 hoy tener superado el error que le llev\u00f3 a perder el liderato de la F\u00f3rmula 1 el domingo en el Gran Premio de Francia. &quot;En un primer momento le das vueltas, normalmente por la noche&quot;, cont\u00f3 el piloto de Ferrari en el circuito de\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/vettel-asume-su-error-en-francia-lo-tengo-superado\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/formula-1-630147_1280.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/formula-1-630147_1280.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t\t<meta property=\"og:image:height\" content=\"851\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-06-29T10:17:16+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-06-29T10:17:16+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Vettel asume su error en Francia: \u00abLo tengo superado\u00bb | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Spielberg (Austria), 28 jun (dpa) - El alem\u00e1n Sebastian Vettel asegur\u00f3 hoy tener superado el error que le llev\u00f3 a perder el liderato de la F\u00f3rmula 1 el domingo en el Gran Premio de Francia. &quot;En un primer momento le das vueltas, normalmente por la noche&quot;, cont\u00f3 el piloto de Ferrari en el circuito de\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/formula-1-630147_1280.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/vettel-asume-su-error-en-francia-lo-tengo-superado\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/#listItem\",\"name\":\"Deporte\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/#listItem\",\"position\":2,\"name\":\"Deporte\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/vettel-asume-su-error-en-francia-lo-tengo-superado\\\/#listItem\",\"name\":\"Vettel asume su error en Francia: \\u00abLo tengo superado\\u00bb\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/vettel-asume-su-error-en-francia-lo-tengo-superado\\\/#listItem\",\"position\":3,\"name\":\"Vettel asume su error en Francia: \\u00abLo tengo superado\\u00bb\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/#listItem\",\"name\":\"Deporte\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/vettel-asume-su-error-en-francia-lo-tengo-superado\\\/#newsarticle\",\"name\":\"Vettel asume su error en Francia: \\u00abLo tengo superado\\u00bb | Cand\\u00e1s 365\",\"headline\":\"Vettel asume su error en Francia: \\u00abLo tengo superado\\u00bb\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/formula-1-630147_1280.jpg\",\"width\":1280,\"height\":851},\"datePublished\":\"2018-06-29T10:17:16+02:00\",\"dateModified\":\"2018-06-29T10:17:16+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/vettel-asume-su-error-en-francia-lo-tengo-superado\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/vettel-asume-su-error-en-francia-lo-tengo-superado\\\/#webpage\"},\"articleSection\":\"Deporte\",\"dateline\":\"Publicado el junio 29, 2018.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/vettel-asume-su-error-en-francia-lo-tengo-superado\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/vettel-asume-su-error-en-francia-lo-tengo-superado\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/vettel-asume-su-error-en-francia-lo-tengo-superado\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/vettel-asume-su-error-en-francia-lo-tengo-superado\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/vettel-asume-su-error-en-francia-lo-tengo-superado\\\/\",\"name\":\"Vettel asume su error en Francia: \\u00abLo tengo superado\\u00bb | Cand\\u00e1s 365\",\"description\":\"Spielberg (Austria), 28 jun (dpa) - El alem\\u00e1n Sebastian Vettel asegur\\u00f3 hoy tener superado el error que le llev\\u00f3 a perder el liderato de la F\\u00f3rmula 1 el domingo en el Gran Premio de Francia. \\\"En un primer momento le das vueltas, normalmente por la noche\\\", cont\\u00f3 el piloto de Ferrari en el circuito de\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/vettel-asume-su-error-en-francia-lo-tengo-superado\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/formula-1-630147_1280.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/vettel-asume-su-error-en-francia-lo-tengo-superado\\\/#mainImage\",\"width\":1280,\"height\":851},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/vettel-asume-su-error-en-francia-lo-tengo-superado\\\/#mainImage\"},\"datePublished\":\"2018-06-29T10:17:16+02:00\",\"dateModified\":\"2018-06-29T10:17:16+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Vettel asume su error en Francia: \u00abLo tengo superado\u00bb | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Vettel asume su error en Francia: \u00abLo tengo superado\u00bb | Cand\u00e1s 365","description":"Spielberg (Austria), 28 jun (dpa) - El alem\u00e1n Sebastian Vettel asegur\u00f3 hoy tener superado el error que le llev\u00f3 a perder el liderato de la F\u00f3rmula 1 el domingo en el Gran Premio de Francia. \"En un primer momento le das vueltas, normalmente por la noche\", cont\u00f3 el piloto de Ferrari en el circuito de","canonical_url":"https:\/\/candas365.es\/noticias\/vettel-asume-su-error-en-francia-lo-tengo-superado\/","robots":"max-image-preview:large","keywords":"deporte","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/vettel-asume-su-error-en-francia-lo-tengo-superado\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/deporte\/#listItem","name":"Deporte"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/deporte\/#listItem","position":2,"name":"Deporte","item":"https:\/\/candas365.es\/noticias\/category\/deporte\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/vettel-asume-su-error-en-francia-lo-tengo-superado\/#listItem","name":"Vettel asume su error en Francia: \u00abLo tengo superado\u00bb"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/vettel-asume-su-error-en-francia-lo-tengo-superado\/#listItem","position":3,"name":"Vettel asume su error en Francia: \u00abLo tengo superado\u00bb","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/deporte\/#listItem","name":"Deporte"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/vettel-asume-su-error-en-francia-lo-tengo-superado\/#newsarticle","name":"Vettel asume su error en Francia: \u00abLo tengo superado\u00bb | Cand\u00e1s 365","headline":"Vettel asume su error en Francia: \u00abLo tengo superado\u00bb","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/formula-1-630147_1280.jpg","width":1280,"height":851},"datePublished":"2018-06-29T10:17:16+02:00","dateModified":"2018-06-29T10:17:16+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/vettel-asume-su-error-en-francia-lo-tengo-superado\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/vettel-asume-su-error-en-francia-lo-tengo-superado\/#webpage"},"articleSection":"Deporte","dateline":"Publicado el junio 29, 2018."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/vettel-asume-su-error-en-francia-lo-tengo-superado\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/vettel-asume-su-error-en-francia-lo-tengo-superado\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/vettel-asume-su-error-en-francia-lo-tengo-superado\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/vettel-asume-su-error-en-francia-lo-tengo-superado\/#webpage","url":"https:\/\/candas365.es\/noticias\/vettel-asume-su-error-en-francia-lo-tengo-superado\/","name":"Vettel asume su error en Francia: \u00abLo tengo superado\u00bb | Cand\u00e1s 365","description":"Spielberg (Austria), 28 jun (dpa) - El alem\u00e1n Sebastian Vettel asegur\u00f3 hoy tener superado el error que le llev\u00f3 a perder el liderato de la F\u00f3rmula 1 el domingo en el Gran Premio de Francia. \"En un primer momento le das vueltas, normalmente por la noche\", cont\u00f3 el piloto de Ferrari en el circuito de","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/vettel-asume-su-error-en-francia-lo-tengo-superado\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/formula-1-630147_1280.jpg","@id":"https:\/\/candas365.es\/noticias\/vettel-asume-su-error-en-francia-lo-tengo-superado\/#mainImage","width":1280,"height":851},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/vettel-asume-su-error-en-francia-lo-tengo-superado\/#mainImage"},"datePublished":"2018-06-29T10:17:16+02:00","dateModified":"2018-06-29T10:17:16+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Vettel asume su error en Francia: \u00abLo tengo superado\u00bb | Cand\u00e1s 365","og:description":"Spielberg (Austria), 28 jun (dpa) - El alem\u00e1n Sebastian Vettel asegur\u00f3 hoy tener superado el error que le llev\u00f3 a perder el liderato de la F\u00f3rmula 1 el domingo en el Gran Premio de Francia. &quot;En un primer momento le das vueltas, normalmente por la noche&quot;, cont\u00f3 el piloto de Ferrari en el circuito de","og:url":"https:\/\/candas365.es\/noticias\/vettel-asume-su-error-en-francia-lo-tengo-superado\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/formula-1-630147_1280.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/formula-1-630147_1280.jpg","og:image:width":1280,"og:image:height":851,"article:published_time":"2018-06-29T10:17:16+00:00","article:modified_time":"2018-06-29T10:17:16+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Vettel asume su error en Francia: \u00abLo tengo superado\u00bb | Cand\u00e1s 365","twitter:description":"Spielberg (Austria), 28 jun (dpa) - El alem\u00e1n Sebastian Vettel asegur\u00f3 hoy tener superado el error que le llev\u00f3 a perder el liderato de la F\u00f3rmula 1 el domingo en el Gran Premio de Francia. &quot;En un primer momento le das vueltas, normalmente por la noche&quot;, cont\u00f3 el piloto de Ferrari en el circuito de","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/formula-1-630147_1280.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"99242","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-27 05:36:10","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 11:49:38","updated":"2025-08-27 05:36:10"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/deporte\/\" title=\"Deporte\">Deporte<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tVettel asume su error en Francia: \u00abLo tengo superado\u00bb\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Deporte","link":"https:\/\/candas365.es\/noticias\/category\/deporte\/"},{"label":"Vettel asume su error en Francia: \u00abLo tengo superado\u00bb","link":"https:\/\/candas365.es\/noticias\/vettel-asume-su-error-en-francia-lo-tengo-superado\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/99242","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=99242"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/99242\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/91805"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=99242"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=99242"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=99242"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}