{"id":98523,"date":"2018-06-20T22:40:59","date_gmt":"2018-06-20T22:40:59","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=98523"},"modified":"2018-06-20T22:40:59","modified_gmt":"2018-06-20T22:40:59","slug":"jonas-hector-regresa-a-los-entrenamientos-de-la-mannschaft","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/jonas-hector-regresa-a-los-entrenamientos-de-la-mannschaft\/","title":{"rendered":"Jonas Hector regresa a los entrenamientos de la \u00abMannschaft\u00bb"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-98026\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/football-1406106_960_720-1-360x241.jpg\" alt=\"\" width=\"360\" height=\"241\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/football-1406106_960_720-1-360x241.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/football-1406106_960_720-1-768x514.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/football-1406106_960_720-1-655x439.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/football-1406106_960_720-1-696x466.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/football-1406106_960_720-1-627x420.jpg 627w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/football-1406106_960_720-1.jpg 960w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Sochi (Rusia), 20 jun (dpa) &#8211; El lateral Jonas Hector regres\u00f3 hoy a las pr\u00e1cticas de la selecci\u00f3n alemana despu\u00e9s de recuperarse de un fuerte resfri\u00f3 que lo dej\u00f3 fuera del debut con derrota de la \u00abMannschaft\u00bb ante M\u00e9xico en el Mundial.<\/p>\n<p>El lateral izquierdo del Colonia fue reemplazado por Marvin Plattenhardt en la ca\u00edda 1-0 ante los aztecas, pero se espera su regreso el s\u00e1bado en el crucial duelo ante Suecia, en la segunda jornada del Grupo F.<\/p>\n<p>Los campeones defensores ya est\u00e1n en un resort del Mar Muerto, al que llegaron desde su campo de entrenamiento en Mosc\u00fa para intentar aclimatarse a las temperaturas m\u00e1s altas de la ciudad costera.<\/p>\n<p>As\u00ed, los 23 jugadores del plantel alem\u00e1n participaron en el primer entrenamiento en Sochi.<\/p>\n<p>Tras la derrota ante M\u00e9xico, los germanos est\u00e1n obligados a ganar ante Suecia para llegar al cierre de la fase de grupos, el pr\u00f3ximo mi\u00e9rcoles ante Corea del Sur, con opciones de meterse en octavos de final.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sochi (Rusia), 20 jun (dpa) &#8211; El lateral Jonas Hector regres\u00f3 hoy a las pr\u00e1cticas de la selecci\u00f3n alemana despu\u00e9s de recuperarse de un fuerte resfri\u00f3 que lo dej\u00f3 fuera del debut con derrota de la \u00abMannschaft\u00bb ante M\u00e9xico en el Mundial. El lateral izquierdo del Colonia fue reemplazado por Marvin Plattenhardt en la ca\u00edda<\/p>\n","protected":false},"author":1,"featured_media":96046,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[319],"tags":[],"class_list":{"0":"post-98523","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-deporte"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7 - aioseo.com -->\n\t<meta name=\"description\" content=\"Sochi (Rusia), 20 jun (dpa) - El lateral Jonas Hector regres\u00f3 hoy a las pr\u00e1cticas de la selecci\u00f3n alemana despu\u00e9s de recuperarse de un fuerte resfri\u00f3 que lo dej\u00f3 fuera del debut con derrota de la &quot;Mannschaft&quot; ante M\u00e9xico en el Mundial. El lateral izquierdo del Colonia fue reemplazado por Marvin Plattenhardt en la ca\u00edda\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"deporte\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/jonas-hector-regresa-a-los-entrenamientos-de-la-mannschaft\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Jonas Hector regresa a los entrenamientos de la \u00abMannschaft\u00bb | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Sochi (Rusia), 20 jun (dpa) - El lateral Jonas Hector regres\u00f3 hoy a las pr\u00e1cticas de la selecci\u00f3n alemana despu\u00e9s de recuperarse de un fuerte resfri\u00f3 que lo dej\u00f3 fuera del debut con derrota de la &quot;Mannschaft&quot; ante M\u00e9xico en el Mundial. El lateral izquierdo del Colonia fue reemplazado por Marvin Plattenhardt en la ca\u00edda\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/jonas-hector-regresa-a-los-entrenamientos-de-la-mannschaft\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/football-3373557_960_720.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/football-3373557_960_720.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-06-20T22:40:59+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-06-20T22:40:59+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Jonas Hector regresa a los entrenamientos de la \u00abMannschaft\u00bb | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Sochi (Rusia), 20 jun (dpa) - El lateral Jonas Hector regres\u00f3 hoy a las pr\u00e1cticas de la selecci\u00f3n alemana despu\u00e9s de recuperarse de un fuerte resfri\u00f3 que lo dej\u00f3 fuera del debut con derrota de la &quot;Mannschaft&quot; ante M\u00e9xico en el Mundial. El lateral izquierdo del Colonia fue reemplazado por Marvin Plattenhardt en la ca\u00edda\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/football-3373557_960_720.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/jonas-hector-regresa-a-los-entrenamientos-de-la-mannschaft\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/#listItem\",\"name\":\"Deporte\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/#listItem\",\"position\":2,\"name\":\"Deporte\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/jonas-hector-regresa-a-los-entrenamientos-de-la-mannschaft\\\/#listItem\",\"name\":\"Jonas Hector regresa a los entrenamientos de la \\u00abMannschaft\\u00bb\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/jonas-hector-regresa-a-los-entrenamientos-de-la-mannschaft\\\/#listItem\",\"position\":3,\"name\":\"Jonas Hector regresa a los entrenamientos de la \\u00abMannschaft\\u00bb\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/#listItem\",\"name\":\"Deporte\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/jonas-hector-regresa-a-los-entrenamientos-de-la-mannschaft\\\/#newsarticle\",\"name\":\"Jonas Hector regresa a los entrenamientos de la \\u00abMannschaft\\u00bb | Cand\\u00e1s 365\",\"headline\":\"Jonas Hector regresa a los entrenamientos de la \\u00abMannschaft\\u00bb\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/football-3373557_960_720.jpg\",\"width\":960,\"height\":640},\"datePublished\":\"2018-06-20T22:40:59+02:00\",\"dateModified\":\"2018-06-20T22:40:59+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/jonas-hector-regresa-a-los-entrenamientos-de-la-mannschaft\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/jonas-hector-regresa-a-los-entrenamientos-de-la-mannschaft\\\/#webpage\"},\"articleSection\":\"Deporte\",\"dateline\":\"Publicado el junio 20, 2018.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/jonas-hector-regresa-a-los-entrenamientos-de-la-mannschaft\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/jonas-hector-regresa-a-los-entrenamientos-de-la-mannschaft\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/jonas-hector-regresa-a-los-entrenamientos-de-la-mannschaft\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/jonas-hector-regresa-a-los-entrenamientos-de-la-mannschaft\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/jonas-hector-regresa-a-los-entrenamientos-de-la-mannschaft\\\/\",\"name\":\"Jonas Hector regresa a los entrenamientos de la \\u00abMannschaft\\u00bb | Cand\\u00e1s 365\",\"description\":\"Sochi (Rusia), 20 jun (dpa) - El lateral Jonas Hector regres\\u00f3 hoy a las pr\\u00e1cticas de la selecci\\u00f3n alemana despu\\u00e9s de recuperarse de un fuerte resfri\\u00f3 que lo dej\\u00f3 fuera del debut con derrota de la \\\"Mannschaft\\\" ante M\\u00e9xico en el Mundial. El lateral izquierdo del Colonia fue reemplazado por Marvin Plattenhardt en la ca\\u00edda\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/jonas-hector-regresa-a-los-entrenamientos-de-la-mannschaft\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/football-3373557_960_720.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/jonas-hector-regresa-a-los-entrenamientos-de-la-mannschaft\\\/#mainImage\",\"width\":960,\"height\":640},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/jonas-hector-regresa-a-los-entrenamientos-de-la-mannschaft\\\/#mainImage\"},\"datePublished\":\"2018-06-20T22:40:59+02:00\",\"dateModified\":\"2018-06-20T22:40:59+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Jonas Hector regresa a los entrenamientos de la \u00abMannschaft\u00bb | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Jonas Hector regresa a los entrenamientos de la \u00abMannschaft\u00bb | Cand\u00e1s 365","description":"Sochi (Rusia), 20 jun (dpa) - El lateral Jonas Hector regres\u00f3 hoy a las pr\u00e1cticas de la selecci\u00f3n alemana despu\u00e9s de recuperarse de un fuerte resfri\u00f3 que lo dej\u00f3 fuera del debut con derrota de la \"Mannschaft\" ante M\u00e9xico en el Mundial. El lateral izquierdo del Colonia fue reemplazado por Marvin Plattenhardt en la ca\u00edda","canonical_url":"https:\/\/candas365.es\/noticias\/jonas-hector-regresa-a-los-entrenamientos-de-la-mannschaft\/","robots":"max-image-preview:large","keywords":"deporte","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/jonas-hector-regresa-a-los-entrenamientos-de-la-mannschaft\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/deporte\/#listItem","name":"Deporte"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/deporte\/#listItem","position":2,"name":"Deporte","item":"https:\/\/candas365.es\/noticias\/category\/deporte\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/jonas-hector-regresa-a-los-entrenamientos-de-la-mannschaft\/#listItem","name":"Jonas Hector regresa a los entrenamientos de la \u00abMannschaft\u00bb"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/jonas-hector-regresa-a-los-entrenamientos-de-la-mannschaft\/#listItem","position":3,"name":"Jonas Hector regresa a los entrenamientos de la \u00abMannschaft\u00bb","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/deporte\/#listItem","name":"Deporte"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/jonas-hector-regresa-a-los-entrenamientos-de-la-mannschaft\/#newsarticle","name":"Jonas Hector regresa a los entrenamientos de la \u00abMannschaft\u00bb | Cand\u00e1s 365","headline":"Jonas Hector regresa a los entrenamientos de la \u00abMannschaft\u00bb","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/football-3373557_960_720.jpg","width":960,"height":640},"datePublished":"2018-06-20T22:40:59+02:00","dateModified":"2018-06-20T22:40:59+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/jonas-hector-regresa-a-los-entrenamientos-de-la-mannschaft\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/jonas-hector-regresa-a-los-entrenamientos-de-la-mannschaft\/#webpage"},"articleSection":"Deporte","dateline":"Publicado el junio 20, 2018."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/jonas-hector-regresa-a-los-entrenamientos-de-la-mannschaft\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/jonas-hector-regresa-a-los-entrenamientos-de-la-mannschaft\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/jonas-hector-regresa-a-los-entrenamientos-de-la-mannschaft\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/jonas-hector-regresa-a-los-entrenamientos-de-la-mannschaft\/#webpage","url":"https:\/\/candas365.es\/noticias\/jonas-hector-regresa-a-los-entrenamientos-de-la-mannschaft\/","name":"Jonas Hector regresa a los entrenamientos de la \u00abMannschaft\u00bb | Cand\u00e1s 365","description":"Sochi (Rusia), 20 jun (dpa) - El lateral Jonas Hector regres\u00f3 hoy a las pr\u00e1cticas de la selecci\u00f3n alemana despu\u00e9s de recuperarse de un fuerte resfri\u00f3 que lo dej\u00f3 fuera del debut con derrota de la \"Mannschaft\" ante M\u00e9xico en el Mundial. El lateral izquierdo del Colonia fue reemplazado por Marvin Plattenhardt en la ca\u00edda","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/jonas-hector-regresa-a-los-entrenamientos-de-la-mannschaft\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/football-3373557_960_720.jpg","@id":"https:\/\/candas365.es\/noticias\/jonas-hector-regresa-a-los-entrenamientos-de-la-mannschaft\/#mainImage","width":960,"height":640},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/jonas-hector-regresa-a-los-entrenamientos-de-la-mannschaft\/#mainImage"},"datePublished":"2018-06-20T22:40:59+02:00","dateModified":"2018-06-20T22:40:59+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Jonas Hector regresa a los entrenamientos de la \u00abMannschaft\u00bb | Cand\u00e1s 365","og:description":"Sochi (Rusia), 20 jun (dpa) - El lateral Jonas Hector regres\u00f3 hoy a las pr\u00e1cticas de la selecci\u00f3n alemana despu\u00e9s de recuperarse de un fuerte resfri\u00f3 que lo dej\u00f3 fuera del debut con derrota de la &quot;Mannschaft&quot; ante M\u00e9xico en el Mundial. El lateral izquierdo del Colonia fue reemplazado por Marvin Plattenhardt en la ca\u00edda","og:url":"https:\/\/candas365.es\/noticias\/jonas-hector-regresa-a-los-entrenamientos-de-la-mannschaft\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/football-3373557_960_720.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/football-3373557_960_720.jpg","og:image:width":960,"og:image:height":640,"article:published_time":"2018-06-20T22:40:59+00:00","article:modified_time":"2018-06-20T22:40:59+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Jonas Hector regresa a los entrenamientos de la \u00abMannschaft\u00bb | Cand\u00e1s 365","twitter:description":"Sochi (Rusia), 20 jun (dpa) - El lateral Jonas Hector regres\u00f3 hoy a las pr\u00e1cticas de la selecci\u00f3n alemana despu\u00e9s de recuperarse de un fuerte resfri\u00f3 que lo dej\u00f3 fuera del debut con derrota de la &quot;Mannschaft&quot; ante M\u00e9xico en el Mundial. El lateral izquierdo del Colonia fue reemplazado por Marvin Plattenhardt en la ca\u00edda","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/football-3373557_960_720.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"1 minuto"},"aioseo_meta_data":{"post_id":"98523","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-27 03:41:16","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 10:49:32","updated":"2025-08-27 03:41:16"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/deporte\/\" title=\"Deporte\">Deporte<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tJonas Hector regresa a los entrenamientos de la \u00abMannschaft\u00bb\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Deporte","link":"https:\/\/candas365.es\/noticias\/category\/deporte\/"},{"label":"Jonas Hector regresa a los entrenamientos de la \u00abMannschaft\u00bb","link":"https:\/\/candas365.es\/noticias\/jonas-hector-regresa-a-los-entrenamientos-de-la-mannschaft\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/98523","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=98523"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/98523\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/96046"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=98523"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=98523"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=98523"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}