{"id":97854,"date":"2018-06-12T20:27:37","date_gmt":"2018-06-12T20:27:37","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=97854"},"modified":"2018-06-12T20:27:37","modified_gmt":"2018-06-12T20:27:37","slug":"llega-la-hierba-vuelve-federer-el-numero-uno-como-objetivo","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/llega-la-hierba-vuelve-federer-el-numero-uno-como-objetivo\/","title":{"rendered":"Llega la hierba, vuelve Federer: el n\u00famero uno como objetivo"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-95170\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/tennis-2891306_960_720-360x203.jpg\" alt=\"\" width=\"360\" height=\"203\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/tennis-2891306_960_720-360x203.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/tennis-2891306_960_720-768x432.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/tennis-2891306_960_720-655x368.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/tennis-2891306_960_720-696x392.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/tennis-2891306_960_720-747x420.jpg 747w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/tennis-2891306_960_720.jpg 960w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Stuttgart\/Berl\u00edn, 12 jun (dpa) &#8211; Con Wimbledon en el horizonte y el n\u00famero uno del ranking como objetivo, el suizo Roger Federer reaparecer\u00e1 ma\u00f1ana en el torneo de Stuttgart tras saltarse toda la gira de arcilla.<\/p>\n<p>Llega la hierba y el campe\u00f3n de 20 Grand Slam regresa a las pistas dispuesto a demostrar su dominio. Debutar\u00e1 en el certamen alem\u00e1n, de categor\u00eda ATP 250, tan solo tres d\u00edas despu\u00e9s de que su rival y amigo Rafael Nadal conquistara su und\u00e9cimo Roland Garros en Par\u00eds.<\/p>\n<p>\u00abEstar en Stuttgart es una motivaci\u00f3n extra. Salir de aqu\u00ed con el n\u00famero uno ser\u00eda estupendo, por supuesto\u00bb, admiti\u00f3 Federer este lunes ante la prensa.<\/p>\n<p>Federer lleva 21 a\u00f1os desempe\u00f1\u00e1ndose como profesional en el mundo del tenis, tantos como tiene el alem\u00e1n Alexander Zverev, que lo sigue en el ranking mundial y es hermano de Mischa Zverev, el primer rival al que se medir\u00e1 en el campeonato germano.<\/p>\n<p>\u00ab(Zverev) siempre es peligroso. Yo hice una pausa durante varios meses y por eso debo bajar las expectativas. Arranco en fr\u00edo y eso no es f\u00e1cil\u00bb, se\u00f1al\u00f3 el multicampe\u00f3n en v\u00edsperas de su enfrentamiento al n\u00famero tres del mundo.<\/p>\n<p>Con 8.670 puntos en el r\u00e1nking mundial de tenis, el suizo se sit\u00faa segundo en el listado de la ATP a tan solo 100 puntos de Nadal. Tres partidos le bastar\u00edan para portar de nuevo la corona de laurel porque con tan solo llegar a la final del torneo germano, Federer lograr\u00eda desbancar al espa\u00f1ol de la primera posici\u00f3n.<\/p>\n<p>Stuttgart es un torneo que Federer conoce bien. Estuvo tanto en 2016 como en 2017. En su \u00faltima participaci\u00f3n perdi\u00f3 en octavos de final ante el local Tommy Haas.<\/p>\n<p>El veterano campe\u00f3n suizo, de 36 a\u00f1os, llega a la hierba alemana despu\u00e9s de tres meses sin competir. Su \u00faltimo partido fue en la primera ronda de Miami, donde cay\u00f3 contra todo pron\u00f3stico.<\/p>\n<p>Despu\u00e9s, y al igual que el a\u00f1o pasado, decidi\u00f3 no competir en la gira europea de polvo de ladrillo para centrarse en Wimbledon, el tercer Grand Slam de la temporada y donde defiende el t\u00edtulo.<\/p>\n<p>Federer ser\u00e1 el gran favorito en Stuttgart, donde tambi\u00e9n estar\u00e1n tenistas como el franc\u00e9s Lucas Pouille, el canadiense Milos Raonic, el surcoreano Hyeon Chung, el australiano Nick Kyrgios y el espa\u00f1ol Feliciano L\u00f3pez.<\/p>\n<p>Solventado el tr\u00e1mite de Stuttgart, Federer centrar\u00e1 todos sus esfuerzos en llegar a punto a Londres. \u00abLa victoria en Wimbledon es lo m\u00e1ximo del tour. Siempre que tengo posibilidad de elegir, opto por ir a Wimbledon\u00bb, subray\u00f3 Federer, recalcando que el torneo ingl\u00e9s supone para \u00e9l un mayor desaf\u00edo que vencer a Nadal en Par\u00eds.<\/p>\n<p>Por Kristina Puck y Mar\u00eda Prieto (dpa)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Stuttgart\/Berl\u00edn, 12 jun (dpa) &#8211; Con Wimbledon en el horizonte y el n\u00famero uno del ranking como objetivo, el suizo Roger Federer reaparecer\u00e1 ma\u00f1ana en el torneo de Stuttgart tras saltarse toda la gira de arcilla. Llega la hierba y el campe\u00f3n de 20 Grand Slam regresa a las pistas dispuesto a demostrar su dominio.<\/p>\n","protected":false},"author":1,"featured_media":95170,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[319],"tags":[],"class_list":{"0":"post-97854","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-deporte"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7 - aioseo.com -->\n\t<meta name=\"description\" content=\"Stuttgart\/Berl\u00edn, 12 jun (dpa) - Con Wimbledon en el horizonte y el n\u00famero uno del ranking como objetivo, el suizo Roger Federer reaparecer\u00e1 ma\u00f1ana en el torneo de Stuttgart tras saltarse toda la gira de arcilla. Llega la hierba y el campe\u00f3n de 20 Grand Slam regresa a las pistas dispuesto a demostrar su dominio.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"deporte\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/llega-la-hierba-vuelve-federer-el-numero-uno-como-objetivo\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Llega la hierba, vuelve Federer: el n\u00famero uno como objetivo | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Stuttgart\/Berl\u00edn, 12 jun (dpa) - Con Wimbledon en el horizonte y el n\u00famero uno del ranking como objetivo, el suizo Roger Federer reaparecer\u00e1 ma\u00f1ana en el torneo de Stuttgart tras saltarse toda la gira de arcilla. Llega la hierba y el campe\u00f3n de 20 Grand Slam regresa a las pistas dispuesto a demostrar su dominio.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/llega-la-hierba-vuelve-federer-el-numero-uno-como-objetivo\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/tennis-2891306_960_720.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/tennis-2891306_960_720.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t\t<meta property=\"og:image:height\" content=\"540\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-06-12T20:27:37+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-06-12T20:27:37+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Llega la hierba, vuelve Federer: el n\u00famero uno como objetivo | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Stuttgart\/Berl\u00edn, 12 jun (dpa) - Con Wimbledon en el horizonte y el n\u00famero uno del ranking como objetivo, el suizo Roger Federer reaparecer\u00e1 ma\u00f1ana en el torneo de Stuttgart tras saltarse toda la gira de arcilla. Llega la hierba y el campe\u00f3n de 20 Grand Slam regresa a las pistas dispuesto a demostrar su dominio.\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/tennis-2891306_960_720.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/llega-la-hierba-vuelve-federer-el-numero-uno-como-objetivo\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/#listItem\",\"name\":\"Deporte\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/#listItem\",\"position\":2,\"name\":\"Deporte\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/llega-la-hierba-vuelve-federer-el-numero-uno-como-objetivo\\\/#listItem\",\"name\":\"Llega la hierba, vuelve Federer: el n\\u00famero uno como objetivo\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/llega-la-hierba-vuelve-federer-el-numero-uno-como-objetivo\\\/#listItem\",\"position\":3,\"name\":\"Llega la hierba, vuelve Federer: el n\\u00famero uno como objetivo\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/#listItem\",\"name\":\"Deporte\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/llega-la-hierba-vuelve-federer-el-numero-uno-como-objetivo\\\/#newsarticle\",\"name\":\"Llega la hierba, vuelve Federer: el n\\u00famero uno como objetivo | Cand\\u00e1s 365\",\"headline\":\"Llega la hierba, vuelve Federer: el n\\u00famero uno como objetivo\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/tennis-2891306_960_720.jpg\",\"width\":960,\"height\":540},\"datePublished\":\"2018-06-12T20:27:37+02:00\",\"dateModified\":\"2018-06-12T20:27:37+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/llega-la-hierba-vuelve-federer-el-numero-uno-como-objetivo\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/llega-la-hierba-vuelve-federer-el-numero-uno-como-objetivo\\\/#webpage\"},\"articleSection\":\"Deporte\",\"dateline\":\"Publicado el junio 12, 2018.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/llega-la-hierba-vuelve-federer-el-numero-uno-como-objetivo\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/llega-la-hierba-vuelve-federer-el-numero-uno-como-objetivo\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/llega-la-hierba-vuelve-federer-el-numero-uno-como-objetivo\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/llega-la-hierba-vuelve-federer-el-numero-uno-como-objetivo\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/llega-la-hierba-vuelve-federer-el-numero-uno-como-objetivo\\\/\",\"name\":\"Llega la hierba, vuelve Federer: el n\\u00famero uno como objetivo | Cand\\u00e1s 365\",\"description\":\"Stuttgart\\\/Berl\\u00edn, 12 jun (dpa) - Con Wimbledon en el horizonte y el n\\u00famero uno del ranking como objetivo, el suizo Roger Federer reaparecer\\u00e1 ma\\u00f1ana en el torneo de Stuttgart tras saltarse toda la gira de arcilla. Llega la hierba y el campe\\u00f3n de 20 Grand Slam regresa a las pistas dispuesto a demostrar su dominio.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/llega-la-hierba-vuelve-federer-el-numero-uno-como-objetivo\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/tennis-2891306_960_720.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/llega-la-hierba-vuelve-federer-el-numero-uno-como-objetivo\\\/#mainImage\",\"width\":960,\"height\":540},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/llega-la-hierba-vuelve-federer-el-numero-uno-como-objetivo\\\/#mainImage\"},\"datePublished\":\"2018-06-12T20:27:37+02:00\",\"dateModified\":\"2018-06-12T20:27:37+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Llega la hierba, vuelve Federer: el n\u00famero uno como objetivo | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Llega la hierba, vuelve Federer: el n\u00famero uno como objetivo | Cand\u00e1s 365","description":"Stuttgart\/Berl\u00edn, 12 jun (dpa) - Con Wimbledon en el horizonte y el n\u00famero uno del ranking como objetivo, el suizo Roger Federer reaparecer\u00e1 ma\u00f1ana en el torneo de Stuttgart tras saltarse toda la gira de arcilla. Llega la hierba y el campe\u00f3n de 20 Grand Slam regresa a las pistas dispuesto a demostrar su dominio.","canonical_url":"https:\/\/candas365.es\/noticias\/llega-la-hierba-vuelve-federer-el-numero-uno-como-objetivo\/","robots":"max-image-preview:large","keywords":"deporte","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/llega-la-hierba-vuelve-federer-el-numero-uno-como-objetivo\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/deporte\/#listItem","name":"Deporte"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/deporte\/#listItem","position":2,"name":"Deporte","item":"https:\/\/candas365.es\/noticias\/category\/deporte\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/llega-la-hierba-vuelve-federer-el-numero-uno-como-objetivo\/#listItem","name":"Llega la hierba, vuelve Federer: el n\u00famero uno como objetivo"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/llega-la-hierba-vuelve-federer-el-numero-uno-como-objetivo\/#listItem","position":3,"name":"Llega la hierba, vuelve Federer: el n\u00famero uno como objetivo","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/deporte\/#listItem","name":"Deporte"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/llega-la-hierba-vuelve-federer-el-numero-uno-como-objetivo\/#newsarticle","name":"Llega la hierba, vuelve Federer: el n\u00famero uno como objetivo | Cand\u00e1s 365","headline":"Llega la hierba, vuelve Federer: el n\u00famero uno como objetivo","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/tennis-2891306_960_720.jpg","width":960,"height":540},"datePublished":"2018-06-12T20:27:37+02:00","dateModified":"2018-06-12T20:27:37+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/llega-la-hierba-vuelve-federer-el-numero-uno-como-objetivo\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/llega-la-hierba-vuelve-federer-el-numero-uno-como-objetivo\/#webpage"},"articleSection":"Deporte","dateline":"Publicado el junio 12, 2018."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/llega-la-hierba-vuelve-federer-el-numero-uno-como-objetivo\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/llega-la-hierba-vuelve-federer-el-numero-uno-como-objetivo\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/llega-la-hierba-vuelve-federer-el-numero-uno-como-objetivo\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/llega-la-hierba-vuelve-federer-el-numero-uno-como-objetivo\/#webpage","url":"https:\/\/candas365.es\/noticias\/llega-la-hierba-vuelve-federer-el-numero-uno-como-objetivo\/","name":"Llega la hierba, vuelve Federer: el n\u00famero uno como objetivo | Cand\u00e1s 365","description":"Stuttgart\/Berl\u00edn, 12 jun (dpa) - Con Wimbledon en el horizonte y el n\u00famero uno del ranking como objetivo, el suizo Roger Federer reaparecer\u00e1 ma\u00f1ana en el torneo de Stuttgart tras saltarse toda la gira de arcilla. Llega la hierba y el campe\u00f3n de 20 Grand Slam regresa a las pistas dispuesto a demostrar su dominio.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/llega-la-hierba-vuelve-federer-el-numero-uno-como-objetivo\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/tennis-2891306_960_720.jpg","@id":"https:\/\/candas365.es\/noticias\/llega-la-hierba-vuelve-federer-el-numero-uno-como-objetivo\/#mainImage","width":960,"height":540},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/llega-la-hierba-vuelve-federer-el-numero-uno-como-objetivo\/#mainImage"},"datePublished":"2018-06-12T20:27:37+02:00","dateModified":"2018-06-12T20:27:37+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Llega la hierba, vuelve Federer: el n\u00famero uno como objetivo | Cand\u00e1s 365","og:description":"Stuttgart\/Berl\u00edn, 12 jun (dpa) - Con Wimbledon en el horizonte y el n\u00famero uno del ranking como objetivo, el suizo Roger Federer reaparecer\u00e1 ma\u00f1ana en el torneo de Stuttgart tras saltarse toda la gira de arcilla. Llega la hierba y el campe\u00f3n de 20 Grand Slam regresa a las pistas dispuesto a demostrar su dominio.","og:url":"https:\/\/candas365.es\/noticias\/llega-la-hierba-vuelve-federer-el-numero-uno-como-objetivo\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/tennis-2891306_960_720.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/tennis-2891306_960_720.jpg","og:image:width":960,"og:image:height":540,"article:published_time":"2018-06-12T20:27:37+00:00","article:modified_time":"2018-06-12T20:27:37+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Llega la hierba, vuelve Federer: el n\u00famero uno como objetivo | Cand\u00e1s 365","twitter:description":"Stuttgart\/Berl\u00edn, 12 jun (dpa) - Con Wimbledon en el horizonte y el n\u00famero uno del ranking como objetivo, el suizo Roger Federer reaparecer\u00e1 ma\u00f1ana en el torneo de Stuttgart tras saltarse toda la gira de arcilla. Llega la hierba y el campe\u00f3n de 20 Grand Slam regresa a las pistas dispuesto a demostrar su dominio.","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/tennis-2891306_960_720.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"97854","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-27 01:53:21","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 11:50:40","updated":"2025-08-27 01:53:21"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/deporte\/\" title=\"Deporte\">Deporte<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tLlega la hierba, vuelve Federer: el n\u00famero uno como objetivo\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Deporte","link":"https:\/\/candas365.es\/noticias\/category\/deporte\/"},{"label":"Llega la hierba, vuelve Federer: el n\u00famero uno como objetivo","link":"https:\/\/candas365.es\/noticias\/llega-la-hierba-vuelve-federer-el-numero-uno-como-objetivo\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/97854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=97854"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/97854\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/95170"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=97854"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=97854"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=97854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}