{"id":97719,"date":"2018-06-10T23:09:41","date_gmt":"2018-06-10T23:09:41","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=97719"},"modified":"2018-06-10T23:09:41","modified_gmt":"2018-06-10T23:09:41","slug":"nadal-agranda-su-leyenda-en-roland-garros","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/nadal-agranda-su-leyenda-en-roland-garros\/","title":{"rendered":"Nadal agranda su leyenda en Roland Garros"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-94738\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/04\/tennis-923659_960_720-360x270.jpg\" alt=\"\" width=\"360\" height=\"270\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/04\/tennis-923659_960_720-360x270.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/04\/tennis-923659_960_720-768x576.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/04\/tennis-923659_960_720-640x480.jpg 640w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/04\/tennis-923659_960_720-80x60.jpg 80w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/04\/tennis-923659_960_720-265x198.jpg 265w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/04\/tennis-923659_960_720-696x522.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/04\/tennis-923659_960_720-560x420.jpg 560w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/04\/tennis-923659_960_720.jpg 960w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Par\u00eds, 10 jun (dpa) &#8211; El espa\u00f1ol Rafael Nadal no tiene l\u00edmites en Par\u00eds, donde hoy alz\u00f3 su und\u00e9cimo t\u00edtulo en el Abierto de tenis de Francia al vencer al austr\u00edaco Dominic Thiem.<\/p>\n<p>El austr\u00edaco, una de las \u00faltimas grandes apariciones en arcilla, no fue suficiente oposici\u00f3n para el campe\u00f3n, que lo derrot\u00f3 con parciales de 6-4, 6-3 y 6-2 en dos horas y 42 minutos y celebr\u00f3 as\u00ed otra consagraci\u00f3n en Par\u00eds.<\/p>\n<p>\u00abGanar 11 veces aqu\u00ed es mucho\u00bb, consider\u00f3 Nadal, que lleg\u00f3 a su d\u00e9cimo s\u00e9ptimo Grand Slam, solo tres menos que el suizo Roger Federer, el m\u00e1s ganador de la historia en el circuito masculino.<\/p>\n<p>Con su triunfo en la Porte d&#8217;Auteuil, Nadal igual\u00f3 adem\u00e1s el r\u00e9cord de ganar 11 veces el mismo torneo que estaba hasta hoy en poder de la australiana Margaret Court, once veces ganadora en el Abierto de su pa\u00eds.<\/p>\n<p>\u00abEs algo casi \u00fanico, es dif\u00edcil de pensar ganar 11 veces el mismo torneo\u00bb, continu\u00f3 el espa\u00f1ol.<\/p>\n<p>\u00abEstoy agradecido a la vida por la posibilidad que me ha dado porque al final hay much\u00edsima gente que trabaja como yo, o m\u00e1s quiz\u00e1, y no tiene la suerte que yo he tenido\u00bb, explic\u00f3 el n\u00famero uno del mundo.<\/p>\n<p>Thiem, de su lado, valor\u00f3 un nuevo triunfo del espa\u00f1ol, al que vio por la televisi\u00f3n cuando gan\u00f3 sus primeros t\u00edtulos en la Porte d&#8217;Auteuil.<\/p>\n<p>\u00abFue un partido decente de mi parte\u00bb, explic\u00f3 el octavo del ranking. \u00ab\u00c9l estaba jugando muy bien, creo, y no por nada gan\u00f3 once veces aqu\u00ed. Es definitivamente una de las mejores cosas que cualquier persona logr\u00f3 jam\u00e1s en el deporte\u00bb, analiz\u00f3.<\/p>\n<p>\u00abF\u00edsicamente disfrut\u00e9 m\u00e1s verlo en mi sof\u00e1\u00bb, sonri\u00f3 Thiem. \u00abCuando gan\u00f3 aqu\u00ed por primera vez, en realidad cuando gan\u00f3 aqu\u00ed las primeras cuatro o cinco veces, siempre estaba mir\u00e1ndolo\u00bb.<\/p>\n<p>\u00abDesde luego que es tremendo que logr\u00e9 competir en una final contra \u00e9l. Es algo tremendo, honestamente, pero aun as\u00ed estoy triste. Era una final. Quer\u00eda de veras ganar\u00bb, apunt\u00f3 el austr\u00edaco.<\/p>\n<p>Por lo pronto, Par\u00eds es el reino de Nadal. Despu\u00e9s de ganar t\u00edtulos consecutivos entre 2005-2008 y 2010-2014, el mallorqu\u00edn defendi\u00f3 con \u00e9xito el trofeo que gan\u00f3 el a\u00f1o pasado y demostr\u00f3, en suma, que a\u00fan ser\u00e1 muy dif\u00edcil destronarlo en la Porte d&#8217;Auteuil.<\/p>\n<p>La victoria de hoy es, adem\u00e1s, una gran prueba de vigencia, ya que es el cuarto tenista en la historia del circuito masculino que gana tres o m\u00e1s grandes despu\u00e9s de haber cumplido los 30 a\u00f1os.<\/p>\n<p>Sin ser arrollador, Nadal fue s\u00f3lido y aprovech\u00f3 la falta de precisi\u00f3n de un Thiem err\u00e1tico y poco efectivo en los momentos definitivos.<\/p>\n<p>Hubo paridad solo al principio, cuando ambos se quebraron el servicio y parec\u00edan no sacarse demasiada ventaja. Pero el espa\u00f1ol, como siempre, abri\u00f3 una grieta all\u00ed cuando hac\u00eda falta.<\/p>\n<p>Thiem sacaba para ponerse 5-5, pero dej\u00f3 una primera pelota en la red. Otros dos fallos dieron una ocasi\u00f3n de oro a Nadal, que gan\u00f3 el set y empez\u00f3 a ser due\u00f1o del partido.<\/p>\n<p>Al austr\u00edaco, de 24 a\u00f1os, le pes\u00f3 la falta de experiencia y no pudo completar una estrategia con la que pudiera amenazar al mallorqu\u00edn.<\/p>\n<p>El espa\u00f1ol, que cerca de la definici\u00f3n del partido tuvo molestias en la mano izquierda y fue atendido dos veces por el doctor del torneo, necesit\u00f3 otros dos quiebres en cada set para sellar la victoria.<\/p>\n<p>Si los dolores hubieran seguido, habr\u00eda igualmente seguido, como confes\u00f3 despu\u00e9s. \u00abHubiera jugado hasta con el brazo derecho, ten\u00eda dos sets de margen\u00bb, se\u00f1al\u00f3 contundente el balear<\/p>\n<p>Pero continu\u00f3 con la izquierda y en su quinta bola de partido, tras una devoluci\u00f3n larga de Thiem, festej\u00f3 un nuevo Roland Garros. En Par\u00eds, Nadal es infinito.<\/p>\n<p>Por Manuel Due\u00f1as (dpa)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Par\u00eds, 10 jun (dpa) &#8211; El espa\u00f1ol Rafael Nadal no tiene l\u00edmites en Par\u00eds, donde hoy alz\u00f3 su und\u00e9cimo t\u00edtulo en el Abierto de tenis de Francia al vencer al austr\u00edaco Dominic Thiem. El austr\u00edaco, una de las \u00faltimas grandes apariciones en arcilla, no fue suficiente oposici\u00f3n para el campe\u00f3n, que lo derrot\u00f3 con parciales<\/p>\n","protected":false},"author":1,"featured_media":94989,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[319],"tags":[],"class_list":{"0":"post-97719","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-deporte"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7 - aioseo.com -->\n\t<meta name=\"description\" content=\"Par\u00eds, 10 jun (dpa) - El espa\u00f1ol Rafael Nadal no tiene l\u00edmites en Par\u00eds, donde hoy alz\u00f3 su und\u00e9cimo t\u00edtulo en el Abierto de tenis de Francia al vencer al austr\u00edaco Dominic Thiem. El austr\u00edaco, una de las \u00faltimas grandes apariciones en arcilla, no fue suficiente oposici\u00f3n para el campe\u00f3n, que lo derrot\u00f3 con parciales\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"deporte\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/nadal-agranda-su-leyenda-en-roland-garros\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Nadal agranda su leyenda en Roland Garros | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Par\u00eds, 10 jun (dpa) - El espa\u00f1ol Rafael Nadal no tiene l\u00edmites en Par\u00eds, donde hoy alz\u00f3 su und\u00e9cimo t\u00edtulo en el Abierto de tenis de Francia al vencer al austr\u00edaco Dominic Thiem. El austr\u00edaco, una de las \u00faltimas grandes apariciones en arcilla, no fue suficiente oposici\u00f3n para el campe\u00f3n, que lo derrot\u00f3 con parciales\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/nadal-agranda-su-leyenda-en-roland-garros\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/04\/tennis-923659_960_720-1.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/04\/tennis-923659_960_720-1.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-06-10T23:09:41+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-06-10T23:09:41+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Nadal agranda su leyenda en Roland Garros | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Par\u00eds, 10 jun (dpa) - El espa\u00f1ol Rafael Nadal no tiene l\u00edmites en Par\u00eds, donde hoy alz\u00f3 su und\u00e9cimo t\u00edtulo en el Abierto de tenis de Francia al vencer al austr\u00edaco Dominic Thiem. El austr\u00edaco, una de las \u00faltimas grandes apariciones en arcilla, no fue suficiente oposici\u00f3n para el campe\u00f3n, que lo derrot\u00f3 con parciales\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/04\/tennis-923659_960_720-1.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/nadal-agranda-su-leyenda-en-roland-garros\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/#listItem\",\"name\":\"Deporte\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/#listItem\",\"position\":2,\"name\":\"Deporte\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/nadal-agranda-su-leyenda-en-roland-garros\\\/#listItem\",\"name\":\"Nadal agranda su leyenda en Roland Garros\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/nadal-agranda-su-leyenda-en-roland-garros\\\/#listItem\",\"position\":3,\"name\":\"Nadal agranda su leyenda en Roland Garros\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/#listItem\",\"name\":\"Deporte\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/nadal-agranda-su-leyenda-en-roland-garros\\\/#newsarticle\",\"name\":\"Nadal agranda su leyenda en Roland Garros | Cand\\u00e1s 365\",\"headline\":\"Nadal agranda su leyenda en Roland Garros\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/tennis-923659_960_720-1.jpg\",\"width\":960,\"height\":720,\"caption\":\"tennis\"},\"datePublished\":\"2018-06-10T23:09:41+02:00\",\"dateModified\":\"2018-06-10T23:09:41+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/nadal-agranda-su-leyenda-en-roland-garros\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/nadal-agranda-su-leyenda-en-roland-garros\\\/#webpage\"},\"articleSection\":\"Deporte\",\"dateline\":\"Publicado el junio 10, 2018.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/nadal-agranda-su-leyenda-en-roland-garros\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/nadal-agranda-su-leyenda-en-roland-garros\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/nadal-agranda-su-leyenda-en-roland-garros\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/nadal-agranda-su-leyenda-en-roland-garros\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/nadal-agranda-su-leyenda-en-roland-garros\\\/\",\"name\":\"Nadal agranda su leyenda en Roland Garros | Cand\\u00e1s 365\",\"description\":\"Par\\u00eds, 10 jun (dpa) - El espa\\u00f1ol Rafael Nadal no tiene l\\u00edmites en Par\\u00eds, donde hoy alz\\u00f3 su und\\u00e9cimo t\\u00edtulo en el Abierto de tenis de Francia al vencer al austr\\u00edaco Dominic Thiem. El austr\\u00edaco, una de las \\u00faltimas grandes apariciones en arcilla, no fue suficiente oposici\\u00f3n para el campe\\u00f3n, que lo derrot\\u00f3 con parciales\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/nadal-agranda-su-leyenda-en-roland-garros\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/tennis-923659_960_720-1.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/nadal-agranda-su-leyenda-en-roland-garros\\\/#mainImage\",\"width\":960,\"height\":720,\"caption\":\"tennis\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/nadal-agranda-su-leyenda-en-roland-garros\\\/#mainImage\"},\"datePublished\":\"2018-06-10T23:09:41+02:00\",\"dateModified\":\"2018-06-10T23:09:41+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Nadal agranda su leyenda en Roland Garros | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Nadal agranda su leyenda en Roland Garros | Cand\u00e1s 365","description":"Par\u00eds, 10 jun (dpa) - El espa\u00f1ol Rafael Nadal no tiene l\u00edmites en Par\u00eds, donde hoy alz\u00f3 su und\u00e9cimo t\u00edtulo en el Abierto de tenis de Francia al vencer al austr\u00edaco Dominic Thiem. El austr\u00edaco, una de las \u00faltimas grandes apariciones en arcilla, no fue suficiente oposici\u00f3n para el campe\u00f3n, que lo derrot\u00f3 con parciales","canonical_url":"https:\/\/candas365.es\/noticias\/nadal-agranda-su-leyenda-en-roland-garros\/","robots":"max-image-preview:large","keywords":"deporte","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/nadal-agranda-su-leyenda-en-roland-garros\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/deporte\/#listItem","name":"Deporte"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/deporte\/#listItem","position":2,"name":"Deporte","item":"https:\/\/candas365.es\/noticias\/category\/deporte\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/nadal-agranda-su-leyenda-en-roland-garros\/#listItem","name":"Nadal agranda su leyenda en Roland Garros"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/nadal-agranda-su-leyenda-en-roland-garros\/#listItem","position":3,"name":"Nadal agranda su leyenda en Roland Garros","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/deporte\/#listItem","name":"Deporte"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/nadal-agranda-su-leyenda-en-roland-garros\/#newsarticle","name":"Nadal agranda su leyenda en Roland Garros | Cand\u00e1s 365","headline":"Nadal agranda su leyenda en Roland Garros","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/04\/tennis-923659_960_720-1.jpg","width":960,"height":720,"caption":"tennis"},"datePublished":"2018-06-10T23:09:41+02:00","dateModified":"2018-06-10T23:09:41+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/nadal-agranda-su-leyenda-en-roland-garros\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/nadal-agranda-su-leyenda-en-roland-garros\/#webpage"},"articleSection":"Deporte","dateline":"Publicado el junio 10, 2018."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/nadal-agranda-su-leyenda-en-roland-garros\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/nadal-agranda-su-leyenda-en-roland-garros\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/nadal-agranda-su-leyenda-en-roland-garros\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/nadal-agranda-su-leyenda-en-roland-garros\/#webpage","url":"https:\/\/candas365.es\/noticias\/nadal-agranda-su-leyenda-en-roland-garros\/","name":"Nadal agranda su leyenda en Roland Garros | Cand\u00e1s 365","description":"Par\u00eds, 10 jun (dpa) - El espa\u00f1ol Rafael Nadal no tiene l\u00edmites en Par\u00eds, donde hoy alz\u00f3 su und\u00e9cimo t\u00edtulo en el Abierto de tenis de Francia al vencer al austr\u00edaco Dominic Thiem. El austr\u00edaco, una de las \u00faltimas grandes apariciones en arcilla, no fue suficiente oposici\u00f3n para el campe\u00f3n, que lo derrot\u00f3 con parciales","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/nadal-agranda-su-leyenda-en-roland-garros\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/04\/tennis-923659_960_720-1.jpg","@id":"https:\/\/candas365.es\/noticias\/nadal-agranda-su-leyenda-en-roland-garros\/#mainImage","width":960,"height":720,"caption":"tennis"},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/nadal-agranda-su-leyenda-en-roland-garros\/#mainImage"},"datePublished":"2018-06-10T23:09:41+02:00","dateModified":"2018-06-10T23:09:41+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Nadal agranda su leyenda en Roland Garros | Cand\u00e1s 365","og:description":"Par\u00eds, 10 jun (dpa) - El espa\u00f1ol Rafael Nadal no tiene l\u00edmites en Par\u00eds, donde hoy alz\u00f3 su und\u00e9cimo t\u00edtulo en el Abierto de tenis de Francia al vencer al austr\u00edaco Dominic Thiem. El austr\u00edaco, una de las \u00faltimas grandes apariciones en arcilla, no fue suficiente oposici\u00f3n para el campe\u00f3n, que lo derrot\u00f3 con parciales","og:url":"https:\/\/candas365.es\/noticias\/nadal-agranda-su-leyenda-en-roland-garros\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/04\/tennis-923659_960_720-1.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/04\/tennis-923659_960_720-1.jpg","og:image:width":960,"og:image:height":720,"article:published_time":"2018-06-10T23:09:41+00:00","article:modified_time":"2018-06-10T23:09:41+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Nadal agranda su leyenda en Roland Garros | Cand\u00e1s 365","twitter:description":"Par\u00eds, 10 jun (dpa) - El espa\u00f1ol Rafael Nadal no tiene l\u00edmites en Par\u00eds, donde hoy alz\u00f3 su und\u00e9cimo t\u00edtulo en el Abierto de tenis de Francia al vencer al austr\u00edaco Dominic Thiem. El austr\u00edaco, una de las \u00faltimas grandes apariciones en arcilla, no fue suficiente oposici\u00f3n para el campe\u00f3n, que lo derrot\u00f3 con parciales","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/04\/tennis-923659_960_720-1.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"3 minutos"},"aioseo_meta_data":{"post_id":"97719","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-27 01:28:13","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 11:50:40","updated":"2025-08-27 01:28:13"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/deporte\/\" title=\"Deporte\">Deporte<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tNadal agranda su leyenda en Roland Garros\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Deporte","link":"https:\/\/candas365.es\/noticias\/category\/deporte\/"},{"label":"Nadal agranda su leyenda en Roland Garros","link":"https:\/\/candas365.es\/noticias\/nadal-agranda-su-leyenda-en-roland-garros\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/97719","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=97719"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/97719\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/94989"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=97719"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=97719"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=97719"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}