{"id":97555,"date":"2018-06-08T23:03:09","date_gmt":"2018-06-08T23:03:09","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=97555"},"modified":"2018-06-08T23:03:09","modified_gmt":"2018-06-08T23:03:09","slug":"roland-garros-2018-nadal-vs-thiem-en-una-nueva-final-de-leyenda","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/roland-garros-2018-nadal-vs-thiem-en-una-nueva-final-de-leyenda\/","title":{"rendered":"Roland Garros 2018: Nadal vs Thiem en una nueva final de \u201cleyenda\u201d"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-93878\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/04\/tennis-2114788_960_720-360x171.jpg\" alt=\"\" width=\"360\" height=\"171\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/04\/tennis-2114788_960_720-360x171.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/04\/tennis-2114788_960_720-696x331.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/04\/tennis-2114788_960_720-882x420.jpg 882w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/04\/tennis-2114788_960_720-768x366.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/04\/tennis-2114788_960_720-655x312.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/04\/tennis-2114788_960_720.jpg 960w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Par\u00eds, 8 jun (dpa) &#8211; El espa\u00f1ol Rafael Nadal super\u00f3 hoy una prueba que result\u00f3 menos dif\u00edcil de lo esperado ante el argentino Juan Mart\u00edn del Potro y buscar\u00e1 el domingo ante el austr\u00edaco Dominic Thiem su und\u00e9cimo t\u00edtulo en el Abierto de tenis de Francia.<\/p>\n<p>Nadal derrot\u00f3 6-4, 6-1 y 6-2 a Del Potro en dos horas y 14 minutos, mientras que Thiem, s\u00e9ptimo preclasificado de Roland Garros, venci\u00f3 m\u00e1s temprano 7-5, 7-6 (12-10) y 6-1 al italiano Marco Cecchinato en dos horas y 21 minutos.<\/p>\n<p>El espa\u00f1ol, que deber\u00e1 ganar el t\u00edtulo para mantener el n\u00famero uno del ranking mundial, se sum\u00f3 as\u00ed al suizo Roger Federer como el segundo jugador en la Era Abierta que llega a once finales en el mismo Grand Slam, ese caso Wimbledon.<\/p>\n<p>El domingo, el n\u00famero uno del mundo se enfrentar\u00e1 a Thiem, el \u00fanico que lo venci\u00f3 en canchas lentas en las \u00faltimas dos temporadas, con triunfos el a\u00f1o pasado en Roma y hace unas semanas en Madrid, las dos veces en cuartos de final.<\/p>\n<p>Y aunque el mallorqu\u00edn domina el historial con seis victorias en nueve partidos, dos de ellas en Roland Garros, el \u00faltimo precedente entre ambos es el triunfo del austr\u00edaco en la capital espa\u00f1ola.<\/p>\n<p>\u00abHoy es un d\u00eda para estar felices, (&#8230;) son 11 veces de estar en una final en Roland Garros, parece menos, pero la realidad es que hoy es un d\u00eda para estar contentos\u00bb, se\u00f1al\u00f3 el campe\u00f3n de 16 Grand Slam.<\/p>\n<p>\u00abEstar en otra final en un torneo como Roland Garros, parece que es lo l\u00f3gico pero no lo es, al menos no quiero que as\u00ed lo sea\u00bb, explic\u00f3 Nadal.<\/p>\n<p>Ante Del Potro, fue de entrada un partido muy cerrado, marcado por los detalles. Y por la falta de efectividad del tandilense y la extrema precisi\u00f3n del espa\u00f1ol.<\/p>\n<p>As\u00ed, el argentino desaprovech\u00f3 las seis bolas de quiebre que gener\u00f3 en el primer set y dio aire a un rival que estaba inc\u00f3modo con su servicio. Nadal hizo todo lo contrario: tom\u00f3 la segunda oportunidad que tuvo y se fue en ventaja.<\/p>\n<p>El fastidio de Del Potro, que tir\u00f3 una raqueta en el descanso entre sets, era l\u00f3gico: no hay que darle espacio al diez veces campe\u00f3n en Par\u00eds. M\u00e1s afianzado, el balear volvi\u00f3 adem\u00e1s a tomar distancia, esta vez casi sin cederle un solo juego al argentino.<\/p>\n<p>El resto fue poco m\u00e1s que un tr\u00e1mite, con un Del Potro sin respuestas y un Nadal lanzado a escribir un nuevo cap\u00edtulo de su historia en la Porte d&#8217;Auteuil.<\/p>\n<p>\u00abMe siento muy afortunado de haber salvado ese primer set, mentalmente he asumido bien el reto y he encarado bien los momentos dif\u00edciles\u00bb, dijo Nadal al respecto.<\/p>\n<p>\u00abLo normal, as\u00ed como ha ido el primer set, es que lo hubiera perdido y esa es una realidad\u00bb, a\u00f1adi\u00f3. \u00abDespues en el 5-4 he jugado un muy buen juego, con buena determinaci\u00f3n, era momento el de apretar y lo he hecho, (&#8230;) a partir de ah\u00ed el partido ha cambiado radicalmente\u00bb, ilustr\u00f3.<\/p>\n<p>M\u00e1s temprano, Thiem firm\u00f3 un partido s\u00f3lido en el que redujo progresivamente a Cecchinato y alcanz\u00f3 su victoria 35 del a\u00f1o, m\u00e1s que ning\u00fan otro jugador en el circuito. Adem\u00e1s, se asegur\u00f3 llegar al s\u00e9ptimo lugar del ranking desde el lunes.<\/p>\n<p>Consciente quiz\u00e1 del peligro que representaba el italiano, que tumb\u00f3 al serbio Novak Djokovic en cuartos despu\u00e9s de ganar unas rondas antes su primer partido en un Grand Slam, Thiem entreg\u00f3 pocos espacios a Cecchinato e impuso paulatinamente su juego.<\/p>\n<p>El austr\u00edaco sali\u00f3 airoso de dos primeros sets m\u00e1s ajustados, sobre todo el segundo, que se defini\u00f3 despu\u00e9s de un intenso tie-break. Para el italiano, sin embargo, ese fue un golpe brutal.<\/p>\n<p>\u00abLa gran clave fue el segundo set, fue un tie-break ajustado y no me hubiera gustado perderlo porque habr\u00eda sido un partido dif\u00edcil\u00bb, reconoci\u00f3 el austr\u00edaco.<\/p>\n<p>\u00abEs lindo haber superado ese momento y llegar a la final aqu\u00ed por primera vez\u00bb, a\u00f1adi\u00f3.<\/p>\n<p>Y es que desde ese momento no hubo m\u00e1s partido: Thiem dobleg\u00f3 definitivamente a Cecchinato y sell\u00f3 con su servicio una victoria que le permite so\u00f1ar, aunque enfrente tendr\u00e1 al rey de la arcilla.<\/p>\n<p>\u00abEs el gran favorito. Pero s\u00e9 c\u00f3mo jugar ante \u00e9l. Tengo un plan\u00bb, afirm\u00f3 Thiem, que sin embargo perdi\u00f3 ante Nadal en Par\u00eds en las semifinales del a\u00f1o pasado.<\/p>\n<p>\u00abIntentar\u00e9 todo para que mi plan funcione aqu\u00ed y no solo en Madrid o en Roma\u00bb, a\u00f1adi\u00f3 el austr\u00edaco, que ir\u00e1 con fe el domingo ante el diez veces campe\u00f3n.<\/p>\n<p><i class=\"lang-es\"><span class=\" readonly\" title=\"\">Por Manuel Due\u00f1as (dpa)<\/span><\/i><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Par\u00eds, 8 jun (dpa) &#8211; El espa\u00f1ol Rafael Nadal super\u00f3 hoy una prueba que result\u00f3 menos dif\u00edcil de lo esperado ante el argentino Juan Mart\u00edn del Potro y buscar\u00e1 el domingo ante el austr\u00edaco Dominic Thiem su und\u00e9cimo t\u00edtulo en el Abierto de tenis de Francia. Nadal derrot\u00f3 6-4, 6-1 y 6-2 a Del Potro<\/p>\n","protected":false},"author":1,"featured_media":94989,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[319],"tags":[],"class_list":{"0":"post-97555","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-deporte"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7 - aioseo.com -->\n\t<meta name=\"description\" content=\"Par\u00eds, 8 jun (dpa) - El espa\u00f1ol Rafael Nadal super\u00f3 hoy una prueba que result\u00f3 menos dif\u00edcil de lo esperado ante el argentino Juan Mart\u00edn del Potro y buscar\u00e1 el domingo ante el austr\u00edaco Dominic Thiem su und\u00e9cimo t\u00edtulo en el Abierto de tenis de Francia. Nadal derrot\u00f3 6-4, 6-1 y 6-2 a Del Potro\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"deporte\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/roland-garros-2018-nadal-vs-thiem-en-una-nueva-final-de-leyenda\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Roland Garros 2018: Nadal vs Thiem en una nueva final de \u201cleyenda\u201d | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Par\u00eds, 8 jun (dpa) - El espa\u00f1ol Rafael Nadal super\u00f3 hoy una prueba que result\u00f3 menos dif\u00edcil de lo esperado ante el argentino Juan Mart\u00edn del Potro y buscar\u00e1 el domingo ante el austr\u00edaco Dominic Thiem su und\u00e9cimo t\u00edtulo en el Abierto de tenis de Francia. Nadal derrot\u00f3 6-4, 6-1 y 6-2 a Del Potro\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/roland-garros-2018-nadal-vs-thiem-en-una-nueva-final-de-leyenda\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/04\/tennis-923659_960_720-1.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/04\/tennis-923659_960_720-1.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-06-08T23:03:09+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-06-08T23:03:09+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Roland Garros 2018: Nadal vs Thiem en una nueva final de \u201cleyenda\u201d | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Par\u00eds, 8 jun (dpa) - El espa\u00f1ol Rafael Nadal super\u00f3 hoy una prueba que result\u00f3 menos dif\u00edcil de lo esperado ante el argentino Juan Mart\u00edn del Potro y buscar\u00e1 el domingo ante el austr\u00edaco Dominic Thiem su und\u00e9cimo t\u00edtulo en el Abierto de tenis de Francia. Nadal derrot\u00f3 6-4, 6-1 y 6-2 a Del Potro\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/04\/tennis-923659_960_720-1.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/roland-garros-2018-nadal-vs-thiem-en-una-nueva-final-de-leyenda\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/#listItem\",\"name\":\"Deporte\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/#listItem\",\"position\":2,\"name\":\"Deporte\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/roland-garros-2018-nadal-vs-thiem-en-una-nueva-final-de-leyenda\\\/#listItem\",\"name\":\"Roland Garros 2018: Nadal vs Thiem en una nueva final de \\u201cleyenda\\u201d\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/roland-garros-2018-nadal-vs-thiem-en-una-nueva-final-de-leyenda\\\/#listItem\",\"position\":3,\"name\":\"Roland Garros 2018: Nadal vs Thiem en una nueva final de \\u201cleyenda\\u201d\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/#listItem\",\"name\":\"Deporte\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/roland-garros-2018-nadal-vs-thiem-en-una-nueva-final-de-leyenda\\\/#newsarticle\",\"name\":\"Roland Garros 2018: Nadal vs Thiem en una nueva final de \\u201cleyenda\\u201d | Cand\\u00e1s 365\",\"headline\":\"Roland Garros 2018: Nadal vs Thiem en una nueva final de \\u201cleyenda\\u201d\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/tennis-923659_960_720-1.jpg\",\"width\":960,\"height\":720,\"caption\":\"tennis\"},\"datePublished\":\"2018-06-08T23:03:09+02:00\",\"dateModified\":\"2018-06-08T23:03:09+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/roland-garros-2018-nadal-vs-thiem-en-una-nueva-final-de-leyenda\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/roland-garros-2018-nadal-vs-thiem-en-una-nueva-final-de-leyenda\\\/#webpage\"},\"articleSection\":\"Deporte\",\"dateline\":\"Publicado el junio 8, 2018.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/roland-garros-2018-nadal-vs-thiem-en-una-nueva-final-de-leyenda\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/roland-garros-2018-nadal-vs-thiem-en-una-nueva-final-de-leyenda\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/roland-garros-2018-nadal-vs-thiem-en-una-nueva-final-de-leyenda\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/roland-garros-2018-nadal-vs-thiem-en-una-nueva-final-de-leyenda\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/roland-garros-2018-nadal-vs-thiem-en-una-nueva-final-de-leyenda\\\/\",\"name\":\"Roland Garros 2018: Nadal vs Thiem en una nueva final de \\u201cleyenda\\u201d | Cand\\u00e1s 365\",\"description\":\"Par\\u00eds, 8 jun (dpa) - El espa\\u00f1ol Rafael Nadal super\\u00f3 hoy una prueba que result\\u00f3 menos dif\\u00edcil de lo esperado ante el argentino Juan Mart\\u00edn del Potro y buscar\\u00e1 el domingo ante el austr\\u00edaco Dominic Thiem su und\\u00e9cimo t\\u00edtulo en el Abierto de tenis de Francia. Nadal derrot\\u00f3 6-4, 6-1 y 6-2 a Del Potro\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/roland-garros-2018-nadal-vs-thiem-en-una-nueva-final-de-leyenda\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/tennis-923659_960_720-1.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/roland-garros-2018-nadal-vs-thiem-en-una-nueva-final-de-leyenda\\\/#mainImage\",\"width\":960,\"height\":720,\"caption\":\"tennis\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/roland-garros-2018-nadal-vs-thiem-en-una-nueva-final-de-leyenda\\\/#mainImage\"},\"datePublished\":\"2018-06-08T23:03:09+02:00\",\"dateModified\":\"2018-06-08T23:03:09+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Roland Garros 2018: Nadal vs Thiem en una nueva final de \u201cleyenda\u201d | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Roland Garros 2018: Nadal vs Thiem en una nueva final de \u201cleyenda\u201d | Cand\u00e1s 365","description":"Par\u00eds, 8 jun (dpa) - El espa\u00f1ol Rafael Nadal super\u00f3 hoy una prueba que result\u00f3 menos dif\u00edcil de lo esperado ante el argentino Juan Mart\u00edn del Potro y buscar\u00e1 el domingo ante el austr\u00edaco Dominic Thiem su und\u00e9cimo t\u00edtulo en el Abierto de tenis de Francia. Nadal derrot\u00f3 6-4, 6-1 y 6-2 a Del Potro","canonical_url":"https:\/\/candas365.es\/noticias\/roland-garros-2018-nadal-vs-thiem-en-una-nueva-final-de-leyenda\/","robots":"max-image-preview:large","keywords":"deporte","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/roland-garros-2018-nadal-vs-thiem-en-una-nueva-final-de-leyenda\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/deporte\/#listItem","name":"Deporte"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/deporte\/#listItem","position":2,"name":"Deporte","item":"https:\/\/candas365.es\/noticias\/category\/deporte\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/roland-garros-2018-nadal-vs-thiem-en-una-nueva-final-de-leyenda\/#listItem","name":"Roland Garros 2018: Nadal vs Thiem en una nueva final de \u201cleyenda\u201d"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/roland-garros-2018-nadal-vs-thiem-en-una-nueva-final-de-leyenda\/#listItem","position":3,"name":"Roland Garros 2018: Nadal vs Thiem en una nueva final de \u201cleyenda\u201d","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/deporte\/#listItem","name":"Deporte"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/roland-garros-2018-nadal-vs-thiem-en-una-nueva-final-de-leyenda\/#newsarticle","name":"Roland Garros 2018: Nadal vs Thiem en una nueva final de \u201cleyenda\u201d | Cand\u00e1s 365","headline":"Roland Garros 2018: Nadal vs Thiem en una nueva final de \u201cleyenda\u201d","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/04\/tennis-923659_960_720-1.jpg","width":960,"height":720,"caption":"tennis"},"datePublished":"2018-06-08T23:03:09+02:00","dateModified":"2018-06-08T23:03:09+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/roland-garros-2018-nadal-vs-thiem-en-una-nueva-final-de-leyenda\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/roland-garros-2018-nadal-vs-thiem-en-una-nueva-final-de-leyenda\/#webpage"},"articleSection":"Deporte","dateline":"Publicado el junio 8, 2018."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/roland-garros-2018-nadal-vs-thiem-en-una-nueva-final-de-leyenda\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/roland-garros-2018-nadal-vs-thiem-en-una-nueva-final-de-leyenda\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/roland-garros-2018-nadal-vs-thiem-en-una-nueva-final-de-leyenda\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/roland-garros-2018-nadal-vs-thiem-en-una-nueva-final-de-leyenda\/#webpage","url":"https:\/\/candas365.es\/noticias\/roland-garros-2018-nadal-vs-thiem-en-una-nueva-final-de-leyenda\/","name":"Roland Garros 2018: Nadal vs Thiem en una nueva final de \u201cleyenda\u201d | Cand\u00e1s 365","description":"Par\u00eds, 8 jun (dpa) - El espa\u00f1ol Rafael Nadal super\u00f3 hoy una prueba que result\u00f3 menos dif\u00edcil de lo esperado ante el argentino Juan Mart\u00edn del Potro y buscar\u00e1 el domingo ante el austr\u00edaco Dominic Thiem su und\u00e9cimo t\u00edtulo en el Abierto de tenis de Francia. Nadal derrot\u00f3 6-4, 6-1 y 6-2 a Del Potro","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/roland-garros-2018-nadal-vs-thiem-en-una-nueva-final-de-leyenda\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/04\/tennis-923659_960_720-1.jpg","@id":"https:\/\/candas365.es\/noticias\/roland-garros-2018-nadal-vs-thiem-en-una-nueva-final-de-leyenda\/#mainImage","width":960,"height":720,"caption":"tennis"},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/roland-garros-2018-nadal-vs-thiem-en-una-nueva-final-de-leyenda\/#mainImage"},"datePublished":"2018-06-08T23:03:09+02:00","dateModified":"2018-06-08T23:03:09+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Roland Garros 2018: Nadal vs Thiem en una nueva final de \u201cleyenda\u201d | Cand\u00e1s 365","og:description":"Par\u00eds, 8 jun (dpa) - El espa\u00f1ol Rafael Nadal super\u00f3 hoy una prueba que result\u00f3 menos dif\u00edcil de lo esperado ante el argentino Juan Mart\u00edn del Potro y buscar\u00e1 el domingo ante el austr\u00edaco Dominic Thiem su und\u00e9cimo t\u00edtulo en el Abierto de tenis de Francia. Nadal derrot\u00f3 6-4, 6-1 y 6-2 a Del Potro","og:url":"https:\/\/candas365.es\/noticias\/roland-garros-2018-nadal-vs-thiem-en-una-nueva-final-de-leyenda\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/04\/tennis-923659_960_720-1.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/04\/tennis-923659_960_720-1.jpg","og:image:width":960,"og:image:height":720,"article:published_time":"2018-06-08T23:03:09+00:00","article:modified_time":"2018-06-08T23:03:09+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Roland Garros 2018: Nadal vs Thiem en una nueva final de \u201cleyenda\u201d | Cand\u00e1s 365","twitter:description":"Par\u00eds, 8 jun (dpa) - El espa\u00f1ol Rafael Nadal super\u00f3 hoy una prueba que result\u00f3 menos dif\u00edcil de lo esperado ante el argentino Juan Mart\u00edn del Potro y buscar\u00e1 el domingo ante el austr\u00edaco Dominic Thiem su und\u00e9cimo t\u00edtulo en el Abierto de tenis de Francia. Nadal derrot\u00f3 6-4, 6-1 y 6-2 a Del Potro","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/04\/tennis-923659_960_720-1.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"4 minutos"},"aioseo_meta_data":{"post_id":"97555","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-27 01:04:10","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 11:50:46","updated":"2025-08-27 01:04:10"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/deporte\/\" title=\"Deporte\">Deporte<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tRoland Garros 2018: Nadal vs Thiem en una nueva final de \u201cleyenda\u201d\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Deporte","link":"https:\/\/candas365.es\/noticias\/category\/deporte\/"},{"label":"Roland Garros 2018: Nadal vs Thiem en una nueva final de \u201cleyenda\u201d","link":"https:\/\/candas365.es\/noticias\/roland-garros-2018-nadal-vs-thiem-en-una-nueva-final-de-leyenda\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/97555","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=97555"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/97555\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/94989"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=97555"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=97555"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=97555"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}