{"id":96512,"date":"2018-05-27T11:55:12","date_gmt":"2018-05-27T11:55:12","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=96512"},"modified":"2018-05-27T11:55:12","modified_gmt":"2018-05-27T11:55:12","slug":"de-ulreich-a-karius-noches-negras-ante-el-real-madrid","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/de-ulreich-a-karius-noches-negras-ante-el-real-madrid\/","title":{"rendered":"De Ulreich a Karius: Noches \u00abnegras\u00bb ante el Real Madrid"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-95192\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/kiev-1880157_960_720-360x240.jpg\" alt=\"\" width=\"360\" height=\"240\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/kiev-1880157_960_720-360x240.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/kiev-1880157_960_720-768x511.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/kiev-1880157_960_720-655x436.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/kiev-1880157_960_720-696x463.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/kiev-1880157_960_720-631x420.jpg 631w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/kiev-1880157_960_720.jpg 960w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Kiev, 27 may (dpa) &#8211; De Sven Ulreich a Loris Karius: cuando se haga el repaso del t\u00edtulo de la Liga de Campeones del Real Madrid, los errores de los arqueros alemanes, coronados con sendos goles de Karim Benzema, tendr\u00e1n un sitio preferencial.<\/p>\n<p>En la final ganada 3-1 por el Real Madrid ante el Liverpool en Kiev, Karius regal\u00f3 el primer gol del conjunto espa\u00f1ol, de forma incluso m\u00e1s grosera a como lo hab\u00eda hecho Ulreich en la semifinal de vuelta ante el Bayern M\u00fanich.<\/p>\n<p>Ya sobre el final, el alem\u00e1n coron\u00f3 su p\u00e9sima noche entregando el tercer gol del conjunto ante un remate que no parec\u00eda llevar peligro del gal\u00e9s Gareth Bale. Fue el corolario de una noche tan aciaga como inolvidable.<\/p>\n<p>En su primer error, el portero del Liverpool, que llegaba al partido bajo duras cr\u00edticas, recogi\u00f3 sin problemas un bal\u00f3n largo e intent\u00f3 salir r\u00e1pido con su mano hacia Dejan Lovren, sin percatarse de que Benzema estaba lo suficientemente cerca. El delantero franc\u00e9s estir\u00f3 su bot\u00edn e intercept\u00f3 el pase, con la fortuna de que el bal\u00f3n march\u00f3 derecho hacia la porter\u00eda ante la desesperaci\u00f3n del arquero alem\u00e1n.<\/p>\n<p>De esa forma, y otra vez en el inicio de la segunda parte, un gol surgido de un error del guardameta rival comenz\u00f3 a abrir el resultado en favor del Real Madrid.<\/p>\n<p>El error de Karius hizo recordar de inmediato a la equivocaci\u00f3n de su compatriota Ulreich en la semifinal disputada en el Bernab\u00e9u.<\/p>\n<p>Aquella noche, Corentin Tolisso envi\u00f3 un peligroso pase hacia atr\u00e1s para el reemplazante de Manuel Neuer, que nunca supo c\u00f3mo resolver. Se arroj\u00f3 al piso como para atrapar el bal\u00f3n, pero no lo tom\u00f3 temiendo una falta indirecta en el \u00e1rea por tocar la pelota con la mano. Tampoco la rechaz\u00f3 con el pie.<\/p>\n<p>Por eso, el bal\u00f3n corri\u00f3 por el \u00e1rea para que Benzema lo capturara en soledad y anotara el segundo gol de su noche para poner al Real Madrid con un decisivo 2-1 a favor. Ulreich acab\u00f3 hundido y pidiendo perd\u00f3n. Lo mismo que Karius en Kiev.<\/p>\n<p>El portero que le gan\u00f3 el puesto a Simon Mignolet al comienzo de la temporada, fall\u00f3 tambi\u00e9n en el tercer gol del Real Madrid. Un remate de 30 metros de Bale que iba al centro del arco se le termin\u00f3 escurriendo entre las manos, para terminar de sentenciar el partido.<\/p>\n<p>Al final, el arquero no ten\u00eda consuelo. Con l\u00e1grimas en los ojos y juntando sus manos en el pecho, el alem\u00e1n no paraba de pedirle perd\u00f3n a los aficionados del Liverpool, que respondieron con t\u00edmidos aplausos. Ni los saludos de Bale ni del t\u00e9cnico J\u00fcrgen Klopp pudieron levantarlo.<\/p>\n<p>\u00abSiempre habr\u00e1 comentarios, no lo puedo cambiar ni me intranquiliza. S\u00f3lo intento jugar al f\u00fatbol, el resto no depende de m\u00ed\u00bb, hab\u00eda dicho recientemente el arquero, que seguramente esta vez escuchar\u00e1 algo m\u00e1s que comentarios sobre su actuaci\u00f3n en Kiev.<\/p>\n<p><i class=\"lang-es\"><span class=\" readonly\" title=\"\">Por Stefan Tabeling (dpa)<\/span><\/i><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kiev, 27 may (dpa) &#8211; De Sven Ulreich a Loris Karius: cuando se haga el repaso del t\u00edtulo de la Liga de Campeones del Real Madrid, los errores de los arqueros alemanes, coronados con sendos goles de Karim Benzema, tendr\u00e1n un sitio preferencial. En la final ganada 3-1 por el Real Madrid ante el Liverpool<\/p>\n","protected":false},"author":1,"featured_media":95192,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[319],"tags":[],"class_list":{"0":"post-96512","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-deporte"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7 - aioseo.com -->\n\t<meta name=\"description\" content=\"Kiev, 27 may (dpa) - De Sven Ulreich a Loris Karius: cuando se haga el repaso del t\u00edtulo de la Liga de Campeones del Real Madrid, los errores de los arqueros alemanes, coronados con sendos goles de Karim Benzema, tendr\u00e1n un sitio preferencial. En la final ganada 3-1 por el Real Madrid ante el Liverpool\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"deporte\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/de-ulreich-a-karius-noches-negras-ante-el-real-madrid\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"De Ulreich a Karius: Noches \u00abnegras\u00bb ante el Real Madrid | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Kiev, 27 may (dpa) - De Sven Ulreich a Loris Karius: cuando se haga el repaso del t\u00edtulo de la Liga de Campeones del Real Madrid, los errores de los arqueros alemanes, coronados con sendos goles de Karim Benzema, tendr\u00e1n un sitio preferencial. En la final ganada 3-1 por el Real Madrid ante el Liverpool\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/de-ulreich-a-karius-noches-negras-ante-el-real-madrid\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/kiev-1880157_960_720.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/kiev-1880157_960_720.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t\t<meta property=\"og:image:height\" content=\"639\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-05-27T11:55:12+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-05-27T11:55:12+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"De Ulreich a Karius: Noches \u00abnegras\u00bb ante el Real Madrid | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Kiev, 27 may (dpa) - De Sven Ulreich a Loris Karius: cuando se haga el repaso del t\u00edtulo de la Liga de Campeones del Real Madrid, los errores de los arqueros alemanes, coronados con sendos goles de Karim Benzema, tendr\u00e1n un sitio preferencial. En la final ganada 3-1 por el Real Madrid ante el Liverpool\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/kiev-1880157_960_720.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/de-ulreich-a-karius-noches-negras-ante-el-real-madrid\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/#listItem\",\"name\":\"Deporte\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/#listItem\",\"position\":2,\"name\":\"Deporte\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/de-ulreich-a-karius-noches-negras-ante-el-real-madrid\\\/#listItem\",\"name\":\"De Ulreich a Karius: Noches \\u00abnegras\\u00bb ante el Real Madrid\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/de-ulreich-a-karius-noches-negras-ante-el-real-madrid\\\/#listItem\",\"position\":3,\"name\":\"De Ulreich a Karius: Noches \\u00abnegras\\u00bb ante el Real Madrid\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/#listItem\",\"name\":\"Deporte\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/de-ulreich-a-karius-noches-negras-ante-el-real-madrid\\\/#newsarticle\",\"name\":\"De Ulreich a Karius: Noches \\u00abnegras\\u00bb ante el Real Madrid | Cand\\u00e1s 365\",\"headline\":\"De Ulreich a Karius: Noches \\u00abnegras\\u00bb ante el Real Madrid\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/kiev-1880157_960_720.jpg\",\"width\":960,\"height\":639},\"datePublished\":\"2018-05-27T11:55:12+02:00\",\"dateModified\":\"2018-05-27T11:55:12+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/de-ulreich-a-karius-noches-negras-ante-el-real-madrid\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/de-ulreich-a-karius-noches-negras-ante-el-real-madrid\\\/#webpage\"},\"articleSection\":\"Deporte\",\"dateline\":\"Publicado el mayo 27, 2018.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/de-ulreich-a-karius-noches-negras-ante-el-real-madrid\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/de-ulreich-a-karius-noches-negras-ante-el-real-madrid\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/de-ulreich-a-karius-noches-negras-ante-el-real-madrid\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/de-ulreich-a-karius-noches-negras-ante-el-real-madrid\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/de-ulreich-a-karius-noches-negras-ante-el-real-madrid\\\/\",\"name\":\"De Ulreich a Karius: Noches \\u00abnegras\\u00bb ante el Real Madrid | Cand\\u00e1s 365\",\"description\":\"Kiev, 27 may (dpa) - De Sven Ulreich a Loris Karius: cuando se haga el repaso del t\\u00edtulo de la Liga de Campeones del Real Madrid, los errores de los arqueros alemanes, coronados con sendos goles de Karim Benzema, tendr\\u00e1n un sitio preferencial. En la final ganada 3-1 por el Real Madrid ante el Liverpool\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/de-ulreich-a-karius-noches-negras-ante-el-real-madrid\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/kiev-1880157_960_720.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/de-ulreich-a-karius-noches-negras-ante-el-real-madrid\\\/#mainImage\",\"width\":960,\"height\":639},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/de-ulreich-a-karius-noches-negras-ante-el-real-madrid\\\/#mainImage\"},\"datePublished\":\"2018-05-27T11:55:12+02:00\",\"dateModified\":\"2018-05-27T11:55:12+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>De Ulreich a Karius: Noches \u00abnegras\u00bb ante el Real Madrid | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"De Ulreich a Karius: Noches \u00abnegras\u00bb ante el Real Madrid | Cand\u00e1s 365","description":"Kiev, 27 may (dpa) - De Sven Ulreich a Loris Karius: cuando se haga el repaso del t\u00edtulo de la Liga de Campeones del Real Madrid, los errores de los arqueros alemanes, coronados con sendos goles de Karim Benzema, tendr\u00e1n un sitio preferencial. En la final ganada 3-1 por el Real Madrid ante el Liverpool","canonical_url":"https:\/\/candas365.es\/noticias\/de-ulreich-a-karius-noches-negras-ante-el-real-madrid\/","robots":"max-image-preview:large","keywords":"deporte","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/de-ulreich-a-karius-noches-negras-ante-el-real-madrid\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/deporte\/#listItem","name":"Deporte"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/deporte\/#listItem","position":2,"name":"Deporte","item":"https:\/\/candas365.es\/noticias\/category\/deporte\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/de-ulreich-a-karius-noches-negras-ante-el-real-madrid\/#listItem","name":"De Ulreich a Karius: Noches \u00abnegras\u00bb ante el Real Madrid"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/de-ulreich-a-karius-noches-negras-ante-el-real-madrid\/#listItem","position":3,"name":"De Ulreich a Karius: Noches \u00abnegras\u00bb ante el Real Madrid","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/deporte\/#listItem","name":"Deporte"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/de-ulreich-a-karius-noches-negras-ante-el-real-madrid\/#newsarticle","name":"De Ulreich a Karius: Noches \u00abnegras\u00bb ante el Real Madrid | Cand\u00e1s 365","headline":"De Ulreich a Karius: Noches \u00abnegras\u00bb ante el Real Madrid","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/kiev-1880157_960_720.jpg","width":960,"height":639},"datePublished":"2018-05-27T11:55:12+02:00","dateModified":"2018-05-27T11:55:12+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/de-ulreich-a-karius-noches-negras-ante-el-real-madrid\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/de-ulreich-a-karius-noches-negras-ante-el-real-madrid\/#webpage"},"articleSection":"Deporte","dateline":"Publicado el mayo 27, 2018."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/de-ulreich-a-karius-noches-negras-ante-el-real-madrid\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/de-ulreich-a-karius-noches-negras-ante-el-real-madrid\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/de-ulreich-a-karius-noches-negras-ante-el-real-madrid\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/de-ulreich-a-karius-noches-negras-ante-el-real-madrid\/#webpage","url":"https:\/\/candas365.es\/noticias\/de-ulreich-a-karius-noches-negras-ante-el-real-madrid\/","name":"De Ulreich a Karius: Noches \u00abnegras\u00bb ante el Real Madrid | Cand\u00e1s 365","description":"Kiev, 27 may (dpa) - De Sven Ulreich a Loris Karius: cuando se haga el repaso del t\u00edtulo de la Liga de Campeones del Real Madrid, los errores de los arqueros alemanes, coronados con sendos goles de Karim Benzema, tendr\u00e1n un sitio preferencial. En la final ganada 3-1 por el Real Madrid ante el Liverpool","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/de-ulreich-a-karius-noches-negras-ante-el-real-madrid\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/kiev-1880157_960_720.jpg","@id":"https:\/\/candas365.es\/noticias\/de-ulreich-a-karius-noches-negras-ante-el-real-madrid\/#mainImage","width":960,"height":639},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/de-ulreich-a-karius-noches-negras-ante-el-real-madrid\/#mainImage"},"datePublished":"2018-05-27T11:55:12+02:00","dateModified":"2018-05-27T11:55:12+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"De Ulreich a Karius: Noches \u00abnegras\u00bb ante el Real Madrid | Cand\u00e1s 365","og:description":"Kiev, 27 may (dpa) - De Sven Ulreich a Loris Karius: cuando se haga el repaso del t\u00edtulo de la Liga de Campeones del Real Madrid, los errores de los arqueros alemanes, coronados con sendos goles de Karim Benzema, tendr\u00e1n un sitio preferencial. En la final ganada 3-1 por el Real Madrid ante el Liverpool","og:url":"https:\/\/candas365.es\/noticias\/de-ulreich-a-karius-noches-negras-ante-el-real-madrid\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/kiev-1880157_960_720.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/kiev-1880157_960_720.jpg","og:image:width":960,"og:image:height":639,"article:published_time":"2018-05-27T11:55:12+00:00","article:modified_time":"2018-05-27T11:55:12+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"De Ulreich a Karius: Noches \u00abnegras\u00bb ante el Real Madrid | Cand\u00e1s 365","twitter:description":"Kiev, 27 may (dpa) - De Sven Ulreich a Loris Karius: cuando se haga el repaso del t\u00edtulo de la Liga de Campeones del Real Madrid, los errores de los arqueros alemanes, coronados con sendos goles de Karim Benzema, tendr\u00e1n un sitio preferencial. En la final ganada 3-1 por el Real Madrid ante el Liverpool","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/kiev-1880157_960_720.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"3 minutos"},"aioseo_meta_data":{"post_id":"96512","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-26 22:12:09","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 11:51:35","updated":"2025-08-26 22:12:09"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/deporte\/\" title=\"Deporte\">Deporte<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tDe Ulreich a Karius: Noches \u00abnegras\u00bb ante el Real Madrid\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Deporte","link":"https:\/\/candas365.es\/noticias\/category\/deporte\/"},{"label":"De Ulreich a Karius: Noches \u00abnegras\u00bb ante el Real Madrid","link":"https:\/\/candas365.es\/noticias\/de-ulreich-a-karius-noches-negras-ante-el-real-madrid\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/96512","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=96512"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/96512\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/95192"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=96512"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=96512"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=96512"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}