{"id":95521,"date":"2018-05-09T20:45:07","date_gmt":"2018-05-09T20:45:07","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=95521"},"modified":"2018-05-09T20:45:07","modified_gmt":"2018-05-09T20:45:07","slug":"el-principado-protegio-a-938-menores-durante-el-2017","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/el-principado-protegio-a-938-menores-durante-el-2017\/","title":{"rendered":"El Principado protegi\u00f3 a 938 menores durante el 2017"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-95522\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/Visita-materno-infantil-360x240.jpg\" alt=\"\" width=\"360\" height=\"240\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/Visita-materno-infantil-360x240.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/Visita-materno-infantil-768x512.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/Visita-materno-infantil-655x436.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/Visita-materno-infantil-696x464.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/Visita-materno-infantil-1068x712.jpg 1068w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/Visita-materno-infantil-630x420.jpg 630w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/Visita-materno-infantil.jpg 1280w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>El Gobierno de Asturias protegi\u00f3 a 938 menores y desarroll\u00f3 programas de prevenci\u00f3n y apoyo a las familias de los que se beneficiaron otros 4.296, seg\u00fan la memoria de actividades del consejo rector del Instituto de Atenci\u00f3n Integral a la Infancia de 2017, que se aprobar\u00e1 en la reuni\u00f3n que mantendr\u00e1 hoy este organismo. Estas actuaciones se plasmaron en medidas de protecci\u00f3n como el acogimiento familiar, el residencial y las adopciones. A finales del pasado a\u00f1o, permanec\u00edan en acogimiento 543 menores: 476 a cargo de familiares y 67 en hogares sin v\u00ednculo de parentesco.<\/p>\n<p>En cuanto al acogimiento residencial, el ejercicio se cerr\u00f3 con 354 menores en esa situaci\u00f3n (204 hombres y 150 mujeres), de los que el 48% ten\u00edan entre 12 y 18 a\u00f1os. Por nacionalidades, 265 eran espa\u00f1oles y 90 extranjeros. En este \u00faltimo caso, 75 eran menores no acompa\u00f1ados. Adem\u00e1s, 41 j\u00f3venes ocupaban plazas residenciales en los programas de transici\u00f3n a la vida adulta. En 2017, un total de 605 personas recibieron apoyo residencial en las 445 plazas disponibles.<\/p>\n<p>En el apartado de adopciones, se hicieron efectivas 41: 38 nacionales y 3 internacionales. El n\u00famero de familias valoradas como id\u00f3neas para formalizar una adopci\u00f3n nacional se situ\u00f3 en 46 y se emitieron 19 certificados de idoneidad para casos internacionales.<\/p>\n<p>Entre los programas de prevenci\u00f3n y apoyo a las familias, que se realizan en colaboraci\u00f3n con ayuntamientos y otras entidades, destac\u00f3 la labor de los equipos de intervenci\u00f3n de apoyo familiar, que prestaron servicios a 1.526 menores; el trabajo de los puntos de encuentro familiar, por los que pasaron otros 588; los talleres de parentalidad positiva, en los se dio formaci\u00f3n a 462 personas, y el programa de participaci\u00f3n infantil, que lleg\u00f3 a mil asistentes.<\/p>\n<p>Adem\u00e1s, en 2017 se abrieron 522 nuevos expedientes que se plasmaron en 180 tutelas, 61 guardas y 173 medidas de acogimiento residencial. Otros 110 menores pasaron por el programa de atenci\u00f3n inmediata. Las solicitudes de intervenci\u00f3n procedieron de los servicios sociales municipales (34,71%), la Fiscal\u00eda de Menores (19,96%), el Cuerpo Nacional de Polic\u00eda o la Guardia Civil (18,71%) y los hospitales (8,99%).<\/p>\n<p>En lo relativo al acuerdo marco de infancia, el Principado mantuvo el ejercicio pasado el concierto de 495 plazas con entidades sociales con una inversi\u00f3n de 9.988.225 euros.<\/p>\n<p><strong>Obras de reparaci\u00f3n en el centro materno infantil y plan de infancia<\/strong><\/p>\n<p>La consejera de Servicios y Derechos Sociales, Pilar Varela, ha facilitado hoy estos datos en la visita que ha realizado al Centro Materno Infantil de Oviedo, donde ha destacado la importancia del sistema de protecci\u00f3n de menores y valorado la tarea que desarrollan los profesionales y entidades que trabajan en este \u00e1mbito.<\/p>\n<p>El Principado ha realizado obras en este centro por valor de 290.310 euros, que afectaron a los tres edificios del complejo. En concreto, en el espacio destinado a los peque\u00f1os se impermeabiliz\u00f3 la cubierta y se renovaron todos los canales y bajantes. Asimismo, se instal\u00f3 un lucernario en el patio interior de juegos, se repararon los suelos y el sistema de saneamiento y se pintaron las paredes interiores. Por otra parte, en el edificio de administraci\u00f3n se instal\u00f3 una cubierta en la sala de visitas, se restauraron cubiertas y bajantes y se cambi\u00f3 el per\u00edmetro de vierteaguas. En el tercer espacio, adem\u00e1s de los trabajos en bajantes y canalones, se impermeabilizaron las terrazas y se sustituyeron las barandillas. Para finalizar, se pintaron las fachadas exteriores del edificio.<\/p>\n<p>Este recurso presta atenci\u00f3n a peque\u00f1os de 0 a 3 a\u00f1os en acogimiento residencial en el sistema de protecci\u00f3n auton\u00f3mico. Actualmente, alberga a 24 menores.<\/p>\n<p>Por otra parte, Varela ha explicado que en la reuni\u00f3n que mantendr\u00e1 hoy el consejo rector del Instituto de Atenci\u00f3n Integral a la Infancia se abordar\u00e1 el Pacto por la Infancia promovido por Unicef en el Parlamento asturiano, que ser\u00e1 una realidad a finales de mes. Tambi\u00e9n se analizar\u00e1 el Plan Integral de Infancia 2018-2021, en la fase final de elaboraci\u00f3n. El documento plantea 10 l\u00edneas estrat\u00e9gicas, entre las que destacan la mejora de procesos para optimizar la atenci\u00f3n a los menores en situaci\u00f3n de desprotecci\u00f3n y sus familias, y para reorganizar el acogimiento residencial e impulsar el familiar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gobierno de Asturias protegi\u00f3 a 938 menores y desarroll\u00f3 programas de prevenci\u00f3n y apoyo a las familias de los que se beneficiaron otros 4.296, seg\u00fan la memoria de actividades del consejo rector del Instituto de Atenci\u00f3n Integral a la Infancia de 2017, que se aprobar\u00e1 en la reuni\u00f3n que mantendr\u00e1 hoy este organismo. Estas<\/p>\n","protected":false},"author":1,"featured_media":95522,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-95521","post","type-post","status-publish","format-standard","has-post-thumbnail","category-asturias"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"El Gobierno de Asturias protegi\u00f3 a 938 menores y desarroll\u00f3 programas de prevenci\u00f3n y apoyo a las familias de los que se beneficiaron otros 4.296, seg\u00fan la memoria de actividades del consejo rector del Instituto de Atenci\u00f3n Integral a la Infancia de 2017, que se aprobar\u00e1 en la reuni\u00f3n que mantendr\u00e1 hoy este organismo. Estas\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"asturias\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/el-principado-protegio-a-938-menores-durante-el-2017\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El Principado protegi\u00f3 a 938 menores durante el 2017 | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"El Gobierno de Asturias protegi\u00f3 a 938 menores y desarroll\u00f3 programas de prevenci\u00f3n y apoyo a las familias de los que se beneficiaron otros 4.296, seg\u00fan la memoria de actividades del consejo rector del Instituto de Atenci\u00f3n Integral a la Infancia de 2017, que se aprobar\u00e1 en la reuni\u00f3n que mantendr\u00e1 hoy este organismo. Estas\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/el-principado-protegio-a-938-menores-durante-el-2017\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/Visita-materno-infantil.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/Visita-materno-infantil.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-05-09T20:45:07+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-05-09T20:45:07+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El Principado protegi\u00f3 a 938 menores durante el 2017 | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El Gobierno de Asturias protegi\u00f3 a 938 menores y desarroll\u00f3 programas de prevenci\u00f3n y apoyo a las familias de los que se beneficiaron otros 4.296, seg\u00fan la memoria de actividades del consejo rector del Instituto de Atenci\u00f3n Integral a la Infancia de 2017, que se aprobar\u00e1 en la reuni\u00f3n que mantendr\u00e1 hoy este organismo. Estas\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/Visita-materno-infantil.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-protegio-a-938-menores-durante-el-2017\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"name\":\"Asturias\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"position\":2,\"name\":\"Asturias\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-protegio-a-938-menores-durante-el-2017\\\/#listItem\",\"name\":\"El Principado protegi\\u00f3 a 938 menores durante el 2017\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-protegio-a-938-menores-durante-el-2017\\\/#listItem\",\"position\":3,\"name\":\"El Principado protegi\\u00f3 a 938 menores durante el 2017\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"name\":\"Asturias\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-protegio-a-938-menores-durante-el-2017\\\/#newsarticle\",\"name\":\"El Principado protegi\\u00f3 a 938 menores durante el 2017 | Cand\\u00e1s 365\",\"headline\":\"El Principado protegi\\u00f3 a 938 menores durante el 2017\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/Visita-materno-infantil.jpg\",\"width\":1280,\"height\":853},\"datePublished\":\"2018-05-09T20:45:07+02:00\",\"dateModified\":\"2018-05-09T20:45:07+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-protegio-a-938-menores-durante-el-2017\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-protegio-a-938-menores-durante-el-2017\\\/#webpage\"},\"articleSection\":\"Asturias\",\"dateline\":\"Publicado el mayo 9, 2018.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-protegio-a-938-menores-durante-el-2017\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-protegio-a-938-menores-durante-el-2017\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-protegio-a-938-menores-durante-el-2017\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-protegio-a-938-menores-durante-el-2017\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-protegio-a-938-menores-durante-el-2017\\\/\",\"name\":\"El Principado protegi\\u00f3 a 938 menores durante el 2017 | Cand\\u00e1s 365\",\"description\":\"El Gobierno de Asturias protegi\\u00f3 a 938 menores y desarroll\\u00f3 programas de prevenci\\u00f3n y apoyo a las familias de los que se beneficiaron otros 4.296, seg\\u00fan la memoria de actividades del consejo rector del Instituto de Atenci\\u00f3n Integral a la Infancia de 2017, que se aprobar\\u00e1 en la reuni\\u00f3n que mantendr\\u00e1 hoy este organismo. Estas\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-protegio-a-938-menores-durante-el-2017\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/Visita-materno-infantil.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-protegio-a-938-menores-durante-el-2017\\\/#mainImage\",\"width\":1280,\"height\":853},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-protegio-a-938-menores-durante-el-2017\\\/#mainImage\"},\"datePublished\":\"2018-05-09T20:45:07+02:00\",\"dateModified\":\"2018-05-09T20:45:07+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>El Principado protegi\u00f3 a 938 menores durante el 2017 | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"El Principado protegi\u00f3 a 938 menores durante el 2017 | Cand\u00e1s 365","description":"El Gobierno de Asturias protegi\u00f3 a 938 menores y desarroll\u00f3 programas de prevenci\u00f3n y apoyo a las familias de los que se beneficiaron otros 4.296, seg\u00fan la memoria de actividades del consejo rector del Instituto de Atenci\u00f3n Integral a la Infancia de 2017, que se aprobar\u00e1 en la reuni\u00f3n que mantendr\u00e1 hoy este organismo. Estas","canonical_url":"https:\/\/candas365.es\/noticias\/el-principado-protegio-a-938-menores-durante-el-2017\/","robots":"max-image-preview:large","keywords":"asturias","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/el-principado-protegio-a-938-menores-durante-el-2017\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","name":"Asturias"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","position":2,"name":"Asturias","item":"https:\/\/candas365.es\/noticias\/category\/asturias\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/el-principado-protegio-a-938-menores-durante-el-2017\/#listItem","name":"El Principado protegi\u00f3 a 938 menores durante el 2017"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/el-principado-protegio-a-938-menores-durante-el-2017\/#listItem","position":3,"name":"El Principado protegi\u00f3 a 938 menores durante el 2017","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","name":"Asturias"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/el-principado-protegio-a-938-menores-durante-el-2017\/#newsarticle","name":"El Principado protegi\u00f3 a 938 menores durante el 2017 | Cand\u00e1s 365","headline":"El Principado protegi\u00f3 a 938 menores durante el 2017","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/Visita-materno-infantil.jpg","width":1280,"height":853},"datePublished":"2018-05-09T20:45:07+02:00","dateModified":"2018-05-09T20:45:07+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/el-principado-protegio-a-938-menores-durante-el-2017\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/el-principado-protegio-a-938-menores-durante-el-2017\/#webpage"},"articleSection":"Asturias","dateline":"Publicado el mayo 9, 2018."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/el-principado-protegio-a-938-menores-durante-el-2017\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/el-principado-protegio-a-938-menores-durante-el-2017\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/el-principado-protegio-a-938-menores-durante-el-2017\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/el-principado-protegio-a-938-menores-durante-el-2017\/#webpage","url":"https:\/\/candas365.es\/noticias\/el-principado-protegio-a-938-menores-durante-el-2017\/","name":"El Principado protegi\u00f3 a 938 menores durante el 2017 | Cand\u00e1s 365","description":"El Gobierno de Asturias protegi\u00f3 a 938 menores y desarroll\u00f3 programas de prevenci\u00f3n y apoyo a las familias de los que se beneficiaron otros 4.296, seg\u00fan la memoria de actividades del consejo rector del Instituto de Atenci\u00f3n Integral a la Infancia de 2017, que se aprobar\u00e1 en la reuni\u00f3n que mantendr\u00e1 hoy este organismo. Estas","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/el-principado-protegio-a-938-menores-durante-el-2017\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/Visita-materno-infantil.jpg","@id":"https:\/\/candas365.es\/noticias\/el-principado-protegio-a-938-menores-durante-el-2017\/#mainImage","width":1280,"height":853},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/el-principado-protegio-a-938-menores-durante-el-2017\/#mainImage"},"datePublished":"2018-05-09T20:45:07+02:00","dateModified":"2018-05-09T20:45:07+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"El Principado protegi\u00f3 a 938 menores durante el 2017 | Cand\u00e1s 365","og:description":"El Gobierno de Asturias protegi\u00f3 a 938 menores y desarroll\u00f3 programas de prevenci\u00f3n y apoyo a las familias de los que se beneficiaron otros 4.296, seg\u00fan la memoria de actividades del consejo rector del Instituto de Atenci\u00f3n Integral a la Infancia de 2017, que se aprobar\u00e1 en la reuni\u00f3n que mantendr\u00e1 hoy este organismo. Estas","og:url":"https:\/\/candas365.es\/noticias\/el-principado-protegio-a-938-menores-durante-el-2017\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/Visita-materno-infantil.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/Visita-materno-infantil.jpg","og:image:width":1280,"og:image:height":853,"article:published_time":"2018-05-09T20:45:07+00:00","article:modified_time":"2018-05-09T20:45:07+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"El Principado protegi\u00f3 a 938 menores durante el 2017 | Cand\u00e1s 365","twitter:description":"El Gobierno de Asturias protegi\u00f3 a 938 menores y desarroll\u00f3 programas de prevenci\u00f3n y apoyo a las familias de los que se beneficiaron otros 4.296, seg\u00fan la memoria de actividades del consejo rector del Instituto de Atenci\u00f3n Integral a la Infancia de 2017, que se aprobar\u00e1 en la reuni\u00f3n que mantendr\u00e1 hoy este organismo. Estas","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/Visita-materno-infantil.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"3 minutos"},"aioseo_meta_data":{"post_id":"95521","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-20 19:29:21","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 11:52:15","updated":"2026-05-20 19:29:21"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/asturias\/\" title=\"Asturias\">Asturias<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tEl Principado protegi\u00f3 a 938 menores durante el 2017\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Asturias","link":"https:\/\/candas365.es\/noticias\/category\/asturias\/"},{"label":"El Principado protegi\u00f3 a 938 menores durante el 2017","link":"https:\/\/candas365.es\/noticias\/el-principado-protegio-a-938-menores-durante-el-2017\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/95521","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=95521"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/95521\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/95522"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=95521"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=95521"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=95521"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}