{"id":95322,"date":"2018-05-05T14:40:02","date_gmt":"2018-05-05T14:40:02","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=95322"},"modified":"2018-05-05T14:40:02","modified_gmt":"2018-05-05T14:40:02","slug":"inauguran-en-alemania-una-polemica-estatua-de-marx","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/inauguran-en-alemania-una-polemica-estatua-de-marx\/","title":{"rendered":"Inauguran en Alemania una pol\u00e9mica estatua de Marx"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-77216\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/08\/news-1729539_960_720-360x238.jpg\" alt=\"\" width=\"360\" height=\"238\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/08\/news-1729539_960_720-360x238.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/08\/news-1729539_960_720-768x508.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/08\/news-1729539_960_720-655x433.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/08\/news-1729539_960_720-696x460.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/08\/news-1729539_960_720-635x420.jpg 635w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/08\/news-1729539_960_720-84x55.jpg 84w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/08\/news-1729539_960_720.jpg 960w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Tr\u00e9veris, 5 may (dpa) &#8211; En medio de una convocatoria de protestas, la ciudad alemana de Tr\u00e9veris rindi\u00f3 hoy homenaje a su vecino m\u00e1s ilustre, Karl Marx, inaugurando una pol\u00e9mica estatua con su figura en el d\u00eda en el que se conmemora el bicentenario del nacimiento del revolucionario fil\u00f3sofo y pensador prusiano.<\/p>\n<p>La escultura, elaborada en bronce y de dimensiones gigantestas -mide 5,50 metros de altura- es un regalo de China que firma el artista del gigante asi\u00e1tico Wu Weishan y ha sido colocada en una plaza cercana a la Porta Nigra, una monumental puerta construida en la \u00e9poca del Imperio romano y calificada como Patrimonio de la Humanidad por la Unesco desde 1986.<\/p>\n<p>La figura muestra a un Karl Marx con su caracter\u00edstica barba, vestido con una levita y caminando. A la inauguraci\u00f3n de la estatua acudieron m\u00e1s de dos centenares de invitados destacados, entre ellos, la l\u00edder del Partido Socialdem\u00f3crata de Alemania (SPD), Andrea Nahles, y el viceministro de Informaci\u00f3n del Consejo Estatal de China, Guo Weimin.<\/p>\n<p>La llegada de la escultura gener\u00f3 una gran controversia entre los vecinos de Tr\u00e9veris en los \u00faltimos meses, despu\u00e9s de que Pek\u00edn hiciese p\u00fablica su intenci\u00f3n de enviar la obra a la patria chica de quien est\u00e1 considerado el ide\u00f3logo del comunismo con motivo del segundo centenario de su nacimiento.<\/p>\n<p>De forma paralela a los actos oficiales, este s\u00e1bado Tr\u00e9veris tambi\u00e9n se convirti\u00f3 en escenario de manifestaciones a favor y en contra de Karl Marx. A primera hora, cientos de manifestantes se congregaron cerca de la estatua para mostrar su oposici\u00f3n a que Tr\u00e9veris aceptase colocar la gigantesca escultura.<\/p>\n<p>Por la tarde, una alianza en favor de la figura de Marx, conformada, entre otras organizaciones, por el partido de La Izquierda y el Partido Comunista Alem\u00e1n, anunciaron una manifestaci\u00f3n para mostrar su rechazo al \u00abcapitalismo y la explotaci\u00f3n\u00bb.<\/p>\n<p>Adem\u00e1s, la Polic\u00eda alemana, que desplegar\u00e1 un operativo especial en Tr\u00e9veris para evitar enfrentamientos o disturbios, tambi\u00e9n espera una manifestaci\u00f3n contraria al acto organizado por el partido ultraderechista Alternativa para Alemania (AfD), el tercero m\u00e1s importante en el Bundestag, que ha convocado a una marcha silenciosa en recuerdo de las v\u00edctimas de reg\u00edmenes comunistas.<\/p>\n<p>Durante el llamado \u00abA\u00f1o de Marx\u00bb, la ciudad natal del fil\u00f3sofo alem\u00e1n tiene previsto celebrar alrededor de 600 actos, desde exposiciones hasta conciertos.<\/p>\n<p>Karl Marx naci\u00f3 hace 200 a\u00f1os, el 5 de mayo de 1818, en la ciudad alemana de Tr\u00e9veris. La muerte lo sorprendi\u00f3 en Londres, ciudad en la que viv\u00eda con su familia en el exilio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tr\u00e9veris, 5 may (dpa) &#8211; En medio de una convocatoria de protestas, la ciudad alemana de Tr\u00e9veris rindi\u00f3 hoy homenaje a su vecino m\u00e1s ilustre, Karl Marx, inaugurando una pol\u00e9mica estatua con su figura en el d\u00eda en el que se conmemora el bicentenario del nacimiento del revolucionario fil\u00f3sofo y pensador prusiano. La escultura, elaborada<\/p>\n","protected":false},"author":1,"featured_media":77216,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343],"tags":[],"class_list":{"0":"post-95322","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-actualidad"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7 - aioseo.com -->\n\t<meta name=\"description\" content=\"Tr\u00e9veris, 5 may (dpa) - En medio de una convocatoria de protestas, la ciudad alemana de Tr\u00e9veris rindi\u00f3 hoy homenaje a su vecino m\u00e1s ilustre, Karl Marx, inaugurando una pol\u00e9mica estatua con su figura en el d\u00eda en el que se conmemora el bicentenario del nacimiento del revolucionario fil\u00f3sofo y pensador prusiano. La escultura, elaborada\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/inauguran-en-alemania-una-polemica-estatua-de-marx\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Inauguran en Alemania una pol\u00e9mica estatua de Marx | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Tr\u00e9veris, 5 may (dpa) - En medio de una convocatoria de protestas, la ciudad alemana de Tr\u00e9veris rindi\u00f3 hoy homenaje a su vecino m\u00e1s ilustre, Karl Marx, inaugurando una pol\u00e9mica estatua con su figura en el d\u00eda en el que se conmemora el bicentenario del nacimiento del revolucionario fil\u00f3sofo y pensador prusiano. La escultura, elaborada\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/inauguran-en-alemania-una-polemica-estatua-de-marx\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/08\/news-1729539_960_720.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/08\/news-1729539_960_720.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t\t<meta property=\"og:image:height\" content=\"635\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-05-05T14:40:02+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-05-05T14:40:02+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Inauguran en Alemania una pol\u00e9mica estatua de Marx | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Tr\u00e9veris, 5 may (dpa) - En medio de una convocatoria de protestas, la ciudad alemana de Tr\u00e9veris rindi\u00f3 hoy homenaje a su vecino m\u00e1s ilustre, Karl Marx, inaugurando una pol\u00e9mica estatua con su figura en el d\u00eda en el que se conmemora el bicentenario del nacimiento del revolucionario fil\u00f3sofo y pensador prusiano. La escultura, elaborada\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/08\/news-1729539_960_720.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/inauguran-en-alemania-una-polemica-estatua-de-marx\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/inauguran-en-alemania-una-polemica-estatua-de-marx\\\/#listItem\",\"name\":\"Inauguran en Alemania una pol\\u00e9mica estatua de Marx\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/inauguran-en-alemania-una-polemica-estatua-de-marx\\\/#listItem\",\"position\":3,\"name\":\"Inauguran en Alemania una pol\\u00e9mica estatua de Marx\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/inauguran-en-alemania-una-polemica-estatua-de-marx\\\/#newsarticle\",\"name\":\"Inauguran en Alemania una pol\\u00e9mica estatua de Marx | Cand\\u00e1s 365\",\"headline\":\"Inauguran en Alemania una pol\\u00e9mica estatua de Marx\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/news-1729539_960_720.jpg\",\"width\":960,\"height\":635},\"datePublished\":\"2018-05-05T14:40:02+02:00\",\"dateModified\":\"2018-05-05T14:40:02+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/inauguran-en-alemania-una-polemica-estatua-de-marx\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/inauguran-en-alemania-una-polemica-estatua-de-marx\\\/#webpage\"},\"articleSection\":\"Actualidad\",\"dateline\":\"Publicado el mayo 5, 2018.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/inauguran-en-alemania-una-polemica-estatua-de-marx\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/inauguran-en-alemania-una-polemica-estatua-de-marx\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/inauguran-en-alemania-una-polemica-estatua-de-marx\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/inauguran-en-alemania-una-polemica-estatua-de-marx\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/inauguran-en-alemania-una-polemica-estatua-de-marx\\\/\",\"name\":\"Inauguran en Alemania una pol\\u00e9mica estatua de Marx | Cand\\u00e1s 365\",\"description\":\"Tr\\u00e9veris, 5 may (dpa) - En medio de una convocatoria de protestas, la ciudad alemana de Tr\\u00e9veris rindi\\u00f3 hoy homenaje a su vecino m\\u00e1s ilustre, Karl Marx, inaugurando una pol\\u00e9mica estatua con su figura en el d\\u00eda en el que se conmemora el bicentenario del nacimiento del revolucionario fil\\u00f3sofo y pensador prusiano. La escultura, elaborada\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/inauguran-en-alemania-una-polemica-estatua-de-marx\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/news-1729539_960_720.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/inauguran-en-alemania-una-polemica-estatua-de-marx\\\/#mainImage\",\"width\":960,\"height\":635},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/inauguran-en-alemania-una-polemica-estatua-de-marx\\\/#mainImage\"},\"datePublished\":\"2018-05-05T14:40:02+02:00\",\"dateModified\":\"2018-05-05T14:40:02+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Inauguran en Alemania una pol\u00e9mica estatua de Marx | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Inauguran en Alemania una pol\u00e9mica estatua de Marx | Cand\u00e1s 365","description":"Tr\u00e9veris, 5 may (dpa) - En medio de una convocatoria de protestas, la ciudad alemana de Tr\u00e9veris rindi\u00f3 hoy homenaje a su vecino m\u00e1s ilustre, Karl Marx, inaugurando una pol\u00e9mica estatua con su figura en el d\u00eda en el que se conmemora el bicentenario del nacimiento del revolucionario fil\u00f3sofo y pensador prusiano. La escultura, elaborada","canonical_url":"https:\/\/candas365.es\/noticias\/inauguran-en-alemania-una-polemica-estatua-de-marx\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/inauguran-en-alemania-una-polemica-estatua-de-marx\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/candas365.es\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/inauguran-en-alemania-una-polemica-estatua-de-marx\/#listItem","name":"Inauguran en Alemania una pol\u00e9mica estatua de Marx"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/inauguran-en-alemania-una-polemica-estatua-de-marx\/#listItem","position":3,"name":"Inauguran en Alemania una pol\u00e9mica estatua de Marx","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/inauguran-en-alemania-una-polemica-estatua-de-marx\/#newsarticle","name":"Inauguran en Alemania una pol\u00e9mica estatua de Marx | Cand\u00e1s 365","headline":"Inauguran en Alemania una pol\u00e9mica estatua de Marx","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/08\/news-1729539_960_720.jpg","width":960,"height":635},"datePublished":"2018-05-05T14:40:02+02:00","dateModified":"2018-05-05T14:40:02+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/inauguran-en-alemania-una-polemica-estatua-de-marx\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/inauguran-en-alemania-una-polemica-estatua-de-marx\/#webpage"},"articleSection":"Actualidad","dateline":"Publicado el mayo 5, 2018."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/inauguran-en-alemania-una-polemica-estatua-de-marx\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/inauguran-en-alemania-una-polemica-estatua-de-marx\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/inauguran-en-alemania-una-polemica-estatua-de-marx\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/inauguran-en-alemania-una-polemica-estatua-de-marx\/#webpage","url":"https:\/\/candas365.es\/noticias\/inauguran-en-alemania-una-polemica-estatua-de-marx\/","name":"Inauguran en Alemania una pol\u00e9mica estatua de Marx | Cand\u00e1s 365","description":"Tr\u00e9veris, 5 may (dpa) - En medio de una convocatoria de protestas, la ciudad alemana de Tr\u00e9veris rindi\u00f3 hoy homenaje a su vecino m\u00e1s ilustre, Karl Marx, inaugurando una pol\u00e9mica estatua con su figura en el d\u00eda en el que se conmemora el bicentenario del nacimiento del revolucionario fil\u00f3sofo y pensador prusiano. La escultura, elaborada","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/inauguran-en-alemania-una-polemica-estatua-de-marx\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/08\/news-1729539_960_720.jpg","@id":"https:\/\/candas365.es\/noticias\/inauguran-en-alemania-una-polemica-estatua-de-marx\/#mainImage","width":960,"height":635},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/inauguran-en-alemania-una-polemica-estatua-de-marx\/#mainImage"},"datePublished":"2018-05-05T14:40:02+02:00","dateModified":"2018-05-05T14:40:02+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Inauguran en Alemania una pol\u00e9mica estatua de Marx | Cand\u00e1s 365","og:description":"Tr\u00e9veris, 5 may (dpa) - En medio de una convocatoria de protestas, la ciudad alemana de Tr\u00e9veris rindi\u00f3 hoy homenaje a su vecino m\u00e1s ilustre, Karl Marx, inaugurando una pol\u00e9mica estatua con su figura en el d\u00eda en el que se conmemora el bicentenario del nacimiento del revolucionario fil\u00f3sofo y pensador prusiano. La escultura, elaborada","og:url":"https:\/\/candas365.es\/noticias\/inauguran-en-alemania-una-polemica-estatua-de-marx\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/08\/news-1729539_960_720.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/08\/news-1729539_960_720.jpg","og:image:width":960,"og:image:height":635,"article:published_time":"2018-05-05T14:40:02+00:00","article:modified_time":"2018-05-05T14:40:02+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Inauguran en Alemania una pol\u00e9mica estatua de Marx | Cand\u00e1s 365","twitter:description":"Tr\u00e9veris, 5 may (dpa) - En medio de una convocatoria de protestas, la ciudad alemana de Tr\u00e9veris rindi\u00f3 hoy homenaje a su vecino m\u00e1s ilustre, Karl Marx, inaugurando una pol\u00e9mica estatua con su figura en el d\u00eda en el que se conmemora el bicentenario del nacimiento del revolucionario fil\u00f3sofo y pensador prusiano. La escultura, elaborada","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/08\/news-1729539_960_720.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"95322","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-26 20:19:18","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 11:52:25","updated":"2025-08-26 20:19:18"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tInauguran en Alemania una pol\u00e9mica estatua de Marx\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Actualidad","link":"https:\/\/candas365.es\/noticias\/category\/actualidad\/"},{"label":"Inauguran en Alemania una pol\u00e9mica estatua de Marx","link":"https:\/\/candas365.es\/noticias\/inauguran-en-alemania-una-polemica-estatua-de-marx\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/95322","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=95322"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/95322\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/77216"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=95322"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=95322"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=95322"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}