{"id":95320,"date":"2018-05-05T14:37:44","date_gmt":"2018-05-05T14:37:44","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=95320"},"modified":"2018-05-05T14:37:44","modified_gmt":"2018-05-05T14:37:44","slug":"el-lokomotive-leipzig-expulsa-a-varios-miembros-del-staff-juvenil","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/el-lokomotive-leipzig-expulsa-a-varios-miembros-del-staff-juvenil\/","title":{"rendered":"El Lokomotive Leipzig expulsa a varios miembros del staff juvenil"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-89552\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280-360x241.jpg\" alt=\"\" width=\"360\" height=\"241\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280-360x241.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280-696x466.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280-1068x715.jpg 1068w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280-627x420.jpg 627w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280-768x514.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280-655x439.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280.jpg 1280w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Leipzig (Alemania), 5 may (dpa) &#8211; El club Lokomotive Leipzig, de la cuarta divisi\u00f3n del f\u00fatbol alem\u00e1n, respondi\u00f3 con firmeza al esc\u00e1ndalo que se gener\u00f3 en sus filas despu\u00e9s de que los miembros del equipo juvenil posaran el fin de semana pasado en una fotograf\u00eda haciendo el saludo nazi.<\/p>\n<p>El conjunto present\u00f3 una denuncia contra el entrenador asistente del equipo juvenil y le prohibi\u00f3 de por vida entrar en las instalaciones deportivas del club despu\u00e9s de que \u00e9ste conminara a los jugadores a emular el saludo con el brazo extendido de los jerarcas del Tercer Reich.<\/p>\n<p>Los directivos decidieron adem\u00e1s expulsar a otro t\u00e9cnico de categor\u00edas inferiores y a quienes participaron en la foto les han prohibido jugar hasta final de temporada. El incidente, seg\u00fan explicaron, tuvo lugar en el predio del Lokomotive Leipzig, un modesto equipo de la cuarta categor\u00eda que disputa en el este del pa\u00eds una de las cinco ligas regionales que integran la \u00abRegionalliga\u00bb del f\u00fatbol alem\u00e1n.<\/p>\n<p>\u00abHacer este saludo no solo es un delito de incitaci\u00f3n a la xenofobia, sino que representa millones de asesinatos de personas en un sistema de injusticia. Esto no es no es ni una ofensa trivial, ni una provocaci\u00f3n ni un juego\u00bb, se\u00f1alaron desde el club en su p\u00e1gina oficial de Facebook.<\/p>\n<p>El club, en colaboraci\u00f3n con la federaci\u00f3n regional de deporte y con una asociaci\u00f3n de aficionados del Leipzig, anunci\u00f3 que impartir\u00e1 varios seminarios a los j\u00f3venes que tomaron parte en la pol\u00e9mica fotograf\u00eda.<\/p>\n<p>Hacer el saludo nazi est\u00e1 prohibido en Alemania, un pa\u00eds en el que la apolog\u00eda del nazismo o la negaci\u00f3n del Holocausto es un delito castigado con penas que pueden ir desde una multa hasta los cinco a\u00f1os de c\u00e1rcel.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Leipzig (Alemania), 5 may (dpa) &#8211; El club Lokomotive Leipzig, de la cuarta divisi\u00f3n del f\u00fatbol alem\u00e1n, respondi\u00f3 con firmeza al esc\u00e1ndalo que se gener\u00f3 en sus filas despu\u00e9s de que los miembros del equipo juvenil posaran el fin de semana pasado en una fotograf\u00eda haciendo el saludo nazi. El conjunto present\u00f3 una denuncia contra<\/p>\n","protected":false},"author":1,"featured_media":89552,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[319],"tags":[],"class_list":{"0":"post-95320","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-deporte"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7 - aioseo.com -->\n\t<meta name=\"description\" content=\"Leipzig (Alemania), 5 may (dpa) - El club Lokomotive Leipzig, de la cuarta divisi\u00f3n del f\u00fatbol alem\u00e1n, respondi\u00f3 con firmeza al esc\u00e1ndalo que se gener\u00f3 en sus filas despu\u00e9s de que los miembros del equipo juvenil posaran el fin de semana pasado en una fotograf\u00eda haciendo el saludo nazi. El conjunto present\u00f3 una denuncia contra\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"deporte\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/el-lokomotive-leipzig-expulsa-a-varios-miembros-del-staff-juvenil\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El Lokomotive Leipzig expulsa a varios miembros del staff juvenil | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Leipzig (Alemania), 5 may (dpa) - El club Lokomotive Leipzig, de la cuarta divisi\u00f3n del f\u00fatbol alem\u00e1n, respondi\u00f3 con firmeza al esc\u00e1ndalo que se gener\u00f3 en sus filas despu\u00e9s de que los miembros del equipo juvenil posaran el fin de semana pasado en una fotograf\u00eda haciendo el saludo nazi. El conjunto present\u00f3 una denuncia contra\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/el-lokomotive-leipzig-expulsa-a-varios-miembros-del-staff-juvenil\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t\t<meta property=\"og:image:height\" content=\"857\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-05-05T14:37:44+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-05-05T14:37:44+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El Lokomotive Leipzig expulsa a varios miembros del staff juvenil | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Leipzig (Alemania), 5 may (dpa) - El club Lokomotive Leipzig, de la cuarta divisi\u00f3n del f\u00fatbol alem\u00e1n, respondi\u00f3 con firmeza al esc\u00e1ndalo que se gener\u00f3 en sus filas despu\u00e9s de que los miembros del equipo juvenil posaran el fin de semana pasado en una fotograf\u00eda haciendo el saludo nazi. El conjunto present\u00f3 una denuncia contra\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-lokomotive-leipzig-expulsa-a-varios-miembros-del-staff-juvenil\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/#listItem\",\"name\":\"Deporte\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/#listItem\",\"position\":2,\"name\":\"Deporte\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-lokomotive-leipzig-expulsa-a-varios-miembros-del-staff-juvenil\\\/#listItem\",\"name\":\"El Lokomotive Leipzig expulsa a varios miembros del staff juvenil\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-lokomotive-leipzig-expulsa-a-varios-miembros-del-staff-juvenil\\\/#listItem\",\"position\":3,\"name\":\"El Lokomotive Leipzig expulsa a varios miembros del staff juvenil\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/#listItem\",\"name\":\"Deporte\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-lokomotive-leipzig-expulsa-a-varios-miembros-del-staff-juvenil\\\/#newsarticle\",\"name\":\"El Lokomotive Leipzig expulsa a varios miembros del staff juvenil | Cand\\u00e1s 365\",\"headline\":\"El Lokomotive Leipzig expulsa a varios miembros del staff juvenil\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/football-1406106_1280.jpg\",\"width\":1280,\"height\":857,\"caption\":\"football\"},\"datePublished\":\"2018-05-05T14:37:44+02:00\",\"dateModified\":\"2018-05-05T14:37:44+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-lokomotive-leipzig-expulsa-a-varios-miembros-del-staff-juvenil\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-lokomotive-leipzig-expulsa-a-varios-miembros-del-staff-juvenil\\\/#webpage\"},\"articleSection\":\"Deporte\",\"dateline\":\"Publicado el mayo 5, 2018.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-lokomotive-leipzig-expulsa-a-varios-miembros-del-staff-juvenil\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-lokomotive-leipzig-expulsa-a-varios-miembros-del-staff-juvenil\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-lokomotive-leipzig-expulsa-a-varios-miembros-del-staff-juvenil\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-lokomotive-leipzig-expulsa-a-varios-miembros-del-staff-juvenil\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-lokomotive-leipzig-expulsa-a-varios-miembros-del-staff-juvenil\\\/\",\"name\":\"El Lokomotive Leipzig expulsa a varios miembros del staff juvenil | Cand\\u00e1s 365\",\"description\":\"Leipzig (Alemania), 5 may (dpa) - El club Lokomotive Leipzig, de la cuarta divisi\\u00f3n del f\\u00fatbol alem\\u00e1n, respondi\\u00f3 con firmeza al esc\\u00e1ndalo que se gener\\u00f3 en sus filas despu\\u00e9s de que los miembros del equipo juvenil posaran el fin de semana pasado en una fotograf\\u00eda haciendo el saludo nazi. El conjunto present\\u00f3 una denuncia contra\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-lokomotive-leipzig-expulsa-a-varios-miembros-del-staff-juvenil\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/football-1406106_1280.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-lokomotive-leipzig-expulsa-a-varios-miembros-del-staff-juvenil\\\/#mainImage\",\"width\":1280,\"height\":857,\"caption\":\"football\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-lokomotive-leipzig-expulsa-a-varios-miembros-del-staff-juvenil\\\/#mainImage\"},\"datePublished\":\"2018-05-05T14:37:44+02:00\",\"dateModified\":\"2018-05-05T14:37:44+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>El Lokomotive Leipzig expulsa a varios miembros del staff juvenil | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"El Lokomotive Leipzig expulsa a varios miembros del staff juvenil | Cand\u00e1s 365","description":"Leipzig (Alemania), 5 may (dpa) - El club Lokomotive Leipzig, de la cuarta divisi\u00f3n del f\u00fatbol alem\u00e1n, respondi\u00f3 con firmeza al esc\u00e1ndalo que se gener\u00f3 en sus filas despu\u00e9s de que los miembros del equipo juvenil posaran el fin de semana pasado en una fotograf\u00eda haciendo el saludo nazi. El conjunto present\u00f3 una denuncia contra","canonical_url":"https:\/\/candas365.es\/noticias\/el-lokomotive-leipzig-expulsa-a-varios-miembros-del-staff-juvenil\/","robots":"max-image-preview:large","keywords":"deporte","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/el-lokomotive-leipzig-expulsa-a-varios-miembros-del-staff-juvenil\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/deporte\/#listItem","name":"Deporte"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/deporte\/#listItem","position":2,"name":"Deporte","item":"https:\/\/candas365.es\/noticias\/category\/deporte\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/el-lokomotive-leipzig-expulsa-a-varios-miembros-del-staff-juvenil\/#listItem","name":"El Lokomotive Leipzig expulsa a varios miembros del staff juvenil"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/el-lokomotive-leipzig-expulsa-a-varios-miembros-del-staff-juvenil\/#listItem","position":3,"name":"El Lokomotive Leipzig expulsa a varios miembros del staff juvenil","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/deporte\/#listItem","name":"Deporte"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/el-lokomotive-leipzig-expulsa-a-varios-miembros-del-staff-juvenil\/#newsarticle","name":"El Lokomotive Leipzig expulsa a varios miembros del staff juvenil | Cand\u00e1s 365","headline":"El Lokomotive Leipzig expulsa a varios miembros del staff juvenil","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280.jpg","width":1280,"height":857,"caption":"football"},"datePublished":"2018-05-05T14:37:44+02:00","dateModified":"2018-05-05T14:37:44+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/el-lokomotive-leipzig-expulsa-a-varios-miembros-del-staff-juvenil\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/el-lokomotive-leipzig-expulsa-a-varios-miembros-del-staff-juvenil\/#webpage"},"articleSection":"Deporte","dateline":"Publicado el mayo 5, 2018."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/el-lokomotive-leipzig-expulsa-a-varios-miembros-del-staff-juvenil\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/el-lokomotive-leipzig-expulsa-a-varios-miembros-del-staff-juvenil\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/el-lokomotive-leipzig-expulsa-a-varios-miembros-del-staff-juvenil\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/el-lokomotive-leipzig-expulsa-a-varios-miembros-del-staff-juvenil\/#webpage","url":"https:\/\/candas365.es\/noticias\/el-lokomotive-leipzig-expulsa-a-varios-miembros-del-staff-juvenil\/","name":"El Lokomotive Leipzig expulsa a varios miembros del staff juvenil | Cand\u00e1s 365","description":"Leipzig (Alemania), 5 may (dpa) - El club Lokomotive Leipzig, de la cuarta divisi\u00f3n del f\u00fatbol alem\u00e1n, respondi\u00f3 con firmeza al esc\u00e1ndalo que se gener\u00f3 en sus filas despu\u00e9s de que los miembros del equipo juvenil posaran el fin de semana pasado en una fotograf\u00eda haciendo el saludo nazi. El conjunto present\u00f3 una denuncia contra","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/el-lokomotive-leipzig-expulsa-a-varios-miembros-del-staff-juvenil\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280.jpg","@id":"https:\/\/candas365.es\/noticias\/el-lokomotive-leipzig-expulsa-a-varios-miembros-del-staff-juvenil\/#mainImage","width":1280,"height":857,"caption":"football"},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/el-lokomotive-leipzig-expulsa-a-varios-miembros-del-staff-juvenil\/#mainImage"},"datePublished":"2018-05-05T14:37:44+02:00","dateModified":"2018-05-05T14:37:44+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"El Lokomotive Leipzig expulsa a varios miembros del staff juvenil | Cand\u00e1s 365","og:description":"Leipzig (Alemania), 5 may (dpa) - El club Lokomotive Leipzig, de la cuarta divisi\u00f3n del f\u00fatbol alem\u00e1n, respondi\u00f3 con firmeza al esc\u00e1ndalo que se gener\u00f3 en sus filas despu\u00e9s de que los miembros del equipo juvenil posaran el fin de semana pasado en una fotograf\u00eda haciendo el saludo nazi. El conjunto present\u00f3 una denuncia contra","og:url":"https:\/\/candas365.es\/noticias\/el-lokomotive-leipzig-expulsa-a-varios-miembros-del-staff-juvenil\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280.jpg","og:image:width":1280,"og:image:height":857,"article:published_time":"2018-05-05T14:37:44+00:00","article:modified_time":"2018-05-05T14:37:44+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"El Lokomotive Leipzig expulsa a varios miembros del staff juvenil | Cand\u00e1s 365","twitter:description":"Leipzig (Alemania), 5 may (dpa) - El club Lokomotive Leipzig, de la cuarta divisi\u00f3n del f\u00fatbol alem\u00e1n, respondi\u00f3 con firmeza al esc\u00e1ndalo que se gener\u00f3 en sus filas despu\u00e9s de que los miembros del equipo juvenil posaran el fin de semana pasado en una fotograf\u00eda haciendo el saludo nazi. El conjunto present\u00f3 una denuncia contra","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"95320","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-26 20:19:16","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 11:52:25","updated":"2025-08-26 20:19:16"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/deporte\/\" title=\"Deporte\">Deporte<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tEl Lokomotive Leipzig expulsa a varios miembros del staff juvenil\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Deporte","link":"https:\/\/candas365.es\/noticias\/category\/deporte\/"},{"label":"El Lokomotive Leipzig expulsa a varios miembros del staff juvenil","link":"https:\/\/candas365.es\/noticias\/el-lokomotive-leipzig-expulsa-a-varios-miembros-del-staff-juvenil\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/95320","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=95320"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/95320\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/89552"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=95320"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=95320"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=95320"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}