{"id":95199,"date":"2018-05-03T19:39:33","date_gmt":"2018-05-03T19:39:33","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=95199"},"modified":"2018-05-03T19:39:33","modified_gmt":"2018-05-03T19:39:33","slug":"mas-cine-en-laboral-cinemateca-durante-mayo-de-2018","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/mas-cine-en-laboral-cinemateca-durante-mayo-de-2018\/","title":{"rendered":"M\u00e1s cine en Laboral Cinemateca durante mayo de 2018"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-80268\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/09\/Laboral-360x239.jpg\" alt=\"\" width=\"360\" height=\"239\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/09\/Laboral-360x239.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/09\/Laboral-768x511.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/09\/Laboral-655x435.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/09\/Laboral-696x463.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/09\/Laboral-1068x710.jpg 1068w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/09\/Laboral-632x420.jpg 632w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/09\/Laboral-84x55.jpg 84w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/09\/Laboral.jpg 1280w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Laboral Cinemateca sigue desarrollando los objetivos fijados en su puesta en marcha y para el mes de mayo ha programado un intenso programa de proyecciones no s\u00f3lo en Gij\u00f3n, su sede principal, sino tambi\u00e9n en trece concejos asturianos gracias al programa La Cinemateca Ambulante. Algunos de los t\u00edtulos de referencia del cine europeo actual, el nuevo cine indie americano, el encuentro con Andr\u00e9s Goteira \u2013uno de los nuevos valores del cine espa\u00f1ol- y la revisi\u00f3n de cl\u00e1sicos de siempre para todos los p\u00fablicos se unen este mes al desarrollo de una Jornada profesional del cortometraje y a la publicaci\u00f3n de una convocatoria del programa de ayudas para proyectos de no ficci\u00f3n realizados por cineastas asturianos.<\/p>\n<p>Seis pel\u00edculas del cine contempor\u00e1neo m\u00e1s reciente, siempre en versi\u00f3n original, se proyectan en el mes de mayo en el Paraninfo de la Laboral en el marco de la muestra Estaciones, con t\u00edtulos como Braguino, del director franc\u00e9s Cl\u00e9ment Cogitori, una pel\u00edcula in\u00e9dita en salas comerciales que retrata el enfrentamiento entre dos familias que habitan en la taiga de Siberia Oriental alejadas de la civilizaci\u00f3n; y A Ciambra, dirigida por Jonas Carpignano y producida por Martin Scorsese, que se alz\u00f3 con el Premio Europa Cinemas Label en Cannes 2017.<\/p>\n<p>A estas pel\u00edculas se suman The party, una comedia inteligente y provocadora dirigida por Sally Potter; Custodia compartida, de Xavier Legrand, un \u00e1spero e inc\u00f3modo retrato de la violencia dom\u00e9stica; y Dhogs, el primer largometraje del realizador gallego Andr\u00e9s Goteira, que presentar\u00e1 la pel\u00edcula y mantendr\u00e1 un encuentro con el p\u00fablico asistente. Influencias de Lynch o Tarantino en Dhogs, un inquietante thriller que acaba de alzarse con el Premio de la Cr\u00edtica en el Festival Internacional de Cine Fant\u00e1stico de Bruselas (BIFFF), uno de los m\u00e1s prestigiosos del panorama internacional, y que ha triunfado en Londres, Buenos Aires (Bafici) o Sitges, entre otros festivales.<\/p>\n<p>Laboral Cinemateca proyectar\u00e1, adem\u00e1s, este mes tres recientes t\u00edtulos del cine independiente americano: el \u00faltimo trabajo de Matthew Porterfield, Soller\u00b4s point, presentado en el pasado Festival de San Sebasti\u00e1n y ambientado en un barrio de la violenta Baltimore, donde seguimos los pasos de un joven infeliz y autodestructivo que acaba de salir de la c\u00e1rcel; la emocionante Gemini, del antih\u00e9roe del indie Aaron Katz, y Gook, pel\u00edcula dirigida, escrita y protagonizada por Justin Chon. Adem\u00e1s, Laboral Cinemateca dedica en mayo su ciclo Historia(s) del cine a Charles Chaplin con la proyecci\u00f3n de dos de sus pel\u00edculas m\u00e1s conocidas El chico (1921) y El circo (1928), protagonizadas por su personaje m\u00e1s popular, Charlot.<\/p>\n<p>La programaci\u00f3n de Laboral Cinemateca para el mes de mayo se completa con las proyecciones de La Cinemateca Ambulante que llevar\u00e1 a 13 concejos asturianos 15 destacadas pel\u00edculas del panorama actual, ofreciendo un total de 31 sesiones, todas en versi\u00f3n original subtitulada en castellano y con entrada libre, con t\u00edtulos de reciente estreno en la cartelera espa\u00f1ola como Custodia compartida; El taller de escritura de Laurent Cantet; o La muerte de Stalin de Armando Iannucci.<\/p>\n<p>Las entradas para las proyecciones en el Paraninfo de la Laboral, pueden adquirirse, a un precio general de 4\u20ac y reducido de 3\u20ac, en la Recepci\u00f3n de Laboral Ciudad de la Cultura en Gij\u00f3n, en la Recepci\u00f3n del Centro Niemeyer en Avil\u00e9s, en el Centro de Informaci\u00f3n Tur\u00edstica del Principado en Oviedo, en <span style=\"color: #ff0000;\"><strong>entradas.liberbank.es<\/strong><\/span>, en el tel\u00e9fono 902 106 601 y en la red de cajeros Liberbank.<\/p>\n<p><strong>Jornada Profesional del Cortometraje y Ayudas de no ficci\u00f3n<\/strong><\/p>\n<p>El s\u00e1bado 26 de mayo se celebrar\u00e1 en la Ciudad de la Cultura la Jornada Profesional del Cortometraje que integra actividades para j\u00f3venes interesados en poner en marcha y difundir sus cortometrajes, adem\u00e1s de proyecciones abiertas a todo tipo de p\u00fablicos. En esta jornada profesional participar\u00e1n como ponentes Ismael Mart\u00edn &#8211; responsable de Distribuci\u00f3n de la Escuela de Cinematograf\u00eda y del Audiovisual de Madrid (ECAM) y desde 2005 del programa Madrid en Corto y autor de un blog de referencia especializado en la industria del corto- y S\u00e9bastien Duclocher \u2013coordinador del Departamento de Educaci\u00f3n del Festival de Clermont-Ferrand- que tratar\u00e1n sobre el desarrollo y financiaci\u00f3n de los proyectos y sobre las claves del \u00e9xito de una obra cinematogr\u00e1fica, respectivamente.<\/p>\n<p>Estas conferencias se complementan con tres sesiones de proyecciones diferenciadas: la primera, una selecci\u00f3n de cortos espa\u00f1oles de gran recorrido en festivales nacionales e internacionales; una segunda sesi\u00f3n tem\u00e1tica en torno a los \u201cCortometrajes y videojuegos\u201d; y la tercera centrada en las nuevas narrativas y con t\u00edtulos recientemente premiados en Clermont Ferrand \u201c10 a\u00f1os de LABO\u201d, comisariada y presentada por Duclocher. La jornada profesional es de libre acceso (hasta completar aforo), siendo imprescindible la retirada de invitaci\u00f3n para las sesiones de proyecciones.<\/p>\n<p>Laboral Cinemateca lanza adem\u00e1s este mes su tercera convocatoria de ayudas para proyectos cinematogr\u00e1ficos asturianos. Esta iniciativa persigue potenciar la producci\u00f3n de largometrajes y cortometrajes de no ficci\u00f3n mediante el apoyo a propuestas de singular valor creativo, en una nueva apuesta por el desarrollo y fortalecimiento del sector audiovisual de la regi\u00f3n. El programa est\u00e1 dirigido a los profesionales y creadores asturianos o con residencia en el Principado de Asturias que incluyan en su objeto social la creaci\u00f3n y producci\u00f3n cinematogr\u00e1fica.<\/p>\n<p>El formulario oficial para la solicitud de las ayudas est\u00e1 ya disponible en la web de <strong>Laboral Cinemateca<\/strong> y deber\u00e1 presentarse, debidamente cumplimentado y junto con toda la documentaci\u00f3n requerida, en las oficinas de la Sociedad P\u00fablica de Promoci\u00f3n Tur\u00edstica y Cultural del Principado en Gij\u00f3n (C\/ Luis Moya Blanco, 261) antes del 30 de junio de 2018.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Laboral Cinemateca sigue desarrollando los objetivos fijados en su puesta en marcha y para el mes de mayo ha programado un intenso programa de proyecciones no s\u00f3lo en Gij\u00f3n, su sede principal, sino tambi\u00e9n en trece concejos asturianos gracias al programa La Cinemateca Ambulante. Algunos de los t\u00edtulos de referencia del cine europeo actual, el<\/p>\n","protected":false},"author":1,"featured_media":84232,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":{"0":"post-95199","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-agenda"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7 - aioseo.com -->\n\t<meta name=\"description\" content=\"Laboral Cinemateca sigue desarrollando los objetivos fijados en su puesta en marcha y para el mes de mayo ha programado un intenso programa de proyecciones no s\u00f3lo en Gij\u00f3n, su sede principal, sino tambi\u00e9n en trece concejos asturianos gracias al programa La Cinemateca Ambulante. Algunos de los t\u00edtulos de referencia del cine europeo actual, el\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"agenda\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/mas-cine-en-laboral-cinemateca-durante-mayo-de-2018\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"M\u00e1s cine en Laboral Cinemateca durante mayo de 2018 | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Laboral Cinemateca sigue desarrollando los objetivos fijados en su puesta en marcha y para el mes de mayo ha programado un intenso programa de proyecciones no s\u00f3lo en Gij\u00f3n, su sede principal, sino tambi\u00e9n en trece concejos asturianos gracias al programa La Cinemateca Ambulante. Algunos de los t\u00edtulos de referencia del cine europeo actual, el\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/mas-cine-en-laboral-cinemateca-durante-mayo-de-2018\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/film-596009_960_720.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/film-596009_960_720.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t\t<meta property=\"og:image:height\" content=\"678\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-05-03T19:39:33+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-05-03T19:39:33+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"M\u00e1s cine en Laboral Cinemateca durante mayo de 2018 | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Laboral Cinemateca sigue desarrollando los objetivos fijados en su puesta en marcha y para el mes de mayo ha programado un intenso programa de proyecciones no s\u00f3lo en Gij\u00f3n, su sede principal, sino tambi\u00e9n en trece concejos asturianos gracias al programa La Cinemateca Ambulante. Algunos de los t\u00edtulos de referencia del cine europeo actual, el\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/film-596009_960_720.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/mas-cine-en-laboral-cinemateca-durante-mayo-de-2018\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/agenda\\\/#listItem\",\"name\":\"Agenda\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/agenda\\\/#listItem\",\"position\":2,\"name\":\"Agenda\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/agenda\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/mas-cine-en-laboral-cinemateca-durante-mayo-de-2018\\\/#listItem\",\"name\":\"M\\u00e1s cine en Laboral Cinemateca durante mayo de 2018\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/mas-cine-en-laboral-cinemateca-durante-mayo-de-2018\\\/#listItem\",\"position\":3,\"name\":\"M\\u00e1s cine en Laboral Cinemateca durante mayo de 2018\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/agenda\\\/#listItem\",\"name\":\"Agenda\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/mas-cine-en-laboral-cinemateca-durante-mayo-de-2018\\\/#newsarticle\",\"name\":\"M\\u00e1s cine en Laboral Cinemateca durante mayo de 2018 | Cand\\u00e1s 365\",\"headline\":\"M\\u00e1s cine en Laboral Cinemateca durante mayo de 2018\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/film-596009_960_720.jpg\",\"width\":960,\"height\":678,\"caption\":\"film\"},\"datePublished\":\"2018-05-03T19:39:33+02:00\",\"dateModified\":\"2018-05-03T19:39:33+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/mas-cine-en-laboral-cinemateca-durante-mayo-de-2018\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/mas-cine-en-laboral-cinemateca-durante-mayo-de-2018\\\/#webpage\"},\"articleSection\":\"Agenda\",\"dateline\":\"Publicado el mayo 3, 2018.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/mas-cine-en-laboral-cinemateca-durante-mayo-de-2018\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/mas-cine-en-laboral-cinemateca-durante-mayo-de-2018\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/mas-cine-en-laboral-cinemateca-durante-mayo-de-2018\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/mas-cine-en-laboral-cinemateca-durante-mayo-de-2018\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/mas-cine-en-laboral-cinemateca-durante-mayo-de-2018\\\/\",\"name\":\"M\\u00e1s cine en Laboral Cinemateca durante mayo de 2018 | Cand\\u00e1s 365\",\"description\":\"Laboral Cinemateca sigue desarrollando los objetivos fijados en su puesta en marcha y para el mes de mayo ha programado un intenso programa de proyecciones no s\\u00f3lo en Gij\\u00f3n, su sede principal, sino tambi\\u00e9n en trece concejos asturianos gracias al programa La Cinemateca Ambulante. Algunos de los t\\u00edtulos de referencia del cine europeo actual, el\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/mas-cine-en-laboral-cinemateca-durante-mayo-de-2018\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/film-596009_960_720.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/mas-cine-en-laboral-cinemateca-durante-mayo-de-2018\\\/#mainImage\",\"width\":960,\"height\":678,\"caption\":\"film\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/mas-cine-en-laboral-cinemateca-durante-mayo-de-2018\\\/#mainImage\"},\"datePublished\":\"2018-05-03T19:39:33+02:00\",\"dateModified\":\"2018-05-03T19:39:33+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>M\u00e1s cine en Laboral Cinemateca durante mayo de 2018 | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"M\u00e1s cine en Laboral Cinemateca durante mayo de 2018 | Cand\u00e1s 365","description":"Laboral Cinemateca sigue desarrollando los objetivos fijados en su puesta en marcha y para el mes de mayo ha programado un intenso programa de proyecciones no s\u00f3lo en Gij\u00f3n, su sede principal, sino tambi\u00e9n en trece concejos asturianos gracias al programa La Cinemateca Ambulante. Algunos de los t\u00edtulos de referencia del cine europeo actual, el","canonical_url":"https:\/\/candas365.es\/noticias\/mas-cine-en-laboral-cinemateca-durante-mayo-de-2018\/","robots":"max-image-preview:large","keywords":"agenda","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/mas-cine-en-laboral-cinemateca-durante-mayo-de-2018\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/agenda\/#listItem","name":"Agenda"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/agenda\/#listItem","position":2,"name":"Agenda","item":"https:\/\/candas365.es\/noticias\/category\/agenda\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/mas-cine-en-laboral-cinemateca-durante-mayo-de-2018\/#listItem","name":"M\u00e1s cine en Laboral Cinemateca durante mayo de 2018"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/mas-cine-en-laboral-cinemateca-durante-mayo-de-2018\/#listItem","position":3,"name":"M\u00e1s cine en Laboral Cinemateca durante mayo de 2018","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/agenda\/#listItem","name":"Agenda"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/mas-cine-en-laboral-cinemateca-durante-mayo-de-2018\/#newsarticle","name":"M\u00e1s cine en Laboral Cinemateca durante mayo de 2018 | Cand\u00e1s 365","headline":"M\u00e1s cine en Laboral Cinemateca durante mayo de 2018","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/film-596009_960_720.jpg","width":960,"height":678,"caption":"film"},"datePublished":"2018-05-03T19:39:33+02:00","dateModified":"2018-05-03T19:39:33+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/mas-cine-en-laboral-cinemateca-durante-mayo-de-2018\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/mas-cine-en-laboral-cinemateca-durante-mayo-de-2018\/#webpage"},"articleSection":"Agenda","dateline":"Publicado el mayo 3, 2018."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/mas-cine-en-laboral-cinemateca-durante-mayo-de-2018\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/mas-cine-en-laboral-cinemateca-durante-mayo-de-2018\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/mas-cine-en-laboral-cinemateca-durante-mayo-de-2018\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/mas-cine-en-laboral-cinemateca-durante-mayo-de-2018\/#webpage","url":"https:\/\/candas365.es\/noticias\/mas-cine-en-laboral-cinemateca-durante-mayo-de-2018\/","name":"M\u00e1s cine en Laboral Cinemateca durante mayo de 2018 | Cand\u00e1s 365","description":"Laboral Cinemateca sigue desarrollando los objetivos fijados en su puesta en marcha y para el mes de mayo ha programado un intenso programa de proyecciones no s\u00f3lo en Gij\u00f3n, su sede principal, sino tambi\u00e9n en trece concejos asturianos gracias al programa La Cinemateca Ambulante. Algunos de los t\u00edtulos de referencia del cine europeo actual, el","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/mas-cine-en-laboral-cinemateca-durante-mayo-de-2018\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/film-596009_960_720.jpg","@id":"https:\/\/candas365.es\/noticias\/mas-cine-en-laboral-cinemateca-durante-mayo-de-2018\/#mainImage","width":960,"height":678,"caption":"film"},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/mas-cine-en-laboral-cinemateca-durante-mayo-de-2018\/#mainImage"},"datePublished":"2018-05-03T19:39:33+02:00","dateModified":"2018-05-03T19:39:33+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"M\u00e1s cine en Laboral Cinemateca durante mayo de 2018 | Cand\u00e1s 365","og:description":"Laboral Cinemateca sigue desarrollando los objetivos fijados en su puesta en marcha y para el mes de mayo ha programado un intenso programa de proyecciones no s\u00f3lo en Gij\u00f3n, su sede principal, sino tambi\u00e9n en trece concejos asturianos gracias al programa La Cinemateca Ambulante. Algunos de los t\u00edtulos de referencia del cine europeo actual, el","og:url":"https:\/\/candas365.es\/noticias\/mas-cine-en-laboral-cinemateca-durante-mayo-de-2018\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/film-596009_960_720.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/film-596009_960_720.jpg","og:image:width":960,"og:image:height":678,"article:published_time":"2018-05-03T19:39:33+00:00","article:modified_time":"2018-05-03T19:39:33+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"M\u00e1s cine en Laboral Cinemateca durante mayo de 2018 | Cand\u00e1s 365","twitter:description":"Laboral Cinemateca sigue desarrollando los objetivos fijados en su puesta en marcha y para el mes de mayo ha programado un intenso programa de proyecciones no s\u00f3lo en Gij\u00f3n, su sede principal, sino tambi\u00e9n en trece concejos asturianos gracias al programa La Cinemateca Ambulante. Algunos de los t\u00edtulos de referencia del cine europeo actual, el","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/film-596009_960_720.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"5 minutos"},"aioseo_meta_data":{"post_id":"95199","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-26 20:10:14","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 11:52:31","updated":"2025-08-26 20:10:14"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/agenda\/\" title=\"Agenda\">Agenda<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tM\u00e1s cine en Laboral Cinemateca durante mayo de 2018\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Agenda","link":"https:\/\/candas365.es\/noticias\/category\/agenda\/"},{"label":"M\u00e1s cine en Laboral Cinemateca durante mayo de 2018","link":"https:\/\/candas365.es\/noticias\/mas-cine-en-laboral-cinemateca-durante-mayo-de-2018\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/95199","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=95199"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/95199\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/84232"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=95199"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=95199"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=95199"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}