{"id":95186,"date":"2018-05-02T22:16:32","date_gmt":"2018-05-02T22:16:32","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=95186"},"modified":"2018-05-02T22:16:32","modified_gmt":"2018-05-02T22:16:32","slug":"el-dia-mundial-de-la-libertad-de-prensa","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/el-dia-mundial-de-la-libertad-de-prensa\/","title":{"rendered":"El D\u00eda Mundial de la Libertad de Prensa"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-95187\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/background-3182873_1920-360x178.jpg\" alt=\"\" width=\"360\" height=\"178\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/background-3182873_1920-360x178.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/background-3182873_1920-768x380.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/background-3182873_1920-655x324.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/background-3182873_1920-324x160.jpg 324w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/background-3182873_1920-696x344.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/background-3182873_1920-1068x528.jpg 1068w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/background-3182873_1920-850x420.jpg 850w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/background-3182873_1920.jpg 1920w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Berl\u00edn, 2 may (dpa) &#8211; A iniciativa de la Unesco, el 3 de diciembre de 1993 la Asamblea General de las Naciones Unidas (ONU) declar\u00f3 el 3 de mayo como D\u00eda Mundial de la Libertad de Prensa para recordar las limitaciones que existen en muchos pa\u00edses del mundo a la hora de informar libremente.<\/p>\n<p>La Unesco, la organizaci\u00f3n de la ONU para la educaci\u00f3n, la ciencia y la cultura, ya hab\u00eda aprobado dos a\u00f1os antes la \u00abDeclaraci\u00f3n de Windhoek\u00bb, que criticaba la censura como grave violaci\u00f3n de los derechos humanos. El mensaje de Windhoek dec\u00eda que todo periodista en cualquier lugar del mundo debe tener el derecho de poder informar libremente y sin miedo.<\/p>\n<p>El D\u00eda Mundial de la Libertad de Prensa se celebr\u00f3 por primera vez en 1994. Desde 1997 ese d\u00eda la Unesco otorga el premio Guillermo Cano en memoria del periodista colombiano asesinado, con el que rinde tributo a una persona, organizaci\u00f3n o instituci\u00f3n que haya contribuido de forma notoria a la defensa y la promoci\u00f3n de la libertad de prensa en cualquier lugar del mundo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Berl\u00edn, 2 may (dpa) &#8211; A iniciativa de la Unesco, el 3 de diciembre de 1993 la Asamblea General de las Naciones Unidas (ONU) declar\u00f3 el 3 de mayo como D\u00eda Mundial de la Libertad de Prensa para recordar las limitaciones que existen en muchos pa\u00edses del mundo a la hora de informar libremente. La<\/p>\n","protected":false},"author":1,"featured_media":95187,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343],"tags":[],"class_list":{"0":"post-95186","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-actualidad"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7 - aioseo.com -->\n\t<meta name=\"description\" content=\"Berl\u00edn, 2 may (dpa) - A iniciativa de la Unesco, el 3 de diciembre de 1993 la Asamblea General de las Naciones Unidas (ONU) declar\u00f3 el 3 de mayo como D\u00eda Mundial de la Libertad de Prensa para recordar las limitaciones que existen en muchos pa\u00edses del mundo a la hora de informar libremente. La\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/el-dia-mundial-de-la-libertad-de-prensa\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El D\u00eda Mundial de la Libertad de Prensa | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Berl\u00edn, 2 may (dpa) - A iniciativa de la Unesco, el 3 de diciembre de 1993 la Asamblea General de las Naciones Unidas (ONU) declar\u00f3 el 3 de mayo como D\u00eda Mundial de la Libertad de Prensa para recordar las limitaciones que existen en muchos pa\u00edses del mundo a la hora de informar libremente. La\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/el-dia-mundial-de-la-libertad-de-prensa\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/background-3182873_1920.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/background-3182873_1920.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t\t<meta property=\"og:image:height\" content=\"949\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-05-02T22:16:32+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-05-02T22:16:32+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El D\u00eda Mundial de la Libertad de Prensa | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Berl\u00edn, 2 may (dpa) - A iniciativa de la Unesco, el 3 de diciembre de 1993 la Asamblea General de las Naciones Unidas (ONU) declar\u00f3 el 3 de mayo como D\u00eda Mundial de la Libertad de Prensa para recordar las limitaciones que existen en muchos pa\u00edses del mundo a la hora de informar libremente. La\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/background-3182873_1920.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-dia-mundial-de-la-libertad-de-prensa\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-dia-mundial-de-la-libertad-de-prensa\\\/#listItem\",\"name\":\"El D\\u00eda Mundial de la Libertad de Prensa\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-dia-mundial-de-la-libertad-de-prensa\\\/#listItem\",\"position\":3,\"name\":\"El D\\u00eda Mundial de la Libertad de Prensa\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-dia-mundial-de-la-libertad-de-prensa\\\/#newsarticle\",\"name\":\"El D\\u00eda Mundial de la Libertad de Prensa | Cand\\u00e1s 365\",\"headline\":\"El D\\u00eda Mundial de la Libertad de Prensa\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/background-3182873_1920.jpg\",\"width\":1920,\"height\":949},\"datePublished\":\"2018-05-02T22:16:32+02:00\",\"dateModified\":\"2018-05-02T22:16:32+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-dia-mundial-de-la-libertad-de-prensa\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-dia-mundial-de-la-libertad-de-prensa\\\/#webpage\"},\"articleSection\":\"Actualidad\",\"dateline\":\"Publicado el mayo 2, 2018.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-dia-mundial-de-la-libertad-de-prensa\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-dia-mundial-de-la-libertad-de-prensa\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-dia-mundial-de-la-libertad-de-prensa\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-dia-mundial-de-la-libertad-de-prensa\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-dia-mundial-de-la-libertad-de-prensa\\\/\",\"name\":\"El D\\u00eda Mundial de la Libertad de Prensa | Cand\\u00e1s 365\",\"description\":\"Berl\\u00edn, 2 may (dpa) - A iniciativa de la Unesco, el 3 de diciembre de 1993 la Asamblea General de las Naciones Unidas (ONU) declar\\u00f3 el 3 de mayo como D\\u00eda Mundial de la Libertad de Prensa para recordar las limitaciones que existen en muchos pa\\u00edses del mundo a la hora de informar libremente. La\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-dia-mundial-de-la-libertad-de-prensa\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/background-3182873_1920.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-dia-mundial-de-la-libertad-de-prensa\\\/#mainImage\",\"width\":1920,\"height\":949},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-dia-mundial-de-la-libertad-de-prensa\\\/#mainImage\"},\"datePublished\":\"2018-05-02T22:16:32+02:00\",\"dateModified\":\"2018-05-02T22:16:32+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>El D\u00eda Mundial de la Libertad de Prensa | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"El D\u00eda Mundial de la Libertad de Prensa | Cand\u00e1s 365","description":"Berl\u00edn, 2 may (dpa) - A iniciativa de la Unesco, el 3 de diciembre de 1993 la Asamblea General de las Naciones Unidas (ONU) declar\u00f3 el 3 de mayo como D\u00eda Mundial de la Libertad de Prensa para recordar las limitaciones que existen en muchos pa\u00edses del mundo a la hora de informar libremente. La","canonical_url":"https:\/\/candas365.es\/noticias\/el-dia-mundial-de-la-libertad-de-prensa\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/el-dia-mundial-de-la-libertad-de-prensa\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/candas365.es\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/el-dia-mundial-de-la-libertad-de-prensa\/#listItem","name":"El D\u00eda Mundial de la Libertad de Prensa"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/el-dia-mundial-de-la-libertad-de-prensa\/#listItem","position":3,"name":"El D\u00eda Mundial de la Libertad de Prensa","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/el-dia-mundial-de-la-libertad-de-prensa\/#newsarticle","name":"El D\u00eda Mundial de la Libertad de Prensa | Cand\u00e1s 365","headline":"El D\u00eda Mundial de la Libertad de Prensa","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/background-3182873_1920.jpg","width":1920,"height":949},"datePublished":"2018-05-02T22:16:32+02:00","dateModified":"2018-05-02T22:16:32+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/el-dia-mundial-de-la-libertad-de-prensa\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/el-dia-mundial-de-la-libertad-de-prensa\/#webpage"},"articleSection":"Actualidad","dateline":"Publicado el mayo 2, 2018."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/el-dia-mundial-de-la-libertad-de-prensa\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/el-dia-mundial-de-la-libertad-de-prensa\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/el-dia-mundial-de-la-libertad-de-prensa\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/el-dia-mundial-de-la-libertad-de-prensa\/#webpage","url":"https:\/\/candas365.es\/noticias\/el-dia-mundial-de-la-libertad-de-prensa\/","name":"El D\u00eda Mundial de la Libertad de Prensa | Cand\u00e1s 365","description":"Berl\u00edn, 2 may (dpa) - A iniciativa de la Unesco, el 3 de diciembre de 1993 la Asamblea General de las Naciones Unidas (ONU) declar\u00f3 el 3 de mayo como D\u00eda Mundial de la Libertad de Prensa para recordar las limitaciones que existen en muchos pa\u00edses del mundo a la hora de informar libremente. La","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/el-dia-mundial-de-la-libertad-de-prensa\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/background-3182873_1920.jpg","@id":"https:\/\/candas365.es\/noticias\/el-dia-mundial-de-la-libertad-de-prensa\/#mainImage","width":1920,"height":949},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/el-dia-mundial-de-la-libertad-de-prensa\/#mainImage"},"datePublished":"2018-05-02T22:16:32+02:00","dateModified":"2018-05-02T22:16:32+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"El D\u00eda Mundial de la Libertad de Prensa | Cand\u00e1s 365","og:description":"Berl\u00edn, 2 may (dpa) - A iniciativa de la Unesco, el 3 de diciembre de 1993 la Asamblea General de las Naciones Unidas (ONU) declar\u00f3 el 3 de mayo como D\u00eda Mundial de la Libertad de Prensa para recordar las limitaciones que existen en muchos pa\u00edses del mundo a la hora de informar libremente. La","og:url":"https:\/\/candas365.es\/noticias\/el-dia-mundial-de-la-libertad-de-prensa\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/background-3182873_1920.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/background-3182873_1920.jpg","og:image:width":1920,"og:image:height":949,"article:published_time":"2018-05-02T22:16:32+00:00","article:modified_time":"2018-05-02T22:16:32+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"El D\u00eda Mundial de la Libertad de Prensa | Cand\u00e1s 365","twitter:description":"Berl\u00edn, 2 may (dpa) - A iniciativa de la Unesco, el 3 de diciembre de 1993 la Asamblea General de las Naciones Unidas (ONU) declar\u00f3 el 3 de mayo como D\u00eda Mundial de la Libertad de Prensa para recordar las limitaciones que existen en muchos pa\u00edses del mundo a la hora de informar libremente. La","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/background-3182873_1920.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"1 minuto"},"aioseo_meta_data":{"post_id":"95186","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-26 20:09:17","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 11:52:31","updated":"2025-08-26 20:09:17"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tEl D\u00eda Mundial de la Libertad de Prensa\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Actualidad","link":"https:\/\/candas365.es\/noticias\/category\/actualidad\/"},{"label":"El D\u00eda Mundial de la Libertad de Prensa","link":"https:\/\/candas365.es\/noticias\/el-dia-mundial-de-la-libertad-de-prensa\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/95186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=95186"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/95186\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/95187"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=95186"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=95186"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=95186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}