{"id":94951,"date":"2018-04-29T21:26:56","date_gmt":"2018-04-29T21:26:56","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=94951"},"modified":"2018-04-29T21:26:56","modified_gmt":"2018-04-29T21:26:56","slug":"horoscopo-de-libra-lunes-30-de-abril-de-2018","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/horoscopo-de-libra-lunes-30-de-abril-de-2018\/","title":{"rendered":"Hor\u00f3scopo de Libra, lunes 30 de abril de 2018"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-94952\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/04\/HOROSCOPO-DIA-30-ABRIL-2018-360x240.jpg\" alt=\"\" width=\"360\" height=\"240\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/04\/HOROSCOPO-DIA-30-ABRIL-2018-360x240.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/04\/HOROSCOPO-DIA-30-ABRIL-2018-768x512.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/04\/HOROSCOPO-DIA-30-ABRIL-2018-655x437.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/04\/HOROSCOPO-DIA-30-ABRIL-2018-696x464.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/04\/HOROSCOPO-DIA-30-ABRIL-2018-630x420.jpg 630w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/04\/HOROSCOPO-DIA-30-ABRIL-2018.jpg 960w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Lunes en el que comienzas una semana en la que tendr\u00e1s una actitud mucho m\u00e1s positiva y en la que ver\u00e1s con otros ojos las ideas de los dem\u00e1s, ser\u00e1 un buen d\u00eda para hablar y para llegar a acuerdos con la gente que te gusta y con las personas con las que hoy compartas t\u00fa tiempo.<\/p>\n<p>Siempre es bueno dedicar unas horas al descanso o al ocio, quiz\u00e1s hoy tengas tiempo para ello, si no tienes grandes planes para hoy deja que sean t\u00fa mente y t\u00fa cuerpo los que hoy te gu\u00eden por la vida, no dudes, trabaja en lo que te gusta y mejora aquello que sea mejorable.<\/p>\n<p>La vida siempre nos ofrece algo que no esperamos, muchas veces llega por \u201csorpresa\u201d y eso es algo que deber\u00e1s tener en cuenta hoy, puede que te toque o puede que no\u2026 nada es igual para todos, qu\u00e9date siempre con lo que \u201cdeseas\u201d y con lo que te llene, suerte \u00a1!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lunes en el que comienzas una semana en la que tendr\u00e1s una actitud mucho m\u00e1s positiva y en la que ver\u00e1s con otros ojos las ideas de los dem\u00e1s, ser\u00e1 un buen d\u00eda para hablar y para llegar a acuerdos con la gente que te gusta y con las personas con las que hoy compartas<\/p>\n","protected":false},"author":1,"featured_media":94952,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[185],"tags":[],"class_list":{"0":"post-94951","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-horoscopo-diario"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7 - aioseo.com -->\n\t<meta name=\"description\" content=\"Lunes en el que comienzas una semana en la que tendr\u00e1s una actitud mucho m\u00e1s positiva y en la que ver\u00e1s con otros ojos las ideas de los dem\u00e1s, ser\u00e1 un buen d\u00eda para hablar y para llegar a acuerdos con la gente que te gusta y con las personas con las que hoy compartas\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"hor\u00f3scopo diario\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/horoscopo-de-libra-lunes-30-de-abril-de-2018\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Hor\u00f3scopo de Libra, lunes 30 de abril de 2018 | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Lunes en el que comienzas una semana en la que tendr\u00e1s una actitud mucho m\u00e1s positiva y en la que ver\u00e1s con otros ojos las ideas de los dem\u00e1s, ser\u00e1 un buen d\u00eda para hablar y para llegar a acuerdos con la gente que te gusta y con las personas con las que hoy compartas\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/horoscopo-de-libra-lunes-30-de-abril-de-2018\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/04\/HOROSCOPO-DIA-30-ABRIL-2018.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/04\/HOROSCOPO-DIA-30-ABRIL-2018.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-04-29T21:26:56+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-04-29T21:26:56+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Hor\u00f3scopo de Libra, lunes 30 de abril de 2018 | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Lunes en el que comienzas una semana en la que tendr\u00e1s una actitud mucho m\u00e1s positiva y en la que ver\u00e1s con otros ojos las ideas de los dem\u00e1s, ser\u00e1 un buen d\u00eda para hablar y para llegar a acuerdos con la gente que te gusta y con las personas con las que hoy compartas\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/04\/HOROSCOPO-DIA-30-ABRIL-2018.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/horoscopo-de-libra-lunes-30-de-abril-de-2018\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/horoscopo-diario\\\/#listItem\",\"name\":\"Hor\\u00f3scopo diario\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/horoscopo-diario\\\/#listItem\",\"position\":2,\"name\":\"Hor\\u00f3scopo diario\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/horoscopo-diario\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/horoscopo-de-libra-lunes-30-de-abril-de-2018\\\/#listItem\",\"name\":\"Hor\\u00f3scopo de Libra, lunes 30 de abril de 2018\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/horoscopo-de-libra-lunes-30-de-abril-de-2018\\\/#listItem\",\"position\":3,\"name\":\"Hor\\u00f3scopo de Libra, lunes 30 de abril de 2018\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/horoscopo-diario\\\/#listItem\",\"name\":\"Hor\\u00f3scopo diario\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/horoscopo-de-libra-lunes-30-de-abril-de-2018\\\/#newsarticle\",\"name\":\"Hor\\u00f3scopo de Libra, lunes 30 de abril de 2018 | Cand\\u00e1s 365\",\"headline\":\"Hor\\u00f3scopo de Libra, lunes 30 de abril de 2018\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/HOROSCOPO-DIA-30-ABRIL-2018.jpg\",\"width\":960,\"height\":640},\"datePublished\":\"2018-04-29T21:26:56+02:00\",\"dateModified\":\"2018-04-29T21:26:56+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/horoscopo-de-libra-lunes-30-de-abril-de-2018\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/horoscopo-de-libra-lunes-30-de-abril-de-2018\\\/#webpage\"},\"articleSection\":\"Hor\\u00f3scopo diario\",\"dateline\":\"Publicado el abril 29, 2018.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/horoscopo-de-libra-lunes-30-de-abril-de-2018\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/horoscopo-de-libra-lunes-30-de-abril-de-2018\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/horoscopo-de-libra-lunes-30-de-abril-de-2018\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/horoscopo-de-libra-lunes-30-de-abril-de-2018\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/horoscopo-de-libra-lunes-30-de-abril-de-2018\\\/\",\"name\":\"Hor\\u00f3scopo de Libra, lunes 30 de abril de 2018 | Cand\\u00e1s 365\",\"description\":\"Lunes en el que comienzas una semana en la que tendr\\u00e1s una actitud mucho m\\u00e1s positiva y en la que ver\\u00e1s con otros ojos las ideas de los dem\\u00e1s, ser\\u00e1 un buen d\\u00eda para hablar y para llegar a acuerdos con la gente que te gusta y con las personas con las que hoy compartas\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/horoscopo-de-libra-lunes-30-de-abril-de-2018\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/HOROSCOPO-DIA-30-ABRIL-2018.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/horoscopo-de-libra-lunes-30-de-abril-de-2018\\\/#mainImage\",\"width\":960,\"height\":640},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/horoscopo-de-libra-lunes-30-de-abril-de-2018\\\/#mainImage\"},\"datePublished\":\"2018-04-29T21:26:56+02:00\",\"dateModified\":\"2018-04-29T21:26:56+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Hor\u00f3scopo de Libra, lunes 30 de abril de 2018 | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Hor\u00f3scopo de Libra, lunes 30 de abril de 2018 | Cand\u00e1s 365","description":"Lunes en el que comienzas una semana en la que tendr\u00e1s una actitud mucho m\u00e1s positiva y en la que ver\u00e1s con otros ojos las ideas de los dem\u00e1s, ser\u00e1 un buen d\u00eda para hablar y para llegar a acuerdos con la gente que te gusta y con las personas con las que hoy compartas","canonical_url":"https:\/\/candas365.es\/noticias\/horoscopo-de-libra-lunes-30-de-abril-de-2018\/","robots":"max-image-preview:large","keywords":"hor\u00f3scopo diario","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/horoscopo-de-libra-lunes-30-de-abril-de-2018\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/horoscopo-diario\/#listItem","name":"Hor\u00f3scopo diario"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/horoscopo-diario\/#listItem","position":2,"name":"Hor\u00f3scopo diario","item":"https:\/\/candas365.es\/noticias\/category\/horoscopo-diario\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/horoscopo-de-libra-lunes-30-de-abril-de-2018\/#listItem","name":"Hor\u00f3scopo de Libra, lunes 30 de abril de 2018"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/horoscopo-de-libra-lunes-30-de-abril-de-2018\/#listItem","position":3,"name":"Hor\u00f3scopo de Libra, lunes 30 de abril de 2018","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/horoscopo-diario\/#listItem","name":"Hor\u00f3scopo diario"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/horoscopo-de-libra-lunes-30-de-abril-de-2018\/#newsarticle","name":"Hor\u00f3scopo de Libra, lunes 30 de abril de 2018 | Cand\u00e1s 365","headline":"Hor\u00f3scopo de Libra, lunes 30 de abril de 2018","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/04\/HOROSCOPO-DIA-30-ABRIL-2018.jpg","width":960,"height":640},"datePublished":"2018-04-29T21:26:56+02:00","dateModified":"2018-04-29T21:26:56+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/horoscopo-de-libra-lunes-30-de-abril-de-2018\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/horoscopo-de-libra-lunes-30-de-abril-de-2018\/#webpage"},"articleSection":"Hor\u00f3scopo diario","dateline":"Publicado el abril 29, 2018."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/horoscopo-de-libra-lunes-30-de-abril-de-2018\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/horoscopo-de-libra-lunes-30-de-abril-de-2018\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/horoscopo-de-libra-lunes-30-de-abril-de-2018\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/horoscopo-de-libra-lunes-30-de-abril-de-2018\/#webpage","url":"https:\/\/candas365.es\/noticias\/horoscopo-de-libra-lunes-30-de-abril-de-2018\/","name":"Hor\u00f3scopo de Libra, lunes 30 de abril de 2018 | Cand\u00e1s 365","description":"Lunes en el que comienzas una semana en la que tendr\u00e1s una actitud mucho m\u00e1s positiva y en la que ver\u00e1s con otros ojos las ideas de los dem\u00e1s, ser\u00e1 un buen d\u00eda para hablar y para llegar a acuerdos con la gente que te gusta y con las personas con las que hoy compartas","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/horoscopo-de-libra-lunes-30-de-abril-de-2018\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/04\/HOROSCOPO-DIA-30-ABRIL-2018.jpg","@id":"https:\/\/candas365.es\/noticias\/horoscopo-de-libra-lunes-30-de-abril-de-2018\/#mainImage","width":960,"height":640},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/horoscopo-de-libra-lunes-30-de-abril-de-2018\/#mainImage"},"datePublished":"2018-04-29T21:26:56+02:00","dateModified":"2018-04-29T21:26:56+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Hor\u00f3scopo de Libra, lunes 30 de abril de 2018 | Cand\u00e1s 365","og:description":"Lunes en el que comienzas una semana en la que tendr\u00e1s una actitud mucho m\u00e1s positiva y en la que ver\u00e1s con otros ojos las ideas de los dem\u00e1s, ser\u00e1 un buen d\u00eda para hablar y para llegar a acuerdos con la gente que te gusta y con las personas con las que hoy compartas","og:url":"https:\/\/candas365.es\/noticias\/horoscopo-de-libra-lunes-30-de-abril-de-2018\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/04\/HOROSCOPO-DIA-30-ABRIL-2018.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/04\/HOROSCOPO-DIA-30-ABRIL-2018.jpg","og:image:width":960,"og:image:height":640,"article:published_time":"2018-04-29T21:26:56+00:00","article:modified_time":"2018-04-29T21:26:56+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Hor\u00f3scopo de Libra, lunes 30 de abril de 2018 | Cand\u00e1s 365","twitter:description":"Lunes en el que comienzas una semana en la que tendr\u00e1s una actitud mucho m\u00e1s positiva y en la que ver\u00e1s con otros ojos las ideas de los dem\u00e1s, ser\u00e1 un buen d\u00eda para hablar y para llegar a acuerdos con la gente que te gusta y con las personas con las que hoy compartas","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/04\/HOROSCOPO-DIA-30-ABRIL-2018.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"1 minuto"},"aioseo_meta_data":{"post_id":"94951","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-26 19:48:12","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 11:52:42","updated":"2025-08-26 19:48:12"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/horoscopo-diario\/\" title=\"Hor\u00f3scopo diario\">Hor\u00f3scopo diario<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tHor\u00f3scopo de Libra, lunes 30 de abril de 2018\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Hor\u00f3scopo diario","link":"https:\/\/candas365.es\/noticias\/category\/horoscopo-diario\/"},{"label":"Hor\u00f3scopo de Libra, lunes 30 de abril de 2018","link":"https:\/\/candas365.es\/noticias\/horoscopo-de-libra-lunes-30-de-abril-de-2018\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/94951","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=94951"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/94951\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/94952"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=94951"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=94951"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=94951"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}