{"id":94875,"date":"2018-04-28T20:25:47","date_gmt":"2018-04-28T20:25:47","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=94875"},"modified":"2018-04-28T20:25:47","modified_gmt":"2018-04-28T20:25:47","slug":"steinmeier-inaugurara-la-casa-de-thomas-mann-en-california","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/steinmeier-inaugurara-la-casa-de-thomas-mann-en-california\/","title":{"rendered":"Steinmeier inaugurar\u00e1 la casa de Thomas Mann en California"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-86307\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/12\/apple-1853306_1280-news2-360x240.jpg\" alt=\"\" width=\"360\" height=\"240\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/12\/apple-1853306_1280-news2-360x240.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/12\/apple-1853306_1280-news2-768x512.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/12\/apple-1853306_1280-news2-655x436.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/12\/apple-1853306_1280-news2-696x464.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/12\/apple-1853306_1280-news2-1068x712.jpg 1068w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/12\/apple-1853306_1280-news2-630x420.jpg 630w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/12\/apple-1853306_1280-news2-84x55.jpg 84w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/12\/apple-1853306_1280-news2.jpg 1280w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Berl\u00edn, 28 abr (dpa) &#8211; El presidente de Alemania, Frank-Walter Steinmeier, viajar\u00e1 a mediados de junio a la costa oeste de Estados Unidos para llevar a cabo una visita de varios d\u00edas a California. El objetivo ser\u00e1 la inauguraci\u00f3n de la casa del escritor Thomas Mann (1875-1955) en las afueras de Los Angeles, inform\u00f3 la oficina presidencial en Berl\u00edn.<\/p>\n<p>La casa donde el Nobel de Literatura alem\u00e1n vivi\u00f3 con la familia durante su exilio -Mann abandon\u00f3 Alemania en 1933 por su oposici\u00f3n al r\u00e9gimen nazi- y hasta 1952 fue comprada por el Gobierno alem\u00e1n en 2016 para evitar que fuera demolida. La intenci\u00f3n es convertirla en una casa de artistas y de intercambio cultural. La villa adem\u00e1s se utilizar\u00e1 como lugar de encuentro y de alojamiento para becarios.<\/p>\n<p>Steinmeier tambi\u00e9n visitar\u00e1 el Silicon Valley, al sur de San Francisco, donde tienen su sede las grandes compa\u00f1\u00edas de la tecnolog\u00eda de la informaci\u00f3n. All\u00ed abordar\u00e1 cuestiones como la digitalizaci\u00f3n y el futuro del mundo laboral.<\/p>\n<p>Durante su estancia en Estados Unidos no est\u00e1 previsto que Steinmeier se re\u00fana con el presidente Donald Trump, quien mantuvo un encuentro con la canciller alemana, Angela Merkel, el viernes.<\/p>\n<p>En 2015, el entonces presidente estadounidense, Barack Obama, recibi\u00f3 en la Casa Blanca al entonces presidente de Alemania, Joachim Gauck. Su predecesor, Christian Wulff no viaj\u00f3 a EEUU, mientras que el antecesor de \u00e9ste, Horst K\u00f6hler, hizo en 2006 una breve visita a Nueva York, aunque tampoco lleg\u00f3 a reunirse con el presidente de Estados Unidos.<\/p>\n<p>En 2016 y en su entonces cargo de ministro de Exteriores, Steinmeier jug\u00f3 un papel decisivo en la compra de la casa de Thomas Mann por unos 13 millones de d\u00f3lares (casi 11 millones de euros) por parte del Gobierno germano. La villa en la zona de Pacific Palisades es algo as\u00ed como la \u00abCasa Blanca del exilio\u00bb, declar\u00f3 entonces al diario \u00abS\u00fcddeutsche Zeitung\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Berl\u00edn, 28 abr (dpa) &#8211; El presidente de Alemania, Frank-Walter Steinmeier, viajar\u00e1 a mediados de junio a la costa oeste de Estados Unidos para llevar a cabo una visita de varios d\u00edas a California. El objetivo ser\u00e1 la inauguraci\u00f3n de la casa del escritor Thomas Mann (1875-1955) en las afueras de Los Angeles, inform\u00f3 la<\/p>\n","protected":false},"author":1,"featured_media":86307,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343],"tags":[],"class_list":{"0":"post-94875","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-actualidad"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7 - aioseo.com -->\n\t<meta name=\"description\" content=\"Berl\u00edn, 28 abr (dpa) - El presidente de Alemania, Frank-Walter Steinmeier, viajar\u00e1 a mediados de junio a la costa oeste de Estados Unidos para llevar a cabo una visita de varios d\u00edas a California. El objetivo ser\u00e1 la inauguraci\u00f3n de la casa del escritor Thomas Mann (1875-1955) en las afueras de Los Angeles, inform\u00f3 la\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/steinmeier-inaugurara-la-casa-de-thomas-mann-en-california\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Steinmeier inaugurar\u00e1 la casa de Thomas Mann en California | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Berl\u00edn, 28 abr (dpa) - El presidente de Alemania, Frank-Walter Steinmeier, viajar\u00e1 a mediados de junio a la costa oeste de Estados Unidos para llevar a cabo una visita de varios d\u00edas a California. El objetivo ser\u00e1 la inauguraci\u00f3n de la casa del escritor Thomas Mann (1875-1955) en las afueras de Los Angeles, inform\u00f3 la\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/steinmeier-inaugurara-la-casa-de-thomas-mann-en-california\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/12\/apple-1853306_1280-news2.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/12\/apple-1853306_1280-news2.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-04-28T20:25:47+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-04-28T20:25:47+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Steinmeier inaugurar\u00e1 la casa de Thomas Mann en California | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Berl\u00edn, 28 abr (dpa) - El presidente de Alemania, Frank-Walter Steinmeier, viajar\u00e1 a mediados de junio a la costa oeste de Estados Unidos para llevar a cabo una visita de varios d\u00edas a California. El objetivo ser\u00e1 la inauguraci\u00f3n de la casa del escritor Thomas Mann (1875-1955) en las afueras de Los Angeles, inform\u00f3 la\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/12\/apple-1853306_1280-news2.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/steinmeier-inaugurara-la-casa-de-thomas-mann-en-california\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/steinmeier-inaugurara-la-casa-de-thomas-mann-en-california\\\/#listItem\",\"name\":\"Steinmeier inaugurar\\u00e1 la casa de Thomas Mann en California\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/steinmeier-inaugurara-la-casa-de-thomas-mann-en-california\\\/#listItem\",\"position\":3,\"name\":\"Steinmeier inaugurar\\u00e1 la casa de Thomas Mann en California\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/steinmeier-inaugurara-la-casa-de-thomas-mann-en-california\\\/#newsarticle\",\"name\":\"Steinmeier inaugurar\\u00e1 la casa de Thomas Mann en California | Cand\\u00e1s 365\",\"headline\":\"Steinmeier inaugurar\\u00e1 la casa de Thomas Mann en California\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/apple-1853306_1280-news2.jpg\",\"width\":1280,\"height\":853},\"datePublished\":\"2018-04-28T20:25:47+02:00\",\"dateModified\":\"2018-04-28T20:25:47+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/steinmeier-inaugurara-la-casa-de-thomas-mann-en-california\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/steinmeier-inaugurara-la-casa-de-thomas-mann-en-california\\\/#webpage\"},\"articleSection\":\"Actualidad\",\"dateline\":\"Publicado el abril 28, 2018.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/steinmeier-inaugurara-la-casa-de-thomas-mann-en-california\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/steinmeier-inaugurara-la-casa-de-thomas-mann-en-california\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/steinmeier-inaugurara-la-casa-de-thomas-mann-en-california\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/steinmeier-inaugurara-la-casa-de-thomas-mann-en-california\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/steinmeier-inaugurara-la-casa-de-thomas-mann-en-california\\\/\",\"name\":\"Steinmeier inaugurar\\u00e1 la casa de Thomas Mann en California | Cand\\u00e1s 365\",\"description\":\"Berl\\u00edn, 28 abr (dpa) - El presidente de Alemania, Frank-Walter Steinmeier, viajar\\u00e1 a mediados de junio a la costa oeste de Estados Unidos para llevar a cabo una visita de varios d\\u00edas a California. El objetivo ser\\u00e1 la inauguraci\\u00f3n de la casa del escritor Thomas Mann (1875-1955) en las afueras de Los Angeles, inform\\u00f3 la\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/steinmeier-inaugurara-la-casa-de-thomas-mann-en-california\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/apple-1853306_1280-news2.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/steinmeier-inaugurara-la-casa-de-thomas-mann-en-california\\\/#mainImage\",\"width\":1280,\"height\":853},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/steinmeier-inaugurara-la-casa-de-thomas-mann-en-california\\\/#mainImage\"},\"datePublished\":\"2018-04-28T20:25:47+02:00\",\"dateModified\":\"2018-04-28T20:25:47+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Steinmeier inaugurar\u00e1 la casa de Thomas Mann en California | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Steinmeier inaugurar\u00e1 la casa de Thomas Mann en California | Cand\u00e1s 365","description":"Berl\u00edn, 28 abr (dpa) - El presidente de Alemania, Frank-Walter Steinmeier, viajar\u00e1 a mediados de junio a la costa oeste de Estados Unidos para llevar a cabo una visita de varios d\u00edas a California. El objetivo ser\u00e1 la inauguraci\u00f3n de la casa del escritor Thomas Mann (1875-1955) en las afueras de Los Angeles, inform\u00f3 la","canonical_url":"https:\/\/candas365.es\/noticias\/steinmeier-inaugurara-la-casa-de-thomas-mann-en-california\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/steinmeier-inaugurara-la-casa-de-thomas-mann-en-california\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/candas365.es\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/steinmeier-inaugurara-la-casa-de-thomas-mann-en-california\/#listItem","name":"Steinmeier inaugurar\u00e1 la casa de Thomas Mann en California"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/steinmeier-inaugurara-la-casa-de-thomas-mann-en-california\/#listItem","position":3,"name":"Steinmeier inaugurar\u00e1 la casa de Thomas Mann en California","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/steinmeier-inaugurara-la-casa-de-thomas-mann-en-california\/#newsarticle","name":"Steinmeier inaugurar\u00e1 la casa de Thomas Mann en California | Cand\u00e1s 365","headline":"Steinmeier inaugurar\u00e1 la casa de Thomas Mann en California","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/12\/apple-1853306_1280-news2.jpg","width":1280,"height":853},"datePublished":"2018-04-28T20:25:47+02:00","dateModified":"2018-04-28T20:25:47+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/steinmeier-inaugurara-la-casa-de-thomas-mann-en-california\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/steinmeier-inaugurara-la-casa-de-thomas-mann-en-california\/#webpage"},"articleSection":"Actualidad","dateline":"Publicado el abril 28, 2018."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/steinmeier-inaugurara-la-casa-de-thomas-mann-en-california\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/steinmeier-inaugurara-la-casa-de-thomas-mann-en-california\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/steinmeier-inaugurara-la-casa-de-thomas-mann-en-california\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/steinmeier-inaugurara-la-casa-de-thomas-mann-en-california\/#webpage","url":"https:\/\/candas365.es\/noticias\/steinmeier-inaugurara-la-casa-de-thomas-mann-en-california\/","name":"Steinmeier inaugurar\u00e1 la casa de Thomas Mann en California | Cand\u00e1s 365","description":"Berl\u00edn, 28 abr (dpa) - El presidente de Alemania, Frank-Walter Steinmeier, viajar\u00e1 a mediados de junio a la costa oeste de Estados Unidos para llevar a cabo una visita de varios d\u00edas a California. El objetivo ser\u00e1 la inauguraci\u00f3n de la casa del escritor Thomas Mann (1875-1955) en las afueras de Los Angeles, inform\u00f3 la","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/steinmeier-inaugurara-la-casa-de-thomas-mann-en-california\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/12\/apple-1853306_1280-news2.jpg","@id":"https:\/\/candas365.es\/noticias\/steinmeier-inaugurara-la-casa-de-thomas-mann-en-california\/#mainImage","width":1280,"height":853},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/steinmeier-inaugurara-la-casa-de-thomas-mann-en-california\/#mainImage"},"datePublished":"2018-04-28T20:25:47+02:00","dateModified":"2018-04-28T20:25:47+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Steinmeier inaugurar\u00e1 la casa de Thomas Mann en California | Cand\u00e1s 365","og:description":"Berl\u00edn, 28 abr (dpa) - El presidente de Alemania, Frank-Walter Steinmeier, viajar\u00e1 a mediados de junio a la costa oeste de Estados Unidos para llevar a cabo una visita de varios d\u00edas a California. El objetivo ser\u00e1 la inauguraci\u00f3n de la casa del escritor Thomas Mann (1875-1955) en las afueras de Los Angeles, inform\u00f3 la","og:url":"https:\/\/candas365.es\/noticias\/steinmeier-inaugurara-la-casa-de-thomas-mann-en-california\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/12\/apple-1853306_1280-news2.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/12\/apple-1853306_1280-news2.jpg","og:image:width":1280,"og:image:height":853,"article:published_time":"2018-04-28T20:25:47+00:00","article:modified_time":"2018-04-28T20:25:47+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Steinmeier inaugurar\u00e1 la casa de Thomas Mann en California | Cand\u00e1s 365","twitter:description":"Berl\u00edn, 28 abr (dpa) - El presidente de Alemania, Frank-Walter Steinmeier, viajar\u00e1 a mediados de junio a la costa oeste de Estados Unidos para llevar a cabo una visita de varios d\u00edas a California. El objetivo ser\u00e1 la inauguraci\u00f3n de la casa del escritor Thomas Mann (1875-1955) en las afueras de Los Angeles, inform\u00f3 la","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/12\/apple-1853306_1280-news2.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"94875","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-26 19:43:09","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 11:52:42","updated":"2025-08-26 19:43:09"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tSteinmeier inaugurar\u00e1 la casa de Thomas Mann en California\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Actualidad","link":"https:\/\/candas365.es\/noticias\/category\/actualidad\/"},{"label":"Steinmeier inaugurar\u00e1 la casa de Thomas Mann en California","link":"https:\/\/candas365.es\/noticias\/steinmeier-inaugurara-la-casa-de-thomas-mann-en-california\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/94875","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=94875"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/94875\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/86307"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=94875"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=94875"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=94875"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}