{"id":94831,"date":"2018-04-28T13:42:33","date_gmt":"2018-04-28T13:42:33","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=94831"},"modified":"2018-04-28T13:42:33","modified_gmt":"2018-04-28T13:42:33","slug":"el-bayer-leverkusen-ficha-a-paulinho-la-nueva-joya-brasilena-de-17-anos","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/el-bayer-leverkusen-ficha-a-paulinho-la-nueva-joya-brasilena-de-17-anos\/","title":{"rendered":"El Bayer Leverkusen ficha a Paulinho, la nueva joya brasile\u00f1a de 17 a\u00f1os"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-89552\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280-360x241.jpg\" alt=\"\" width=\"360\" height=\"241\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280-360x241.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280-696x466.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280-1068x715.jpg 1068w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280-627x420.jpg 627w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280-768x514.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280-655x439.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280.jpg 1280w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Leverkusen (Alemania), 28 abr (dpa) &#8211; El Bayer Leverkusen anunci\u00f3 el viernes el fichaje del delantero Paulinho, considerado a sus 17 a\u00f1os como la nueva joya del f\u00fatbol brasile\u00f1o.<\/p>\n<p>Paulinho dejar\u00e1 el Vasco da Gama para pasar a las filas del club germano el 15 de julio, cuando cumpla la mayor\u00eda de edad, comunic\u00f3 el Leverkusen.<\/p>\n<p>\u00abEl fichaje de Paulinho es para nosotros un gran \u00e9xito\u00bb, celebr\u00f3 el directivo Michael Schade. Seg\u00fan medios alemanes, la transferencia se cerr\u00f3 por 20 millones de euros (24 millones de d\u00f3lares).<\/p>\n<p>\u00abMe alegra que podamos mantener nuestra especial tradici\u00f3n brasile\u00f1a\u00bb, agreg\u00f3 Rudi V\u00f6ller, director deportivo del Leverkusen, donde brillaron en el pasado jugadores del gigante sudamericano como Emerson, L\u00facio, Z\u00e9 Roberto o Jorginho.<\/p>\n<p>Leverkusen \u00abtiene una gran fama en mi pa\u00eds, todos lo conocen como el club en Europa donde fueron felices muchos brasile\u00f1os\u00bb, indic\u00f3 Paulinho.<\/p>\n<p>\u00abMe parece importante dar el paso al extranjero de forma bien pensada y por eso eleg\u00ed un club que trabaja con seridad. Quiero jugar la Champions League y seguir mejorando\u00bb, lo cit\u00f3 su nuevo club.<\/p>\n<p>Paulinho, que debut\u00f3 a los 16 a\u00f1os en la \u00e9lite del f\u00fatbol brasile\u00f1o, es considerado como una de las grandes promesas de Brasil, junto con el atacante Vinicius Jr., ya fichado por el Real Madrid.<\/p>\n<p>Ambos jugadores son de la misma edad y naturales de R\u00edo de Janeiro, donde militan en dos de los grandes clubes cariocas: Vasco da Gama y Flamengo.<\/p>\n<p>Los medios brasile\u00f1os calentaron en los \u00faltimos meses el duelo entre los dos grandes talentos, frustrado en gran medida porque Vinicius no era titular en Flamengo, mientras que Paulinho brillaba con Vasco.<\/p>\n<p>El delantero sufri\u00f3 recientemente una fractura en un brazo tras caer mal durante un partido de Copa Libertadores entre Vasco y Cruzeiro, as\u00ed que no est\u00e1 claro si volver\u00e1 a jugar con su club actual.<\/p>\n<p>Seg\u00fan medios brasile\u00f1os, Paulinho era codiciado tambi\u00e9n por el Bayern M\u00fanich y el Borussia Dortmund, entre otros clubes de la Bundesliga, pero el joven artillero carioca se decidi\u00f3 por un equipo en el que cree que tendr\u00e1 m\u00e1s posibilidades de tener minutos.<\/p>\n<p>Paulinho, descubierto en 2010 cuando jugaba con el peque\u00f1o club Madureira en R\u00edo, \u00abes una de las referencias de la generaci\u00f3n de 2000\u00bb, lo elogi\u00f3 Vasco al anunciar la despedida del \u00abmenino de oro\u00bb, que se despide del club tras 35 juegos como profesional.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Leverkusen (Alemania), 28 abr (dpa) &#8211; El Bayer Leverkusen anunci\u00f3 el viernes el fichaje del delantero Paulinho, considerado a sus 17 a\u00f1os como la nueva joya del f\u00fatbol brasile\u00f1o. Paulinho dejar\u00e1 el Vasco da Gama para pasar a las filas del club germano el 15 de julio, cuando cumpla la mayor\u00eda de edad, comunic\u00f3 el<\/p>\n","protected":false},"author":1,"featured_media":89552,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[319],"tags":[],"class_list":{"0":"post-94831","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-deporte"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7 - aioseo.com -->\n\t<meta name=\"description\" content=\"Leverkusen (Alemania), 28 abr (dpa) - El Bayer Leverkusen anunci\u00f3 el viernes el fichaje del delantero Paulinho, considerado a sus 17 a\u00f1os como la nueva joya del f\u00fatbol brasile\u00f1o. Paulinho dejar\u00e1 el Vasco da Gama para pasar a las filas del club germano el 15 de julio, cuando cumpla la mayor\u00eda de edad, comunic\u00f3 el\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"deporte\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/el-bayer-leverkusen-ficha-a-paulinho-la-nueva-joya-brasilena-de-17-anos\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El Bayer Leverkusen ficha a Paulinho, la nueva joya brasile\u00f1a de 17 a\u00f1os | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Leverkusen (Alemania), 28 abr (dpa) - El Bayer Leverkusen anunci\u00f3 el viernes el fichaje del delantero Paulinho, considerado a sus 17 a\u00f1os como la nueva joya del f\u00fatbol brasile\u00f1o. Paulinho dejar\u00e1 el Vasco da Gama para pasar a las filas del club germano el 15 de julio, cuando cumpla la mayor\u00eda de edad, comunic\u00f3 el\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/el-bayer-leverkusen-ficha-a-paulinho-la-nueva-joya-brasilena-de-17-anos\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t\t<meta property=\"og:image:height\" content=\"857\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-04-28T13:42:33+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-04-28T13:42:33+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El Bayer Leverkusen ficha a Paulinho, la nueva joya brasile\u00f1a de 17 a\u00f1os | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Leverkusen (Alemania), 28 abr (dpa) - El Bayer Leverkusen anunci\u00f3 el viernes el fichaje del delantero Paulinho, considerado a sus 17 a\u00f1os como la nueva joya del f\u00fatbol brasile\u00f1o. Paulinho dejar\u00e1 el Vasco da Gama para pasar a las filas del club germano el 15 de julio, cuando cumpla la mayor\u00eda de edad, comunic\u00f3 el\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-bayer-leverkusen-ficha-a-paulinho-la-nueva-joya-brasilena-de-17-anos\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/#listItem\",\"name\":\"Deporte\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/#listItem\",\"position\":2,\"name\":\"Deporte\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-bayer-leverkusen-ficha-a-paulinho-la-nueva-joya-brasilena-de-17-anos\\\/#listItem\",\"name\":\"El Bayer Leverkusen ficha a Paulinho, la nueva joya brasile\\u00f1a de 17 a\\u00f1os\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-bayer-leverkusen-ficha-a-paulinho-la-nueva-joya-brasilena-de-17-anos\\\/#listItem\",\"position\":3,\"name\":\"El Bayer Leverkusen ficha a Paulinho, la nueva joya brasile\\u00f1a de 17 a\\u00f1os\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/#listItem\",\"name\":\"Deporte\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-bayer-leverkusen-ficha-a-paulinho-la-nueva-joya-brasilena-de-17-anos\\\/#newsarticle\",\"name\":\"El Bayer Leverkusen ficha a Paulinho, la nueva joya brasile\\u00f1a de 17 a\\u00f1os | Cand\\u00e1s 365\",\"headline\":\"El Bayer Leverkusen ficha a Paulinho, la nueva joya brasile\\u00f1a de 17 a\\u00f1os\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/football-1406106_1280.jpg\",\"width\":1280,\"height\":857,\"caption\":\"football\"},\"datePublished\":\"2018-04-28T13:42:33+02:00\",\"dateModified\":\"2018-04-28T13:42:33+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-bayer-leverkusen-ficha-a-paulinho-la-nueva-joya-brasilena-de-17-anos\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-bayer-leverkusen-ficha-a-paulinho-la-nueva-joya-brasilena-de-17-anos\\\/#webpage\"},\"articleSection\":\"Deporte\",\"dateline\":\"Publicado el abril 28, 2018.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-bayer-leverkusen-ficha-a-paulinho-la-nueva-joya-brasilena-de-17-anos\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-bayer-leverkusen-ficha-a-paulinho-la-nueva-joya-brasilena-de-17-anos\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-bayer-leverkusen-ficha-a-paulinho-la-nueva-joya-brasilena-de-17-anos\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-bayer-leverkusen-ficha-a-paulinho-la-nueva-joya-brasilena-de-17-anos\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-bayer-leverkusen-ficha-a-paulinho-la-nueva-joya-brasilena-de-17-anos\\\/\",\"name\":\"El Bayer Leverkusen ficha a Paulinho, la nueva joya brasile\\u00f1a de 17 a\\u00f1os | Cand\\u00e1s 365\",\"description\":\"Leverkusen (Alemania), 28 abr (dpa) - El Bayer Leverkusen anunci\\u00f3 el viernes el fichaje del delantero Paulinho, considerado a sus 17 a\\u00f1os como la nueva joya del f\\u00fatbol brasile\\u00f1o. Paulinho dejar\\u00e1 el Vasco da Gama para pasar a las filas del club germano el 15 de julio, cuando cumpla la mayor\\u00eda de edad, comunic\\u00f3 el\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-bayer-leverkusen-ficha-a-paulinho-la-nueva-joya-brasilena-de-17-anos\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/football-1406106_1280.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-bayer-leverkusen-ficha-a-paulinho-la-nueva-joya-brasilena-de-17-anos\\\/#mainImage\",\"width\":1280,\"height\":857,\"caption\":\"football\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-bayer-leverkusen-ficha-a-paulinho-la-nueva-joya-brasilena-de-17-anos\\\/#mainImage\"},\"datePublished\":\"2018-04-28T13:42:33+02:00\",\"dateModified\":\"2018-04-28T13:42:33+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>El Bayer Leverkusen ficha a Paulinho, la nueva joya brasile\u00f1a de 17 a\u00f1os | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"El Bayer Leverkusen ficha a Paulinho, la nueva joya brasile\u00f1a de 17 a\u00f1os | Cand\u00e1s 365","description":"Leverkusen (Alemania), 28 abr (dpa) - El Bayer Leverkusen anunci\u00f3 el viernes el fichaje del delantero Paulinho, considerado a sus 17 a\u00f1os como la nueva joya del f\u00fatbol brasile\u00f1o. Paulinho dejar\u00e1 el Vasco da Gama para pasar a las filas del club germano el 15 de julio, cuando cumpla la mayor\u00eda de edad, comunic\u00f3 el","canonical_url":"https:\/\/candas365.es\/noticias\/el-bayer-leverkusen-ficha-a-paulinho-la-nueva-joya-brasilena-de-17-anos\/","robots":"max-image-preview:large","keywords":"deporte","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/el-bayer-leverkusen-ficha-a-paulinho-la-nueva-joya-brasilena-de-17-anos\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/deporte\/#listItem","name":"Deporte"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/deporte\/#listItem","position":2,"name":"Deporte","item":"https:\/\/candas365.es\/noticias\/category\/deporte\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/el-bayer-leverkusen-ficha-a-paulinho-la-nueva-joya-brasilena-de-17-anos\/#listItem","name":"El Bayer Leverkusen ficha a Paulinho, la nueva joya brasile\u00f1a de 17 a\u00f1os"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/el-bayer-leverkusen-ficha-a-paulinho-la-nueva-joya-brasilena-de-17-anos\/#listItem","position":3,"name":"El Bayer Leverkusen ficha a Paulinho, la nueva joya brasile\u00f1a de 17 a\u00f1os","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/deporte\/#listItem","name":"Deporte"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/el-bayer-leverkusen-ficha-a-paulinho-la-nueva-joya-brasilena-de-17-anos\/#newsarticle","name":"El Bayer Leverkusen ficha a Paulinho, la nueva joya brasile\u00f1a de 17 a\u00f1os | Cand\u00e1s 365","headline":"El Bayer Leverkusen ficha a Paulinho, la nueva joya brasile\u00f1a de 17 a\u00f1os","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280.jpg","width":1280,"height":857,"caption":"football"},"datePublished":"2018-04-28T13:42:33+02:00","dateModified":"2018-04-28T13:42:33+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/el-bayer-leverkusen-ficha-a-paulinho-la-nueva-joya-brasilena-de-17-anos\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/el-bayer-leverkusen-ficha-a-paulinho-la-nueva-joya-brasilena-de-17-anos\/#webpage"},"articleSection":"Deporte","dateline":"Publicado el abril 28, 2018."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/el-bayer-leverkusen-ficha-a-paulinho-la-nueva-joya-brasilena-de-17-anos\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/el-bayer-leverkusen-ficha-a-paulinho-la-nueva-joya-brasilena-de-17-anos\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/el-bayer-leverkusen-ficha-a-paulinho-la-nueva-joya-brasilena-de-17-anos\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/el-bayer-leverkusen-ficha-a-paulinho-la-nueva-joya-brasilena-de-17-anos\/#webpage","url":"https:\/\/candas365.es\/noticias\/el-bayer-leverkusen-ficha-a-paulinho-la-nueva-joya-brasilena-de-17-anos\/","name":"El Bayer Leverkusen ficha a Paulinho, la nueva joya brasile\u00f1a de 17 a\u00f1os | Cand\u00e1s 365","description":"Leverkusen (Alemania), 28 abr (dpa) - El Bayer Leverkusen anunci\u00f3 el viernes el fichaje del delantero Paulinho, considerado a sus 17 a\u00f1os como la nueva joya del f\u00fatbol brasile\u00f1o. Paulinho dejar\u00e1 el Vasco da Gama para pasar a las filas del club germano el 15 de julio, cuando cumpla la mayor\u00eda de edad, comunic\u00f3 el","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/el-bayer-leverkusen-ficha-a-paulinho-la-nueva-joya-brasilena-de-17-anos\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280.jpg","@id":"https:\/\/candas365.es\/noticias\/el-bayer-leverkusen-ficha-a-paulinho-la-nueva-joya-brasilena-de-17-anos\/#mainImage","width":1280,"height":857,"caption":"football"},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/el-bayer-leverkusen-ficha-a-paulinho-la-nueva-joya-brasilena-de-17-anos\/#mainImage"},"datePublished":"2018-04-28T13:42:33+02:00","dateModified":"2018-04-28T13:42:33+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"El Bayer Leverkusen ficha a Paulinho, la nueva joya brasile\u00f1a de 17 a\u00f1os | Cand\u00e1s 365","og:description":"Leverkusen (Alemania), 28 abr (dpa) - El Bayer Leverkusen anunci\u00f3 el viernes el fichaje del delantero Paulinho, considerado a sus 17 a\u00f1os como la nueva joya del f\u00fatbol brasile\u00f1o. Paulinho dejar\u00e1 el Vasco da Gama para pasar a las filas del club germano el 15 de julio, cuando cumpla la mayor\u00eda de edad, comunic\u00f3 el","og:url":"https:\/\/candas365.es\/noticias\/el-bayer-leverkusen-ficha-a-paulinho-la-nueva-joya-brasilena-de-17-anos\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280.jpg","og:image:width":1280,"og:image:height":857,"article:published_time":"2018-04-28T13:42:33+00:00","article:modified_time":"2018-04-28T13:42:33+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"El Bayer Leverkusen ficha a Paulinho, la nueva joya brasile\u00f1a de 17 a\u00f1os | Cand\u00e1s 365","twitter:description":"Leverkusen (Alemania), 28 abr (dpa) - El Bayer Leverkusen anunci\u00f3 el viernes el fichaje del delantero Paulinho, considerado a sus 17 a\u00f1os como la nueva joya del f\u00fatbol brasile\u00f1o. Paulinho dejar\u00e1 el Vasco da Gama para pasar a las filas del club germano el 15 de julio, cuando cumpla la mayor\u00eda de edad, comunic\u00f3 el","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"94831","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-26 19:39:09","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 11:52:48","updated":"2025-08-26 19:39:09"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/deporte\/\" title=\"Deporte\">Deporte<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tEl Bayer Leverkusen ficha a Paulinho, la nueva joya brasile\u00f1a de 17 a\u00f1os\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Deporte","link":"https:\/\/candas365.es\/noticias\/category\/deporte\/"},{"label":"El Bayer Leverkusen ficha a Paulinho, la nueva joya brasile\u00f1a de 17 a\u00f1os","link":"https:\/\/candas365.es\/noticias\/el-bayer-leverkusen-ficha-a-paulinho-la-nueva-joya-brasilena-de-17-anos\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/94831","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=94831"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/94831\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/89552"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=94831"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=94831"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=94831"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}