{"id":94555,"date":"2018-04-24T20:51:10","date_gmt":"2018-04-24T20:51:10","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=94555"},"modified":"2018-04-24T20:51:10","modified_gmt":"2018-04-24T20:51:10","slug":"la-ultraderecha-alemana-pide-la-reforma-del-delito-de-odio","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/la-ultraderecha-alemana-pide-la-reforma-del-delito-de-odio\/","title":{"rendered":"La ultraderecha alemana pide la reforma del delito de odio"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-85069\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720-360x240.jpg\" alt=\"\" width=\"360\" height=\"240\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720-360x240.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720-768x512.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720-655x437.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720-696x464.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720-630x420.jpg 630w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720-84x55.jpg 84w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720.jpg 960w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Berl\u00edn, 24 abr (dpa) &#8211; La fracci\u00f3n parlamentaria del partido ultraderechista Alternativa para Alemania (AfD) pidi\u00f3 hoy un cambio en el delito de \u00abincitaci\u00f3n al odio y la xenofobia\u00bb recogido en el c\u00f3digo penal alem\u00e1n.<\/p>\n<p>La formaci\u00f3n de tintes xen\u00f3fobos, que obtuvo el 12,6% en las \u00faltimas elecciones federales alemanas y es la tercera fuerza m\u00e1s importante del Bundestag (c\u00e1mara baja del Parlamento alem\u00e1n), pretende que \u00abel pueblo alem\u00e1n\u00bb en su conjunto tambi\u00e9n pueda ser v\u00edctima de un delito de \u00abincitaci\u00f3n al odio y la xenofobia\u00bb.<\/p>\n<p>Hasta ahora, este delito ha sido aplicado a declaraciones dirigidas contra individuos, grupos o minor\u00edas de la sociedad alemana, como destac\u00f3 Jens Maier, parlamentario de AfD. Maier present\u00f3 este martes el correspondiente proyecto de ley sobre el que tendr\u00e1 que debatir esta semana el Bundestag.<\/p>\n<p>La conformaci\u00f3n de la tercera Gran Coalici\u00f3n (conservadores y socialdem\u00f3cratas) de la era Merkel entreg\u00f3 a AfD el liderazgo de la oposici\u00f3n parlamentaria. Ello le permite presidir relevantes comisiones y el derecho a ser la primera fracci\u00f3n en responder a discursos de miembros del Ejecutivo o de la misma canciller.<\/p>\n<p>AfD, cuya fundaci\u00f3n se remonta al a\u00f1o 2013, evolucion\u00f3 de sus primeras posiciones euroesc\u00e9pticas hasta su actual dial\u00e9ctica xen\u00f3foba, islam\u00f3foba y ultranacionalista. Pese a las salidas de tono de sus l\u00edderes, el joven partido ultraderechista se mantiene estable como tercera fuerza en las encuestas de intenci\u00f3n de voto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Berl\u00edn, 24 abr (dpa) &#8211; La fracci\u00f3n parlamentaria del partido ultraderechista Alternativa para Alemania (AfD) pidi\u00f3 hoy un cambio en el delito de \u00abincitaci\u00f3n al odio y la xenofobia\u00bb recogido en el c\u00f3digo penal alem\u00e1n. La formaci\u00f3n de tintes xen\u00f3fobos, que obtuvo el 12,6% en las \u00faltimas elecciones federales alemanas y es la tercera fuerza<\/p>\n","protected":false},"author":1,"featured_media":85069,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343],"tags":[],"class_list":{"0":"post-94555","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-actualidad"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7 - aioseo.com -->\n\t<meta name=\"description\" content=\"Berl\u00edn, 24 abr (dpa) - La fracci\u00f3n parlamentaria del partido ultraderechista Alternativa para Alemania (AfD) pidi\u00f3 hoy un cambio en el delito de &quot;incitaci\u00f3n al odio y la xenofobia&quot; recogido en el c\u00f3digo penal alem\u00e1n. La formaci\u00f3n de tintes xen\u00f3fobos, que obtuvo el 12,6% en las \u00faltimas elecciones federales alemanas y es la tercera fuerza\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/la-ultraderecha-alemana-pide-la-reforma-del-delito-de-odio\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"La ultraderecha alemana pide la reforma del delito de odio | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Berl\u00edn, 24 abr (dpa) - La fracci\u00f3n parlamentaria del partido ultraderechista Alternativa para Alemania (AfD) pidi\u00f3 hoy un cambio en el delito de &quot;incitaci\u00f3n al odio y la xenofobia&quot; recogido en el c\u00f3digo penal alem\u00e1n. La formaci\u00f3n de tintes xen\u00f3fobos, que obtuvo el 12,6% en las \u00faltimas elecciones federales alemanas y es la tercera fuerza\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/la-ultraderecha-alemana-pide-la-reforma-del-delito-de-odio\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-04-24T20:51:10+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-04-24T20:51:10+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"La ultraderecha alemana pide la reforma del delito de odio | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Berl\u00edn, 24 abr (dpa) - La fracci\u00f3n parlamentaria del partido ultraderechista Alternativa para Alemania (AfD) pidi\u00f3 hoy un cambio en el delito de &quot;incitaci\u00f3n al odio y la xenofobia&quot; recogido en el c\u00f3digo penal alem\u00e1n. La formaci\u00f3n de tintes xen\u00f3fobos, que obtuvo el 12,6% en las \u00faltimas elecciones federales alemanas y es la tercera fuerza\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-ultraderecha-alemana-pide-la-reforma-del-delito-de-odio\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-ultraderecha-alemana-pide-la-reforma-del-delito-de-odio\\\/#listItem\",\"name\":\"La ultraderecha alemana pide la reforma del delito de odio\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-ultraderecha-alemana-pide-la-reforma-del-delito-de-odio\\\/#listItem\",\"position\":3,\"name\":\"La ultraderecha alemana pide la reforma del delito de odio\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-ultraderecha-alemana-pide-la-reforma-del-delito-de-odio\\\/#newsarticle\",\"name\":\"La ultraderecha alemana pide la reforma del delito de odio | Cand\\u00e1s 365\",\"headline\":\"La ultraderecha alemana pide la reforma del delito de odio\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/bundestag-2463231_960_720.jpg\",\"width\":960,\"height\":640,\"caption\":\"bundestag\"},\"datePublished\":\"2018-04-24T20:51:10+02:00\",\"dateModified\":\"2018-04-24T20:51:10+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-ultraderecha-alemana-pide-la-reforma-del-delito-de-odio\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-ultraderecha-alemana-pide-la-reforma-del-delito-de-odio\\\/#webpage\"},\"articleSection\":\"Actualidad\",\"dateline\":\"Publicado el abril 24, 2018.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-ultraderecha-alemana-pide-la-reforma-del-delito-de-odio\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-ultraderecha-alemana-pide-la-reforma-del-delito-de-odio\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-ultraderecha-alemana-pide-la-reforma-del-delito-de-odio\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-ultraderecha-alemana-pide-la-reforma-del-delito-de-odio\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-ultraderecha-alemana-pide-la-reforma-del-delito-de-odio\\\/\",\"name\":\"La ultraderecha alemana pide la reforma del delito de odio | Cand\\u00e1s 365\",\"description\":\"Berl\\u00edn, 24 abr (dpa) - La fracci\\u00f3n parlamentaria del partido ultraderechista Alternativa para Alemania (AfD) pidi\\u00f3 hoy un cambio en el delito de \\\"incitaci\\u00f3n al odio y la xenofobia\\\" recogido en el c\\u00f3digo penal alem\\u00e1n. La formaci\\u00f3n de tintes xen\\u00f3fobos, que obtuvo el 12,6% en las \\u00faltimas elecciones federales alemanas y es la tercera fuerza\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-ultraderecha-alemana-pide-la-reforma-del-delito-de-odio\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/bundestag-2463231_960_720.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-ultraderecha-alemana-pide-la-reforma-del-delito-de-odio\\\/#mainImage\",\"width\":960,\"height\":640,\"caption\":\"bundestag\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-ultraderecha-alemana-pide-la-reforma-del-delito-de-odio\\\/#mainImage\"},\"datePublished\":\"2018-04-24T20:51:10+02:00\",\"dateModified\":\"2018-04-24T20:51:10+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>La ultraderecha alemana pide la reforma del delito de odio | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"La ultraderecha alemana pide la reforma del delito de odio | Cand\u00e1s 365","description":"Berl\u00edn, 24 abr (dpa) - La fracci\u00f3n parlamentaria del partido ultraderechista Alternativa para Alemania (AfD) pidi\u00f3 hoy un cambio en el delito de \"incitaci\u00f3n al odio y la xenofobia\" recogido en el c\u00f3digo penal alem\u00e1n. La formaci\u00f3n de tintes xen\u00f3fobos, que obtuvo el 12,6% en las \u00faltimas elecciones federales alemanas y es la tercera fuerza","canonical_url":"https:\/\/candas365.es\/noticias\/la-ultraderecha-alemana-pide-la-reforma-del-delito-de-odio\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/la-ultraderecha-alemana-pide-la-reforma-del-delito-de-odio\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/candas365.es\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/la-ultraderecha-alemana-pide-la-reforma-del-delito-de-odio\/#listItem","name":"La ultraderecha alemana pide la reforma del delito de odio"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/la-ultraderecha-alemana-pide-la-reforma-del-delito-de-odio\/#listItem","position":3,"name":"La ultraderecha alemana pide la reforma del delito de odio","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/la-ultraderecha-alemana-pide-la-reforma-del-delito-de-odio\/#newsarticle","name":"La ultraderecha alemana pide la reforma del delito de odio | Cand\u00e1s 365","headline":"La ultraderecha alemana pide la reforma del delito de odio","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720.jpg","width":960,"height":640,"caption":"bundestag"},"datePublished":"2018-04-24T20:51:10+02:00","dateModified":"2018-04-24T20:51:10+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/la-ultraderecha-alemana-pide-la-reforma-del-delito-de-odio\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/la-ultraderecha-alemana-pide-la-reforma-del-delito-de-odio\/#webpage"},"articleSection":"Actualidad","dateline":"Publicado el abril 24, 2018."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/la-ultraderecha-alemana-pide-la-reforma-del-delito-de-odio\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/la-ultraderecha-alemana-pide-la-reforma-del-delito-de-odio\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/la-ultraderecha-alemana-pide-la-reforma-del-delito-de-odio\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/la-ultraderecha-alemana-pide-la-reforma-del-delito-de-odio\/#webpage","url":"https:\/\/candas365.es\/noticias\/la-ultraderecha-alemana-pide-la-reforma-del-delito-de-odio\/","name":"La ultraderecha alemana pide la reforma del delito de odio | Cand\u00e1s 365","description":"Berl\u00edn, 24 abr (dpa) - La fracci\u00f3n parlamentaria del partido ultraderechista Alternativa para Alemania (AfD) pidi\u00f3 hoy un cambio en el delito de \"incitaci\u00f3n al odio y la xenofobia\" recogido en el c\u00f3digo penal alem\u00e1n. La formaci\u00f3n de tintes xen\u00f3fobos, que obtuvo el 12,6% en las \u00faltimas elecciones federales alemanas y es la tercera fuerza","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/la-ultraderecha-alemana-pide-la-reforma-del-delito-de-odio\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720.jpg","@id":"https:\/\/candas365.es\/noticias\/la-ultraderecha-alemana-pide-la-reforma-del-delito-de-odio\/#mainImage","width":960,"height":640,"caption":"bundestag"},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/la-ultraderecha-alemana-pide-la-reforma-del-delito-de-odio\/#mainImage"},"datePublished":"2018-04-24T20:51:10+02:00","dateModified":"2018-04-24T20:51:10+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"La ultraderecha alemana pide la reforma del delito de odio | Cand\u00e1s 365","og:description":"Berl\u00edn, 24 abr (dpa) - La fracci\u00f3n parlamentaria del partido ultraderechista Alternativa para Alemania (AfD) pidi\u00f3 hoy un cambio en el delito de &quot;incitaci\u00f3n al odio y la xenofobia&quot; recogido en el c\u00f3digo penal alem\u00e1n. La formaci\u00f3n de tintes xen\u00f3fobos, que obtuvo el 12,6% en las \u00faltimas elecciones federales alemanas y es la tercera fuerza","og:url":"https:\/\/candas365.es\/noticias\/la-ultraderecha-alemana-pide-la-reforma-del-delito-de-odio\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720.jpg","og:image:width":960,"og:image:height":640,"article:published_time":"2018-04-24T20:51:10+00:00","article:modified_time":"2018-04-24T20:51:10+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"La ultraderecha alemana pide la reforma del delito de odio | Cand\u00e1s 365","twitter:description":"Berl\u00edn, 24 abr (dpa) - La fracci\u00f3n parlamentaria del partido ultraderechista Alternativa para Alemania (AfD) pidi\u00f3 hoy un cambio en el delito de &quot;incitaci\u00f3n al odio y la xenofobia&quot; recogido en el c\u00f3digo penal alem\u00e1n. La formaci\u00f3n de tintes xen\u00f3fobos, que obtuvo el 12,6% en las \u00faltimas elecciones federales alemanas y es la tercera fuerza","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"1 minuto"},"aioseo_meta_data":{"post_id":"94555","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-26 19:17:14","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 11:53:01","updated":"2025-08-26 19:17:14"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tLa ultraderecha alemana pide la reforma del delito de odio\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Actualidad","link":"https:\/\/candas365.es\/noticias\/category\/actualidad\/"},{"label":"La ultraderecha alemana pide la reforma del delito de odio","link":"https:\/\/candas365.es\/noticias\/la-ultraderecha-alemana-pide-la-reforma-del-delito-de-odio\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/94555","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=94555"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/94555\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/85069"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=94555"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=94555"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=94555"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}