{"id":94459,"date":"2018-04-23T21:15:49","date_gmt":"2018-04-23T21:15:49","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=94459"},"modified":"2018-04-23T21:15:49","modified_gmt":"2018-04-23T21:15:49","slug":"alemania-condena-la-violencia-en-nicaragua","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/alemania-condena-la-violencia-en-nicaragua\/","title":{"rendered":"Alemania condena la violencia en Nicaragua"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-85069\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720-360x240.jpg\" alt=\"\" width=\"360\" height=\"240\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720-360x240.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720-768x512.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720-655x437.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720-696x464.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720-630x420.jpg 630w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720-84x55.jpg 84w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720.jpg 960w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Berl\u00edn, 23 abr (dpa) &#8211; Alemania conden\u00f3 hoy el uso de armas en las protestas que se sucedieron en los \u00faltimos d\u00edas en Nicaragua por el anuncio de una controvertida reforma del seguro social y del sistema de jubilaciones, que se han saldado con por lo menos diez muertos.<\/p>\n<p>\u00abLlamamos a todas las facciones a renunciar de inmediato al uso de la fuerza\u00bb, se\u00f1ala un comunicado emitido en Berl\u00edn.<\/p>\n<p>\u00abEsperamos que el Gobierno de Nicaragua esclarezca sin demora y de forma cabal los casos de v\u00edctimas fatales\u00bb, reza el comunicado del Ejecutivo de la canciller Angela Merkel.<\/p>\n<p>\u00abLas restricciones a la libertad de prensa por parte del Gobierno son inaceptables\u00bb, sostiene Berl\u00edn, que demanda que \u00aba la brevedad\u00bb se garantice el restablecimiento de \u00abuna cobertura period\u00edstica libre\u00bb.<\/p>\n<p>\u00abLa retirada de las controvertidas reformas del sistema de seguro social por parte del Gobierno puede ser un primer paso en direcci\u00f3n al di\u00e1logo nacional. En \u00e9l deben poder participar todas las fuerzas sociales\u00bb.<\/p>\n<p>Las protestas de los \u00faltimos d\u00edas en Nicaragua fueron reprimidas con violencia por grupos de choque oficialistas y polic\u00edas antimotines, con un saldo de diez muertos seg\u00fan el Gobierno y m\u00e1s de 30 fallecidos seg\u00fan medios de prensa de Managua.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Berl\u00edn, 23 abr (dpa) &#8211; Alemania conden\u00f3 hoy el uso de armas en las protestas que se sucedieron en los \u00faltimos d\u00edas en Nicaragua por el anuncio de una controvertida reforma del seguro social y del sistema de jubilaciones, que se han saldado con por lo menos diez muertos. \u00abLlamamos a todas las facciones a<\/p>\n","protected":false},"author":1,"featured_media":85069,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343],"tags":[],"class_list":{"0":"post-94459","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-actualidad"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Berl\u00edn, 23 abr (dpa) - Alemania conden\u00f3 hoy el uso de armas en las protestas que se sucedieron en los \u00faltimos d\u00edas en Nicaragua por el anuncio de una controvertida reforma del seguro social y del sistema de jubilaciones, que se han saldado con por lo menos diez muertos. &quot;Llamamos a todas las facciones a\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/alemania-condena-la-violencia-en-nicaragua\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Alemania condena la violencia en Nicaragua | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Berl\u00edn, 23 abr (dpa) - Alemania conden\u00f3 hoy el uso de armas en las protestas que se sucedieron en los \u00faltimos d\u00edas en Nicaragua por el anuncio de una controvertida reforma del seguro social y del sistema de jubilaciones, que se han saldado con por lo menos diez muertos. &quot;Llamamos a todas las facciones a\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/alemania-condena-la-violencia-en-nicaragua\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-04-23T21:15:49+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-04-23T21:15:49+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Alemania condena la violencia en Nicaragua | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Berl\u00edn, 23 abr (dpa) - Alemania conden\u00f3 hoy el uso de armas en las protestas que se sucedieron en los \u00faltimos d\u00edas en Nicaragua por el anuncio de una controvertida reforma del seguro social y del sistema de jubilaciones, que se han saldado con por lo menos diez muertos. &quot;Llamamos a todas las facciones a\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/alemania-condena-la-violencia-en-nicaragua\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/alemania-condena-la-violencia-en-nicaragua\\\/#listItem\",\"name\":\"Alemania condena la violencia en Nicaragua\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/alemania-condena-la-violencia-en-nicaragua\\\/#listItem\",\"position\":3,\"name\":\"Alemania condena la violencia en Nicaragua\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/alemania-condena-la-violencia-en-nicaragua\\\/#newsarticle\",\"name\":\"Alemania condena la violencia en Nicaragua | Cand\\u00e1s 365\",\"headline\":\"Alemania condena la violencia en Nicaragua\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/bundestag-2463231_960_720.jpg\",\"width\":960,\"height\":640,\"caption\":\"bundestag\"},\"datePublished\":\"2018-04-23T21:15:49+02:00\",\"dateModified\":\"2018-04-23T21:15:49+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/alemania-condena-la-violencia-en-nicaragua\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/alemania-condena-la-violencia-en-nicaragua\\\/#webpage\"},\"articleSection\":\"Actualidad\",\"dateline\":\"Publicado el abril 23, 2018.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/alemania-condena-la-violencia-en-nicaragua\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/alemania-condena-la-violencia-en-nicaragua\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/alemania-condena-la-violencia-en-nicaragua\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/alemania-condena-la-violencia-en-nicaragua\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/alemania-condena-la-violencia-en-nicaragua\\\/\",\"name\":\"Alemania condena la violencia en Nicaragua | Cand\\u00e1s 365\",\"description\":\"Berl\\u00edn, 23 abr (dpa) - Alemania conden\\u00f3 hoy el uso de armas en las protestas que se sucedieron en los \\u00faltimos d\\u00edas en Nicaragua por el anuncio de una controvertida reforma del seguro social y del sistema de jubilaciones, que se han saldado con por lo menos diez muertos. \\\"Llamamos a todas las facciones a\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/alemania-condena-la-violencia-en-nicaragua\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/bundestag-2463231_960_720.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/alemania-condena-la-violencia-en-nicaragua\\\/#mainImage\",\"width\":960,\"height\":640,\"caption\":\"bundestag\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/alemania-condena-la-violencia-en-nicaragua\\\/#mainImage\"},\"datePublished\":\"2018-04-23T21:15:49+02:00\",\"dateModified\":\"2018-04-23T21:15:49+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Alemania condena la violencia en Nicaragua | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Alemania condena la violencia en Nicaragua | Cand\u00e1s 365","description":"Berl\u00edn, 23 abr (dpa) - Alemania conden\u00f3 hoy el uso de armas en las protestas que se sucedieron en los \u00faltimos d\u00edas en Nicaragua por el anuncio de una controvertida reforma del seguro social y del sistema de jubilaciones, que se han saldado con por lo menos diez muertos. \"Llamamos a todas las facciones a","canonical_url":"https:\/\/candas365.es\/noticias\/alemania-condena-la-violencia-en-nicaragua\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/alemania-condena-la-violencia-en-nicaragua\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/candas365.es\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/alemania-condena-la-violencia-en-nicaragua\/#listItem","name":"Alemania condena la violencia en Nicaragua"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/alemania-condena-la-violencia-en-nicaragua\/#listItem","position":3,"name":"Alemania condena la violencia en Nicaragua","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/alemania-condena-la-violencia-en-nicaragua\/#newsarticle","name":"Alemania condena la violencia en Nicaragua | Cand\u00e1s 365","headline":"Alemania condena la violencia en Nicaragua","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720.jpg","width":960,"height":640,"caption":"bundestag"},"datePublished":"2018-04-23T21:15:49+02:00","dateModified":"2018-04-23T21:15:49+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/alemania-condena-la-violencia-en-nicaragua\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/alemania-condena-la-violencia-en-nicaragua\/#webpage"},"articleSection":"Actualidad","dateline":"Publicado el abril 23, 2018."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/alemania-condena-la-violencia-en-nicaragua\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/alemania-condena-la-violencia-en-nicaragua\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/alemania-condena-la-violencia-en-nicaragua\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/alemania-condena-la-violencia-en-nicaragua\/#webpage","url":"https:\/\/candas365.es\/noticias\/alemania-condena-la-violencia-en-nicaragua\/","name":"Alemania condena la violencia en Nicaragua | Cand\u00e1s 365","description":"Berl\u00edn, 23 abr (dpa) - Alemania conden\u00f3 hoy el uso de armas en las protestas que se sucedieron en los \u00faltimos d\u00edas en Nicaragua por el anuncio de una controvertida reforma del seguro social y del sistema de jubilaciones, que se han saldado con por lo menos diez muertos. \"Llamamos a todas las facciones a","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/alemania-condena-la-violencia-en-nicaragua\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720.jpg","@id":"https:\/\/candas365.es\/noticias\/alemania-condena-la-violencia-en-nicaragua\/#mainImage","width":960,"height":640,"caption":"bundestag"},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/alemania-condena-la-violencia-en-nicaragua\/#mainImage"},"datePublished":"2018-04-23T21:15:49+02:00","dateModified":"2018-04-23T21:15:49+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Alemania condena la violencia en Nicaragua | Cand\u00e1s 365","og:description":"Berl\u00edn, 23 abr (dpa) - Alemania conden\u00f3 hoy el uso de armas en las protestas que se sucedieron en los \u00faltimos d\u00edas en Nicaragua por el anuncio de una controvertida reforma del seguro social y del sistema de jubilaciones, que se han saldado con por lo menos diez muertos. &quot;Llamamos a todas las facciones a","og:url":"https:\/\/candas365.es\/noticias\/alemania-condena-la-violencia-en-nicaragua\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720.jpg","og:image:width":960,"og:image:height":640,"article:published_time":"2018-04-23T21:15:49+00:00","article:modified_time":"2018-04-23T21:15:49+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Alemania condena la violencia en Nicaragua | Cand\u00e1s 365","twitter:description":"Berl\u00edn, 23 abr (dpa) - Alemania conden\u00f3 hoy el uso de armas en las protestas que se sucedieron en los \u00faltimos d\u00edas en Nicaragua por el anuncio de una controvertida reforma del seguro social y del sistema de jubilaciones, que se han saldado con por lo menos diez muertos. &quot;Llamamos a todas las facciones a","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"1 minuto"},"aioseo_meta_data":{"post_id":"94459","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-26 19:09:13","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 11:53:07","updated":"2025-08-26 19:09:13"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tAlemania condena la violencia en Nicaragua\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Actualidad","link":"https:\/\/candas365.es\/noticias\/category\/actualidad\/"},{"label":"Alemania condena la violencia en Nicaragua","link":"https:\/\/candas365.es\/noticias\/alemania-condena-la-violencia-en-nicaragua\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/94459","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=94459"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/94459\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/85069"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=94459"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=94459"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=94459"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}