{"id":93940,"date":"2018-04-16T22:45:50","date_gmt":"2018-04-16T22:45:50","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=93940"},"modified":"2018-04-16T22:45:50","modified_gmt":"2018-04-16T22:45:50","slug":"arturo-vidal-debera-someterse-a-una-pequena-operacion-de-rodilla","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/arturo-vidal-debera-someterse-a-una-pequena-operacion-de-rodilla\/","title":{"rendered":"Arturo Vidal deber\u00e1 someterse a una peque\u00f1a operaci\u00f3n de rodilla"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-91549\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/football-2697618_1280-360x270.jpg\" alt=\"\" width=\"360\" height=\"270\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/football-2697618_1280-360x270.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/football-2697618_1280-80x60.jpg 80w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/football-2697618_1280-265x198.jpg 265w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/football-2697618_1280-696x522.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/football-2697618_1280-1068x801.jpg 1068w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/football-2697618_1280-560x420.jpg 560w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/football-2697618_1280-768x576.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/football-2697618_1280-640x480.jpg 640w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/football-2697618_1280-90x67.jpg 90w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/football-2697618_1280.jpg 1280w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>M\u00fanich, 16 abr (dpa) &#8211; El futbolista chileno Arturo Vidal deber\u00e1 someterse a una peque\u00f1a operaci\u00f3n de rodilla justo cuando el Bayern M\u00fanich est\u00e1 a un pu\u00f1ado de partidos del triplete, anunci\u00f3 hoy el club alem\u00e1n.<\/p>\n<p>\u00abHe hablado por tel\u00e9fono con el doctor M\u00fcller-Wohlfahrt (el m\u00e9dico del Bayern). Se le realiz\u00f3 una resonancia magn\u00e9tica y Arturo tiene un cuerpo libre articular en la rodilla, lo que le impide estirarla\u00bb, declar\u00f3 el entrenador del club alem\u00e1n, Jupp Heynckes, en una rueda de prensa en M\u00fanich.<\/p>\n<p>\u00abEst\u00e1 camino de Augsburgo (para ponerse en manos del doctor Ulrich Boenisch). Debe ser sometido a una peque\u00f1a intervenci\u00f3n artrosc\u00f3pica. Y seguramente causar\u00e1 baja en el corto plazo\u00bb, agreg\u00f3 el veterano entrenador.<\/p>\n<p>La lesi\u00f3n de Vidal, que consiste en el desprendimiento de un fragmento de cart\u00edlago en la articulaci\u00f3n, frena los planes de reincorporaci\u00f3n inmediata del chileno y deja abierta su posible participaci\u00f3n en las semifinales de la Liga de Campeones europea ante el Real Madrid. La ida se jugar\u00e1 el 25 de abril en M\u00fanich y la serie se definir\u00e1 una semana despu\u00e9s en la capital espa\u00f1ola.<\/p>\n<p>Lo que est\u00e1 claro es que Vidal se perder\u00e1 ma\u00f1ana las semifinales de la Copa alemana ante el Bayer Leverkusen. Los b\u00e1varos son el \u00fanico equipo de Europa que tiene posibilidades todav\u00eda de conseguir el triplete: con la Bundesliga ya en el bolsillo, est\u00e1n a a cinco partidos de repetir la gesta de 2013.<\/p>\n<p>Heynckes evit\u00f3 pronosticar una fecha de regreso a la rutina del chileno. \u00abEs un luchador nato, tiene una gran ambici\u00f3n y har\u00e1 todo lo posible para poder estar de nuevo a punto\u00bb, se limit\u00f3 a decir el estratega.<\/p>\n<p>Vidal, que se estaba recuperando de la lesi\u00f3n de rodilla que sufri\u00f3 el 3 de abril en la ida de los cuartos de la Champions ante el Sevilla, tuvo que abandonar este domingo los entrenamientos con fuertes molestias.<\/p>\n<p>El jugador cay\u00f3 tendido al c\u00e9sped tras dar una gran zancada para atrapar el bal\u00f3n y sufrir una fuerte torcedura en la rodilla derecha.<\/p>\n<p>Con notables dificultades para caminar, el internacional fue llevado en volandas por su compa\u00f1ero Franck Rib\u00e9ry y por el fisioterapeuta del Bayern Gianni Bianchi hasta un carrito de golf.<\/p>\n<p>Posteriormente, fue trasladado en camilla a bordo del veh\u00edculo presumiblemente a la enfermer\u00eda del centro de entrenamiento del Bayern en la S\u00e4bener Strasse.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00fanich, 16 abr (dpa) &#8211; El futbolista chileno Arturo Vidal deber\u00e1 someterse a una peque\u00f1a operaci\u00f3n de rodilla justo cuando el Bayern M\u00fanich est\u00e1 a un pu\u00f1ado de partidos del triplete, anunci\u00f3 hoy el club alem\u00e1n. \u00abHe hablado por tel\u00e9fono con el doctor M\u00fcller-Wohlfahrt (el m\u00e9dico del Bayern). Se le realiz\u00f3 una resonancia magn\u00e9tica y<\/p>\n","protected":false},"author":1,"featured_media":91549,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[319],"tags":[],"class_list":{"0":"post-93940","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-deporte"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7 - aioseo.com -->\n\t<meta name=\"description\" content=\"M\u00fanich, 16 abr (dpa) - El futbolista chileno Arturo Vidal deber\u00e1 someterse a una peque\u00f1a operaci\u00f3n de rodilla justo cuando el Bayern M\u00fanich est\u00e1 a un pu\u00f1ado de partidos del triplete, anunci\u00f3 hoy el club alem\u00e1n. &quot;He hablado por tel\u00e9fono con el doctor M\u00fcller-Wohlfahrt (el m\u00e9dico del Bayern). Se le realiz\u00f3 una resonancia magn\u00e9tica y\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"deporte\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/arturo-vidal-debera-someterse-a-una-pequena-operacion-de-rodilla\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Arturo Vidal deber\u00e1 someterse a una peque\u00f1a operaci\u00f3n de rodilla | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"M\u00fanich, 16 abr (dpa) - El futbolista chileno Arturo Vidal deber\u00e1 someterse a una peque\u00f1a operaci\u00f3n de rodilla justo cuando el Bayern M\u00fanich est\u00e1 a un pu\u00f1ado de partidos del triplete, anunci\u00f3 hoy el club alem\u00e1n. &quot;He hablado por tel\u00e9fono con el doctor M\u00fcller-Wohlfahrt (el m\u00e9dico del Bayern). Se le realiz\u00f3 una resonancia magn\u00e9tica y\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/arturo-vidal-debera-someterse-a-una-pequena-operacion-de-rodilla\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/football-2697618_1280.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/football-2697618_1280.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-04-16T22:45:50+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-04-16T22:45:50+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Arturo Vidal deber\u00e1 someterse a una peque\u00f1a operaci\u00f3n de rodilla | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"M\u00fanich, 16 abr (dpa) - El futbolista chileno Arturo Vidal deber\u00e1 someterse a una peque\u00f1a operaci\u00f3n de rodilla justo cuando el Bayern M\u00fanich est\u00e1 a un pu\u00f1ado de partidos del triplete, anunci\u00f3 hoy el club alem\u00e1n. &quot;He hablado por tel\u00e9fono con el doctor M\u00fcller-Wohlfahrt (el m\u00e9dico del Bayern). Se le realiz\u00f3 una resonancia magn\u00e9tica y\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/football-2697618_1280.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/arturo-vidal-debera-someterse-a-una-pequena-operacion-de-rodilla\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/#listItem\",\"name\":\"Deporte\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/#listItem\",\"position\":2,\"name\":\"Deporte\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/arturo-vidal-debera-someterse-a-una-pequena-operacion-de-rodilla\\\/#listItem\",\"name\":\"Arturo Vidal deber\\u00e1 someterse a una peque\\u00f1a operaci\\u00f3n de rodilla\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/arturo-vidal-debera-someterse-a-una-pequena-operacion-de-rodilla\\\/#listItem\",\"position\":3,\"name\":\"Arturo Vidal deber\\u00e1 someterse a una peque\\u00f1a operaci\\u00f3n de rodilla\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/#listItem\",\"name\":\"Deporte\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/arturo-vidal-debera-someterse-a-una-pequena-operacion-de-rodilla\\\/#newsarticle\",\"name\":\"Arturo Vidal deber\\u00e1 someterse a una peque\\u00f1a operaci\\u00f3n de rodilla | Cand\\u00e1s 365\",\"headline\":\"Arturo Vidal deber\\u00e1 someterse a una peque\\u00f1a operaci\\u00f3n de rodilla\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/football-2697618_1280.jpg\",\"width\":1280,\"height\":960},\"datePublished\":\"2018-04-16T22:45:50+02:00\",\"dateModified\":\"2018-04-16T22:45:50+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/arturo-vidal-debera-someterse-a-una-pequena-operacion-de-rodilla\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/arturo-vidal-debera-someterse-a-una-pequena-operacion-de-rodilla\\\/#webpage\"},\"articleSection\":\"Deporte\",\"dateline\":\"Publicado el abril 16, 2018.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/arturo-vidal-debera-someterse-a-una-pequena-operacion-de-rodilla\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/arturo-vidal-debera-someterse-a-una-pequena-operacion-de-rodilla\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/arturo-vidal-debera-someterse-a-una-pequena-operacion-de-rodilla\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/arturo-vidal-debera-someterse-a-una-pequena-operacion-de-rodilla\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/arturo-vidal-debera-someterse-a-una-pequena-operacion-de-rodilla\\\/\",\"name\":\"Arturo Vidal deber\\u00e1 someterse a una peque\\u00f1a operaci\\u00f3n de rodilla | Cand\\u00e1s 365\",\"description\":\"M\\u00fanich, 16 abr (dpa) - El futbolista chileno Arturo Vidal deber\\u00e1 someterse a una peque\\u00f1a operaci\\u00f3n de rodilla justo cuando el Bayern M\\u00fanich est\\u00e1 a un pu\\u00f1ado de partidos del triplete, anunci\\u00f3 hoy el club alem\\u00e1n. \\\"He hablado por tel\\u00e9fono con el doctor M\\u00fcller-Wohlfahrt (el m\\u00e9dico del Bayern). Se le realiz\\u00f3 una resonancia magn\\u00e9tica y\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/arturo-vidal-debera-someterse-a-una-pequena-operacion-de-rodilla\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/football-2697618_1280.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/arturo-vidal-debera-someterse-a-una-pequena-operacion-de-rodilla\\\/#mainImage\",\"width\":1280,\"height\":960},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/arturo-vidal-debera-someterse-a-una-pequena-operacion-de-rodilla\\\/#mainImage\"},\"datePublished\":\"2018-04-16T22:45:50+02:00\",\"dateModified\":\"2018-04-16T22:45:50+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Arturo Vidal deber\u00e1 someterse a una peque\u00f1a operaci\u00f3n de rodilla | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Arturo Vidal deber\u00e1 someterse a una peque\u00f1a operaci\u00f3n de rodilla | Cand\u00e1s 365","description":"M\u00fanich, 16 abr (dpa) - El futbolista chileno Arturo Vidal deber\u00e1 someterse a una peque\u00f1a operaci\u00f3n de rodilla justo cuando el Bayern M\u00fanich est\u00e1 a un pu\u00f1ado de partidos del triplete, anunci\u00f3 hoy el club alem\u00e1n. \"He hablado por tel\u00e9fono con el doctor M\u00fcller-Wohlfahrt (el m\u00e9dico del Bayern). Se le realiz\u00f3 una resonancia magn\u00e9tica y","canonical_url":"https:\/\/candas365.es\/noticias\/arturo-vidal-debera-someterse-a-una-pequena-operacion-de-rodilla\/","robots":"max-image-preview:large","keywords":"deporte","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/arturo-vidal-debera-someterse-a-una-pequena-operacion-de-rodilla\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/deporte\/#listItem","name":"Deporte"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/deporte\/#listItem","position":2,"name":"Deporte","item":"https:\/\/candas365.es\/noticias\/category\/deporte\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/arturo-vidal-debera-someterse-a-una-pequena-operacion-de-rodilla\/#listItem","name":"Arturo Vidal deber\u00e1 someterse a una peque\u00f1a operaci\u00f3n de rodilla"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/arturo-vidal-debera-someterse-a-una-pequena-operacion-de-rodilla\/#listItem","position":3,"name":"Arturo Vidal deber\u00e1 someterse a una peque\u00f1a operaci\u00f3n de rodilla","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/deporte\/#listItem","name":"Deporte"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/arturo-vidal-debera-someterse-a-una-pequena-operacion-de-rodilla\/#newsarticle","name":"Arturo Vidal deber\u00e1 someterse a una peque\u00f1a operaci\u00f3n de rodilla | Cand\u00e1s 365","headline":"Arturo Vidal deber\u00e1 someterse a una peque\u00f1a operaci\u00f3n de rodilla","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/football-2697618_1280.jpg","width":1280,"height":960},"datePublished":"2018-04-16T22:45:50+02:00","dateModified":"2018-04-16T22:45:50+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/arturo-vidal-debera-someterse-a-una-pequena-operacion-de-rodilla\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/arturo-vidal-debera-someterse-a-una-pequena-operacion-de-rodilla\/#webpage"},"articleSection":"Deporte","dateline":"Publicado el abril 16, 2018."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/arturo-vidal-debera-someterse-a-una-pequena-operacion-de-rodilla\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/arturo-vidal-debera-someterse-a-una-pequena-operacion-de-rodilla\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/arturo-vidal-debera-someterse-a-una-pequena-operacion-de-rodilla\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/arturo-vidal-debera-someterse-a-una-pequena-operacion-de-rodilla\/#webpage","url":"https:\/\/candas365.es\/noticias\/arturo-vidal-debera-someterse-a-una-pequena-operacion-de-rodilla\/","name":"Arturo Vidal deber\u00e1 someterse a una peque\u00f1a operaci\u00f3n de rodilla | Cand\u00e1s 365","description":"M\u00fanich, 16 abr (dpa) - El futbolista chileno Arturo Vidal deber\u00e1 someterse a una peque\u00f1a operaci\u00f3n de rodilla justo cuando el Bayern M\u00fanich est\u00e1 a un pu\u00f1ado de partidos del triplete, anunci\u00f3 hoy el club alem\u00e1n. \"He hablado por tel\u00e9fono con el doctor M\u00fcller-Wohlfahrt (el m\u00e9dico del Bayern). Se le realiz\u00f3 una resonancia magn\u00e9tica y","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/arturo-vidal-debera-someterse-a-una-pequena-operacion-de-rodilla\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/football-2697618_1280.jpg","@id":"https:\/\/candas365.es\/noticias\/arturo-vidal-debera-someterse-a-una-pequena-operacion-de-rodilla\/#mainImage","width":1280,"height":960},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/arturo-vidal-debera-someterse-a-una-pequena-operacion-de-rodilla\/#mainImage"},"datePublished":"2018-04-16T22:45:50+02:00","dateModified":"2018-04-16T22:45:50+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Arturo Vidal deber\u00e1 someterse a una peque\u00f1a operaci\u00f3n de rodilla | Cand\u00e1s 365","og:description":"M\u00fanich, 16 abr (dpa) - El futbolista chileno Arturo Vidal deber\u00e1 someterse a una peque\u00f1a operaci\u00f3n de rodilla justo cuando el Bayern M\u00fanich est\u00e1 a un pu\u00f1ado de partidos del triplete, anunci\u00f3 hoy el club alem\u00e1n. &quot;He hablado por tel\u00e9fono con el doctor M\u00fcller-Wohlfahrt (el m\u00e9dico del Bayern). Se le realiz\u00f3 una resonancia magn\u00e9tica y","og:url":"https:\/\/candas365.es\/noticias\/arturo-vidal-debera-someterse-a-una-pequena-operacion-de-rodilla\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/football-2697618_1280.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/football-2697618_1280.jpg","og:image:width":1280,"og:image:height":960,"article:published_time":"2018-04-16T22:45:50+00:00","article:modified_time":"2018-04-16T22:45:50+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Arturo Vidal deber\u00e1 someterse a una peque\u00f1a operaci\u00f3n de rodilla | Cand\u00e1s 365","twitter:description":"M\u00fanich, 16 abr (dpa) - El futbolista chileno Arturo Vidal deber\u00e1 someterse a una peque\u00f1a operaci\u00f3n de rodilla justo cuando el Bayern M\u00fanich est\u00e1 a un pu\u00f1ado de partidos del triplete, anunci\u00f3 hoy el club alem\u00e1n. &quot;He hablado por tel\u00e9fono con el doctor M\u00fcller-Wohlfahrt (el m\u00e9dico del Bayern). Se le realiz\u00f3 una resonancia magn\u00e9tica y","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/football-2697618_1280.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"93940","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-26 18:24:10","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 11:53:24","updated":"2025-08-26 18:24:10"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/deporte\/\" title=\"Deporte\">Deporte<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tArturo Vidal deber\u00e1 someterse a una peque\u00f1a operaci\u00f3n de rodilla\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Deporte","link":"https:\/\/candas365.es\/noticias\/category\/deporte\/"},{"label":"Arturo Vidal deber\u00e1 someterse a una peque\u00f1a operaci\u00f3n de rodilla","link":"https:\/\/candas365.es\/noticias\/arturo-vidal-debera-someterse-a-una-pequena-operacion-de-rodilla\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/93940","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=93940"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/93940\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/91549"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=93940"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=93940"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=93940"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}