{"id":93517,"date":"2018-04-11T00:26:36","date_gmt":"2018-04-11T00:26:36","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=93517"},"modified":"2018-04-11T00:26:36","modified_gmt":"2018-04-11T00:26:36","slug":"el-real-madrid-aspira-a-convertir-en-un-tramite-su-pase-a-semifinales","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/el-real-madrid-aspira-a-convertir-en-un-tramite-su-pase-a-semifinales\/","title":{"rendered":"El Real Madrid aspira a convertir en un tr\u00e1mite su pase a semifinales"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-92011\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/woman-638384_1280-360x239.jpg\" alt=\"\" width=\"360\" height=\"239\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/woman-638384_1280-360x239.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/woman-638384_1280-696x462.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/woman-638384_1280-1068x709.jpg 1068w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/woman-638384_1280-632x420.jpg 632w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/woman-638384_1280-768x510.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/woman-638384_1280-655x435.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/woman-638384_1280.jpg 1280w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Madrid, 10 abr (dpa) &#8211; El Real Madrid aspira a convertir ma\u00f1ana en un tr\u00e1mite su pase a las semifinales de la Liga de Campeones despu\u00e9s del 3-0 cosechado la pasada semana en Tur\u00edn ante la Juventus, un resultado que sit\u00faa a los blancos con todo a favor para estar entre los cuatro mejores de Europa por octavo a\u00f1o consecutivo.<\/p>\n<p>La fiabilidad del Real Madrid en la m\u00e1xima competici\u00f3n continental contrasta con sus actuaciones en la Liga espa\u00f1ola, donde s\u00f3lo gan\u00f3 tres de las \u00faltimas diez ediciones. Esta temporada transita por la cuarta posici\u00f3n en el torneo nacional, algo de dif\u00edcil explicaci\u00f3n cuando se trata de un claro aspirante a ganar su tercera Liga de Campeones consecutiva.<\/p>\n<p>El conjunto de Zinedine Zidane demostr\u00f3 en Tur\u00edn toda su fortaleza en Europa con un resultado concluyente que tambi\u00e9n dej\u00f3 para el recuerdo un tremendo gol de Cristiano Ronaldo. Cualquier otra cosa que no sea la clasificaci\u00f3n blanca ser\u00eda contemplado como un terremoto.<\/p>\n<p>Pero Zidane no quiere confianzas. \u00ab(La ventaja) No va a cambiar nada. Es otra historia, otro partido. Lo que pas\u00f3, pas\u00f3. Hicimos un buen resultado, pero ahora hay delante el 50 por ciento de la eliminatoria. Hay que hacer otro gran partido\u00bb, manifest\u00f3 hoy en rueda de prensa.<\/p>\n<p>El preparador blanco contar\u00e1 con la ausencia por sanci\u00f3n del central Sergio Ramos y es probable que Carlos Casemiro retrase su posici\u00f3n hasta la defensa ante la baja por lesi\u00f3n de Nacho Fern\u00e1ndez y los problemas f\u00edsicos que arrastr\u00f3 en los \u00faltimos d\u00edas Jes\u00fas Vallejo.<\/p>\n<p>Si as\u00ed sucede, quedar\u00eda una vacante en el centro del campo que podr\u00eda ser ocupada por el croata Mateo Kovacic. Otras opciones, m\u00e1s ofensivas, son Lucas V\u00e1zquez o Marco Asensio.<\/p>\n<p>Isco tambi\u00e9n tiene un puesto casi garantizado en el centro del campo y, dado que Karim Benzema y Cristiano Ronaldo son fijos para Zidane, se prev\u00e9 una nueva suplencia para Gareth Bale, un jugador inmerso en miles de rumores sobre su futuro para la pr\u00f3xima temporada.<\/p>\n<p>La Juventus llega a Madrid apesadumbrado por su pobre papel en la ida y la cuesti\u00f3n es ver si su t\u00e9cnico, Massimiliano Allegri, decide pelear la eliminatoria o si se conforma con cumplir una actuaci\u00f3n decorosa en el Santiago Bernab\u00e9u.<\/p>\n<p>La prensa italiana apunta la posibilidad de que juegue con cuatro delanteros. Ser\u00edan Douglas Costa y Juan Guillermo Cuadrado en los extremos, m\u00e1s Gonzalo Higua\u00edn y Mario Mandzucic en la punta. Cabe recordar que Allegri no podr\u00e1 contar con el argentino Paulo Dybala, expulsado en la ida y muy criticado por su actuaci\u00f3n.<\/p>\n<p>El Real Madrid espera lucir sus \u00abgalones\u00bb de Liga de Campeones ante un Santiago Bernab\u00e9u ansioso de so\u00f1ar con un nuevo t\u00edtulo continental, el \u00fanico que pueden ganar los blancos esta temporada. La Juventus, sin nada que perder, se encomienda a lo m\u00e1s parecido que puede haber a un \u00abmilagro\u00bb en el mundo del f\u00fatbol.<\/p>\n<p>Por Alberto Bravo (dpa)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Madrid, 10 abr (dpa) &#8211; El Real Madrid aspira a convertir ma\u00f1ana en un tr\u00e1mite su pase a las semifinales de la Liga de Campeones despu\u00e9s del 3-0 cosechado la pasada semana en Tur\u00edn ante la Juventus, un resultado que sit\u00faa a los blancos con todo a favor para estar entre los cuatro mejores de<\/p>\n","protected":false},"author":1,"featured_media":92011,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[319],"tags":[],"class_list":{"0":"post-93517","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-deporte"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7 - aioseo.com -->\n\t<meta name=\"description\" content=\"Madrid, 10 abr (dpa) - El Real Madrid aspira a convertir ma\u00f1ana en un tr\u00e1mite su pase a las semifinales de la Liga de Campeones despu\u00e9s del 3-0 cosechado la pasada semana en Tur\u00edn ante la Juventus, un resultado que sit\u00faa a los blancos con todo a favor para estar entre los cuatro mejores de\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"deporte\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/el-real-madrid-aspira-a-convertir-en-un-tramite-su-pase-a-semifinales\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El Real Madrid aspira a convertir en un tr\u00e1mite su pase a semifinales | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Madrid, 10 abr (dpa) - El Real Madrid aspira a convertir ma\u00f1ana en un tr\u00e1mite su pase a las semifinales de la Liga de Campeones despu\u00e9s del 3-0 cosechado la pasada semana en Tur\u00edn ante la Juventus, un resultado que sit\u00faa a los blancos con todo a favor para estar entre los cuatro mejores de\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/el-real-madrid-aspira-a-convertir-en-un-tramite-su-pase-a-semifinales\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/woman-638384_1280.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/woman-638384_1280.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t\t<meta property=\"og:image:height\" content=\"850\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-04-11T00:26:36+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-04-11T00:26:36+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El Real Madrid aspira a convertir en un tr\u00e1mite su pase a semifinales | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Madrid, 10 abr (dpa) - El Real Madrid aspira a convertir ma\u00f1ana en un tr\u00e1mite su pase a las semifinales de la Liga de Campeones despu\u00e9s del 3-0 cosechado la pasada semana en Tur\u00edn ante la Juventus, un resultado que sit\u00faa a los blancos con todo a favor para estar entre los cuatro mejores de\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/woman-638384_1280.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-real-madrid-aspira-a-convertir-en-un-tramite-su-pase-a-semifinales\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/#listItem\",\"name\":\"Deporte\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/#listItem\",\"position\":2,\"name\":\"Deporte\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-real-madrid-aspira-a-convertir-en-un-tramite-su-pase-a-semifinales\\\/#listItem\",\"name\":\"El Real Madrid aspira a convertir en un tr\\u00e1mite su pase a semifinales\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-real-madrid-aspira-a-convertir-en-un-tramite-su-pase-a-semifinales\\\/#listItem\",\"position\":3,\"name\":\"El Real Madrid aspira a convertir en un tr\\u00e1mite su pase a semifinales\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/#listItem\",\"name\":\"Deporte\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-real-madrid-aspira-a-convertir-en-un-tramite-su-pase-a-semifinales\\\/#newsarticle\",\"name\":\"El Real Madrid aspira a convertir en un tr\\u00e1mite su pase a semifinales | Cand\\u00e1s 365\",\"headline\":\"El Real Madrid aspira a convertir en un tr\\u00e1mite su pase a semifinales\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/woman-638384_1280.jpg\",\"width\":1280,\"height\":850},\"datePublished\":\"2018-04-11T00:26:36+02:00\",\"dateModified\":\"2018-04-11T00:26:36+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-real-madrid-aspira-a-convertir-en-un-tramite-su-pase-a-semifinales\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-real-madrid-aspira-a-convertir-en-un-tramite-su-pase-a-semifinales\\\/#webpage\"},\"articleSection\":\"Deporte\",\"dateline\":\"Publicado el abril 11, 2018.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-real-madrid-aspira-a-convertir-en-un-tramite-su-pase-a-semifinales\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-real-madrid-aspira-a-convertir-en-un-tramite-su-pase-a-semifinales\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-real-madrid-aspira-a-convertir-en-un-tramite-su-pase-a-semifinales\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-real-madrid-aspira-a-convertir-en-un-tramite-su-pase-a-semifinales\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-real-madrid-aspira-a-convertir-en-un-tramite-su-pase-a-semifinales\\\/\",\"name\":\"El Real Madrid aspira a convertir en un tr\\u00e1mite su pase a semifinales | Cand\\u00e1s 365\",\"description\":\"Madrid, 10 abr (dpa) - El Real Madrid aspira a convertir ma\\u00f1ana en un tr\\u00e1mite su pase a las semifinales de la Liga de Campeones despu\\u00e9s del 3-0 cosechado la pasada semana en Tur\\u00edn ante la Juventus, un resultado que sit\\u00faa a los blancos con todo a favor para estar entre los cuatro mejores de\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-real-madrid-aspira-a-convertir-en-un-tramite-su-pase-a-semifinales\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/woman-638384_1280.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-real-madrid-aspira-a-convertir-en-un-tramite-su-pase-a-semifinales\\\/#mainImage\",\"width\":1280,\"height\":850},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-real-madrid-aspira-a-convertir-en-un-tramite-su-pase-a-semifinales\\\/#mainImage\"},\"datePublished\":\"2018-04-11T00:26:36+02:00\",\"dateModified\":\"2018-04-11T00:26:36+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>El Real Madrid aspira a convertir en un tr\u00e1mite su pase a semifinales | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"El Real Madrid aspira a convertir en un tr\u00e1mite su pase a semifinales | Cand\u00e1s 365","description":"Madrid, 10 abr (dpa) - El Real Madrid aspira a convertir ma\u00f1ana en un tr\u00e1mite su pase a las semifinales de la Liga de Campeones despu\u00e9s del 3-0 cosechado la pasada semana en Tur\u00edn ante la Juventus, un resultado que sit\u00faa a los blancos con todo a favor para estar entre los cuatro mejores de","canonical_url":"https:\/\/candas365.es\/noticias\/el-real-madrid-aspira-a-convertir-en-un-tramite-su-pase-a-semifinales\/","robots":"max-image-preview:large","keywords":"deporte","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/el-real-madrid-aspira-a-convertir-en-un-tramite-su-pase-a-semifinales\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/deporte\/#listItem","name":"Deporte"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/deporte\/#listItem","position":2,"name":"Deporte","item":"https:\/\/candas365.es\/noticias\/category\/deporte\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/el-real-madrid-aspira-a-convertir-en-un-tramite-su-pase-a-semifinales\/#listItem","name":"El Real Madrid aspira a convertir en un tr\u00e1mite su pase a semifinales"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/el-real-madrid-aspira-a-convertir-en-un-tramite-su-pase-a-semifinales\/#listItem","position":3,"name":"El Real Madrid aspira a convertir en un tr\u00e1mite su pase a semifinales","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/deporte\/#listItem","name":"Deporte"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/el-real-madrid-aspira-a-convertir-en-un-tramite-su-pase-a-semifinales\/#newsarticle","name":"El Real Madrid aspira a convertir en un tr\u00e1mite su pase a semifinales | Cand\u00e1s 365","headline":"El Real Madrid aspira a convertir en un tr\u00e1mite su pase a semifinales","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/woman-638384_1280.jpg","width":1280,"height":850},"datePublished":"2018-04-11T00:26:36+02:00","dateModified":"2018-04-11T00:26:36+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/el-real-madrid-aspira-a-convertir-en-un-tramite-su-pase-a-semifinales\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/el-real-madrid-aspira-a-convertir-en-un-tramite-su-pase-a-semifinales\/#webpage"},"articleSection":"Deporte","dateline":"Publicado el abril 11, 2018."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/el-real-madrid-aspira-a-convertir-en-un-tramite-su-pase-a-semifinales\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/el-real-madrid-aspira-a-convertir-en-un-tramite-su-pase-a-semifinales\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/el-real-madrid-aspira-a-convertir-en-un-tramite-su-pase-a-semifinales\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/el-real-madrid-aspira-a-convertir-en-un-tramite-su-pase-a-semifinales\/#webpage","url":"https:\/\/candas365.es\/noticias\/el-real-madrid-aspira-a-convertir-en-un-tramite-su-pase-a-semifinales\/","name":"El Real Madrid aspira a convertir en un tr\u00e1mite su pase a semifinales | Cand\u00e1s 365","description":"Madrid, 10 abr (dpa) - El Real Madrid aspira a convertir ma\u00f1ana en un tr\u00e1mite su pase a las semifinales de la Liga de Campeones despu\u00e9s del 3-0 cosechado la pasada semana en Tur\u00edn ante la Juventus, un resultado que sit\u00faa a los blancos con todo a favor para estar entre los cuatro mejores de","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/el-real-madrid-aspira-a-convertir-en-un-tramite-su-pase-a-semifinales\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/woman-638384_1280.jpg","@id":"https:\/\/candas365.es\/noticias\/el-real-madrid-aspira-a-convertir-en-un-tramite-su-pase-a-semifinales\/#mainImage","width":1280,"height":850},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/el-real-madrid-aspira-a-convertir-en-un-tramite-su-pase-a-semifinales\/#mainImage"},"datePublished":"2018-04-11T00:26:36+02:00","dateModified":"2018-04-11T00:26:36+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"El Real Madrid aspira a convertir en un tr\u00e1mite su pase a semifinales | Cand\u00e1s 365","og:description":"Madrid, 10 abr (dpa) - El Real Madrid aspira a convertir ma\u00f1ana en un tr\u00e1mite su pase a las semifinales de la Liga de Campeones despu\u00e9s del 3-0 cosechado la pasada semana en Tur\u00edn ante la Juventus, un resultado que sit\u00faa a los blancos con todo a favor para estar entre los cuatro mejores de","og:url":"https:\/\/candas365.es\/noticias\/el-real-madrid-aspira-a-convertir-en-un-tramite-su-pase-a-semifinales\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/woman-638384_1280.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/woman-638384_1280.jpg","og:image:width":1280,"og:image:height":850,"article:published_time":"2018-04-11T00:26:36+00:00","article:modified_time":"2018-04-11T00:26:36+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"El Real Madrid aspira a convertir en un tr\u00e1mite su pase a semifinales | Cand\u00e1s 365","twitter:description":"Madrid, 10 abr (dpa) - El Real Madrid aspira a convertir ma\u00f1ana en un tr\u00e1mite su pase a las semifinales de la Liga de Campeones despu\u00e9s del 3-0 cosechado la pasada semana en Tur\u00edn ante la Juventus, un resultado que sit\u00faa a los blancos con todo a favor para estar entre los cuatro mejores de","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/woman-638384_1280.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"3 minutos"},"aioseo_meta_data":{"post_id":"93517","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-26 17:49:15","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 11:53:45","updated":"2025-08-26 17:49:15"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/deporte\/\" title=\"Deporte\">Deporte<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tEl Real Madrid aspira a convertir en un tr\u00e1mite su pase a semifinales\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Deporte","link":"https:\/\/candas365.es\/noticias\/category\/deporte\/"},{"label":"El Real Madrid aspira a convertir en un tr\u00e1mite su pase a semifinales","link":"https:\/\/candas365.es\/noticias\/el-real-madrid-aspira-a-convertir-en-un-tramite-su-pase-a-semifinales\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/93517","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=93517"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/93517\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/92011"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=93517"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=93517"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=93517"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}