{"id":93190,"date":"2018-04-05T20:47:05","date_gmt":"2018-04-05T20:47:05","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=93190"},"modified":"2018-04-05T20:47:05","modified_gmt":"2018-04-05T20:47:05","slug":"manuel-neuer-sigue-recuperandose-y-apunta-al-mundial-de-rusia","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/manuel-neuer-sigue-recuperandose-y-apunta-al-mundial-de-rusia\/","title":{"rendered":"Manuel Neuer sigue recuper\u00e1ndose y apunta al Mundial de Rusia"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-92011\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/woman-638384_1280-360x239.jpg\" alt=\"\" width=\"360\" height=\"239\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/woman-638384_1280-360x239.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/woman-638384_1280-696x462.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/woman-638384_1280-1068x709.jpg 1068w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/woman-638384_1280-632x420.jpg 632w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/woman-638384_1280-768x510.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/woman-638384_1280-655x435.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/woman-638384_1280.jpg 1280w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>M\u00fanich, 5 abr (dpa) &#8211; El arquero alem\u00e1n Manuel Neuer sigue avanzando con paso firme en su recuperaci\u00f3n de una fractura en el pie y culmin\u00f3 hoy su primer entrenamiento bajo los palos en seis meses.<\/p>\n<p>En esta nueva fase de su preparaci\u00f3n, el internacional alem\u00e1n que sue\u00f1a con estar a punto para el Mundial de Rusia, ya par\u00f3 varios disparos en la porter\u00eda.<\/p>\n<p>\u00abLos reflejos todav\u00eda est\u00e1n ah\u00ed\u00bb, escribi\u00f3 el campe\u00f3n del mundo tras estas primeras pruebas.<\/p>\n<p>La semana pasada, Neuer public\u00f3 un video de corta duraci\u00f3n en el que expresaba su satisfacci\u00f3n por los progresos alcanzados tras poder volver a entrenar en el campo. \u00abMaravilloso, por fin fuera\u00bb, indici\u00f3 en un texto posteado en su perfil de Facebook.<\/p>\n<p>Neuer lleva m\u00e1s de seis meses sin jugar tras la \u00faltima fractura que sufri\u00f3 en el pie. El capit\u00e1n del Bayern y de la selecci\u00f3n alemana espera volver a la actividad esta temporada y regresar al arco de la \u00abMannschaft\u00bb para el Mundial de Rusia, aunque los plazos exactos son todav\u00eda una inc\u00f3gnita. El torneo arranca el 14 de junio.<\/p>\n<p>Hace dos semanas, en una entrevista al canal de televisi\u00f3n del Bayern, Neuer expres\u00f3 su deseo de ser cauteloso y de no apurar su recuperaci\u00f3n. \u00abHay que ser especialmente cuidadoso ahora. Es realmente importante que nada le suceda al pie\u00bb, coment\u00f3 en ese entonces.<\/p>\n<p>Neuer, de no contar con contratiempos en su recuperaci\u00f3n, llegar\u00e1 al Mundial de Rusia casi sin rodaje y con la seria de posibilidad de perder el puesto a manos de Marc-Andr\u00e9 ter Stegen, portero del Barcelona.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00fanich, 5 abr (dpa) &#8211; El arquero alem\u00e1n Manuel Neuer sigue avanzando con paso firme en su recuperaci\u00f3n de una fractura en el pie y culmin\u00f3 hoy su primer entrenamiento bajo los palos en seis meses. En esta nueva fase de su preparaci\u00f3n, el internacional alem\u00e1n que sue\u00f1a con estar a punto para el Mundial<\/p>\n","protected":false},"author":1,"featured_media":92011,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[319],"tags":[],"class_list":{"0":"post-93190","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-deporte"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7 - aioseo.com -->\n\t<meta name=\"description\" content=\"M\u00fanich, 5 abr (dpa) - El arquero alem\u00e1n Manuel Neuer sigue avanzando con paso firme en su recuperaci\u00f3n de una fractura en el pie y culmin\u00f3 hoy su primer entrenamiento bajo los palos en seis meses. En esta nueva fase de su preparaci\u00f3n, el internacional alem\u00e1n que sue\u00f1a con estar a punto para el Mundial\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"deporte\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/manuel-neuer-sigue-recuperandose-y-apunta-al-mundial-de-rusia\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Manuel Neuer sigue recuper\u00e1ndose y apunta al Mundial de Rusia | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"M\u00fanich, 5 abr (dpa) - El arquero alem\u00e1n Manuel Neuer sigue avanzando con paso firme en su recuperaci\u00f3n de una fractura en el pie y culmin\u00f3 hoy su primer entrenamiento bajo los palos en seis meses. En esta nueva fase de su preparaci\u00f3n, el internacional alem\u00e1n que sue\u00f1a con estar a punto para el Mundial\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/manuel-neuer-sigue-recuperandose-y-apunta-al-mundial-de-rusia\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/woman-638384_1280.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/woman-638384_1280.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t\t<meta property=\"og:image:height\" content=\"850\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-04-05T20:47:05+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-04-05T20:47:05+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Manuel Neuer sigue recuper\u00e1ndose y apunta al Mundial de Rusia | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"M\u00fanich, 5 abr (dpa) - El arquero alem\u00e1n Manuel Neuer sigue avanzando con paso firme en su recuperaci\u00f3n de una fractura en el pie y culmin\u00f3 hoy su primer entrenamiento bajo los palos en seis meses. En esta nueva fase de su preparaci\u00f3n, el internacional alem\u00e1n que sue\u00f1a con estar a punto para el Mundial\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/woman-638384_1280.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/manuel-neuer-sigue-recuperandose-y-apunta-al-mundial-de-rusia\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/#listItem\",\"name\":\"Deporte\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/#listItem\",\"position\":2,\"name\":\"Deporte\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/manuel-neuer-sigue-recuperandose-y-apunta-al-mundial-de-rusia\\\/#listItem\",\"name\":\"Manuel Neuer sigue recuper\\u00e1ndose y apunta al Mundial de Rusia\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/manuel-neuer-sigue-recuperandose-y-apunta-al-mundial-de-rusia\\\/#listItem\",\"position\":3,\"name\":\"Manuel Neuer sigue recuper\\u00e1ndose y apunta al Mundial de Rusia\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/#listItem\",\"name\":\"Deporte\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/manuel-neuer-sigue-recuperandose-y-apunta-al-mundial-de-rusia\\\/#newsarticle\",\"name\":\"Manuel Neuer sigue recuper\\u00e1ndose y apunta al Mundial de Rusia | Cand\\u00e1s 365\",\"headline\":\"Manuel Neuer sigue recuper\\u00e1ndose y apunta al Mundial de Rusia\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/woman-638384_1280.jpg\",\"width\":1280,\"height\":850},\"datePublished\":\"2018-04-05T20:47:05+02:00\",\"dateModified\":\"2018-04-05T20:47:05+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/manuel-neuer-sigue-recuperandose-y-apunta-al-mundial-de-rusia\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/manuel-neuer-sigue-recuperandose-y-apunta-al-mundial-de-rusia\\\/#webpage\"},\"articleSection\":\"Deporte\",\"dateline\":\"Publicado el abril 5, 2018.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/manuel-neuer-sigue-recuperandose-y-apunta-al-mundial-de-rusia\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/manuel-neuer-sigue-recuperandose-y-apunta-al-mundial-de-rusia\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/manuel-neuer-sigue-recuperandose-y-apunta-al-mundial-de-rusia\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/manuel-neuer-sigue-recuperandose-y-apunta-al-mundial-de-rusia\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/manuel-neuer-sigue-recuperandose-y-apunta-al-mundial-de-rusia\\\/\",\"name\":\"Manuel Neuer sigue recuper\\u00e1ndose y apunta al Mundial de Rusia | Cand\\u00e1s 365\",\"description\":\"M\\u00fanich, 5 abr (dpa) - El arquero alem\\u00e1n Manuel Neuer sigue avanzando con paso firme en su recuperaci\\u00f3n de una fractura en el pie y culmin\\u00f3 hoy su primer entrenamiento bajo los palos en seis meses. En esta nueva fase de su preparaci\\u00f3n, el internacional alem\\u00e1n que sue\\u00f1a con estar a punto para el Mundial\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/manuel-neuer-sigue-recuperandose-y-apunta-al-mundial-de-rusia\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/woman-638384_1280.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/manuel-neuer-sigue-recuperandose-y-apunta-al-mundial-de-rusia\\\/#mainImage\",\"width\":1280,\"height\":850},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/manuel-neuer-sigue-recuperandose-y-apunta-al-mundial-de-rusia\\\/#mainImage\"},\"datePublished\":\"2018-04-05T20:47:05+02:00\",\"dateModified\":\"2018-04-05T20:47:05+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Manuel Neuer sigue recuper\u00e1ndose y apunta al Mundial de Rusia | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Manuel Neuer sigue recuper\u00e1ndose y apunta al Mundial de Rusia | Cand\u00e1s 365","description":"M\u00fanich, 5 abr (dpa) - El arquero alem\u00e1n Manuel Neuer sigue avanzando con paso firme en su recuperaci\u00f3n de una fractura en el pie y culmin\u00f3 hoy su primer entrenamiento bajo los palos en seis meses. En esta nueva fase de su preparaci\u00f3n, el internacional alem\u00e1n que sue\u00f1a con estar a punto para el Mundial","canonical_url":"https:\/\/candas365.es\/noticias\/manuel-neuer-sigue-recuperandose-y-apunta-al-mundial-de-rusia\/","robots":"max-image-preview:large","keywords":"deporte","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/manuel-neuer-sigue-recuperandose-y-apunta-al-mundial-de-rusia\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/deporte\/#listItem","name":"Deporte"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/deporte\/#listItem","position":2,"name":"Deporte","item":"https:\/\/candas365.es\/noticias\/category\/deporte\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/manuel-neuer-sigue-recuperandose-y-apunta-al-mundial-de-rusia\/#listItem","name":"Manuel Neuer sigue recuper\u00e1ndose y apunta al Mundial de Rusia"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/manuel-neuer-sigue-recuperandose-y-apunta-al-mundial-de-rusia\/#listItem","position":3,"name":"Manuel Neuer sigue recuper\u00e1ndose y apunta al Mundial de Rusia","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/deporte\/#listItem","name":"Deporte"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/manuel-neuer-sigue-recuperandose-y-apunta-al-mundial-de-rusia\/#newsarticle","name":"Manuel Neuer sigue recuper\u00e1ndose y apunta al Mundial de Rusia | Cand\u00e1s 365","headline":"Manuel Neuer sigue recuper\u00e1ndose y apunta al Mundial de Rusia","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/woman-638384_1280.jpg","width":1280,"height":850},"datePublished":"2018-04-05T20:47:05+02:00","dateModified":"2018-04-05T20:47:05+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/manuel-neuer-sigue-recuperandose-y-apunta-al-mundial-de-rusia\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/manuel-neuer-sigue-recuperandose-y-apunta-al-mundial-de-rusia\/#webpage"},"articleSection":"Deporte","dateline":"Publicado el abril 5, 2018."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/manuel-neuer-sigue-recuperandose-y-apunta-al-mundial-de-rusia\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/manuel-neuer-sigue-recuperandose-y-apunta-al-mundial-de-rusia\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/manuel-neuer-sigue-recuperandose-y-apunta-al-mundial-de-rusia\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/manuel-neuer-sigue-recuperandose-y-apunta-al-mundial-de-rusia\/#webpage","url":"https:\/\/candas365.es\/noticias\/manuel-neuer-sigue-recuperandose-y-apunta-al-mundial-de-rusia\/","name":"Manuel Neuer sigue recuper\u00e1ndose y apunta al Mundial de Rusia | Cand\u00e1s 365","description":"M\u00fanich, 5 abr (dpa) - El arquero alem\u00e1n Manuel Neuer sigue avanzando con paso firme en su recuperaci\u00f3n de una fractura en el pie y culmin\u00f3 hoy su primer entrenamiento bajo los palos en seis meses. En esta nueva fase de su preparaci\u00f3n, el internacional alem\u00e1n que sue\u00f1a con estar a punto para el Mundial","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/manuel-neuer-sigue-recuperandose-y-apunta-al-mundial-de-rusia\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/woman-638384_1280.jpg","@id":"https:\/\/candas365.es\/noticias\/manuel-neuer-sigue-recuperandose-y-apunta-al-mundial-de-rusia\/#mainImage","width":1280,"height":850},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/manuel-neuer-sigue-recuperandose-y-apunta-al-mundial-de-rusia\/#mainImage"},"datePublished":"2018-04-05T20:47:05+02:00","dateModified":"2018-04-05T20:47:05+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Manuel Neuer sigue recuper\u00e1ndose y apunta al Mundial de Rusia | Cand\u00e1s 365","og:description":"M\u00fanich, 5 abr (dpa) - El arquero alem\u00e1n Manuel Neuer sigue avanzando con paso firme en su recuperaci\u00f3n de una fractura en el pie y culmin\u00f3 hoy su primer entrenamiento bajo los palos en seis meses. En esta nueva fase de su preparaci\u00f3n, el internacional alem\u00e1n que sue\u00f1a con estar a punto para el Mundial","og:url":"https:\/\/candas365.es\/noticias\/manuel-neuer-sigue-recuperandose-y-apunta-al-mundial-de-rusia\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/woman-638384_1280.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/woman-638384_1280.jpg","og:image:width":1280,"og:image:height":850,"article:published_time":"2018-04-05T20:47:05+00:00","article:modified_time":"2018-04-05T20:47:05+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Manuel Neuer sigue recuper\u00e1ndose y apunta al Mundial de Rusia | Cand\u00e1s 365","twitter:description":"M\u00fanich, 5 abr (dpa) - El arquero alem\u00e1n Manuel Neuer sigue avanzando con paso firme en su recuperaci\u00f3n de una fractura en el pie y culmin\u00f3 hoy su primer entrenamiento bajo los palos en seis meses. En esta nueva fase de su preparaci\u00f3n, el internacional alem\u00e1n que sue\u00f1a con estar a punto para el Mundial","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/woman-638384_1280.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"1 minuto"},"aioseo_meta_data":{"post_id":"93190","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-26 17:20:11","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 11:53:54","updated":"2025-08-26 17:20:11"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/deporte\/\" title=\"Deporte\">Deporte<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tManuel Neuer sigue recuper\u00e1ndose y apunta al Mundial de Rusia\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Deporte","link":"https:\/\/candas365.es\/noticias\/category\/deporte\/"},{"label":"Manuel Neuer sigue recuper\u00e1ndose y apunta al Mundial de Rusia","link":"https:\/\/candas365.es\/noticias\/manuel-neuer-sigue-recuperandose-y-apunta-al-mundial-de-rusia\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/93190","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=93190"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/93190\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/92011"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=93190"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=93190"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=93190"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}