{"id":92778,"date":"2018-03-30T15:56:42","date_gmt":"2018-03-30T15:56:42","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=92778"},"modified":"2018-03-30T15:56:42","modified_gmt":"2018-03-30T15:56:42","slug":"una-ex-nadadora-olimpica-alemana-subasta-sis-medallas-para-saldar-deudas","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/una-ex-nadadora-olimpica-alemana-subasta-sis-medallas-para-saldar-deudas\/","title":{"rendered":"Una ex nadadora ol\u00edmpica alemana subasta sis medallas para saldar deudas"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-86307\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/12\/apple-1853306_1280-news2-360x240.jpg\" alt=\"\" width=\"360\" height=\"240\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/12\/apple-1853306_1280-news2-360x240.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/12\/apple-1853306_1280-news2-768x512.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/12\/apple-1853306_1280-news2-655x436.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/12\/apple-1853306_1280-news2-696x464.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/12\/apple-1853306_1280-news2-1068x712.jpg 1068w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/12\/apple-1853306_1280-news2-630x420.jpg 630w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/12\/apple-1853306_1280-news2-84x55.jpg 84w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/12\/apple-1853306_1280-news2.jpg 1280w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Hamburgo, 30 mar (dpa) &#8211; La ex nadadora alemana Sandra V\u00f6lker subast\u00f3 las tres medallas ol\u00edmpicas que gan\u00f3 en los Juegos de Atlanta 1996 para saldar sus deudas, confirm\u00f3 ayer la propia deportista.<\/p>\n<p>\u00abPor supuesto que estoy contenta y aliviada\u00bb, afirm\u00f3 V\u00f6lker a dpa, despu\u00e9s de que el procedimiento por insolvencia concluyera antes de lo previsto.<\/p>\n<p>La subasta de las medallas, una de plata y dos de bronce ganadas en los Juegos de 1996, recaud\u00f3 67.500 euros (unos 83.000 d\u00f3lares), seg\u00fan inform\u00f3 la administradora de la insolvencia Verena Vogt, quien dijo que todos los acreedores acordaron en que V\u00f6lker estaba ahora libre de las deudas.<\/p>\n<p>V\u00f6lker, de 43 a\u00f1os, hab\u00eda presentado una demanda por insolvencia personal en 2013. En los Juegos de Atlanta, la ex nadadora hab\u00eda sido segunda en los 100 metros libre, y tercera en los 50 metros libre y en la posta 4&#215;100 libre.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hamburgo, 30 mar (dpa) &#8211; La ex nadadora alemana Sandra V\u00f6lker subast\u00f3 las tres medallas ol\u00edmpicas que gan\u00f3 en los Juegos de Atlanta 1996 para saldar sus deudas, confirm\u00f3 ayer la propia deportista. \u00abPor supuesto que estoy contenta y aliviada\u00bb, afirm\u00f3 V\u00f6lker a dpa, despu\u00e9s de que el procedimiento por insolvencia concluyera antes de lo<\/p>\n","protected":false},"author":1,"featured_media":86307,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[319],"tags":[],"class_list":{"0":"post-92778","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-deporte"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7 - aioseo.com -->\n\t<meta name=\"description\" content=\"Hamburgo, 30 mar (dpa) - La ex nadadora alemana Sandra V\u00f6lker subast\u00f3 las tres medallas ol\u00edmpicas que gan\u00f3 en los Juegos de Atlanta 1996 para saldar sus deudas, confirm\u00f3 ayer la propia deportista. &quot;Por supuesto que estoy contenta y aliviada&quot;, afirm\u00f3 V\u00f6lker a dpa, despu\u00e9s de que el procedimiento por insolvencia concluyera antes de lo\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"deporte\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/una-ex-nadadora-olimpica-alemana-subasta-sis-medallas-para-saldar-deudas\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Una ex nadadora ol\u00edmpica alemana subasta sis medallas para saldar deudas | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Hamburgo, 30 mar (dpa) - La ex nadadora alemana Sandra V\u00f6lker subast\u00f3 las tres medallas ol\u00edmpicas que gan\u00f3 en los Juegos de Atlanta 1996 para saldar sus deudas, confirm\u00f3 ayer la propia deportista. &quot;Por supuesto que estoy contenta y aliviada&quot;, afirm\u00f3 V\u00f6lker a dpa, despu\u00e9s de que el procedimiento por insolvencia concluyera antes de lo\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/una-ex-nadadora-olimpica-alemana-subasta-sis-medallas-para-saldar-deudas\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/12\/apple-1853306_1280-news2.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/12\/apple-1853306_1280-news2.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-03-30T15:56:42+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-03-30T15:56:42+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Una ex nadadora ol\u00edmpica alemana subasta sis medallas para saldar deudas | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Hamburgo, 30 mar (dpa) - La ex nadadora alemana Sandra V\u00f6lker subast\u00f3 las tres medallas ol\u00edmpicas que gan\u00f3 en los Juegos de Atlanta 1996 para saldar sus deudas, confirm\u00f3 ayer la propia deportista. &quot;Por supuesto que estoy contenta y aliviada&quot;, afirm\u00f3 V\u00f6lker a dpa, despu\u00e9s de que el procedimiento por insolvencia concluyera antes de lo\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/12\/apple-1853306_1280-news2.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/una-ex-nadadora-olimpica-alemana-subasta-sis-medallas-para-saldar-deudas\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/#listItem\",\"name\":\"Deporte\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/#listItem\",\"position\":2,\"name\":\"Deporte\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/una-ex-nadadora-olimpica-alemana-subasta-sis-medallas-para-saldar-deudas\\\/#listItem\",\"name\":\"Una ex nadadora ol\\u00edmpica alemana subasta sis medallas para saldar deudas\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/una-ex-nadadora-olimpica-alemana-subasta-sis-medallas-para-saldar-deudas\\\/#listItem\",\"position\":3,\"name\":\"Una ex nadadora ol\\u00edmpica alemana subasta sis medallas para saldar deudas\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/#listItem\",\"name\":\"Deporte\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/una-ex-nadadora-olimpica-alemana-subasta-sis-medallas-para-saldar-deudas\\\/#newsarticle\",\"name\":\"Una ex nadadora ol\\u00edmpica alemana subasta sis medallas para saldar deudas | Cand\\u00e1s 365\",\"headline\":\"Una ex nadadora ol\\u00edmpica alemana subasta sis medallas para saldar deudas\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/apple-1853306_1280-news2.jpg\",\"width\":1280,\"height\":853},\"datePublished\":\"2018-03-30T15:56:42+02:00\",\"dateModified\":\"2018-03-30T15:56:42+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/una-ex-nadadora-olimpica-alemana-subasta-sis-medallas-para-saldar-deudas\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/una-ex-nadadora-olimpica-alemana-subasta-sis-medallas-para-saldar-deudas\\\/#webpage\"},\"articleSection\":\"Deporte\",\"dateline\":\"Publicado el marzo 30, 2018.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/una-ex-nadadora-olimpica-alemana-subasta-sis-medallas-para-saldar-deudas\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/una-ex-nadadora-olimpica-alemana-subasta-sis-medallas-para-saldar-deudas\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/una-ex-nadadora-olimpica-alemana-subasta-sis-medallas-para-saldar-deudas\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/una-ex-nadadora-olimpica-alemana-subasta-sis-medallas-para-saldar-deudas\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/una-ex-nadadora-olimpica-alemana-subasta-sis-medallas-para-saldar-deudas\\\/\",\"name\":\"Una ex nadadora ol\\u00edmpica alemana subasta sis medallas para saldar deudas | Cand\\u00e1s 365\",\"description\":\"Hamburgo, 30 mar (dpa) - La ex nadadora alemana Sandra V\\u00f6lker subast\\u00f3 las tres medallas ol\\u00edmpicas que gan\\u00f3 en los Juegos de Atlanta 1996 para saldar sus deudas, confirm\\u00f3 ayer la propia deportista. \\\"Por supuesto que estoy contenta y aliviada\\\", afirm\\u00f3 V\\u00f6lker a dpa, despu\\u00e9s de que el procedimiento por insolvencia concluyera antes de lo\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/una-ex-nadadora-olimpica-alemana-subasta-sis-medallas-para-saldar-deudas\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/apple-1853306_1280-news2.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/una-ex-nadadora-olimpica-alemana-subasta-sis-medallas-para-saldar-deudas\\\/#mainImage\",\"width\":1280,\"height\":853},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/una-ex-nadadora-olimpica-alemana-subasta-sis-medallas-para-saldar-deudas\\\/#mainImage\"},\"datePublished\":\"2018-03-30T15:56:42+02:00\",\"dateModified\":\"2018-03-30T15:56:42+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Una ex nadadora ol\u00edmpica alemana subasta sis medallas para saldar deudas | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Una ex nadadora ol\u00edmpica alemana subasta sis medallas para saldar deudas | Cand\u00e1s 365","description":"Hamburgo, 30 mar (dpa) - La ex nadadora alemana Sandra V\u00f6lker subast\u00f3 las tres medallas ol\u00edmpicas que gan\u00f3 en los Juegos de Atlanta 1996 para saldar sus deudas, confirm\u00f3 ayer la propia deportista. \"Por supuesto que estoy contenta y aliviada\", afirm\u00f3 V\u00f6lker a dpa, despu\u00e9s de que el procedimiento por insolvencia concluyera antes de lo","canonical_url":"https:\/\/candas365.es\/noticias\/una-ex-nadadora-olimpica-alemana-subasta-sis-medallas-para-saldar-deudas\/","robots":"max-image-preview:large","keywords":"deporte","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/una-ex-nadadora-olimpica-alemana-subasta-sis-medallas-para-saldar-deudas\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/deporte\/#listItem","name":"Deporte"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/deporte\/#listItem","position":2,"name":"Deporte","item":"https:\/\/candas365.es\/noticias\/category\/deporte\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/una-ex-nadadora-olimpica-alemana-subasta-sis-medallas-para-saldar-deudas\/#listItem","name":"Una ex nadadora ol\u00edmpica alemana subasta sis medallas para saldar deudas"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/una-ex-nadadora-olimpica-alemana-subasta-sis-medallas-para-saldar-deudas\/#listItem","position":3,"name":"Una ex nadadora ol\u00edmpica alemana subasta sis medallas para saldar deudas","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/deporte\/#listItem","name":"Deporte"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/una-ex-nadadora-olimpica-alemana-subasta-sis-medallas-para-saldar-deudas\/#newsarticle","name":"Una ex nadadora ol\u00edmpica alemana subasta sis medallas para saldar deudas | Cand\u00e1s 365","headline":"Una ex nadadora ol\u00edmpica alemana subasta sis medallas para saldar deudas","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/12\/apple-1853306_1280-news2.jpg","width":1280,"height":853},"datePublished":"2018-03-30T15:56:42+02:00","dateModified":"2018-03-30T15:56:42+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/una-ex-nadadora-olimpica-alemana-subasta-sis-medallas-para-saldar-deudas\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/una-ex-nadadora-olimpica-alemana-subasta-sis-medallas-para-saldar-deudas\/#webpage"},"articleSection":"Deporte","dateline":"Publicado el marzo 30, 2018."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/una-ex-nadadora-olimpica-alemana-subasta-sis-medallas-para-saldar-deudas\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/una-ex-nadadora-olimpica-alemana-subasta-sis-medallas-para-saldar-deudas\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/una-ex-nadadora-olimpica-alemana-subasta-sis-medallas-para-saldar-deudas\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/una-ex-nadadora-olimpica-alemana-subasta-sis-medallas-para-saldar-deudas\/#webpage","url":"https:\/\/candas365.es\/noticias\/una-ex-nadadora-olimpica-alemana-subasta-sis-medallas-para-saldar-deudas\/","name":"Una ex nadadora ol\u00edmpica alemana subasta sis medallas para saldar deudas | Cand\u00e1s 365","description":"Hamburgo, 30 mar (dpa) - La ex nadadora alemana Sandra V\u00f6lker subast\u00f3 las tres medallas ol\u00edmpicas que gan\u00f3 en los Juegos de Atlanta 1996 para saldar sus deudas, confirm\u00f3 ayer la propia deportista. \"Por supuesto que estoy contenta y aliviada\", afirm\u00f3 V\u00f6lker a dpa, despu\u00e9s de que el procedimiento por insolvencia concluyera antes de lo","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/una-ex-nadadora-olimpica-alemana-subasta-sis-medallas-para-saldar-deudas\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/12\/apple-1853306_1280-news2.jpg","@id":"https:\/\/candas365.es\/noticias\/una-ex-nadadora-olimpica-alemana-subasta-sis-medallas-para-saldar-deudas\/#mainImage","width":1280,"height":853},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/una-ex-nadadora-olimpica-alemana-subasta-sis-medallas-para-saldar-deudas\/#mainImage"},"datePublished":"2018-03-30T15:56:42+02:00","dateModified":"2018-03-30T15:56:42+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Una ex nadadora ol\u00edmpica alemana subasta sis medallas para saldar deudas | Cand\u00e1s 365","og:description":"Hamburgo, 30 mar (dpa) - La ex nadadora alemana Sandra V\u00f6lker subast\u00f3 las tres medallas ol\u00edmpicas que gan\u00f3 en los Juegos de Atlanta 1996 para saldar sus deudas, confirm\u00f3 ayer la propia deportista. &quot;Por supuesto que estoy contenta y aliviada&quot;, afirm\u00f3 V\u00f6lker a dpa, despu\u00e9s de que el procedimiento por insolvencia concluyera antes de lo","og:url":"https:\/\/candas365.es\/noticias\/una-ex-nadadora-olimpica-alemana-subasta-sis-medallas-para-saldar-deudas\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/12\/apple-1853306_1280-news2.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/12\/apple-1853306_1280-news2.jpg","og:image:width":1280,"og:image:height":853,"article:published_time":"2018-03-30T15:56:42+00:00","article:modified_time":"2018-03-30T15:56:42+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Una ex nadadora ol\u00edmpica alemana subasta sis medallas para saldar deudas | Cand\u00e1s 365","twitter:description":"Hamburgo, 30 mar (dpa) - La ex nadadora alemana Sandra V\u00f6lker subast\u00f3 las tres medallas ol\u00edmpicas que gan\u00f3 en los Juegos de Atlanta 1996 para saldar sus deudas, confirm\u00f3 ayer la propia deportista. &quot;Por supuesto que estoy contenta y aliviada&quot;, afirm\u00f3 V\u00f6lker a dpa, despu\u00e9s de que el procedimiento por insolvencia concluyera antes de lo","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/12\/apple-1853306_1280-news2.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"1 minuto"},"aioseo_meta_data":{"post_id":"92778","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-26 16:42:20","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 11:54:10","updated":"2025-08-26 16:42:20"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/deporte\/\" title=\"Deporte\">Deporte<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tUna ex nadadora ol\u00edmpica alemana subasta sis medallas para saldar deudas\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Deporte","link":"https:\/\/candas365.es\/noticias\/category\/deporte\/"},{"label":"Una ex nadadora ol\u00edmpica alemana subasta sis medallas para saldar deudas","link":"https:\/\/candas365.es\/noticias\/una-ex-nadadora-olimpica-alemana-subasta-sis-medallas-para-saldar-deudas\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/92778","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=92778"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/92778\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/86307"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=92778"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=92778"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=92778"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}