{"id":92337,"date":"2018-03-24T15:49:57","date_gmt":"2018-03-24T15:49:57","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=92337"},"modified":"2018-03-24T15:49:57","modified_gmt":"2018-03-24T15:49:57","slug":"neuer-avanza-en-su-recuperacion-un-paso-importante","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/neuer-avanza-en-su-recuperacion-un-paso-importante\/","title":{"rendered":"Neuer avanza en su recuperaci\u00f3n: \u00abUn paso importante\u00bb"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-89552\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280-360x241.jpg\" alt=\"\" width=\"360\" height=\"241\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280-360x241.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280-696x466.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280-1068x715.jpg 1068w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280-627x420.jpg 627w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280-768x514.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280-655x439.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280.jpg 1280w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>M\u00fanich, 24 mar (dpa) &#8211; El arquero alem\u00e1n Manuel Neuer dio un importante paso en la recuperaci\u00f3n de su lesi\u00f3n en el pie al correr el viernes por primera vez al cien por ciento.<\/p>\n<p>\u00abPor primera vez he podido correr al cien por ciento. Ha sido un paso importante para m\u00ed\u00bb, dijo el portero del Bayern M\u00fanich en declaraciones a la emisora de televisi\u00f3n del club b\u00e1varo.<\/p>\n<p>\u00abSi todo marcha bien, espero volver a correr en un campo en el transcurso de esta semana\u00bb, agreg\u00f3.<\/p>\n<p>Neuer, de 31 a\u00f1os, lleva m\u00e1s de seis meses sin jugar tras la \u00faltima fractura que sufri\u00f3 en el pie. El capit\u00e1n del Bayern y de la selecci\u00f3n alemana espera volver a la actividad esta temporada y regresar al arco de la \u00abMannschaft\u00bb para el Mundial de Rusia, aunque los plazos exactos son todav\u00eda una inc\u00f3gnita.<\/p>\n<p>El arquero dej\u00f3 en claro que no apurar\u00e1 su recuperaci\u00f3n. \u00abHay que ser especialmente cuidadoso ahora. Es realmente importante que nada le suceda al pie\u00bb, coment\u00f3.<\/p>\n<p>Neuer no particip\u00f3 en el amistoso que Alemania jug\u00f3 el viernes ante Espa\u00f1a en D\u00fcsseldorf y tampoco lo har\u00e1 el martes ante Brasil en Berl\u00edn. Por ello, llegar\u00e1 al Mundial de Rusia casi sin rodaje y con la seria posibilidad de perder el puesto a manos de Marc-Andr\u00e9 ter Stegen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00fanich, 24 mar (dpa) &#8211; El arquero alem\u00e1n Manuel Neuer dio un importante paso en la recuperaci\u00f3n de su lesi\u00f3n en el pie al correr el viernes por primera vez al cien por ciento. \u00abPor primera vez he podido correr al cien por ciento. Ha sido un paso importante para m\u00ed\u00bb, dijo el portero del<\/p>\n","protected":false},"author":1,"featured_media":89552,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[319],"tags":[],"class_list":{"0":"post-92337","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-deporte"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7 - aioseo.com -->\n\t<meta name=\"description\" content=\"M\u00fanich, 24 mar (dpa) - El arquero alem\u00e1n Manuel Neuer dio un importante paso en la recuperaci\u00f3n de su lesi\u00f3n en el pie al correr el viernes por primera vez al cien por ciento. &quot;Por primera vez he podido correr al cien por ciento. Ha sido un paso importante para m\u00ed&quot;, dijo el portero del\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"deporte\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/neuer-avanza-en-su-recuperacion-un-paso-importante\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Neuer avanza en su recuperaci\u00f3n: \u00abUn paso importante\u00bb | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"M\u00fanich, 24 mar (dpa) - El arquero alem\u00e1n Manuel Neuer dio un importante paso en la recuperaci\u00f3n de su lesi\u00f3n en el pie al correr el viernes por primera vez al cien por ciento. &quot;Por primera vez he podido correr al cien por ciento. Ha sido un paso importante para m\u00ed&quot;, dijo el portero del\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/neuer-avanza-en-su-recuperacion-un-paso-importante\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t\t<meta property=\"og:image:height\" content=\"857\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-03-24T15:49:57+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-03-24T15:49:57+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Neuer avanza en su recuperaci\u00f3n: \u00abUn paso importante\u00bb | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"M\u00fanich, 24 mar (dpa) - El arquero alem\u00e1n Manuel Neuer dio un importante paso en la recuperaci\u00f3n de su lesi\u00f3n en el pie al correr el viernes por primera vez al cien por ciento. &quot;Por primera vez he podido correr al cien por ciento. Ha sido un paso importante para m\u00ed&quot;, dijo el portero del\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/neuer-avanza-en-su-recuperacion-un-paso-importante\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/#listItem\",\"name\":\"Deporte\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/#listItem\",\"position\":2,\"name\":\"Deporte\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/neuer-avanza-en-su-recuperacion-un-paso-importante\\\/#listItem\",\"name\":\"Neuer avanza en su recuperaci\\u00f3n: \\u00abUn paso importante\\u00bb\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/neuer-avanza-en-su-recuperacion-un-paso-importante\\\/#listItem\",\"position\":3,\"name\":\"Neuer avanza en su recuperaci\\u00f3n: \\u00abUn paso importante\\u00bb\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/#listItem\",\"name\":\"Deporte\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/neuer-avanza-en-su-recuperacion-un-paso-importante\\\/#newsarticle\",\"name\":\"Neuer avanza en su recuperaci\\u00f3n: \\u00abUn paso importante\\u00bb | Cand\\u00e1s 365\",\"headline\":\"Neuer avanza en su recuperaci\\u00f3n: \\u00abUn paso importante\\u00bb\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/football-1406106_1280.jpg\",\"width\":1280,\"height\":857,\"caption\":\"football\"},\"datePublished\":\"2018-03-24T15:49:57+01:00\",\"dateModified\":\"2018-03-24T15:49:57+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/neuer-avanza-en-su-recuperacion-un-paso-importante\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/neuer-avanza-en-su-recuperacion-un-paso-importante\\\/#webpage\"},\"articleSection\":\"Deporte\",\"dateline\":\"Publicado el marzo 24, 2018.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/neuer-avanza-en-su-recuperacion-un-paso-importante\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/neuer-avanza-en-su-recuperacion-un-paso-importante\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/neuer-avanza-en-su-recuperacion-un-paso-importante\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/neuer-avanza-en-su-recuperacion-un-paso-importante\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/neuer-avanza-en-su-recuperacion-un-paso-importante\\\/\",\"name\":\"Neuer avanza en su recuperaci\\u00f3n: \\u00abUn paso importante\\u00bb | Cand\\u00e1s 365\",\"description\":\"M\\u00fanich, 24 mar (dpa) - El arquero alem\\u00e1n Manuel Neuer dio un importante paso en la recuperaci\\u00f3n de su lesi\\u00f3n en el pie al correr el viernes por primera vez al cien por ciento. \\\"Por primera vez he podido correr al cien por ciento. Ha sido un paso importante para m\\u00ed\\\", dijo el portero del\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/neuer-avanza-en-su-recuperacion-un-paso-importante\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/football-1406106_1280.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/neuer-avanza-en-su-recuperacion-un-paso-importante\\\/#mainImage\",\"width\":1280,\"height\":857,\"caption\":\"football\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/neuer-avanza-en-su-recuperacion-un-paso-importante\\\/#mainImage\"},\"datePublished\":\"2018-03-24T15:49:57+01:00\",\"dateModified\":\"2018-03-24T15:49:57+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Neuer avanza en su recuperaci\u00f3n: \u00abUn paso importante\u00bb | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Neuer avanza en su recuperaci\u00f3n: \u00abUn paso importante\u00bb | Cand\u00e1s 365","description":"M\u00fanich, 24 mar (dpa) - El arquero alem\u00e1n Manuel Neuer dio un importante paso en la recuperaci\u00f3n de su lesi\u00f3n en el pie al correr el viernes por primera vez al cien por ciento. \"Por primera vez he podido correr al cien por ciento. Ha sido un paso importante para m\u00ed\", dijo el portero del","canonical_url":"https:\/\/candas365.es\/noticias\/neuer-avanza-en-su-recuperacion-un-paso-importante\/","robots":"max-image-preview:large","keywords":"deporte","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/neuer-avanza-en-su-recuperacion-un-paso-importante\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/deporte\/#listItem","name":"Deporte"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/deporte\/#listItem","position":2,"name":"Deporte","item":"https:\/\/candas365.es\/noticias\/category\/deporte\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/neuer-avanza-en-su-recuperacion-un-paso-importante\/#listItem","name":"Neuer avanza en su recuperaci\u00f3n: \u00abUn paso importante\u00bb"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/neuer-avanza-en-su-recuperacion-un-paso-importante\/#listItem","position":3,"name":"Neuer avanza en su recuperaci\u00f3n: \u00abUn paso importante\u00bb","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/deporte\/#listItem","name":"Deporte"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/neuer-avanza-en-su-recuperacion-un-paso-importante\/#newsarticle","name":"Neuer avanza en su recuperaci\u00f3n: \u00abUn paso importante\u00bb | Cand\u00e1s 365","headline":"Neuer avanza en su recuperaci\u00f3n: \u00abUn paso importante\u00bb","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280.jpg","width":1280,"height":857,"caption":"football"},"datePublished":"2018-03-24T15:49:57+01:00","dateModified":"2018-03-24T15:49:57+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/neuer-avanza-en-su-recuperacion-un-paso-importante\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/neuer-avanza-en-su-recuperacion-un-paso-importante\/#webpage"},"articleSection":"Deporte","dateline":"Publicado el marzo 24, 2018."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/neuer-avanza-en-su-recuperacion-un-paso-importante\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/neuer-avanza-en-su-recuperacion-un-paso-importante\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/neuer-avanza-en-su-recuperacion-un-paso-importante\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/neuer-avanza-en-su-recuperacion-un-paso-importante\/#webpage","url":"https:\/\/candas365.es\/noticias\/neuer-avanza-en-su-recuperacion-un-paso-importante\/","name":"Neuer avanza en su recuperaci\u00f3n: \u00abUn paso importante\u00bb | Cand\u00e1s 365","description":"M\u00fanich, 24 mar (dpa) - El arquero alem\u00e1n Manuel Neuer dio un importante paso en la recuperaci\u00f3n de su lesi\u00f3n en el pie al correr el viernes por primera vez al cien por ciento. \"Por primera vez he podido correr al cien por ciento. Ha sido un paso importante para m\u00ed\", dijo el portero del","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/neuer-avanza-en-su-recuperacion-un-paso-importante\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280.jpg","@id":"https:\/\/candas365.es\/noticias\/neuer-avanza-en-su-recuperacion-un-paso-importante\/#mainImage","width":1280,"height":857,"caption":"football"},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/neuer-avanza-en-su-recuperacion-un-paso-importante\/#mainImage"},"datePublished":"2018-03-24T15:49:57+01:00","dateModified":"2018-03-24T15:49:57+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Neuer avanza en su recuperaci\u00f3n: \u00abUn paso importante\u00bb | Cand\u00e1s 365","og:description":"M\u00fanich, 24 mar (dpa) - El arquero alem\u00e1n Manuel Neuer dio un importante paso en la recuperaci\u00f3n de su lesi\u00f3n en el pie al correr el viernes por primera vez al cien por ciento. &quot;Por primera vez he podido correr al cien por ciento. Ha sido un paso importante para m\u00ed&quot;, dijo el portero del","og:url":"https:\/\/candas365.es\/noticias\/neuer-avanza-en-su-recuperacion-un-paso-importante\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280.jpg","og:image:width":1280,"og:image:height":857,"article:published_time":"2018-03-24T15:49:57+00:00","article:modified_time":"2018-03-24T15:49:57+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Neuer avanza en su recuperaci\u00f3n: \u00abUn paso importante\u00bb | Cand\u00e1s 365","twitter:description":"M\u00fanich, 24 mar (dpa) - El arquero alem\u00e1n Manuel Neuer dio un importante paso en la recuperaci\u00f3n de su lesi\u00f3n en el pie al correr el viernes por primera vez al cien por ciento. &quot;Por primera vez he podido correr al cien por ciento. Ha sido un paso importante para m\u00ed&quot;, dijo el portero del","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"1 minuto"},"aioseo_meta_data":{"post_id":"92337","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-26 16:05:10","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 11:54:31","updated":"2025-08-26 16:05:10"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/deporte\/\" title=\"Deporte\">Deporte<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tNeuer avanza en su recuperaci\u00f3n: \u00abUn paso importante\u00bb\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Deporte","link":"https:\/\/candas365.es\/noticias\/category\/deporte\/"},{"label":"Neuer avanza en su recuperaci\u00f3n: \u00abUn paso importante\u00bb","link":"https:\/\/candas365.es\/noticias\/neuer-avanza-en-su-recuperacion-un-paso-importante\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/92337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=92337"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/92337\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/89552"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=92337"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=92337"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=92337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}