{"id":92232,"date":"2018-03-23T19:13:54","date_gmt":"2018-03-23T19:13:54","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=92232"},"modified":"2018-03-23T19:13:54","modified_gmt":"2018-03-23T19:13:54","slug":"show-o-desafio-deportivo-bolt-se-prueba-con-el-borussia-dortmund","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/show-o-desafio-deportivo-bolt-se-prueba-con-el-borussia-dortmund\/","title":{"rendered":"\u00bfShow o desaf\u00edo deportivo? Bolt se prueba con el Borussia Dortmund"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-89552\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280-360x241.jpg\" alt=\"\" width=\"360\" height=\"241\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280-360x241.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280-696x466.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280-1068x715.jpg 1068w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280-627x420.jpg 627w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280-768x514.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280-655x439.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280.jpg 1280w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Dortmund (Alemania), 23 mar (dpa) &#8211; En medio de aplausos y al ritmo del reggae de su Jamaica natal, el plusmarquista Usain Bolt entren\u00f3 hoy con los jugadores del Borussia Dortmund de la primera divisi\u00f3n del f\u00fatbol alem\u00e1n.<\/p>\n<p>Unos 1.400 entusiastas acudieron al estadio de pr\u00e1cticas del Dortmund para ver a la superestrella del atletismo, de 31 a\u00f1os, atarse los botines de f\u00fatbol y correr tras un bal\u00f3n como uno m\u00e1s.<\/p>\n<p>Decenas de c\u00e1maras de televisi\u00f3n siguieron al espigado caribe\u00f1o, que practic\u00f3 durante 58 minutos luciendo la camiseta negra y amarilla del tradicional club del oeste alem\u00e1n.<\/p>\n<p>Al comienzo de los ejercicios bajo las \u00f3rdenes del t\u00e9cnico Peter St\u00f6ger, el retirado sprinter cumpli\u00f3 una rutina de trote, efectu\u00f3 elongaciones y realiz\u00f3 pases de pelota con Mario G\u00f6tze y Nuri Sahin.<\/p>\n<p>All\u00ed fue cuando se vio la diferencia entre el corredor y los profesionales del balompi\u00e9. Bolt se movi\u00f3 con cierta dificultad con la pelota, pero demostr\u00f3 que tiene talento. Meti\u00f3 un gol de cabeza para el j\u00fabilo de todos y convirti\u00f3 con solvencia un tiro penal.<\/p>\n<p>Todo estuvo organizado como un gran evento publicitario, a pesar de que Bolt hab\u00eda dicho que no lo ser\u00eda. El hombre m\u00e1s r\u00e1pido del mundo y los futbolistas del Dortmund tienen el mismo proveedor de art\u00edculos deportivos, el alem\u00e1n Puma.<\/p>\n<p>\u00abEstuvo bien\u00bb, coment\u00f3 Bolt al t\u00e9rmino del entrenamiento ante m\u00e1s de un centenar de periodistas.<\/p>\n<p>El jamaicano reiter\u00f3 que sopesa seriamente comenzar una segunda carrera como futbolista tras finalizar a\u00f1os de \u00e9xitos en el atletismo que lo llevaron a cosechar ocho oros ol\u00edmpicos. \u00abTengo la seria intenci\u00f3n, definitivamente. Voy a tratar de dar lo mejor de m\u00ed\u00bb, anticip\u00f3 y admiti\u00f3 que precisa entrenar mucho.<\/p>\n<p>El t\u00e9cnico del Dortmund no quiso emitir un juicio sobre las posibilidades que tendr\u00eda Bolt como futbolista profesional. \u00abEst\u00e1 en una edad en la que dir\u00eda que no puede desarrollarse much\u00edsimo\u00bb.<\/p>\n<p>Sin embargo, St\u00f6ger tambi\u00e9n tuvo elogios para con su disc\u00edpulo de un d\u00eda: \u00abSe ve que entiende el juego. Tiene talento. Lo que le falta es trabajo en equipo\u00bb.<\/p>\n<p>Algo que Bolt podr\u00eda aprender si sigue entrenando con equipos de f\u00fatbol. El atleta prometi\u00f3 volver a Dortmund, donde el d\u00eda anterior hab\u00eda entrenado con los jugadores a puerta cerrada.<\/p>\n<p>Al final todos quedaron contentos. Bolt, porque pudo entrenar como cualquier futbolista y el Dortmund, porque no todos los d\u00edas recibe una visita tan ilustre.<\/p>\n<p><i class=\"lang-es\"><span class=\" readonly\" title=\"\">Por Dietmar Fuchs (dpa)<\/span><\/i><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dortmund (Alemania), 23 mar (dpa) &#8211; En medio de aplausos y al ritmo del reggae de su Jamaica natal, el plusmarquista Usain Bolt entren\u00f3 hoy con los jugadores del Borussia Dortmund de la primera divisi\u00f3n del f\u00fatbol alem\u00e1n. Unos 1.400 entusiastas acudieron al estadio de pr\u00e1cticas del Dortmund para ver a la superestrella del atletismo,<\/p>\n","protected":false},"author":1,"featured_media":89552,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[319],"tags":[],"class_list":{"0":"post-92232","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-deporte"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7 - aioseo.com -->\n\t<meta name=\"description\" content=\"Dortmund (Alemania), 23 mar (dpa) - En medio de aplausos y al ritmo del reggae de su Jamaica natal, el plusmarquista Usain Bolt entren\u00f3 hoy con los jugadores del Borussia Dortmund de la primera divisi\u00f3n del f\u00fatbol alem\u00e1n. Unos 1.400 entusiastas acudieron al estadio de pr\u00e1cticas del Dortmund para ver a la superestrella del atletismo,\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"deporte\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/show-o-desafio-deportivo-bolt-se-prueba-con-el-borussia-dortmund\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"\u00bfShow o desaf\u00edo deportivo? Bolt se prueba con el Borussia Dortmund | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Dortmund (Alemania), 23 mar (dpa) - En medio de aplausos y al ritmo del reggae de su Jamaica natal, el plusmarquista Usain Bolt entren\u00f3 hoy con los jugadores del Borussia Dortmund de la primera divisi\u00f3n del f\u00fatbol alem\u00e1n. Unos 1.400 entusiastas acudieron al estadio de pr\u00e1cticas del Dortmund para ver a la superestrella del atletismo,\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/show-o-desafio-deportivo-bolt-se-prueba-con-el-borussia-dortmund\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t\t<meta property=\"og:image:height\" content=\"857\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-03-23T19:13:54+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-03-23T19:13:54+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"\u00bfShow o desaf\u00edo deportivo? Bolt se prueba con el Borussia Dortmund | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Dortmund (Alemania), 23 mar (dpa) - En medio de aplausos y al ritmo del reggae de su Jamaica natal, el plusmarquista Usain Bolt entren\u00f3 hoy con los jugadores del Borussia Dortmund de la primera divisi\u00f3n del f\u00fatbol alem\u00e1n. Unos 1.400 entusiastas acudieron al estadio de pr\u00e1cticas del Dortmund para ver a la superestrella del atletismo,\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/show-o-desafio-deportivo-bolt-se-prueba-con-el-borussia-dortmund\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/#listItem\",\"name\":\"Deporte\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/#listItem\",\"position\":2,\"name\":\"Deporte\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/show-o-desafio-deportivo-bolt-se-prueba-con-el-borussia-dortmund\\\/#listItem\",\"name\":\"\\u00bfShow o desaf\\u00edo deportivo? Bolt se prueba con el Borussia Dortmund\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/show-o-desafio-deportivo-bolt-se-prueba-con-el-borussia-dortmund\\\/#listItem\",\"position\":3,\"name\":\"\\u00bfShow o desaf\\u00edo deportivo? Bolt se prueba con el Borussia Dortmund\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/#listItem\",\"name\":\"Deporte\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/show-o-desafio-deportivo-bolt-se-prueba-con-el-borussia-dortmund\\\/#newsarticle\",\"name\":\"\\u00bfShow o desaf\\u00edo deportivo? Bolt se prueba con el Borussia Dortmund | Cand\\u00e1s 365\",\"headline\":\"\\u00bfShow o desaf\\u00edo deportivo? Bolt se prueba con el Borussia Dortmund\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/football-1406106_1280.jpg\",\"width\":1280,\"height\":857,\"caption\":\"football\"},\"datePublished\":\"2018-03-23T19:13:54+01:00\",\"dateModified\":\"2018-03-23T19:13:54+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/show-o-desafio-deportivo-bolt-se-prueba-con-el-borussia-dortmund\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/show-o-desafio-deportivo-bolt-se-prueba-con-el-borussia-dortmund\\\/#webpage\"},\"articleSection\":\"Deporte\",\"dateline\":\"Publicado el marzo 23, 2018.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/show-o-desafio-deportivo-bolt-se-prueba-con-el-borussia-dortmund\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/show-o-desafio-deportivo-bolt-se-prueba-con-el-borussia-dortmund\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/show-o-desafio-deportivo-bolt-se-prueba-con-el-borussia-dortmund\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/show-o-desafio-deportivo-bolt-se-prueba-con-el-borussia-dortmund\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/show-o-desafio-deportivo-bolt-se-prueba-con-el-borussia-dortmund\\\/\",\"name\":\"\\u00bfShow o desaf\\u00edo deportivo? Bolt se prueba con el Borussia Dortmund | Cand\\u00e1s 365\",\"description\":\"Dortmund (Alemania), 23 mar (dpa) - En medio de aplausos y al ritmo del reggae de su Jamaica natal, el plusmarquista Usain Bolt entren\\u00f3 hoy con los jugadores del Borussia Dortmund de la primera divisi\\u00f3n del f\\u00fatbol alem\\u00e1n. Unos 1.400 entusiastas acudieron al estadio de pr\\u00e1cticas del Dortmund para ver a la superestrella del atletismo,\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/show-o-desafio-deportivo-bolt-se-prueba-con-el-borussia-dortmund\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/football-1406106_1280.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/show-o-desafio-deportivo-bolt-se-prueba-con-el-borussia-dortmund\\\/#mainImage\",\"width\":1280,\"height\":857,\"caption\":\"football\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/show-o-desafio-deportivo-bolt-se-prueba-con-el-borussia-dortmund\\\/#mainImage\"},\"datePublished\":\"2018-03-23T19:13:54+01:00\",\"dateModified\":\"2018-03-23T19:13:54+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>\u00bfShow o desaf\u00edo deportivo? Bolt se prueba con el Borussia Dortmund | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"\u00bfShow o desaf\u00edo deportivo? Bolt se prueba con el Borussia Dortmund | Cand\u00e1s 365","description":"Dortmund (Alemania), 23 mar (dpa) - En medio de aplausos y al ritmo del reggae de su Jamaica natal, el plusmarquista Usain Bolt entren\u00f3 hoy con los jugadores del Borussia Dortmund de la primera divisi\u00f3n del f\u00fatbol alem\u00e1n. Unos 1.400 entusiastas acudieron al estadio de pr\u00e1cticas del Dortmund para ver a la superestrella del atletismo,","canonical_url":"https:\/\/candas365.es\/noticias\/show-o-desafio-deportivo-bolt-se-prueba-con-el-borussia-dortmund\/","robots":"max-image-preview:large","keywords":"deporte","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/show-o-desafio-deportivo-bolt-se-prueba-con-el-borussia-dortmund\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/deporte\/#listItem","name":"Deporte"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/deporte\/#listItem","position":2,"name":"Deporte","item":"https:\/\/candas365.es\/noticias\/category\/deporte\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/show-o-desafio-deportivo-bolt-se-prueba-con-el-borussia-dortmund\/#listItem","name":"\u00bfShow o desaf\u00edo deportivo? Bolt se prueba con el Borussia Dortmund"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/show-o-desafio-deportivo-bolt-se-prueba-con-el-borussia-dortmund\/#listItem","position":3,"name":"\u00bfShow o desaf\u00edo deportivo? Bolt se prueba con el Borussia Dortmund","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/deporte\/#listItem","name":"Deporte"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/show-o-desafio-deportivo-bolt-se-prueba-con-el-borussia-dortmund\/#newsarticle","name":"\u00bfShow o desaf\u00edo deportivo? Bolt se prueba con el Borussia Dortmund | Cand\u00e1s 365","headline":"\u00bfShow o desaf\u00edo deportivo? Bolt se prueba con el Borussia Dortmund","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280.jpg","width":1280,"height":857,"caption":"football"},"datePublished":"2018-03-23T19:13:54+01:00","dateModified":"2018-03-23T19:13:54+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/show-o-desafio-deportivo-bolt-se-prueba-con-el-borussia-dortmund\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/show-o-desafio-deportivo-bolt-se-prueba-con-el-borussia-dortmund\/#webpage"},"articleSection":"Deporte","dateline":"Publicado el marzo 23, 2018."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/show-o-desafio-deportivo-bolt-se-prueba-con-el-borussia-dortmund\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/show-o-desafio-deportivo-bolt-se-prueba-con-el-borussia-dortmund\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/show-o-desafio-deportivo-bolt-se-prueba-con-el-borussia-dortmund\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/show-o-desafio-deportivo-bolt-se-prueba-con-el-borussia-dortmund\/#webpage","url":"https:\/\/candas365.es\/noticias\/show-o-desafio-deportivo-bolt-se-prueba-con-el-borussia-dortmund\/","name":"\u00bfShow o desaf\u00edo deportivo? Bolt se prueba con el Borussia Dortmund | Cand\u00e1s 365","description":"Dortmund (Alemania), 23 mar (dpa) - En medio de aplausos y al ritmo del reggae de su Jamaica natal, el plusmarquista Usain Bolt entren\u00f3 hoy con los jugadores del Borussia Dortmund de la primera divisi\u00f3n del f\u00fatbol alem\u00e1n. Unos 1.400 entusiastas acudieron al estadio de pr\u00e1cticas del Dortmund para ver a la superestrella del atletismo,","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/show-o-desafio-deportivo-bolt-se-prueba-con-el-borussia-dortmund\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280.jpg","@id":"https:\/\/candas365.es\/noticias\/show-o-desafio-deportivo-bolt-se-prueba-con-el-borussia-dortmund\/#mainImage","width":1280,"height":857,"caption":"football"},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/show-o-desafio-deportivo-bolt-se-prueba-con-el-borussia-dortmund\/#mainImage"},"datePublished":"2018-03-23T19:13:54+01:00","dateModified":"2018-03-23T19:13:54+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"\u00bfShow o desaf\u00edo deportivo? Bolt se prueba con el Borussia Dortmund | Cand\u00e1s 365","og:description":"Dortmund (Alemania), 23 mar (dpa) - En medio de aplausos y al ritmo del reggae de su Jamaica natal, el plusmarquista Usain Bolt entren\u00f3 hoy con los jugadores del Borussia Dortmund de la primera divisi\u00f3n del f\u00fatbol alem\u00e1n. Unos 1.400 entusiastas acudieron al estadio de pr\u00e1cticas del Dortmund para ver a la superestrella del atletismo,","og:url":"https:\/\/candas365.es\/noticias\/show-o-desafio-deportivo-bolt-se-prueba-con-el-borussia-dortmund\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280.jpg","og:image:width":1280,"og:image:height":857,"article:published_time":"2018-03-23T19:13:54+00:00","article:modified_time":"2018-03-23T19:13:54+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"\u00bfShow o desaf\u00edo deportivo? Bolt se prueba con el Borussia Dortmund | Cand\u00e1s 365","twitter:description":"Dortmund (Alemania), 23 mar (dpa) - En medio de aplausos y al ritmo del reggae de su Jamaica natal, el plusmarquista Usain Bolt entren\u00f3 hoy con los jugadores del Borussia Dortmund de la primera divisi\u00f3n del f\u00fatbol alem\u00e1n. Unos 1.400 entusiastas acudieron al estadio de pr\u00e1cticas del Dortmund para ver a la superestrella del atletismo,","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"92232","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-26 15:55:52","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 11:54:31","updated":"2025-08-26 15:55:52"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/deporte\/\" title=\"Deporte\">Deporte<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t\u00bfShow o desaf\u00edo deportivo? Bolt se prueba con el Borussia Dortmund\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Deporte","link":"https:\/\/candas365.es\/noticias\/category\/deporte\/"},{"label":"\u00bfShow o desaf\u00edo deportivo? Bolt se prueba con el Borussia Dortmund","link":"https:\/\/candas365.es\/noticias\/show-o-desafio-deportivo-bolt-se-prueba-con-el-borussia-dortmund\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/92232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=92232"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/92232\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/89552"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=92232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=92232"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=92232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}