{"id":91948,"date":"2018-03-21T19:04:02","date_gmt":"2018-03-21T19:04:02","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=91948"},"modified":"2018-03-21T19:04:02","modified_gmt":"2018-03-21T19:04:02","slug":"xabi-alonso-la-seleccion-alemana-ha-mejorado-desde-2014","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/xabi-alonso-la-seleccion-alemana-ha-mejorado-desde-2014\/","title":{"rendered":"Xabi Alonso: \u00abLa selecci\u00f3n alemana ha mejorado desde 2014\u00bb"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-89552\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280-360x241.jpg\" alt=\"\" width=\"360\" height=\"241\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280-360x241.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280-696x466.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280-1068x715.jpg 1068w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280-627x420.jpg 627w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280-768x514.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280-655x439.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280.jpg 1280w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Hannover (Alemania), 21 mar (dpa) &#8211; El antiguo centrocampista de la selecci\u00f3n espa\u00f1ola Xabi Alonso considera que el combinado nacional de Alemania que participar\u00e1 este a\u00f1o en el Mundial de f\u00fatbol de Rusia es m\u00e1s fuerte que el que se coron\u00f3 campe\u00f3n hace cuatro a\u00f1os en Brasil.<\/p>\n<p>\u00abAlemania defiende el t\u00edtulo y ha mejorado respecto a 2014, tiene nuevos jugadores y una incre\u00edble confianza en s\u00ed misma\u00bb pronunci\u00f3 Alonso en una entrevista publicada el martes por el portal en l\u00ednea \u00abSportbuzzer\u00bb.<\/p>\n<p>El ex jugador de 36 a\u00f1os, quien fue campe\u00f3n mundial y europeo jugando para Espa\u00f1a, apunt\u00f3 que Alemania ya ha demostrado su gran potencial con su victoria en la Copa Confederaciones del a\u00f1o pasado.<\/p>\n<p>Alonso dijo adem\u00e1s estar especialmente impresionado con el desarrollo del jugador alem\u00e1n Joshua Kimmich, cuyo trayecto ha seguido con inter\u00e9s desde el final de su propia carrera deportiva hace un a\u00f1o. \u00abTiene un gran futuro por delante si contin\u00faa de esta manera\u00bb, se\u00f1al\u00f3.<\/p>\n<p>Alonso, un jugador que destac\u00f3 tanto en equipos como Liverpool, Real Madrid o Bayern M\u00fanich, elogi\u00f3 adem\u00e1s la labor del entrenador de la selecci\u00f3n alemana, Joachim L\u00f6w. A su entender, el t\u00e9cnico se encuentra desarrollando una escuadra que puede disputar el t\u00edtulo no s\u00f3lo en Rusia 2018 sino tambi\u00e9n en Qatar 2022. \u00ab\u00c9sta es su gran fortaleza. \u00c9l ve el presente, pero tambi\u00e9n mira hacia el futuro\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hannover (Alemania), 21 mar (dpa) &#8211; El antiguo centrocampista de la selecci\u00f3n espa\u00f1ola Xabi Alonso considera que el combinado nacional de Alemania que participar\u00e1 este a\u00f1o en el Mundial de f\u00fatbol de Rusia es m\u00e1s fuerte que el que se coron\u00f3 campe\u00f3n hace cuatro a\u00f1os en Brasil. \u00abAlemania defiende el t\u00edtulo y ha mejorado respecto<\/p>\n","protected":false},"author":1,"featured_media":89552,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[319],"tags":[],"class_list":{"0":"post-91948","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-deporte"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7 - aioseo.com -->\n\t<meta name=\"description\" content=\"Hannover (Alemania), 21 mar (dpa) - El antiguo centrocampista de la selecci\u00f3n espa\u00f1ola Xabi Alonso considera que el combinado nacional de Alemania que participar\u00e1 este a\u00f1o en el Mundial de f\u00fatbol de Rusia es m\u00e1s fuerte que el que se coron\u00f3 campe\u00f3n hace cuatro a\u00f1os en Brasil. &quot;Alemania defiende el t\u00edtulo y ha mejorado respecto\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"deporte\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/xabi-alonso-la-seleccion-alemana-ha-mejorado-desde-2014\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Xabi Alonso: \u00abLa selecci\u00f3n alemana ha mejorado desde 2014\u00bb | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Hannover (Alemania), 21 mar (dpa) - El antiguo centrocampista de la selecci\u00f3n espa\u00f1ola Xabi Alonso considera que el combinado nacional de Alemania que participar\u00e1 este a\u00f1o en el Mundial de f\u00fatbol de Rusia es m\u00e1s fuerte que el que se coron\u00f3 campe\u00f3n hace cuatro a\u00f1os en Brasil. &quot;Alemania defiende el t\u00edtulo y ha mejorado respecto\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/xabi-alonso-la-seleccion-alemana-ha-mejorado-desde-2014\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t\t<meta property=\"og:image:height\" content=\"857\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-03-21T19:04:02+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-03-21T19:04:02+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Xabi Alonso: \u00abLa selecci\u00f3n alemana ha mejorado desde 2014\u00bb | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Hannover (Alemania), 21 mar (dpa) - El antiguo centrocampista de la selecci\u00f3n espa\u00f1ola Xabi Alonso considera que el combinado nacional de Alemania que participar\u00e1 este a\u00f1o en el Mundial de f\u00fatbol de Rusia es m\u00e1s fuerte que el que se coron\u00f3 campe\u00f3n hace cuatro a\u00f1os en Brasil. &quot;Alemania defiende el t\u00edtulo y ha mejorado respecto\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/xabi-alonso-la-seleccion-alemana-ha-mejorado-desde-2014\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/#listItem\",\"name\":\"Deporte\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/#listItem\",\"position\":2,\"name\":\"Deporte\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/xabi-alonso-la-seleccion-alemana-ha-mejorado-desde-2014\\\/#listItem\",\"name\":\"Xabi Alonso: \\u00abLa selecci\\u00f3n alemana ha mejorado desde 2014\\u00bb\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/xabi-alonso-la-seleccion-alemana-ha-mejorado-desde-2014\\\/#listItem\",\"position\":3,\"name\":\"Xabi Alonso: \\u00abLa selecci\\u00f3n alemana ha mejorado desde 2014\\u00bb\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/#listItem\",\"name\":\"Deporte\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/xabi-alonso-la-seleccion-alemana-ha-mejorado-desde-2014\\\/#newsarticle\",\"name\":\"Xabi Alonso: \\u00abLa selecci\\u00f3n alemana ha mejorado desde 2014\\u00bb | Cand\\u00e1s 365\",\"headline\":\"Xabi Alonso: \\u00abLa selecci\\u00f3n alemana ha mejorado desde 2014\\u00bb\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/football-1406106_1280.jpg\",\"width\":1280,\"height\":857,\"caption\":\"football\"},\"datePublished\":\"2018-03-21T19:04:02+01:00\",\"dateModified\":\"2018-03-21T19:04:02+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/xabi-alonso-la-seleccion-alemana-ha-mejorado-desde-2014\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/xabi-alonso-la-seleccion-alemana-ha-mejorado-desde-2014\\\/#webpage\"},\"articleSection\":\"Deporte\",\"dateline\":\"Publicado el marzo 21, 2018.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/xabi-alonso-la-seleccion-alemana-ha-mejorado-desde-2014\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/xabi-alonso-la-seleccion-alemana-ha-mejorado-desde-2014\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/xabi-alonso-la-seleccion-alemana-ha-mejorado-desde-2014\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/xabi-alonso-la-seleccion-alemana-ha-mejorado-desde-2014\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/xabi-alonso-la-seleccion-alemana-ha-mejorado-desde-2014\\\/\",\"name\":\"Xabi Alonso: \\u00abLa selecci\\u00f3n alemana ha mejorado desde 2014\\u00bb | Cand\\u00e1s 365\",\"description\":\"Hannover (Alemania), 21 mar (dpa) - El antiguo centrocampista de la selecci\\u00f3n espa\\u00f1ola Xabi Alonso considera que el combinado nacional de Alemania que participar\\u00e1 este a\\u00f1o en el Mundial de f\\u00fatbol de Rusia es m\\u00e1s fuerte que el que se coron\\u00f3 campe\\u00f3n hace cuatro a\\u00f1os en Brasil. \\\"Alemania defiende el t\\u00edtulo y ha mejorado respecto\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/xabi-alonso-la-seleccion-alemana-ha-mejorado-desde-2014\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/football-1406106_1280.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/xabi-alonso-la-seleccion-alemana-ha-mejorado-desde-2014\\\/#mainImage\",\"width\":1280,\"height\":857,\"caption\":\"football\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/xabi-alonso-la-seleccion-alemana-ha-mejorado-desde-2014\\\/#mainImage\"},\"datePublished\":\"2018-03-21T19:04:02+01:00\",\"dateModified\":\"2018-03-21T19:04:02+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Xabi Alonso: \u00abLa selecci\u00f3n alemana ha mejorado desde 2014\u00bb | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Xabi Alonso: \u00abLa selecci\u00f3n alemana ha mejorado desde 2014\u00bb | Cand\u00e1s 365","description":"Hannover (Alemania), 21 mar (dpa) - El antiguo centrocampista de la selecci\u00f3n espa\u00f1ola Xabi Alonso considera que el combinado nacional de Alemania que participar\u00e1 este a\u00f1o en el Mundial de f\u00fatbol de Rusia es m\u00e1s fuerte que el que se coron\u00f3 campe\u00f3n hace cuatro a\u00f1os en Brasil. \"Alemania defiende el t\u00edtulo y ha mejorado respecto","canonical_url":"https:\/\/candas365.es\/noticias\/xabi-alonso-la-seleccion-alemana-ha-mejorado-desde-2014\/","robots":"max-image-preview:large","keywords":"deporte","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/xabi-alonso-la-seleccion-alemana-ha-mejorado-desde-2014\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/deporte\/#listItem","name":"Deporte"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/deporte\/#listItem","position":2,"name":"Deporte","item":"https:\/\/candas365.es\/noticias\/category\/deporte\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/xabi-alonso-la-seleccion-alemana-ha-mejorado-desde-2014\/#listItem","name":"Xabi Alonso: \u00abLa selecci\u00f3n alemana ha mejorado desde 2014\u00bb"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/xabi-alonso-la-seleccion-alemana-ha-mejorado-desde-2014\/#listItem","position":3,"name":"Xabi Alonso: \u00abLa selecci\u00f3n alemana ha mejorado desde 2014\u00bb","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/deporte\/#listItem","name":"Deporte"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/xabi-alonso-la-seleccion-alemana-ha-mejorado-desde-2014\/#newsarticle","name":"Xabi Alonso: \u00abLa selecci\u00f3n alemana ha mejorado desde 2014\u00bb | Cand\u00e1s 365","headline":"Xabi Alonso: \u00abLa selecci\u00f3n alemana ha mejorado desde 2014\u00bb","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280.jpg","width":1280,"height":857,"caption":"football"},"datePublished":"2018-03-21T19:04:02+01:00","dateModified":"2018-03-21T19:04:02+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/xabi-alonso-la-seleccion-alemana-ha-mejorado-desde-2014\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/xabi-alonso-la-seleccion-alemana-ha-mejorado-desde-2014\/#webpage"},"articleSection":"Deporte","dateline":"Publicado el marzo 21, 2018."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/xabi-alonso-la-seleccion-alemana-ha-mejorado-desde-2014\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/xabi-alonso-la-seleccion-alemana-ha-mejorado-desde-2014\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/xabi-alonso-la-seleccion-alemana-ha-mejorado-desde-2014\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/xabi-alonso-la-seleccion-alemana-ha-mejorado-desde-2014\/#webpage","url":"https:\/\/candas365.es\/noticias\/xabi-alonso-la-seleccion-alemana-ha-mejorado-desde-2014\/","name":"Xabi Alonso: \u00abLa selecci\u00f3n alemana ha mejorado desde 2014\u00bb | Cand\u00e1s 365","description":"Hannover (Alemania), 21 mar (dpa) - El antiguo centrocampista de la selecci\u00f3n espa\u00f1ola Xabi Alonso considera que el combinado nacional de Alemania que participar\u00e1 este a\u00f1o en el Mundial de f\u00fatbol de Rusia es m\u00e1s fuerte que el que se coron\u00f3 campe\u00f3n hace cuatro a\u00f1os en Brasil. \"Alemania defiende el t\u00edtulo y ha mejorado respecto","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/xabi-alonso-la-seleccion-alemana-ha-mejorado-desde-2014\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280.jpg","@id":"https:\/\/candas365.es\/noticias\/xabi-alonso-la-seleccion-alemana-ha-mejorado-desde-2014\/#mainImage","width":1280,"height":857,"caption":"football"},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/xabi-alonso-la-seleccion-alemana-ha-mejorado-desde-2014\/#mainImage"},"datePublished":"2018-03-21T19:04:02+01:00","dateModified":"2018-03-21T19:04:02+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Xabi Alonso: \u00abLa selecci\u00f3n alemana ha mejorado desde 2014\u00bb | Cand\u00e1s 365","og:description":"Hannover (Alemania), 21 mar (dpa) - El antiguo centrocampista de la selecci\u00f3n espa\u00f1ola Xabi Alonso considera que el combinado nacional de Alemania que participar\u00e1 este a\u00f1o en el Mundial de f\u00fatbol de Rusia es m\u00e1s fuerte que el que se coron\u00f3 campe\u00f3n hace cuatro a\u00f1os en Brasil. &quot;Alemania defiende el t\u00edtulo y ha mejorado respecto","og:url":"https:\/\/candas365.es\/noticias\/xabi-alonso-la-seleccion-alemana-ha-mejorado-desde-2014\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280.jpg","og:image:width":1280,"og:image:height":857,"article:published_time":"2018-03-21T19:04:02+00:00","article:modified_time":"2018-03-21T19:04:02+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Xabi Alonso: \u00abLa selecci\u00f3n alemana ha mejorado desde 2014\u00bb | Cand\u00e1s 365","twitter:description":"Hannover (Alemania), 21 mar (dpa) - El antiguo centrocampista de la selecci\u00f3n espa\u00f1ola Xabi Alonso considera que el combinado nacional de Alemania que participar\u00e1 este a\u00f1o en el Mundial de f\u00fatbol de Rusia es m\u00e1s fuerte que el que se coron\u00f3 campe\u00f3n hace cuatro a\u00f1os en Brasil. &quot;Alemania defiende el t\u00edtulo y ha mejorado respecto","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/football-1406106_1280.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"1 minuto"},"aioseo_meta_data":{"post_id":"91948","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-26 15:37:12","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 11:54:46","updated":"2025-08-26 15:37:12"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/deporte\/\" title=\"Deporte\">Deporte<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tXabi Alonso: \u00abLa selecci\u00f3n alemana ha mejorado desde 2014\u00bb\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Deporte","link":"https:\/\/candas365.es\/noticias\/category\/deporte\/"},{"label":"Xabi Alonso: \u00abLa selecci\u00f3n alemana ha mejorado desde 2014\u00bb","link":"https:\/\/candas365.es\/noticias\/xabi-alonso-la-seleccion-alemana-ha-mejorado-desde-2014\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/91948","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=91948"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/91948\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/89552"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=91948"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=91948"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=91948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}