{"id":91421,"date":"2018-03-14T01:24:19","date_gmt":"2018-03-14T01:24:19","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=91421"},"modified":"2018-03-14T01:24:19","modified_gmt":"2018-03-14T01:24:19","slug":"volkswagen-dispara-ganancias-cupula-se-embolsa-50-millones-de-euros","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/volkswagen-dispara-ganancias-cupula-se-embolsa-50-millones-de-euros\/","title":{"rendered":"Volkswagen dispara ganancias: C\u00fapula se embolsa 50 millones de euros"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-19556\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/11\/euros-360x198.jpg\" alt=\"\" width=\"360\" height=\"198\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/11\/euros-360x198.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/11\/euros-650x357.jpg 650w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/11\/euros-150x82.jpg 150w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/11\/euros-450x247.jpg 450w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/11\/euros.jpg 655w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Berl\u00edn, 13 mar (dpa) &#8211; Los beneficios de la automotriz alemana Volkswagen se dispararon notablemente en 2017 impulsados por la importante demanda de autom\u00f3viles en el mercado global, comunic\u00f3 hoy la compa\u00f1\u00eda desde Berl\u00edn al presentar sus resultados anuales.<\/p>\n<p>Tras descontar los costes derivados del esc\u00e1ndalo de manipulaci\u00f3n de once millones de veh\u00edculos que salt\u00f3 a la luz en 2015, las ganancias de la marca insignia de Volkswagen ascendieron el a\u00f1o pasado a los 3.300 millones de euros (4.072 millones de d\u00f3lares).<\/p>\n<p>Las buenas cifras han permitido adem\u00e1s que la c\u00fapula directiva de la empresa se embolsase, en su conjunto, cerca de 50 millones de euros, frente a los 39,5 millones que recibieron un a\u00f1o antes.<\/p>\n<p>\u00abEstoy m\u00e1s que contento. El 2017 ha sido el a\u00f1o en que volvimos a la ofensiva\u00bb, declar\u00f3 el presidente del gigante automotor, Matthias M\u00fcller.<\/p>\n<p>Los resultados superan con creces los logrados tan solo un a\u00f1o antes, cuando la compa\u00f1\u00eda firm\u00f3 ganancias por 1.900 millones de euros en un momento en el que su imagen se hab\u00eda visto fuertemente da\u00f1ada debido al esc\u00e1ndalo de manipulaci\u00f3n.<\/p>\n<p>De acuerdo con la informaci\u00f3n facilitada por Volkswagen, en 2017 la empresa destin\u00f3 2.800 millones de euros a indemnizaciones y costes de litigios judiciales relacionados con el trucaje de veh\u00edculos. Un a\u00f1o antes, la partida dedicada a este concepto fue de 5,2 millones de euros.<\/p>\n<p>La facturaci\u00f3n de la principal marca del grupo Volkswagen se situ\u00f3 el a\u00f1o pasado en los 80.000 millones de euros, un 24,3 por ciento menos que en el ejercicio precedente. No obstante, esta ca\u00edda no es directamente comparable con las cifras de 2016 porque Volkswagen ha dejado de contabilizar como propias algunas empresas importadoras con las que trabaja en el extranjero.<\/p>\n<p>En 2015, la automotriz alemana registr\u00f3 p\u00e9rdidas hist\u00f3ricas de m\u00e1s de mil millones de euros por las provisiones que se vio obligada a realizar para hacer frente al esc\u00e1ndalo de manipulaci\u00f3n de emisiones, que afect\u00f3 a 11 millones de veh\u00edculos en todo el mundo.<\/p>\n<p>Volkswagen ha afrontado una situaci\u00f3n financiera complicada en los \u00faltimos tiempos. El esc\u00e1ndalo de manipulaci\u00f3n de motores oblig\u00f3 a la empresa a realizar ajustes, al tiempo que necesitaba mantener inversiones en tecnolog\u00eda e investigaci\u00f3n para no quedarse descolgada o anticuada en un sector que aspira a seguir liderando.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Berl\u00edn, 13 mar (dpa) &#8211; Los beneficios de la automotriz alemana Volkswagen se dispararon notablemente en 2017 impulsados por la importante demanda de autom\u00f3viles en el mercado global, comunic\u00f3 hoy la compa\u00f1\u00eda desde Berl\u00edn al presentar sus resultados anuales. Tras descontar los costes derivados del esc\u00e1ndalo de manipulaci\u00f3n de once millones de veh\u00edculos que salt\u00f3<\/p>\n","protected":false},"author":1,"featured_media":8123,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[151],"tags":[],"class_list":{"0":"post-91421","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-canal-empresas"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7 - aioseo.com -->\n\t<meta name=\"description\" content=\"Berl\u00edn, 13 mar (dpa) - Los beneficios de la automotriz alemana Volkswagen se dispararon notablemente en 2017 impulsados por la importante demanda de autom\u00f3viles en el mercado global, comunic\u00f3 hoy la compa\u00f1\u00eda desde Berl\u00edn al presentar sus resultados anuales. Tras descontar los costes derivados del esc\u00e1ndalo de manipulaci\u00f3n de once millones de veh\u00edculos que salt\u00f3\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"canal empresas\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/volkswagen-dispara-ganancias-cupula-se-embolsa-50-millones-de-euros\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Volkswagen dispara ganancias: C\u00fapula se embolsa 50 millones de euros | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Berl\u00edn, 13 mar (dpa) - Los beneficios de la automotriz alemana Volkswagen se dispararon notablemente en 2017 impulsados por la importante demanda de autom\u00f3viles en el mercado global, comunic\u00f3 hoy la compa\u00f1\u00eda desde Berl\u00edn al presentar sus resultados anuales. Tras descontar los costes derivados del esc\u00e1ndalo de manipulaci\u00f3n de once millones de veh\u00edculos que salt\u00f3\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/volkswagen-dispara-ganancias-cupula-se-embolsa-50-millones-de-euros\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/03\/euros.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/03\/euros.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"360\" \/>\n\t\t<meta property=\"og:image:height\" content=\"235\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-03-14T01:24:19+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-03-14T01:24:19+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Volkswagen dispara ganancias: C\u00fapula se embolsa 50 millones de euros | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Berl\u00edn, 13 mar (dpa) - Los beneficios de la automotriz alemana Volkswagen se dispararon notablemente en 2017 impulsados por la importante demanda de autom\u00f3viles en el mercado global, comunic\u00f3 hoy la compa\u00f1\u00eda desde Berl\u00edn al presentar sus resultados anuales. Tras descontar los costes derivados del esc\u00e1ndalo de manipulaci\u00f3n de once millones de veh\u00edculos que salt\u00f3\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/03\/euros.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/volkswagen-dispara-ganancias-cupula-se-embolsa-50-millones-de-euros\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"name\":\"Canal Empresas\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"position\":2,\"name\":\"Canal Empresas\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/volkswagen-dispara-ganancias-cupula-se-embolsa-50-millones-de-euros\\\/#listItem\",\"name\":\"Volkswagen dispara ganancias: C\\u00fapula se embolsa 50 millones de euros\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/volkswagen-dispara-ganancias-cupula-se-embolsa-50-millones-de-euros\\\/#listItem\",\"position\":3,\"name\":\"Volkswagen dispara ganancias: C\\u00fapula se embolsa 50 millones de euros\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"name\":\"Canal Empresas\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/volkswagen-dispara-ganancias-cupula-se-embolsa-50-millones-de-euros\\\/#newsarticle\",\"name\":\"Volkswagen dispara ganancias: C\\u00fapula se embolsa 50 millones de euros | Cand\\u00e1s 365\",\"headline\":\"Volkswagen dispara ganancias: C\\u00fapula se embolsa 50 millones de euros\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/euros.jpg\",\"width\":360,\"height\":235},\"datePublished\":\"2018-03-14T01:24:19+01:00\",\"dateModified\":\"2018-03-14T01:24:19+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/volkswagen-dispara-ganancias-cupula-se-embolsa-50-millones-de-euros\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/volkswagen-dispara-ganancias-cupula-se-embolsa-50-millones-de-euros\\\/#webpage\"},\"articleSection\":\"Canal Empresas\",\"dateline\":\"Publicado el marzo 14, 2018.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/volkswagen-dispara-ganancias-cupula-se-embolsa-50-millones-de-euros\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/volkswagen-dispara-ganancias-cupula-se-embolsa-50-millones-de-euros\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/volkswagen-dispara-ganancias-cupula-se-embolsa-50-millones-de-euros\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/volkswagen-dispara-ganancias-cupula-se-embolsa-50-millones-de-euros\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/volkswagen-dispara-ganancias-cupula-se-embolsa-50-millones-de-euros\\\/\",\"name\":\"Volkswagen dispara ganancias: C\\u00fapula se embolsa 50 millones de euros | Cand\\u00e1s 365\",\"description\":\"Berl\\u00edn, 13 mar (dpa) - Los beneficios de la automotriz alemana Volkswagen se dispararon notablemente en 2017 impulsados por la importante demanda de autom\\u00f3viles en el mercado global, comunic\\u00f3 hoy la compa\\u00f1\\u00eda desde Berl\\u00edn al presentar sus resultados anuales. Tras descontar los costes derivados del esc\\u00e1ndalo de manipulaci\\u00f3n de once millones de veh\\u00edculos que salt\\u00f3\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/volkswagen-dispara-ganancias-cupula-se-embolsa-50-millones-de-euros\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/euros.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/volkswagen-dispara-ganancias-cupula-se-embolsa-50-millones-de-euros\\\/#mainImage\",\"width\":360,\"height\":235},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/volkswagen-dispara-ganancias-cupula-se-embolsa-50-millones-de-euros\\\/#mainImage\"},\"datePublished\":\"2018-03-14T01:24:19+01:00\",\"dateModified\":\"2018-03-14T01:24:19+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Volkswagen dispara ganancias: C\u00fapula se embolsa 50 millones de euros | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Volkswagen dispara ganancias: C\u00fapula se embolsa 50 millones de euros | Cand\u00e1s 365","description":"Berl\u00edn, 13 mar (dpa) - Los beneficios de la automotriz alemana Volkswagen se dispararon notablemente en 2017 impulsados por la importante demanda de autom\u00f3viles en el mercado global, comunic\u00f3 hoy la compa\u00f1\u00eda desde Berl\u00edn al presentar sus resultados anuales. Tras descontar los costes derivados del esc\u00e1ndalo de manipulaci\u00f3n de once millones de veh\u00edculos que salt\u00f3","canonical_url":"https:\/\/candas365.es\/noticias\/volkswagen-dispara-ganancias-cupula-se-embolsa-50-millones-de-euros\/","robots":"max-image-preview:large","keywords":"canal empresas","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/volkswagen-dispara-ganancias-cupula-se-embolsa-50-millones-de-euros\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","name":"Canal Empresas"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","position":2,"name":"Canal Empresas","item":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/volkswagen-dispara-ganancias-cupula-se-embolsa-50-millones-de-euros\/#listItem","name":"Volkswagen dispara ganancias: C\u00fapula se embolsa 50 millones de euros"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/volkswagen-dispara-ganancias-cupula-se-embolsa-50-millones-de-euros\/#listItem","position":3,"name":"Volkswagen dispara ganancias: C\u00fapula se embolsa 50 millones de euros","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","name":"Canal Empresas"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/volkswagen-dispara-ganancias-cupula-se-embolsa-50-millones-de-euros\/#newsarticle","name":"Volkswagen dispara ganancias: C\u00fapula se embolsa 50 millones de euros | Cand\u00e1s 365","headline":"Volkswagen dispara ganancias: C\u00fapula se embolsa 50 millones de euros","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/03\/euros.jpg","width":360,"height":235},"datePublished":"2018-03-14T01:24:19+01:00","dateModified":"2018-03-14T01:24:19+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/volkswagen-dispara-ganancias-cupula-se-embolsa-50-millones-de-euros\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/volkswagen-dispara-ganancias-cupula-se-embolsa-50-millones-de-euros\/#webpage"},"articleSection":"Canal Empresas","dateline":"Publicado el marzo 14, 2018."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/volkswagen-dispara-ganancias-cupula-se-embolsa-50-millones-de-euros\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/volkswagen-dispara-ganancias-cupula-se-embolsa-50-millones-de-euros\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/volkswagen-dispara-ganancias-cupula-se-embolsa-50-millones-de-euros\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/volkswagen-dispara-ganancias-cupula-se-embolsa-50-millones-de-euros\/#webpage","url":"https:\/\/candas365.es\/noticias\/volkswagen-dispara-ganancias-cupula-se-embolsa-50-millones-de-euros\/","name":"Volkswagen dispara ganancias: C\u00fapula se embolsa 50 millones de euros | Cand\u00e1s 365","description":"Berl\u00edn, 13 mar (dpa) - Los beneficios de la automotriz alemana Volkswagen se dispararon notablemente en 2017 impulsados por la importante demanda de autom\u00f3viles en el mercado global, comunic\u00f3 hoy la compa\u00f1\u00eda desde Berl\u00edn al presentar sus resultados anuales. Tras descontar los costes derivados del esc\u00e1ndalo de manipulaci\u00f3n de once millones de veh\u00edculos que salt\u00f3","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/volkswagen-dispara-ganancias-cupula-se-embolsa-50-millones-de-euros\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/03\/euros.jpg","@id":"https:\/\/candas365.es\/noticias\/volkswagen-dispara-ganancias-cupula-se-embolsa-50-millones-de-euros\/#mainImage","width":360,"height":235},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/volkswagen-dispara-ganancias-cupula-se-embolsa-50-millones-de-euros\/#mainImage"},"datePublished":"2018-03-14T01:24:19+01:00","dateModified":"2018-03-14T01:24:19+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Volkswagen dispara ganancias: C\u00fapula se embolsa 50 millones de euros | Cand\u00e1s 365","og:description":"Berl\u00edn, 13 mar (dpa) - Los beneficios de la automotriz alemana Volkswagen se dispararon notablemente en 2017 impulsados por la importante demanda de autom\u00f3viles en el mercado global, comunic\u00f3 hoy la compa\u00f1\u00eda desde Berl\u00edn al presentar sus resultados anuales. Tras descontar los costes derivados del esc\u00e1ndalo de manipulaci\u00f3n de once millones de veh\u00edculos que salt\u00f3","og:url":"https:\/\/candas365.es\/noticias\/volkswagen-dispara-ganancias-cupula-se-embolsa-50-millones-de-euros\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/03\/euros.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/03\/euros.jpg","og:image:width":360,"og:image:height":235,"article:published_time":"2018-03-14T01:24:19+00:00","article:modified_time":"2018-03-14T01:24:19+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Volkswagen dispara ganancias: C\u00fapula se embolsa 50 millones de euros | Cand\u00e1s 365","twitter:description":"Berl\u00edn, 13 mar (dpa) - Los beneficios de la automotriz alemana Volkswagen se dispararon notablemente en 2017 impulsados por la importante demanda de autom\u00f3viles en el mercado global, comunic\u00f3 hoy la compa\u00f1\u00eda desde Berl\u00edn al presentar sus resultados anuales. Tras descontar los costes derivados del esc\u00e1ndalo de manipulaci\u00f3n de once millones de veh\u00edculos que salt\u00f3","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/03\/euros.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"91421","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-26 14:55:10","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 11:55:01","updated":"2025-08-26 14:55:10"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/\" title=\"Canal Empresas\">Canal Empresas<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tVolkswagen dispara ganancias: C\u00fapula se embolsa 50 millones de euros\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Canal Empresas","link":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/"},{"label":"Volkswagen dispara ganancias: C\u00fapula se embolsa 50 millones de euros","link":"https:\/\/candas365.es\/noticias\/volkswagen-dispara-ganancias-cupula-se-embolsa-50-millones-de-euros\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/91421","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=91421"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/91421\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/8123"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=91421"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=91421"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=91421"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}