{"id":91411,"date":"2018-03-14T01:17:56","date_gmt":"2018-03-14T01:17:56","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=91411"},"modified":"2018-03-14T01:17:56","modified_gmt":"2018-03-14T01:17:56","slug":"socio-discolo-de-merkel-deja-baviera-y-augura-batalla-en-berlin","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/socio-discolo-de-merkel-deja-baviera-y-augura-batalla-en-berlin\/","title":{"rendered":"Socio d\u00edscolo de Merkel deja Baviera y augura batalla en Berl\u00edn"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-85069\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720-360x240.jpg\" alt=\"\" width=\"360\" height=\"240\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720-360x240.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720-768x512.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720-655x437.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720-696x464.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720-630x420.jpg 630w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720-84x55.jpg 84w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720.jpg 960w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>M\u00fanich, 13 mar (dpa) &#8211; Horst Seehofer, el socio conservador de la canciller alemana, Angela Merkel, y uno de sus aliados m\u00e1s d\u00edscolos se despidi\u00f3 hoy de la jefatura de Gobierno de Baviera en la v\u00edspera de jurar su cargo como ministro del Interior en Berl\u00edn, como miembro del nuevo Gobierno germano.<\/p>\n<p>\u00abMi base va a seguir siendo Baviera (&#8230;). Todav\u00eda est\u00e1 por ver si busco una vivienda en Berl\u00edn o si me quedo en el s\u00f3tano del ministerio\u00bb, se\u00f1al\u00f3 el veterano pol\u00edtico, de 68 a\u00f1os, tras presidir hoy su \u00faltimo Consejo de Gobierno en M\u00fanich.<\/p>\n<p>El bar\u00f3n de la conservadora Uni\u00f3n Cristianosocial (CSU), que gobernaba la pr\u00f3spera regi\u00f3n del sur de Alemania con mayor\u00eda absoluta desde hace nueve a\u00f1os, hace las maletas para instalarse en la capital alemana tras poner fin a la lucha de poder que manten\u00eda con su principal rival interno, su hasta ahora ministro de Finanzas, Markus S\u00f6der, que pasar\u00e1 a convertirse en su sucesor.<\/p>\n<p>Su salida del Gobierno regional, no obstante, no va ligada a un abandono de la c\u00fapula partido, que el pol\u00edtico conservador continuar\u00e1 presidiendo de aqu\u00ed en adelante.<\/p>\n<p>Seehofer luchaba por su supervivencia pol\u00edtica desde las elecciones generales del pasado septiembre, en las que su agrupaci\u00f3n, acostumbrada a obtener mayor\u00edas absolutas, obtuvo un 38,8 por ciento de los votos.<\/p>\n<p>La CSU fue el partido m\u00e1s castigado en las urnas, con una p\u00e9rdida de casi diez puntos respecto de 2013. Esto coincidi\u00f3 con el mete\u00f3rico ascenso de la ultraderechista Alternativa para Alemania (AfD) tras la llegada en 2015 y 2016 de m\u00e1s de 1,2 millones de refugiados.<\/p>\n<p>El resultado y los temores de perder la mayor\u00eda absoluta en los comicios regionales que este a\u00f1o se celebrar\u00e1n en Baviera desataron luchas intestinas entre Seehofer y S\u00f6der.<\/p>\n<p>S\u00f6der, de 50 a\u00f1os, result\u00f3 ganador de la contienda. El pol\u00edtico ser\u00e1 elegido este viernes primer ministro b\u00e1varo y a final de a\u00f1o se convertir\u00e1 tambi\u00e9n en el candidato de la CSU a los comicios regionales en las que la CSU buscar\u00e1 retener la mayor\u00eda absoluta.<\/p>\n<p>Por ese entonces, Seehofer estar\u00e1 previsiblemente muy asentado en su sill\u00f3n de ministro del Interior. Como responsable de la pol\u00edtica migratoria quiz\u00e1s vuelva a poner en m\u00e1s de un apuro a su aliada Angela Merkel. Ya en el pasado, en su condici\u00f3n de dirigente del estado al que llegaron la mayor\u00eda de refugiados en 2015, no dud\u00f3 en criticarla en p\u00fablico de una manera humillante, incluso sin importarle que la canciller estuviera presente.<\/p>\n<p>Por Mar\u00eda Prieto (dpa)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00fanich, 13 mar (dpa) &#8211; Horst Seehofer, el socio conservador de la canciller alemana, Angela Merkel, y uno de sus aliados m\u00e1s d\u00edscolos se despidi\u00f3 hoy de la jefatura de Gobierno de Baviera en la v\u00edspera de jurar su cargo como ministro del Interior en Berl\u00edn, como miembro del nuevo Gobierno germano. \u00abMi base va<\/p>\n","protected":false},"author":1,"featured_media":85069,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343],"tags":[],"class_list":["post-91411","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"M\u00fanich, 13 mar (dpa) - Horst Seehofer, el socio conservador de la canciller alemana, Angela Merkel, y uno de sus aliados m\u00e1s d\u00edscolos se despidi\u00f3 hoy de la jefatura de Gobierno de Baviera en la v\u00edspera de jurar su cargo como ministro del Interior en Berl\u00edn, como miembro del nuevo Gobierno germano. &quot;Mi base va\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/socio-discolo-de-merkel-deja-baviera-y-augura-batalla-en-berlin\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Socio d\u00edscolo de Merkel deja Baviera y augura batalla en Berl\u00edn | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"M\u00fanich, 13 mar (dpa) - Horst Seehofer, el socio conservador de la canciller alemana, Angela Merkel, y uno de sus aliados m\u00e1s d\u00edscolos se despidi\u00f3 hoy de la jefatura de Gobierno de Baviera en la v\u00edspera de jurar su cargo como ministro del Interior en Berl\u00edn, como miembro del nuevo Gobierno germano. &quot;Mi base va\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/socio-discolo-de-merkel-deja-baviera-y-augura-batalla-en-berlin\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-03-14T01:17:56+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-03-14T01:17:56+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Socio d\u00edscolo de Merkel deja Baviera y augura batalla en Berl\u00edn | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"M\u00fanich, 13 mar (dpa) - Horst Seehofer, el socio conservador de la canciller alemana, Angela Merkel, y uno de sus aliados m\u00e1s d\u00edscolos se despidi\u00f3 hoy de la jefatura de Gobierno de Baviera en la v\u00edspera de jurar su cargo como ministro del Interior en Berl\u00edn, como miembro del nuevo Gobierno germano. &quot;Mi base va\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/socio-discolo-de-merkel-deja-baviera-y-augura-batalla-en-berlin\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/socio-discolo-de-merkel-deja-baviera-y-augura-batalla-en-berlin\\\/#listItem\",\"name\":\"Socio d\\u00edscolo de Merkel deja Baviera y augura batalla en Berl\\u00edn\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/socio-discolo-de-merkel-deja-baviera-y-augura-batalla-en-berlin\\\/#listItem\",\"position\":3,\"name\":\"Socio d\\u00edscolo de Merkel deja Baviera y augura batalla en Berl\\u00edn\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/socio-discolo-de-merkel-deja-baviera-y-augura-batalla-en-berlin\\\/#newsarticle\",\"name\":\"Socio d\\u00edscolo de Merkel deja Baviera y augura batalla en Berl\\u00edn | Cand\\u00e1s 365\",\"headline\":\"Socio d\\u00edscolo de Merkel deja Baviera y augura batalla en Berl\\u00edn\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/bundestag-2463231_960_720.jpg\",\"width\":960,\"height\":640,\"caption\":\"bundestag\"},\"datePublished\":\"2018-03-14T01:17:56+01:00\",\"dateModified\":\"2018-03-14T01:17:56+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/socio-discolo-de-merkel-deja-baviera-y-augura-batalla-en-berlin\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/socio-discolo-de-merkel-deja-baviera-y-augura-batalla-en-berlin\\\/#webpage\"},\"articleSection\":\"Actualidad\",\"dateline\":\"Publicado el marzo 14, 2018.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/socio-discolo-de-merkel-deja-baviera-y-augura-batalla-en-berlin\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/socio-discolo-de-merkel-deja-baviera-y-augura-batalla-en-berlin\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/socio-discolo-de-merkel-deja-baviera-y-augura-batalla-en-berlin\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/socio-discolo-de-merkel-deja-baviera-y-augura-batalla-en-berlin\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/socio-discolo-de-merkel-deja-baviera-y-augura-batalla-en-berlin\\\/\",\"name\":\"Socio d\\u00edscolo de Merkel deja Baviera y augura batalla en Berl\\u00edn | Cand\\u00e1s 365\",\"description\":\"M\\u00fanich, 13 mar (dpa) - Horst Seehofer, el socio conservador de la canciller alemana, Angela Merkel, y uno de sus aliados m\\u00e1s d\\u00edscolos se despidi\\u00f3 hoy de la jefatura de Gobierno de Baviera en la v\\u00edspera de jurar su cargo como ministro del Interior en Berl\\u00edn, como miembro del nuevo Gobierno germano. \\\"Mi base va\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/socio-discolo-de-merkel-deja-baviera-y-augura-batalla-en-berlin\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/bundestag-2463231_960_720.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/socio-discolo-de-merkel-deja-baviera-y-augura-batalla-en-berlin\\\/#mainImage\",\"width\":960,\"height\":640,\"caption\":\"bundestag\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/socio-discolo-de-merkel-deja-baviera-y-augura-batalla-en-berlin\\\/#mainImage\"},\"datePublished\":\"2018-03-14T01:17:56+01:00\",\"dateModified\":\"2018-03-14T01:17:56+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Socio d\u00edscolo de Merkel deja Baviera y augura batalla en Berl\u00edn | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Socio d\u00edscolo de Merkel deja Baviera y augura batalla en Berl\u00edn | Cand\u00e1s 365","description":"M\u00fanich, 13 mar (dpa) - Horst Seehofer, el socio conservador de la canciller alemana, Angela Merkel, y uno de sus aliados m\u00e1s d\u00edscolos se despidi\u00f3 hoy de la jefatura de Gobierno de Baviera en la v\u00edspera de jurar su cargo como ministro del Interior en Berl\u00edn, como miembro del nuevo Gobierno germano. \"Mi base va","canonical_url":"https:\/\/candas365.es\/noticias\/socio-discolo-de-merkel-deja-baviera-y-augura-batalla-en-berlin\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/socio-discolo-de-merkel-deja-baviera-y-augura-batalla-en-berlin\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/candas365.es\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/socio-discolo-de-merkel-deja-baviera-y-augura-batalla-en-berlin\/#listItem","name":"Socio d\u00edscolo de Merkel deja Baviera y augura batalla en Berl\u00edn"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/socio-discolo-de-merkel-deja-baviera-y-augura-batalla-en-berlin\/#listItem","position":3,"name":"Socio d\u00edscolo de Merkel deja Baviera y augura batalla en Berl\u00edn","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/socio-discolo-de-merkel-deja-baviera-y-augura-batalla-en-berlin\/#newsarticle","name":"Socio d\u00edscolo de Merkel deja Baviera y augura batalla en Berl\u00edn | Cand\u00e1s 365","headline":"Socio d\u00edscolo de Merkel deja Baviera y augura batalla en Berl\u00edn","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720.jpg","width":960,"height":640,"caption":"bundestag"},"datePublished":"2018-03-14T01:17:56+01:00","dateModified":"2018-03-14T01:17:56+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/socio-discolo-de-merkel-deja-baviera-y-augura-batalla-en-berlin\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/socio-discolo-de-merkel-deja-baviera-y-augura-batalla-en-berlin\/#webpage"},"articleSection":"Actualidad","dateline":"Publicado el marzo 14, 2018."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/socio-discolo-de-merkel-deja-baviera-y-augura-batalla-en-berlin\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/socio-discolo-de-merkel-deja-baviera-y-augura-batalla-en-berlin\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/socio-discolo-de-merkel-deja-baviera-y-augura-batalla-en-berlin\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/socio-discolo-de-merkel-deja-baviera-y-augura-batalla-en-berlin\/#webpage","url":"https:\/\/candas365.es\/noticias\/socio-discolo-de-merkel-deja-baviera-y-augura-batalla-en-berlin\/","name":"Socio d\u00edscolo de Merkel deja Baviera y augura batalla en Berl\u00edn | Cand\u00e1s 365","description":"M\u00fanich, 13 mar (dpa) - Horst Seehofer, el socio conservador de la canciller alemana, Angela Merkel, y uno de sus aliados m\u00e1s d\u00edscolos se despidi\u00f3 hoy de la jefatura de Gobierno de Baviera en la v\u00edspera de jurar su cargo como ministro del Interior en Berl\u00edn, como miembro del nuevo Gobierno germano. \"Mi base va","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/socio-discolo-de-merkel-deja-baviera-y-augura-batalla-en-berlin\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720.jpg","@id":"https:\/\/candas365.es\/noticias\/socio-discolo-de-merkel-deja-baviera-y-augura-batalla-en-berlin\/#mainImage","width":960,"height":640,"caption":"bundestag"},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/socio-discolo-de-merkel-deja-baviera-y-augura-batalla-en-berlin\/#mainImage"},"datePublished":"2018-03-14T01:17:56+01:00","dateModified":"2018-03-14T01:17:56+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Socio d\u00edscolo de Merkel deja Baviera y augura batalla en Berl\u00edn | Cand\u00e1s 365","og:description":"M\u00fanich, 13 mar (dpa) - Horst Seehofer, el socio conservador de la canciller alemana, Angela Merkel, y uno de sus aliados m\u00e1s d\u00edscolos se despidi\u00f3 hoy de la jefatura de Gobierno de Baviera en la v\u00edspera de jurar su cargo como ministro del Interior en Berl\u00edn, como miembro del nuevo Gobierno germano. &quot;Mi base va","og:url":"https:\/\/candas365.es\/noticias\/socio-discolo-de-merkel-deja-baviera-y-augura-batalla-en-berlin\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720.jpg","og:image:width":960,"og:image:height":640,"article:published_time":"2018-03-14T01:17:56+00:00","article:modified_time":"2018-03-14T01:17:56+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Socio d\u00edscolo de Merkel deja Baviera y augura batalla en Berl\u00edn | Cand\u00e1s 365","twitter:description":"M\u00fanich, 13 mar (dpa) - Horst Seehofer, el socio conservador de la canciller alemana, Angela Merkel, y uno de sus aliados m\u00e1s d\u00edscolos se despidi\u00f3 hoy de la jefatura de Gobierno de Baviera en la v\u00edspera de jurar su cargo como ministro del Interior en Berl\u00edn, como miembro del nuevo Gobierno germano. &quot;Mi base va","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"91411","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-20 07:57:19","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 11:55:07","updated":"2026-05-20 07:57:19"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tSocio d\u00edscolo de Merkel deja Baviera y augura batalla en Berl\u00edn\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Actualidad","link":"https:\/\/candas365.es\/noticias\/category\/actualidad\/"},{"label":"Socio d\u00edscolo de Merkel deja Baviera y augura batalla en Berl\u00edn","link":"https:\/\/candas365.es\/noticias\/socio-discolo-de-merkel-deja-baviera-y-augura-batalla-en-berlin\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/91411","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=91411"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/91411\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/85069"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=91411"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=91411"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=91411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}