{"id":91356,"date":"2018-03-13T02:05:09","date_gmt":"2018-03-13T02:05:09","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=91356"},"modified":"2018-03-13T02:05:09","modified_gmt":"2018-03-13T02:05:09","slug":"firman-acuerdo-para-nuevo-gobierno-de-coalicion-de-merkel","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/firman-acuerdo-para-nuevo-gobierno-de-coalicion-de-merkel\/","title":{"rendered":"Firman acuerdo para nuevo Gobierno de coalici\u00f3n de Merkel"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-85069\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720-360x240.jpg\" alt=\"\" width=\"360\" height=\"240\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720-360x240.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720-768x512.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720-655x437.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720-696x464.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720-630x420.jpg 630w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720-84x55.jpg 84w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720.jpg 960w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Berl\u00edn, 12 mar (dpa) &#8211; Casi seis meses despu\u00e9s de las elecciones generales, los conservadores de la canciller Angela Merkel y los socialdem\u00f3cratas firmaron finalmente el lunes el contrato de coalici\u00f3n para reeditar la alianza de Gobierno, en una ceremonia en uno de los edificios del Parlamento alem\u00e1n.<\/p>\n<p>\u00abEl contrato establece las bases para tener un Gobierno estable y un Gobierno con capacidad para actuar\u00bb, declar\u00f3 la presidenta de la Uni\u00f3n Cristianodem\u00f3crata (CDU) durante la concurrida ceremonia. \u00abIncluye mejoras concretas para las personas\u00bb, indic\u00f3.<\/p>\n<p>Merkel, l\u00edder de la Uni\u00f3n Cristianosocial (CSU), Horst Seehofer, y el presidente interino del Partido Socialdem\u00f3crata (SPD), Olaf Scholz, estamparon su firma en el documento en un acto oficial en donde estuvieron acompa\u00f1ados de la plana mayor del futuro Ejecutivo.<\/p>\n<p>\u00abTenemos mucho trabajo por delante. Trabajo duro\u00bb, reconoci\u00f3 la mandataria, que poco antes compareci\u00f3 con sus futuros socios de Gobierno ante la prensa durante m\u00e1s de una hora e indic\u00f3 que \u00abes hora de comenzar con el trabajo\u00bb.<\/p>\n<p>La mandataria destac\u00f3 que la nueva coalici\u00f3n de Gobierno trabajar\u00e1 a favor de una mayor din\u00e1mica para Europa y para Alemania. \u00abLa gran coalici\u00f3n se concentrar\u00e1 en lo que necesitan y quieren las personas\u00bb, afirm\u00f3. \u00abLas personas quieren un Estado con capacidad para actuar. Tenemos mucho trabajo ante nosotros y queremos ponernos con ello\u00bb, se\u00f1al\u00f3.<\/p>\n<p>\u00abFirmamos un contrato de coalici\u00f3n para fomentar nuestro pa\u00eds y nuestra sociedad\u00bb, coment\u00f3 por su parte Scholz. \u00abNuestro pa\u00eds est\u00e1 en una buena posici\u00f3n y tenemos raz\u00f3n para mirar el futuro con optimismo\u00bb, indic\u00f3 el presidente interino del partido hasta que Andrea Nahles sea elegida l\u00edder del SPD en abril. \u00abSer\u00e1 un buen Gobierno\u00bb, afirm\u00f3. \u00abY un Gobierno social\u00bb, agreg\u00f3 por su parte Seehofer.<\/p>\n<p>El contrato de coalici\u00f3n hab\u00eda sido firmado de manera provisional por Merkel, as\u00ed como por el entonces l\u00edder del SPD, Martin Schulz, y por Seehofer, cuando concluyeron las negociaciones formales entre los tres partidos a principios de febrero.<\/p>\n<p>Sin embargo, no fue hasta primeros de marzo cuando la potencia europea salv\u00f3 el \u00faltimo escollo necesario para poner en marcha un nuevo Ejecutivo, despu\u00e9s de que el SPD confirmara que su militancia daba el visto bueno a la reedici\u00f3n de la alianza que ya dirigi\u00f3 los designios del pa\u00eds durante los \u00faltimos cuatro a\u00f1os.<\/p>\n<p>\u00abLa cuarta gran coalici\u00f3n en Alemania no parti\u00f3 como un matrimonio de amor\u00bb, reconoci\u00f3 Scholz sobre las dificultades para lograr una alianza. \u00abSin embargo, estamos en situaci\u00f3n de cooperar de manera constructiva entre nosotros y gobernar de manera adecuada\u00bb.<\/p>\n<p>\u00abEl SPD quiere gobernar para lograr una mayor justicia social en Alemania\u00bb, record\u00f3. \u00abPaso a paso, d\u00eda a d\u00eda\u00bb, agreg\u00f3 Scholz. Mientras, Seehofer coment\u00f3 que los alemanes esperan tras meses de negociaciones \u00abuna r\u00e1pida implementaci\u00f3n del contrato de coalici\u00f3n\u00bb.<\/p>\n<p>El mi\u00e9rcoles, m\u00e1s de cinco meses despu\u00e9s de celebrar elecciones generales, Merkel ser\u00e1 investida en el Parlamento alem\u00e1n como canciller por cuarta vez consecutiva y Alemania contar\u00e1 por fin con un Gobierno con plenos poderes, despu\u00e9s de que los conservadores ganaran los comicios, pero sin la mayor\u00eda necesaria para gobernar en solitario.<\/p>\n<p>El retraso en la formaci\u00f3n de Gobierno se debi\u00f3 a que en un principio Merkel intent\u00f3 forjar una in\u00e9dita alianza con el Partido Liberal (FDP) y Los Verdes, despu\u00e9s de que los socialdem\u00f3cratas, tras sufrir su peor resultado hist\u00f3rico desde 1949, descartaran categ\u00f3ricamente la misma noche electoral formar parte del Gobierno y anunciaran a bombo y platillo que pasar\u00edan a las filas de la oposici\u00f3n.<\/p>\n<p>El fracaso de las negociaciones oblig\u00f3 al SPD a replantearse su postura de volver a la oposici\u00f3n y la presi\u00f3n social y pol\u00edtica les empuj\u00f3 a sentarse a negociar con los conservadores en un intento por evitar nuevas elecciones en el pa\u00eds. Finalmente, tras d\u00edas intensos de negociaciones y lograr el voto a favor de los delegados y despu\u00e9s de los militantes, el SPD dio luz verde al nuevo Gobierno.<\/p>\n<p>Las negociaciones acabaron dividiendo al SPD. Poco despu\u00e9s de alcanzar el acuerdo, Schulz anunci\u00f3 su decisi\u00f3n de dejar su puesto como l\u00edder del SPD a favor de la presidenta del grupo parlamentario del SPD, Andrea Nahles, con el objetivo de ser el nuevo ministro de Exteriores de Alemania.<\/p>\n<p>Sin embargo, sus deseos de ocupar esa poderosa cartera se vieron truncados debido a la presi\u00f3n interna de su partido, que lo acus\u00f3 de no ser fiel a su palabra al haber dicho en el pasado que nunca formar\u00eda parte de un Gobierno liderado por Merkel. Dos d\u00edas despu\u00e9s del anuncio, volvi\u00f3 a salir a la palestra para renunciar a su intenci\u00f3n de ser ministro de Exteriores.<\/p>\n<p>Por Almudena de Cabo (dpa)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Berl\u00edn, 12 mar (dpa) &#8211; Casi seis meses despu\u00e9s de las elecciones generales, los conservadores de la canciller Angela Merkel y los socialdem\u00f3cratas firmaron finalmente el lunes el contrato de coalici\u00f3n para reeditar la alianza de Gobierno, en una ceremonia en uno de los edificios del Parlamento alem\u00e1n. \u00abEl contrato establece las bases para tener<\/p>\n","protected":false},"author":1,"featured_media":85069,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343],"tags":[],"class_list":["post-91356","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Berl\u00edn, 12 mar (dpa) - Casi seis meses despu\u00e9s de las elecciones generales, los conservadores de la canciller Angela Merkel y los socialdem\u00f3cratas firmaron finalmente el lunes el contrato de coalici\u00f3n para reeditar la alianza de Gobierno, en una ceremonia en uno de los edificios del Parlamento alem\u00e1n. &quot;El contrato establece las bases para tener\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/firman-acuerdo-para-nuevo-gobierno-de-coalicion-de-merkel\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Firman acuerdo para nuevo Gobierno de coalici\u00f3n de Merkel | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Berl\u00edn, 12 mar (dpa) - Casi seis meses despu\u00e9s de las elecciones generales, los conservadores de la canciller Angela Merkel y los socialdem\u00f3cratas firmaron finalmente el lunes el contrato de coalici\u00f3n para reeditar la alianza de Gobierno, en una ceremonia en uno de los edificios del Parlamento alem\u00e1n. &quot;El contrato establece las bases para tener\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/firman-acuerdo-para-nuevo-gobierno-de-coalicion-de-merkel\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-03-13T02:05:09+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-03-13T02:05:09+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Firman acuerdo para nuevo Gobierno de coalici\u00f3n de Merkel | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Berl\u00edn, 12 mar (dpa) - Casi seis meses despu\u00e9s de las elecciones generales, los conservadores de la canciller Angela Merkel y los socialdem\u00f3cratas firmaron finalmente el lunes el contrato de coalici\u00f3n para reeditar la alianza de Gobierno, en una ceremonia en uno de los edificios del Parlamento alem\u00e1n. &quot;El contrato establece las bases para tener\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/firman-acuerdo-para-nuevo-gobierno-de-coalicion-de-merkel\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/firman-acuerdo-para-nuevo-gobierno-de-coalicion-de-merkel\\\/#listItem\",\"name\":\"Firman acuerdo para nuevo Gobierno de coalici\\u00f3n de Merkel\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/firman-acuerdo-para-nuevo-gobierno-de-coalicion-de-merkel\\\/#listItem\",\"position\":3,\"name\":\"Firman acuerdo para nuevo Gobierno de coalici\\u00f3n de Merkel\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/firman-acuerdo-para-nuevo-gobierno-de-coalicion-de-merkel\\\/#newsarticle\",\"name\":\"Firman acuerdo para nuevo Gobierno de coalici\\u00f3n de Merkel | Cand\\u00e1s 365\",\"headline\":\"Firman acuerdo para nuevo Gobierno de coalici\\u00f3n de Merkel\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/bundestag-2463231_960_720.jpg\",\"width\":960,\"height\":640,\"caption\":\"bundestag\"},\"datePublished\":\"2018-03-13T02:05:09+01:00\",\"dateModified\":\"2018-03-13T02:05:09+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/firman-acuerdo-para-nuevo-gobierno-de-coalicion-de-merkel\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/firman-acuerdo-para-nuevo-gobierno-de-coalicion-de-merkel\\\/#webpage\"},\"articleSection\":\"Actualidad\",\"dateline\":\"Publicado el marzo 13, 2018.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/firman-acuerdo-para-nuevo-gobierno-de-coalicion-de-merkel\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/firman-acuerdo-para-nuevo-gobierno-de-coalicion-de-merkel\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/firman-acuerdo-para-nuevo-gobierno-de-coalicion-de-merkel\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/firman-acuerdo-para-nuevo-gobierno-de-coalicion-de-merkel\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/firman-acuerdo-para-nuevo-gobierno-de-coalicion-de-merkel\\\/\",\"name\":\"Firman acuerdo para nuevo Gobierno de coalici\\u00f3n de Merkel | Cand\\u00e1s 365\",\"description\":\"Berl\\u00edn, 12 mar (dpa) - Casi seis meses despu\\u00e9s de las elecciones generales, los conservadores de la canciller Angela Merkel y los socialdem\\u00f3cratas firmaron finalmente el lunes el contrato de coalici\\u00f3n para reeditar la alianza de Gobierno, en una ceremonia en uno de los edificios del Parlamento alem\\u00e1n. \\\"El contrato establece las bases para tener\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/firman-acuerdo-para-nuevo-gobierno-de-coalicion-de-merkel\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/bundestag-2463231_960_720.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/firman-acuerdo-para-nuevo-gobierno-de-coalicion-de-merkel\\\/#mainImage\",\"width\":960,\"height\":640,\"caption\":\"bundestag\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/firman-acuerdo-para-nuevo-gobierno-de-coalicion-de-merkel\\\/#mainImage\"},\"datePublished\":\"2018-03-13T02:05:09+01:00\",\"dateModified\":\"2018-03-13T02:05:09+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Firman acuerdo para nuevo Gobierno de coalici\u00f3n de Merkel | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Firman acuerdo para nuevo Gobierno de coalici\u00f3n de Merkel | Cand\u00e1s 365","description":"Berl\u00edn, 12 mar (dpa) - Casi seis meses despu\u00e9s de las elecciones generales, los conservadores de la canciller Angela Merkel y los socialdem\u00f3cratas firmaron finalmente el lunes el contrato de coalici\u00f3n para reeditar la alianza de Gobierno, en una ceremonia en uno de los edificios del Parlamento alem\u00e1n. \"El contrato establece las bases para tener","canonical_url":"https:\/\/candas365.es\/noticias\/firman-acuerdo-para-nuevo-gobierno-de-coalicion-de-merkel\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/firman-acuerdo-para-nuevo-gobierno-de-coalicion-de-merkel\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/candas365.es\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/firman-acuerdo-para-nuevo-gobierno-de-coalicion-de-merkel\/#listItem","name":"Firman acuerdo para nuevo Gobierno de coalici\u00f3n de Merkel"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/firman-acuerdo-para-nuevo-gobierno-de-coalicion-de-merkel\/#listItem","position":3,"name":"Firman acuerdo para nuevo Gobierno de coalici\u00f3n de Merkel","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/firman-acuerdo-para-nuevo-gobierno-de-coalicion-de-merkel\/#newsarticle","name":"Firman acuerdo para nuevo Gobierno de coalici\u00f3n de Merkel | Cand\u00e1s 365","headline":"Firman acuerdo para nuevo Gobierno de coalici\u00f3n de Merkel","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720.jpg","width":960,"height":640,"caption":"bundestag"},"datePublished":"2018-03-13T02:05:09+01:00","dateModified":"2018-03-13T02:05:09+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/firman-acuerdo-para-nuevo-gobierno-de-coalicion-de-merkel\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/firman-acuerdo-para-nuevo-gobierno-de-coalicion-de-merkel\/#webpage"},"articleSection":"Actualidad","dateline":"Publicado el marzo 13, 2018."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/firman-acuerdo-para-nuevo-gobierno-de-coalicion-de-merkel\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/firman-acuerdo-para-nuevo-gobierno-de-coalicion-de-merkel\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/firman-acuerdo-para-nuevo-gobierno-de-coalicion-de-merkel\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/firman-acuerdo-para-nuevo-gobierno-de-coalicion-de-merkel\/#webpage","url":"https:\/\/candas365.es\/noticias\/firman-acuerdo-para-nuevo-gobierno-de-coalicion-de-merkel\/","name":"Firman acuerdo para nuevo Gobierno de coalici\u00f3n de Merkel | Cand\u00e1s 365","description":"Berl\u00edn, 12 mar (dpa) - Casi seis meses despu\u00e9s de las elecciones generales, los conservadores de la canciller Angela Merkel y los socialdem\u00f3cratas firmaron finalmente el lunes el contrato de coalici\u00f3n para reeditar la alianza de Gobierno, en una ceremonia en uno de los edificios del Parlamento alem\u00e1n. \"El contrato establece las bases para tener","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/firman-acuerdo-para-nuevo-gobierno-de-coalicion-de-merkel\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720.jpg","@id":"https:\/\/candas365.es\/noticias\/firman-acuerdo-para-nuevo-gobierno-de-coalicion-de-merkel\/#mainImage","width":960,"height":640,"caption":"bundestag"},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/firman-acuerdo-para-nuevo-gobierno-de-coalicion-de-merkel\/#mainImage"},"datePublished":"2018-03-13T02:05:09+01:00","dateModified":"2018-03-13T02:05:09+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Firman acuerdo para nuevo Gobierno de coalici\u00f3n de Merkel | Cand\u00e1s 365","og:description":"Berl\u00edn, 12 mar (dpa) - Casi seis meses despu\u00e9s de las elecciones generales, los conservadores de la canciller Angela Merkel y los socialdem\u00f3cratas firmaron finalmente el lunes el contrato de coalici\u00f3n para reeditar la alianza de Gobierno, en una ceremonia en uno de los edificios del Parlamento alem\u00e1n. &quot;El contrato establece las bases para tener","og:url":"https:\/\/candas365.es\/noticias\/firman-acuerdo-para-nuevo-gobierno-de-coalicion-de-merkel\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720.jpg","og:image:width":960,"og:image:height":640,"article:published_time":"2018-03-13T02:05:09+00:00","article:modified_time":"2018-03-13T02:05:09+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Firman acuerdo para nuevo Gobierno de coalici\u00f3n de Merkel | Cand\u00e1s 365","twitter:description":"Berl\u00edn, 12 mar (dpa) - Casi seis meses despu\u00e9s de las elecciones generales, los conservadores de la canciller Angela Merkel y los socialdem\u00f3cratas firmaron finalmente el lunes el contrato de coalici\u00f3n para reeditar la alianza de Gobierno, en una ceremonia en uno de los edificios del Parlamento alem\u00e1n. &quot;El contrato establece las bases para tener","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"4 minutos"},"aioseo_meta_data":{"post_id":"91356","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-20 07:47:15","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 11:55:07","updated":"2026-05-20 07:47:15"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tFirman acuerdo para nuevo Gobierno de coalici\u00f3n de Merkel\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Actualidad","link":"https:\/\/candas365.es\/noticias\/category\/actualidad\/"},{"label":"Firman acuerdo para nuevo Gobierno de coalici\u00f3n de Merkel","link":"https:\/\/candas365.es\/noticias\/firman-acuerdo-para-nuevo-gobierno-de-coalicion-de-merkel\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/91356","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=91356"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/91356\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/85069"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=91356"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=91356"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=91356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}