{"id":91319,"date":"2018-03-11T22:42:31","date_gmt":"2018-03-11T22:42:31","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=91319"},"modified":"2018-03-11T22:42:31","modified_gmt":"2018-03-11T22:42:31","slug":"continua-la-busqueda-de-la-mujer-desaparecida-en-santa-maria-del-mar","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/continua-la-busqueda-de-la-mujer-desaparecida-en-santa-maria-del-mar\/","title":{"rendered":"Contin\u00faa la b\u00fasqueda de la mujer desaparecida en Santa Mar\u00eda del Mar"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-16375\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/09\/mar-655x360-360x198.jpg\" alt=\"\" width=\"360\" height=\"198\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/09\/mar-655x360-360x198.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/09\/mar-655x360-650x357.jpg 650w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/09\/mar-655x360-150x82.jpg 150w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/09\/mar-655x360-450x247.jpg 450w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/09\/mar-655x360.jpg 655w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Bomberos del Servicio de Emergencias del Principado de Asturias (SEPA), al frente del operativo de rastreo de la mujer desaparecida en Santa Mar\u00eda del Mar en Castrill\u00f3n, ha organizado hoy 16 grupos de b\u00fasqueda con equipos mixtos de profesionales y ciudadanos.<\/p>\n<p>Debido a las condiciones meteorol\u00f3gicas en la zona se ha incrementado el n\u00famero de efectivos profesionales que acompa\u00f1an a cada grupo de ciudadanos en el rastreo.<\/p>\n<p>Dadas las condiciones de viento y las zonas de b\u00fasqueda en l\u00ednea de costa, Bomberos del SEPA est\u00e1 extremando las precauciones para garantizar la seguridad de los grupos, objetivo prioritario en este tipo de rastreos donde participan personas sin experiencia. Se ha limitado el n\u00famero de equipos para poder aumentar en cada uno de ellos el personal profesional que los acompa\u00f1a, entre 3 y 5 profesionales por cada 8 \u2013 10 ciudadanos.<\/p>\n<p>En lo que se refiere al rastreo se mantienen las 11 zonas de b\u00fasqueda y por aire se turnar\u00e1n el helic\u00f3ptero \u201cHelimer\u201d de Salvamento Mar\u00edtimo con uno de las aerenovaes de Bomberos del SEPA con el Grupo de Rescate.<\/p>\n<p>El rastreo con embarcaciones, por el momento, se ha suspendido dadas las condiciones de la mar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bomberos del Servicio de Emergencias del Principado de Asturias (SEPA), al frente del operativo de rastreo de la mujer desaparecida en Santa Mar\u00eda del Mar en Castrill\u00f3n, ha organizado hoy 16 grupos de b\u00fasqueda con equipos mixtos de profesionales y ciudadanos. Debido a las condiciones meteorol\u00f3gicas en la zona se ha incrementado el n\u00famero de<\/p>\n","protected":false},"author":1,"featured_media":16375,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-91319","post","type-post","status-publish","format-standard","has-post-thumbnail","category-asturias"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Bomberos del Servicio de Emergencias del Principado de Asturias (SEPA), al frente del operativo de rastreo de la mujer desaparecida en Santa Mar\u00eda del Mar en Castrill\u00f3n, ha organizado hoy 16 grupos de b\u00fasqueda con equipos mixtos de profesionales y ciudadanos. Debido a las condiciones meteorol\u00f3gicas en la zona se ha incrementado el n\u00famero de\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"asturias\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/continua-la-busqueda-de-la-mujer-desaparecida-en-santa-maria-del-mar\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Contin\u00faa la b\u00fasqueda de la mujer desaparecida en Santa Mar\u00eda del Mar | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Bomberos del Servicio de Emergencias del Principado de Asturias (SEPA), al frente del operativo de rastreo de la mujer desaparecida en Santa Mar\u00eda del Mar en Castrill\u00f3n, ha organizado hoy 16 grupos de b\u00fasqueda con equipos mixtos de profesionales y ciudadanos. Debido a las condiciones meteorol\u00f3gicas en la zona se ha incrementado el n\u00famero de\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/continua-la-busqueda-de-la-mujer-desaparecida-en-santa-maria-del-mar\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/09\/mar-655x360.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/09\/mar-655x360.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"655\" \/>\n\t\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-03-11T22:42:31+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-03-11T22:42:31+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Contin\u00faa la b\u00fasqueda de la mujer desaparecida en Santa Mar\u00eda del Mar | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Bomberos del Servicio de Emergencias del Principado de Asturias (SEPA), al frente del operativo de rastreo de la mujer desaparecida en Santa Mar\u00eda del Mar en Castrill\u00f3n, ha organizado hoy 16 grupos de b\u00fasqueda con equipos mixtos de profesionales y ciudadanos. Debido a las condiciones meteorol\u00f3gicas en la zona se ha incrementado el n\u00famero de\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/09\/mar-655x360.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/continua-la-busqueda-de-la-mujer-desaparecida-en-santa-maria-del-mar\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"name\":\"Asturias\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"position\":2,\"name\":\"Asturias\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/continua-la-busqueda-de-la-mujer-desaparecida-en-santa-maria-del-mar\\\/#listItem\",\"name\":\"Contin\\u00faa la b\\u00fasqueda de la mujer desaparecida en Santa Mar\\u00eda del Mar\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/continua-la-busqueda-de-la-mujer-desaparecida-en-santa-maria-del-mar\\\/#listItem\",\"position\":3,\"name\":\"Contin\\u00faa la b\\u00fasqueda de la mujer desaparecida en Santa Mar\\u00eda del Mar\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"name\":\"Asturias\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/continua-la-busqueda-de-la-mujer-desaparecida-en-santa-maria-del-mar\\\/#newsarticle\",\"name\":\"Contin\\u00faa la b\\u00fasqueda de la mujer desaparecida en Santa Mar\\u00eda del Mar | Cand\\u00e1s 365\",\"headline\":\"Contin\\u00faa la b\\u00fasqueda de la mujer desaparecida en Santa Mar\\u00eda del Mar\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/mar-655x360.jpg\",\"width\":655,\"height\":360},\"datePublished\":\"2018-03-11T22:42:31+01:00\",\"dateModified\":\"2018-03-11T22:42:31+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/continua-la-busqueda-de-la-mujer-desaparecida-en-santa-maria-del-mar\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/continua-la-busqueda-de-la-mujer-desaparecida-en-santa-maria-del-mar\\\/#webpage\"},\"articleSection\":\"Asturias\",\"dateline\":\"Publicado el marzo 11, 2018.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/continua-la-busqueda-de-la-mujer-desaparecida-en-santa-maria-del-mar\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/continua-la-busqueda-de-la-mujer-desaparecida-en-santa-maria-del-mar\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/continua-la-busqueda-de-la-mujer-desaparecida-en-santa-maria-del-mar\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/continua-la-busqueda-de-la-mujer-desaparecida-en-santa-maria-del-mar\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/continua-la-busqueda-de-la-mujer-desaparecida-en-santa-maria-del-mar\\\/\",\"name\":\"Contin\\u00faa la b\\u00fasqueda de la mujer desaparecida en Santa Mar\\u00eda del Mar | Cand\\u00e1s 365\",\"description\":\"Bomberos del Servicio de Emergencias del Principado de Asturias (SEPA), al frente del operativo de rastreo de la mujer desaparecida en Santa Mar\\u00eda del Mar en Castrill\\u00f3n, ha organizado hoy 16 grupos de b\\u00fasqueda con equipos mixtos de profesionales y ciudadanos. Debido a las condiciones meteorol\\u00f3gicas en la zona se ha incrementado el n\\u00famero de\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/continua-la-busqueda-de-la-mujer-desaparecida-en-santa-maria-del-mar\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/mar-655x360.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/continua-la-busqueda-de-la-mujer-desaparecida-en-santa-maria-del-mar\\\/#mainImage\",\"width\":655,\"height\":360},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/continua-la-busqueda-de-la-mujer-desaparecida-en-santa-maria-del-mar\\\/#mainImage\"},\"datePublished\":\"2018-03-11T22:42:31+01:00\",\"dateModified\":\"2018-03-11T22:42:31+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Contin\u00faa la b\u00fasqueda de la mujer desaparecida en Santa Mar\u00eda del Mar | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Contin\u00faa la b\u00fasqueda de la mujer desaparecida en Santa Mar\u00eda del Mar | Cand\u00e1s 365","description":"Bomberos del Servicio de Emergencias del Principado de Asturias (SEPA), al frente del operativo de rastreo de la mujer desaparecida en Santa Mar\u00eda del Mar en Castrill\u00f3n, ha organizado hoy 16 grupos de b\u00fasqueda con equipos mixtos de profesionales y ciudadanos. Debido a las condiciones meteorol\u00f3gicas en la zona se ha incrementado el n\u00famero de","canonical_url":"https:\/\/candas365.es\/noticias\/continua-la-busqueda-de-la-mujer-desaparecida-en-santa-maria-del-mar\/","robots":"max-image-preview:large","keywords":"asturias","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/continua-la-busqueda-de-la-mujer-desaparecida-en-santa-maria-del-mar\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","name":"Asturias"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","position":2,"name":"Asturias","item":"https:\/\/candas365.es\/noticias\/category\/asturias\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/continua-la-busqueda-de-la-mujer-desaparecida-en-santa-maria-del-mar\/#listItem","name":"Contin\u00faa la b\u00fasqueda de la mujer desaparecida en Santa Mar\u00eda del Mar"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/continua-la-busqueda-de-la-mujer-desaparecida-en-santa-maria-del-mar\/#listItem","position":3,"name":"Contin\u00faa la b\u00fasqueda de la mujer desaparecida en Santa Mar\u00eda del Mar","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","name":"Asturias"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/continua-la-busqueda-de-la-mujer-desaparecida-en-santa-maria-del-mar\/#newsarticle","name":"Contin\u00faa la b\u00fasqueda de la mujer desaparecida en Santa Mar\u00eda del Mar | Cand\u00e1s 365","headline":"Contin\u00faa la b\u00fasqueda de la mujer desaparecida en Santa Mar\u00eda del Mar","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/09\/mar-655x360.jpg","width":655,"height":360},"datePublished":"2018-03-11T22:42:31+01:00","dateModified":"2018-03-11T22:42:31+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/continua-la-busqueda-de-la-mujer-desaparecida-en-santa-maria-del-mar\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/continua-la-busqueda-de-la-mujer-desaparecida-en-santa-maria-del-mar\/#webpage"},"articleSection":"Asturias","dateline":"Publicado el marzo 11, 2018."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/continua-la-busqueda-de-la-mujer-desaparecida-en-santa-maria-del-mar\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/continua-la-busqueda-de-la-mujer-desaparecida-en-santa-maria-del-mar\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/continua-la-busqueda-de-la-mujer-desaparecida-en-santa-maria-del-mar\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/continua-la-busqueda-de-la-mujer-desaparecida-en-santa-maria-del-mar\/#webpage","url":"https:\/\/candas365.es\/noticias\/continua-la-busqueda-de-la-mujer-desaparecida-en-santa-maria-del-mar\/","name":"Contin\u00faa la b\u00fasqueda de la mujer desaparecida en Santa Mar\u00eda del Mar | Cand\u00e1s 365","description":"Bomberos del Servicio de Emergencias del Principado de Asturias (SEPA), al frente del operativo de rastreo de la mujer desaparecida en Santa Mar\u00eda del Mar en Castrill\u00f3n, ha organizado hoy 16 grupos de b\u00fasqueda con equipos mixtos de profesionales y ciudadanos. Debido a las condiciones meteorol\u00f3gicas en la zona se ha incrementado el n\u00famero de","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/continua-la-busqueda-de-la-mujer-desaparecida-en-santa-maria-del-mar\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/09\/mar-655x360.jpg","@id":"https:\/\/candas365.es\/noticias\/continua-la-busqueda-de-la-mujer-desaparecida-en-santa-maria-del-mar\/#mainImage","width":655,"height":360},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/continua-la-busqueda-de-la-mujer-desaparecida-en-santa-maria-del-mar\/#mainImage"},"datePublished":"2018-03-11T22:42:31+01:00","dateModified":"2018-03-11T22:42:31+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Contin\u00faa la b\u00fasqueda de la mujer desaparecida en Santa Mar\u00eda del Mar | Cand\u00e1s 365","og:description":"Bomberos del Servicio de Emergencias del Principado de Asturias (SEPA), al frente del operativo de rastreo de la mujer desaparecida en Santa Mar\u00eda del Mar en Castrill\u00f3n, ha organizado hoy 16 grupos de b\u00fasqueda con equipos mixtos de profesionales y ciudadanos. Debido a las condiciones meteorol\u00f3gicas en la zona se ha incrementado el n\u00famero de","og:url":"https:\/\/candas365.es\/noticias\/continua-la-busqueda-de-la-mujer-desaparecida-en-santa-maria-del-mar\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/09\/mar-655x360.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/09\/mar-655x360.jpg","og:image:width":655,"og:image:height":360,"article:published_time":"2018-03-11T22:42:31+00:00","article:modified_time":"2018-03-11T22:42:31+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Contin\u00faa la b\u00fasqueda de la mujer desaparecida en Santa Mar\u00eda del Mar | Cand\u00e1s 365","twitter:description":"Bomberos del Servicio de Emergencias del Principado de Asturias (SEPA), al frente del operativo de rastreo de la mujer desaparecida en Santa Mar\u00eda del Mar en Castrill\u00f3n, ha organizado hoy 16 grupos de b\u00fasqueda con equipos mixtos de profesionales y ciudadanos. Debido a las condiciones meteorol\u00f3gicas en la zona se ha incrementado el n\u00famero de","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/09\/mar-655x360.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"1 minuto"},"aioseo_meta_data":{"post_id":"91319","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-20 07:41:15","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 11:55:07","updated":"2026-05-20 07:41:15"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/asturias\/\" title=\"Asturias\">Asturias<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tContin\u00faa la b\u00fasqueda de la mujer desaparecida en Santa Mar\u00eda del Mar\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Asturias","link":"https:\/\/candas365.es\/noticias\/category\/asturias\/"},{"label":"Contin\u00faa la b\u00fasqueda de la mujer desaparecida en Santa Mar\u00eda del Mar","link":"https:\/\/candas365.es\/noticias\/continua-la-busqueda-de-la-mujer-desaparecida-en-santa-maria-del-mar\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/91319","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=91319"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/91319\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/16375"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=91319"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=91319"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=91319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}