{"id":91287,"date":"2018-03-11T08:18:21","date_gmt":"2018-03-11T08:18:21","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=91287"},"modified":"2018-03-11T08:18:21","modified_gmt":"2018-03-11T08:18:21","slug":"el-tiempo-11-de-marzo-de-2018","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/el-tiempo-11-de-marzo-de-2018\/","title":{"rendered":"El tiempo, 11 de marzo de 2018"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-20033\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/11\/NUBOSO2-360x270.jpg\" alt=\"\" width=\"360\" height=\"270\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/11\/NUBOSO2-360x270.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/11\/NUBOSO2-640x480.jpg 640w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/11\/NUBOSO2-768x576.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/11\/NUBOSO2-150x113.jpg 150w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/11\/NUBOSO2-450x338.jpg 450w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/11\/NUBOSO2-80x60.jpg 80w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/11\/NUBOSO2-265x198.jpg 265w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/11\/NUBOSO2-696x522.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/11\/NUBOSO2-560x420.jpg 560w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/11\/NUBOSO2-90x67.jpg 90w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/11\/NUBOSO2.jpg 1024w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Cielos muy nubosos o cubiertos con precipitaciones generalizadas en la mayor parte de la Pen\u00ednsula que pueden ir acompa\u00f1adas de tormentas, m\u00e1s probables e intensas hacia el oeste. En Galicia, oeste de Castilla y Le\u00f3n, norte de Extremadura, Pirineos, \u00e1rea del Estrecho y sierras orientales andaluzas, podr\u00e1n ser localmente fuertes y\/o persistentes. Se esperan nevadas en los sistemas monta\u00f1osos de la mitad norte peninsular. En el Cant\u00e1brico oriental son probables precipitaciones ocasionales y dispersas. Ser\u00e1n d\u00e9biles y menos probables en el Valle del Ebro, y en el extremo oriental de la Pen\u00ednsula, no esper\u00e1ndose precipitaciones en el litoral este peninsular. En Baleares no se descartan hacia el este del archipi\u00e9lago y no se esperan en Canarias.<\/p>\n<p>Cota de nieve en la Pen\u00ednsula: 1000\/1400 m en el noroeste, 1400\/1800 m en el resto bajando a 1200\/1400 m.<\/p>\n<p>Temperaturas en descenso generalizado, m\u00e1s acusado en el interior este peninsular, con heladas d\u00e9biles en zonas altas de la mitad norte peninsular.<\/p>\n<p>Viento de componente oeste y suroeste en la Pen\u00ednsula y Baleares, fuerte, con rachas muy fuertes en amplias zonas, especialmente en la costa gallega a primeras horas. En Canarias viento del noreste.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cielos muy nubosos o cubiertos con precipitaciones generalizadas en la mayor parte de la Pen\u00ednsula que pueden ir acompa\u00f1adas de tormentas, m\u00e1s probables e intensas hacia el oeste. En Galicia, oeste de Castilla y Le\u00f3n, norte de Extremadura, Pirineos, \u00e1rea del Estrecho y sierras orientales andaluzas, podr\u00e1n ser localmente fuertes y\/o persistentes. Se esperan nevadas<\/p>\n","protected":false},"author":1,"featured_media":20033,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-91287","post","type-post","status-publish","format-standard","has-post-thumbnail","category-agenda"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Cielos muy nubosos o cubiertos con precipitaciones generalizadas en la mayor parte de la Pen\u00ednsula que pueden ir acompa\u00f1adas de tormentas, m\u00e1s probables e intensas hacia el oeste. En Galicia, oeste de Castilla y Le\u00f3n, norte de Extremadura, Pirineos, \u00e1rea del Estrecho y sierras orientales andaluzas, podr\u00e1n ser localmente fuertes y\/o persistentes. Se esperan nevadas\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"agenda\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/el-tiempo-11-de-marzo-de-2018\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El tiempo, 11 de marzo de 2018 | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Cielos muy nubosos o cubiertos con precipitaciones generalizadas en la mayor parte de la Pen\u00ednsula que pueden ir acompa\u00f1adas de tormentas, m\u00e1s probables e intensas hacia el oeste. En Galicia, oeste de Castilla y Le\u00f3n, norte de Extremadura, Pirineos, \u00e1rea del Estrecho y sierras orientales andaluzas, podr\u00e1n ser localmente fuertes y\/o persistentes. Se esperan nevadas\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/el-tiempo-11-de-marzo-de-2018\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/11\/NUBOSO2.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/11\/NUBOSO2.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-03-11T08:18:21+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-03-11T08:18:21+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El tiempo, 11 de marzo de 2018 | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Cielos muy nubosos o cubiertos con precipitaciones generalizadas en la mayor parte de la Pen\u00ednsula que pueden ir acompa\u00f1adas de tormentas, m\u00e1s probables e intensas hacia el oeste. En Galicia, oeste de Castilla y Le\u00f3n, norte de Extremadura, Pirineos, \u00e1rea del Estrecho y sierras orientales andaluzas, podr\u00e1n ser localmente fuertes y\/o persistentes. Se esperan nevadas\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/11\/NUBOSO2.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-tiempo-11-de-marzo-de-2018\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/agenda\\\/#listItem\",\"name\":\"Agenda\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/agenda\\\/#listItem\",\"position\":2,\"name\":\"Agenda\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/agenda\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-tiempo-11-de-marzo-de-2018\\\/#listItem\",\"name\":\"El tiempo, 11 de marzo de 2018\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-tiempo-11-de-marzo-de-2018\\\/#listItem\",\"position\":3,\"name\":\"El tiempo, 11 de marzo de 2018\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/agenda\\\/#listItem\",\"name\":\"Agenda\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-tiempo-11-de-marzo-de-2018\\\/#newsarticle\",\"name\":\"El tiempo, 11 de marzo de 2018 | Cand\\u00e1s 365\",\"headline\":\"El tiempo, 11 de marzo de 2018\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/NUBOSO2.jpg\",\"width\":1024,\"height\":768,\"caption\":\"nuboso\"},\"datePublished\":\"2018-03-11T08:18:21+01:00\",\"dateModified\":\"2018-03-11T08:18:21+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-tiempo-11-de-marzo-de-2018\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-tiempo-11-de-marzo-de-2018\\\/#webpage\"},\"articleSection\":\"Agenda\",\"dateline\":\"Publicado el marzo 11, 2018.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-tiempo-11-de-marzo-de-2018\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-tiempo-11-de-marzo-de-2018\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-tiempo-11-de-marzo-de-2018\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-tiempo-11-de-marzo-de-2018\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-tiempo-11-de-marzo-de-2018\\\/\",\"name\":\"El tiempo, 11 de marzo de 2018 | Cand\\u00e1s 365\",\"description\":\"Cielos muy nubosos o cubiertos con precipitaciones generalizadas en la mayor parte de la Pen\\u00ednsula que pueden ir acompa\\u00f1adas de tormentas, m\\u00e1s probables e intensas hacia el oeste. En Galicia, oeste de Castilla y Le\\u00f3n, norte de Extremadura, Pirineos, \\u00e1rea del Estrecho y sierras orientales andaluzas, podr\\u00e1n ser localmente fuertes y\\\/o persistentes. Se esperan nevadas\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-tiempo-11-de-marzo-de-2018\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/NUBOSO2.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-tiempo-11-de-marzo-de-2018\\\/#mainImage\",\"width\":1024,\"height\":768,\"caption\":\"nuboso\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-tiempo-11-de-marzo-de-2018\\\/#mainImage\"},\"datePublished\":\"2018-03-11T08:18:21+01:00\",\"dateModified\":\"2018-03-11T08:18:21+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>El tiempo, 11 de marzo de 2018 | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"El tiempo, 11 de marzo de 2018 | Cand\u00e1s 365","description":"Cielos muy nubosos o cubiertos con precipitaciones generalizadas en la mayor parte de la Pen\u00ednsula que pueden ir acompa\u00f1adas de tormentas, m\u00e1s probables e intensas hacia el oeste. En Galicia, oeste de Castilla y Le\u00f3n, norte de Extremadura, Pirineos, \u00e1rea del Estrecho y sierras orientales andaluzas, podr\u00e1n ser localmente fuertes y\/o persistentes. Se esperan nevadas","canonical_url":"https:\/\/candas365.es\/noticias\/el-tiempo-11-de-marzo-de-2018\/","robots":"max-image-preview:large","keywords":"agenda","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/el-tiempo-11-de-marzo-de-2018\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/agenda\/#listItem","name":"Agenda"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/agenda\/#listItem","position":2,"name":"Agenda","item":"https:\/\/candas365.es\/noticias\/category\/agenda\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/el-tiempo-11-de-marzo-de-2018\/#listItem","name":"El tiempo, 11 de marzo de 2018"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/el-tiempo-11-de-marzo-de-2018\/#listItem","position":3,"name":"El tiempo, 11 de marzo de 2018","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/agenda\/#listItem","name":"Agenda"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/el-tiempo-11-de-marzo-de-2018\/#newsarticle","name":"El tiempo, 11 de marzo de 2018 | Cand\u00e1s 365","headline":"El tiempo, 11 de marzo de 2018","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/11\/NUBOSO2.jpg","width":1024,"height":768,"caption":"nuboso"},"datePublished":"2018-03-11T08:18:21+01:00","dateModified":"2018-03-11T08:18:21+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/el-tiempo-11-de-marzo-de-2018\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/el-tiempo-11-de-marzo-de-2018\/#webpage"},"articleSection":"Agenda","dateline":"Publicado el marzo 11, 2018."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/el-tiempo-11-de-marzo-de-2018\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/el-tiempo-11-de-marzo-de-2018\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/el-tiempo-11-de-marzo-de-2018\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/el-tiempo-11-de-marzo-de-2018\/#webpage","url":"https:\/\/candas365.es\/noticias\/el-tiempo-11-de-marzo-de-2018\/","name":"El tiempo, 11 de marzo de 2018 | Cand\u00e1s 365","description":"Cielos muy nubosos o cubiertos con precipitaciones generalizadas en la mayor parte de la Pen\u00ednsula que pueden ir acompa\u00f1adas de tormentas, m\u00e1s probables e intensas hacia el oeste. En Galicia, oeste de Castilla y Le\u00f3n, norte de Extremadura, Pirineos, \u00e1rea del Estrecho y sierras orientales andaluzas, podr\u00e1n ser localmente fuertes y\/o persistentes. Se esperan nevadas","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/el-tiempo-11-de-marzo-de-2018\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/11\/NUBOSO2.jpg","@id":"https:\/\/candas365.es\/noticias\/el-tiempo-11-de-marzo-de-2018\/#mainImage","width":1024,"height":768,"caption":"nuboso"},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/el-tiempo-11-de-marzo-de-2018\/#mainImage"},"datePublished":"2018-03-11T08:18:21+01:00","dateModified":"2018-03-11T08:18:21+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"El tiempo, 11 de marzo de 2018 | Cand\u00e1s 365","og:description":"Cielos muy nubosos o cubiertos con precipitaciones generalizadas en la mayor parte de la Pen\u00ednsula que pueden ir acompa\u00f1adas de tormentas, m\u00e1s probables e intensas hacia el oeste. En Galicia, oeste de Castilla y Le\u00f3n, norte de Extremadura, Pirineos, \u00e1rea del Estrecho y sierras orientales andaluzas, podr\u00e1n ser localmente fuertes y\/o persistentes. Se esperan nevadas","og:url":"https:\/\/candas365.es\/noticias\/el-tiempo-11-de-marzo-de-2018\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/11\/NUBOSO2.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/11\/NUBOSO2.jpg","og:image:width":1024,"og:image:height":768,"article:published_time":"2018-03-11T08:18:21+00:00","article:modified_time":"2018-03-11T08:18:21+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"El tiempo, 11 de marzo de 2018 | Cand\u00e1s 365","twitter:description":"Cielos muy nubosos o cubiertos con precipitaciones generalizadas en la mayor parte de la Pen\u00ednsula que pueden ir acompa\u00f1adas de tormentas, m\u00e1s probables e intensas hacia el oeste. En Galicia, oeste de Castilla y Le\u00f3n, norte de Extremadura, Pirineos, \u00e1rea del Estrecho y sierras orientales andaluzas, podr\u00e1n ser localmente fuertes y\/o persistentes. Se esperan nevadas","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/11\/NUBOSO2.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"1 minuto"},"aioseo_meta_data":{"post_id":"91287","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-20 07:34:18","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 11:55:07","updated":"2026-05-20 07:34:18"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/agenda\/\" title=\"Agenda\">Agenda<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tEl tiempo, 11 de marzo de 2018\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Agenda","link":"https:\/\/candas365.es\/noticias\/category\/agenda\/"},{"label":"El tiempo, 11 de marzo de 2018","link":"https:\/\/candas365.es\/noticias\/el-tiempo-11-de-marzo-de-2018\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/91287","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=91287"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/91287\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/20033"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=91287"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=91287"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=91287"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}