{"id":91195,"date":"2018-03-08T09:57:07","date_gmt":"2018-03-08T09:57:07","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=91195"},"modified":"2018-03-08T09:57:07","modified_gmt":"2018-03-08T09:57:07","slug":"el-principado-trabajara-para-evitar-el-acceso-de-los-menores-al-juego-y-las-apuestas","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/el-principado-trabajara-para-evitar-el-acceso-de-los-menores-al-juego-y-las-apuestas\/","title":{"rendered":"El Principado trabajar\u00e1 para evitar el acceso de los menores al juego y las apuestas"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-91196\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/Consejero-presentacion-protocolo-menores-juego-360x230.jpg\" alt=\"\" width=\"360\" height=\"230\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/Consejero-presentacion-protocolo-menores-juego-360x230.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/Consejero-presentacion-protocolo-menores-juego-696x444.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/Consejero-presentacion-protocolo-menores-juego-1068x682.jpg 1068w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/Consejero-presentacion-protocolo-menores-juego-658x420.jpg 658w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/Consejero-presentacion-protocolo-menores-juego-768x490.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/Consejero-presentacion-protocolo-menores-juego-655x418.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/Consejero-presentacion-protocolo-menores-juego.jpg 1280w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>El Gobierno de Asturias ha elaborado el primer protocolo auton\u00f3mico para reforzar las medidas que evitan el acceso de los menores a los juegos de azar y las apuestas. La iniciativa, pionera en el pa\u00eds, aborda los riesgos de este tipo de pr\u00e1cticas con el prop\u00f3sito de prevenir conductas adictivas y contribuir a que las entidades y colectivos implicados puedan ofrecer una respuesta coordinada y eficaz.<\/p>\n<p>El Protocolo de menores en materia de juego y apuestas contribuir\u00e1 a garantizar el cumplimiento de la normativa reguladora para frenar el acceso de j\u00f3venes que a\u00fan no han cumplido la mayor\u00eda de edad a los locales de este sector. Tambi\u00e9n fija los procedimientos de respuesta para favorecer la coordinaci\u00f3n interinstitucional en la intervenci\u00f3n preventiva.<\/p>\n<p>El \u00e1mbito de aplicaci\u00f3n de la gu\u00eda se circunscribe \u00fanicamente a las pr\u00e1cticas realizadas de modo presencial.<\/p>\n<p>Ante los potenciales riesgos para los menores y la preocupaci\u00f3n expresada por los representantes del sector, el nuevo protocolo busca mejorar la eficacia del conjunto de profesionales que se dedica a esta actividad, as\u00ed como de las instituciones p\u00fablicas y de las fuerzas y cuerpos de seguridad, y garantizar, adem\u00e1s, la protecci\u00f3n y atenci\u00f3n de los j\u00f3venes en las diferentes situaciones que pueden producirse.<\/p>\n<p>Para la elaboraci\u00f3n del documento se ha llevado a cabo un an\u00e1lisis previo de la poblaci\u00f3n joven de Asturias y su distribuci\u00f3n geogr\u00e1fica, y tambi\u00e9n una radiograf\u00eda del sector del juego, con la intenci\u00f3n de determinar acciones espec\u00edficas en funci\u00f3n de la clasificaci\u00f3n de los establecimientos por tipolog\u00eda y sistemas de control.<\/p>\n<p>El protocolo forma parte del plan de prevenci\u00f3n de la ludopat\u00eda en el que trabaja el Gobierno de Asturias y que se presentar\u00e1 pr\u00f3ximamente. Los objetivos de la gu\u00eda son los siguientes:<\/p>\n<p>&#8211; Recoger de manera ordenada y sistem\u00e1tica las actuaciones para la prevenci\u00f3n del juego en menores de edad.<\/p>\n<p>&#8211; Orientar y coordinar el trabajo de los profesionales y de los servicios de los \u00e1mbitos de intervenci\u00f3n implicados: empresas operadoras, polic\u00edas locales y el Grupo de Inspecci\u00f3n del Juego del Principado.<\/p>\n<p>&#8211; Implicar a sectores sociales e institucionales en la intervenci\u00f3n con menores de 18 a\u00f1os.<\/p>\n<p>&#8211; Dar visibilidad al problema y sensibilizar a la poblaci\u00f3n.<\/p>\n<p>&#8211; Fijar criterios comunes de intervenci\u00f3n.<\/p>\n<p>El consejero de Presidencia y Participaci\u00f3n Ciudadana, Guillermo Mart\u00ednez, ha expresado hoy su agradecimiento a todas las entidades que han colaborado en su elaboraci\u00f3n, \u201cpor la sensibilidad y la preocupaci\u00f3n mostradas para hacer frente de manera conjunta a un problem\u00e1tica que, m\u00e1s all\u00e1 del cumplimiento de la normativa, exige un verdadero ejercicio de responsabilidad colectiva\u201d, ha asegurado.<\/p>\n<p>A su juicio, el valor del protocolo radica principalmente en la manera en que se aborda la protecci\u00f3n de los menores mediante una respuesta integral y coordinada, fruto del consenso y la reflexi\u00f3n de todas las entidades representadas en el Consejo del Juego del Principado: empresas operadoras, administraciones, sindicatos, asociaciones de consumidores y usuarios, el Consejo de la Juventud y el colectivo de jugadores con ludopat\u00eda en rehabilitaci\u00f3n.<\/p>\n<p>Asturias cuenta con un Grupo de Inspecci\u00f3n del Juego integrado por cinco agentes de la Polic\u00eda Nacional, adscritos al Principado en virtud de un convenio de colaboraci\u00f3n con el Ministerio del Interior, que son los encargados de vigilar el cumplimiento de la normativa en materia de juego y apuestas. Para reforzar su labor, el Gobierno auton\u00f3mico ultima un nuevo plan inspector que aborda la realidad actual del sector con el fin de responder a las necesidades de forma ordenada y sistem\u00e1tica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gobierno de Asturias ha elaborado el primer protocolo auton\u00f3mico para reforzar las medidas que evitan el acceso de los menores a los juegos de azar y las apuestas. La iniciativa, pionera en el pa\u00eds, aborda los riesgos de este tipo de pr\u00e1cticas con el prop\u00f3sito de prevenir conductas adictivas y contribuir a que las<\/p>\n","protected":false},"author":1,"featured_media":91196,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-91195","post","type-post","status-publish","format-standard","has-post-thumbnail","category-asturias"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"El Gobierno de Asturias ha elaborado el primer protocolo auton\u00f3mico para reforzar las medidas que evitan el acceso de los menores a los juegos de azar y las apuestas. La iniciativa, pionera en el pa\u00eds, aborda los riesgos de este tipo de pr\u00e1cticas con el prop\u00f3sito de prevenir conductas adictivas y contribuir a que las\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"asturias\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/el-principado-trabajara-para-evitar-el-acceso-de-los-menores-al-juego-y-las-apuestas\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El Principado trabajar\u00e1 para evitar el acceso de los menores al juego y las apuestas | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"El Gobierno de Asturias ha elaborado el primer protocolo auton\u00f3mico para reforzar las medidas que evitan el acceso de los menores a los juegos de azar y las apuestas. La iniciativa, pionera en el pa\u00eds, aborda los riesgos de este tipo de pr\u00e1cticas con el prop\u00f3sito de prevenir conductas adictivas y contribuir a que las\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/el-principado-trabajara-para-evitar-el-acceso-de-los-menores-al-juego-y-las-apuestas\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/Consejero-presentacion-protocolo-menores-juego.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/Consejero-presentacion-protocolo-menores-juego.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t\t<meta property=\"og:image:height\" content=\"817\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-03-08T09:57:07+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-03-08T09:57:07+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El Principado trabajar\u00e1 para evitar el acceso de los menores al juego y las apuestas | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El Gobierno de Asturias ha elaborado el primer protocolo auton\u00f3mico para reforzar las medidas que evitan el acceso de los menores a los juegos de azar y las apuestas. La iniciativa, pionera en el pa\u00eds, aborda los riesgos de este tipo de pr\u00e1cticas con el prop\u00f3sito de prevenir conductas adictivas y contribuir a que las\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/Consejero-presentacion-protocolo-menores-juego.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-trabajara-para-evitar-el-acceso-de-los-menores-al-juego-y-las-apuestas\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"name\":\"Asturias\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"position\":2,\"name\":\"Asturias\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-trabajara-para-evitar-el-acceso-de-los-menores-al-juego-y-las-apuestas\\\/#listItem\",\"name\":\"El Principado trabajar\\u00e1 para evitar el acceso de los menores al juego y las apuestas\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-trabajara-para-evitar-el-acceso-de-los-menores-al-juego-y-las-apuestas\\\/#listItem\",\"position\":3,\"name\":\"El Principado trabajar\\u00e1 para evitar el acceso de los menores al juego y las apuestas\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"name\":\"Asturias\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-trabajara-para-evitar-el-acceso-de-los-menores-al-juego-y-las-apuestas\\\/#newsarticle\",\"name\":\"El Principado trabajar\\u00e1 para evitar el acceso de los menores al juego y las apuestas | Cand\\u00e1s 365\",\"headline\":\"El Principado trabajar\\u00e1 para evitar el acceso de los menores al juego y las apuestas\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/Consejero-presentacion-protocolo-menores-juego.jpg\",\"width\":1280,\"height\":817},\"datePublished\":\"2018-03-08T09:57:07+01:00\",\"dateModified\":\"2018-03-08T09:57:07+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-trabajara-para-evitar-el-acceso-de-los-menores-al-juego-y-las-apuestas\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-trabajara-para-evitar-el-acceso-de-los-menores-al-juego-y-las-apuestas\\\/#webpage\"},\"articleSection\":\"Asturias\",\"dateline\":\"Publicado el marzo 8, 2018.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-trabajara-para-evitar-el-acceso-de-los-menores-al-juego-y-las-apuestas\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-trabajara-para-evitar-el-acceso-de-los-menores-al-juego-y-las-apuestas\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-trabajara-para-evitar-el-acceso-de-los-menores-al-juego-y-las-apuestas\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-trabajara-para-evitar-el-acceso-de-los-menores-al-juego-y-las-apuestas\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-trabajara-para-evitar-el-acceso-de-los-menores-al-juego-y-las-apuestas\\\/\",\"name\":\"El Principado trabajar\\u00e1 para evitar el acceso de los menores al juego y las apuestas | Cand\\u00e1s 365\",\"description\":\"El Gobierno de Asturias ha elaborado el primer protocolo auton\\u00f3mico para reforzar las medidas que evitan el acceso de los menores a los juegos de azar y las apuestas. La iniciativa, pionera en el pa\\u00eds, aborda los riesgos de este tipo de pr\\u00e1cticas con el prop\\u00f3sito de prevenir conductas adictivas y contribuir a que las\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-trabajara-para-evitar-el-acceso-de-los-menores-al-juego-y-las-apuestas\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/Consejero-presentacion-protocolo-menores-juego.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-trabajara-para-evitar-el-acceso-de-los-menores-al-juego-y-las-apuestas\\\/#mainImage\",\"width\":1280,\"height\":817},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-trabajara-para-evitar-el-acceso-de-los-menores-al-juego-y-las-apuestas\\\/#mainImage\"},\"datePublished\":\"2018-03-08T09:57:07+01:00\",\"dateModified\":\"2018-03-08T09:57:07+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>El Principado trabajar\u00e1 para evitar el acceso de los menores al juego y las apuestas | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"El Principado trabajar\u00e1 para evitar el acceso de los menores al juego y las apuestas | Cand\u00e1s 365","description":"El Gobierno de Asturias ha elaborado el primer protocolo auton\u00f3mico para reforzar las medidas que evitan el acceso de los menores a los juegos de azar y las apuestas. La iniciativa, pionera en el pa\u00eds, aborda los riesgos de este tipo de pr\u00e1cticas con el prop\u00f3sito de prevenir conductas adictivas y contribuir a que las","canonical_url":"https:\/\/candas365.es\/noticias\/el-principado-trabajara-para-evitar-el-acceso-de-los-menores-al-juego-y-las-apuestas\/","robots":"max-image-preview:large","keywords":"asturias","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/el-principado-trabajara-para-evitar-el-acceso-de-los-menores-al-juego-y-las-apuestas\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","name":"Asturias"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","position":2,"name":"Asturias","item":"https:\/\/candas365.es\/noticias\/category\/asturias\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/el-principado-trabajara-para-evitar-el-acceso-de-los-menores-al-juego-y-las-apuestas\/#listItem","name":"El Principado trabajar\u00e1 para evitar el acceso de los menores al juego y las apuestas"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/el-principado-trabajara-para-evitar-el-acceso-de-los-menores-al-juego-y-las-apuestas\/#listItem","position":3,"name":"El Principado trabajar\u00e1 para evitar el acceso de los menores al juego y las apuestas","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","name":"Asturias"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/el-principado-trabajara-para-evitar-el-acceso-de-los-menores-al-juego-y-las-apuestas\/#newsarticle","name":"El Principado trabajar\u00e1 para evitar el acceso de los menores al juego y las apuestas | Cand\u00e1s 365","headline":"El Principado trabajar\u00e1 para evitar el acceso de los menores al juego y las apuestas","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/Consejero-presentacion-protocolo-menores-juego.jpg","width":1280,"height":817},"datePublished":"2018-03-08T09:57:07+01:00","dateModified":"2018-03-08T09:57:07+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/el-principado-trabajara-para-evitar-el-acceso-de-los-menores-al-juego-y-las-apuestas\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/el-principado-trabajara-para-evitar-el-acceso-de-los-menores-al-juego-y-las-apuestas\/#webpage"},"articleSection":"Asturias","dateline":"Publicado el marzo 8, 2018."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/el-principado-trabajara-para-evitar-el-acceso-de-los-menores-al-juego-y-las-apuestas\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/el-principado-trabajara-para-evitar-el-acceso-de-los-menores-al-juego-y-las-apuestas\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/el-principado-trabajara-para-evitar-el-acceso-de-los-menores-al-juego-y-las-apuestas\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/el-principado-trabajara-para-evitar-el-acceso-de-los-menores-al-juego-y-las-apuestas\/#webpage","url":"https:\/\/candas365.es\/noticias\/el-principado-trabajara-para-evitar-el-acceso-de-los-menores-al-juego-y-las-apuestas\/","name":"El Principado trabajar\u00e1 para evitar el acceso de los menores al juego y las apuestas | Cand\u00e1s 365","description":"El Gobierno de Asturias ha elaborado el primer protocolo auton\u00f3mico para reforzar las medidas que evitan el acceso de los menores a los juegos de azar y las apuestas. La iniciativa, pionera en el pa\u00eds, aborda los riesgos de este tipo de pr\u00e1cticas con el prop\u00f3sito de prevenir conductas adictivas y contribuir a que las","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/el-principado-trabajara-para-evitar-el-acceso-de-los-menores-al-juego-y-las-apuestas\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/Consejero-presentacion-protocolo-menores-juego.jpg","@id":"https:\/\/candas365.es\/noticias\/el-principado-trabajara-para-evitar-el-acceso-de-los-menores-al-juego-y-las-apuestas\/#mainImage","width":1280,"height":817},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/el-principado-trabajara-para-evitar-el-acceso-de-los-menores-al-juego-y-las-apuestas\/#mainImage"},"datePublished":"2018-03-08T09:57:07+01:00","dateModified":"2018-03-08T09:57:07+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"El Principado trabajar\u00e1 para evitar el acceso de los menores al juego y las apuestas | Cand\u00e1s 365","og:description":"El Gobierno de Asturias ha elaborado el primer protocolo auton\u00f3mico para reforzar las medidas que evitan el acceso de los menores a los juegos de azar y las apuestas. La iniciativa, pionera en el pa\u00eds, aborda los riesgos de este tipo de pr\u00e1cticas con el prop\u00f3sito de prevenir conductas adictivas y contribuir a que las","og:url":"https:\/\/candas365.es\/noticias\/el-principado-trabajara-para-evitar-el-acceso-de-los-menores-al-juego-y-las-apuestas\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/Consejero-presentacion-protocolo-menores-juego.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/Consejero-presentacion-protocolo-menores-juego.jpg","og:image:width":1280,"og:image:height":817,"article:published_time":"2018-03-08T09:57:07+00:00","article:modified_time":"2018-03-08T09:57:07+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"El Principado trabajar\u00e1 para evitar el acceso de los menores al juego y las apuestas | Cand\u00e1s 365","twitter:description":"El Gobierno de Asturias ha elaborado el primer protocolo auton\u00f3mico para reforzar las medidas que evitan el acceso de los menores a los juegos de azar y las apuestas. La iniciativa, pionera en el pa\u00eds, aborda los riesgos de este tipo de pr\u00e1cticas con el prop\u00f3sito de prevenir conductas adictivas y contribuir a que las","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/Consejero-presentacion-protocolo-menores-juego.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"3 minutos"},"aioseo_meta_data":{"post_id":"91195","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-20 07:21:13","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 11:55:15","updated":"2026-05-20 07:21:13"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/asturias\/\" title=\"Asturias\">Asturias<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tEl Principado trabajar\u00e1 para evitar el acceso de los menores al juego y las apuestas\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Asturias","link":"https:\/\/candas365.es\/noticias\/category\/asturias\/"},{"label":"El Principado trabajar\u00e1 para evitar el acceso de los menores al juego y las apuestas","link":"https:\/\/candas365.es\/noticias\/el-principado-trabajara-para-evitar-el-acceso-de-los-menores-al-juego-y-las-apuestas\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/91195","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=91195"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/91195\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/91196"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=91195"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=91195"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=91195"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}