{"id":91128,"date":"2018-03-05T13:09:06","date_gmt":"2018-03-05T13:09:06","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=91128"},"modified":"2018-03-05T13:09:06","modified_gmt":"2018-03-05T13:09:06","slug":"desarrollo-rural-destina-670-000-euros-este-ano-a-promocionar-los-alimentos-de-calidad-asturianos","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/desarrollo-rural-destina-670-000-euros-este-ano-a-promocionar-los-alimentos-de-calidad-asturianos\/","title":{"rendered":"Desarrollo Rural destina 670.000 euros este a\u00f1o a promocionar los alimentos de calidad asturianos"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-91129\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/2018_03_03-Consejera-feria-Gustoko-360x270.jpg\" alt=\"\" width=\"360\" height=\"270\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/2018_03_03-Consejera-feria-Gustoko-360x270.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/2018_03_03-Consejera-feria-Gustoko-80x60.jpg 80w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/2018_03_03-Consejera-feria-Gustoko-265x198.jpg 265w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/2018_03_03-Consejera-feria-Gustoko-696x522.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/2018_03_03-Consejera-feria-Gustoko-1068x801.jpg 1068w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/2018_03_03-Consejera-feria-Gustoko-560x420.jpg 560w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/2018_03_03-Consejera-feria-Gustoko-768x576.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/2018_03_03-Consejera-feria-Gustoko-640x480.jpg 640w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/2018_03_03-Consejera-feria-Gustoko-90x67.jpg 90w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/2018_03_03-Consejera-feria-Gustoko.jpg 1280w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>La consejera de Desarrollo Rural y Recursos Naturales, Mar\u00eda Jes\u00fas \u00c1lvarez, ha manifestado que su departamento dedicar\u00e1 este a\u00f1o un total de 670.000 euros a la promoci\u00f3n de los productos agroalimentarios de calidad en diferentes ferias y mercados, tanto nacionales como internaciones. Estos fondos financiar\u00e1n tanto las actividades que prev\u00e9 realizar la propia consejer\u00eda como las de los consejos reguladores.<\/p>\n<p>Mar\u00eda Jes\u00fas \u00c1lvarez ha visitado en Baracaldo (Vizcaya) la feria de producto alimentario y gastron\u00f3mico Gustoko, dirigida a hosteleros, distribuidores, comerciantes y p\u00fablico en general, y a la que el Gobierno de Asturias acude, por vez primera, con un estand institucional para promocionar la marca Alimentos del Para\u00edso Natural.<\/p>\n<p>\u201cEsta es la gran feria de productos de calidad del Pa\u00eds Vasco, en la que nos acompa\u00f1an 18 productores a los que venimos a apoyar para dar a conocer su magn\u00edfica oferta, que ofrece todas la garant\u00edas\u201d, ha indicado la consejera, que ha a\u00f1adido que los consumidores \u201cpueden estar seguros de que detr\u00e1s del logo de la marca hay siempre un trozo del para\u00edso\u201d.<\/p>\n<p>\u201cLa marca Asturias vende porque nuestra comunidad es sin\u00f3nimo de calidad en gastronom\u00eda, producciones primarias, conservaci\u00f3n de la naturaleza y paisaje\u201d, ha a\u00f1adido la titular de Desarrollo Rural.<\/p>\n<p>Adem\u00e1s del estand del Principado, los expositores asturianos que est\u00e1n presentes en Gustoko son: Legumbres El cam\u00edn astur; Vesana Superfoods, Harina Casta\u00f1a Bosqfrut; Queser\u00eda Vega de Tord\u00edn Cabrales DOP, Quesos Artesanales Reboll\u00edn-La Corte; Miel Er\u00eda de Valles; El Viejo Mundo, Cocina Maruma, C\u00e1rnicas Arango-IGP Chosco de Tineo, Miel La Boalesa, Queser\u00eda Temia, Miel La Puela, Quesos Ecol\u00f3gicos Ov\u00edn, Bodega Vidas-DOP Cangas, Queser\u00eda Los Puertos Cabrales DOP, El Mol\u00edn de Pe\u00f1amellera-Harinas Ecol\u00f3gicas, Asturcilla y Cerveza Ecol\u00f3gica Asgaya.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La consejera de Desarrollo Rural y Recursos Naturales, Mar\u00eda Jes\u00fas \u00c1lvarez, ha manifestado que su departamento dedicar\u00e1 este a\u00f1o un total de 670.000 euros a la promoci\u00f3n de los productos agroalimentarios de calidad en diferentes ferias y mercados, tanto nacionales como internaciones. Estos fondos financiar\u00e1n tanto las actividades que prev\u00e9 realizar la propia consejer\u00eda como<\/p>\n","protected":false},"author":1,"featured_media":91129,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-91128","post","type-post","status-publish","format-standard","has-post-thumbnail","category-asturias"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"La consejera de Desarrollo Rural y Recursos Naturales, Mar\u00eda Jes\u00fas \u00c1lvarez, ha manifestado que su departamento dedicar\u00e1 este a\u00f1o un total de 670.000 euros a la promoci\u00f3n de los productos agroalimentarios de calidad en diferentes ferias y mercados, tanto nacionales como internaciones. Estos fondos financiar\u00e1n tanto las actividades que prev\u00e9 realizar la propia consejer\u00eda como\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"asturias\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/desarrollo-rural-destina-670-000-euros-este-ano-a-promocionar-los-alimentos-de-calidad-asturianos\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Desarrollo Rural destina 670.000 euros este a\u00f1o a promocionar los alimentos de calidad asturianos | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"La consejera de Desarrollo Rural y Recursos Naturales, Mar\u00eda Jes\u00fas \u00c1lvarez, ha manifestado que su departamento dedicar\u00e1 este a\u00f1o un total de 670.000 euros a la promoci\u00f3n de los productos agroalimentarios de calidad en diferentes ferias y mercados, tanto nacionales como internaciones. Estos fondos financiar\u00e1n tanto las actividades que prev\u00e9 realizar la propia consejer\u00eda como\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/desarrollo-rural-destina-670-000-euros-este-ano-a-promocionar-los-alimentos-de-calidad-asturianos\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/2018_03_03-Consejera-feria-Gustoko.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/2018_03_03-Consejera-feria-Gustoko.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-03-05T13:09:06+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-03-05T13:09:06+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Desarrollo Rural destina 670.000 euros este a\u00f1o a promocionar los alimentos de calidad asturianos | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La consejera de Desarrollo Rural y Recursos Naturales, Mar\u00eda Jes\u00fas \u00c1lvarez, ha manifestado que su departamento dedicar\u00e1 este a\u00f1o un total de 670.000 euros a la promoci\u00f3n de los productos agroalimentarios de calidad en diferentes ferias y mercados, tanto nacionales como internaciones. Estos fondos financiar\u00e1n tanto las actividades que prev\u00e9 realizar la propia consejer\u00eda como\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/2018_03_03-Consejera-feria-Gustoko.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/desarrollo-rural-destina-670-000-euros-este-ano-a-promocionar-los-alimentos-de-calidad-asturianos\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"name\":\"Asturias\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"position\":2,\"name\":\"Asturias\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/desarrollo-rural-destina-670-000-euros-este-ano-a-promocionar-los-alimentos-de-calidad-asturianos\\\/#listItem\",\"name\":\"Desarrollo Rural destina 670.000 euros este a\\u00f1o a promocionar los alimentos de calidad asturianos\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/desarrollo-rural-destina-670-000-euros-este-ano-a-promocionar-los-alimentos-de-calidad-asturianos\\\/#listItem\",\"position\":3,\"name\":\"Desarrollo Rural destina 670.000 euros este a\\u00f1o a promocionar los alimentos de calidad asturianos\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"name\":\"Asturias\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/desarrollo-rural-destina-670-000-euros-este-ano-a-promocionar-los-alimentos-de-calidad-asturianos\\\/#newsarticle\",\"name\":\"Desarrollo Rural destina 670.000 euros este a\\u00f1o a promocionar los alimentos de calidad asturianos | Cand\\u00e1s 365\",\"headline\":\"Desarrollo Rural destina 670.000 euros este a\\u00f1o a promocionar los alimentos de calidad asturianos\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/2018_03_03-Consejera-feria-Gustoko.jpg\",\"width\":1280,\"height\":960},\"datePublished\":\"2018-03-05T13:09:06+01:00\",\"dateModified\":\"2018-03-05T13:09:06+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/desarrollo-rural-destina-670-000-euros-este-ano-a-promocionar-los-alimentos-de-calidad-asturianos\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/desarrollo-rural-destina-670-000-euros-este-ano-a-promocionar-los-alimentos-de-calidad-asturianos\\\/#webpage\"},\"articleSection\":\"Asturias\",\"dateline\":\"Publicado el marzo 5, 2018.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/desarrollo-rural-destina-670-000-euros-este-ano-a-promocionar-los-alimentos-de-calidad-asturianos\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/desarrollo-rural-destina-670-000-euros-este-ano-a-promocionar-los-alimentos-de-calidad-asturianos\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/desarrollo-rural-destina-670-000-euros-este-ano-a-promocionar-los-alimentos-de-calidad-asturianos\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/desarrollo-rural-destina-670-000-euros-este-ano-a-promocionar-los-alimentos-de-calidad-asturianos\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/desarrollo-rural-destina-670-000-euros-este-ano-a-promocionar-los-alimentos-de-calidad-asturianos\\\/\",\"name\":\"Desarrollo Rural destina 670.000 euros este a\\u00f1o a promocionar los alimentos de calidad asturianos | Cand\\u00e1s 365\",\"description\":\"La consejera de Desarrollo Rural y Recursos Naturales, Mar\\u00eda Jes\\u00fas \\u00c1lvarez, ha manifestado que su departamento dedicar\\u00e1 este a\\u00f1o un total de 670.000 euros a la promoci\\u00f3n de los productos agroalimentarios de calidad en diferentes ferias y mercados, tanto nacionales como internaciones. Estos fondos financiar\\u00e1n tanto las actividades que prev\\u00e9 realizar la propia consejer\\u00eda como\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/desarrollo-rural-destina-670-000-euros-este-ano-a-promocionar-los-alimentos-de-calidad-asturianos\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/2018_03_03-Consejera-feria-Gustoko.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/desarrollo-rural-destina-670-000-euros-este-ano-a-promocionar-los-alimentos-de-calidad-asturianos\\\/#mainImage\",\"width\":1280,\"height\":960},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/desarrollo-rural-destina-670-000-euros-este-ano-a-promocionar-los-alimentos-de-calidad-asturianos\\\/#mainImage\"},\"datePublished\":\"2018-03-05T13:09:06+01:00\",\"dateModified\":\"2018-03-05T13:09:06+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Desarrollo Rural destina 670.000 euros este a\u00f1o a promocionar los alimentos de calidad asturianos | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Desarrollo Rural destina 670.000 euros este a\u00f1o a promocionar los alimentos de calidad asturianos | Cand\u00e1s 365","description":"La consejera de Desarrollo Rural y Recursos Naturales, Mar\u00eda Jes\u00fas \u00c1lvarez, ha manifestado que su departamento dedicar\u00e1 este a\u00f1o un total de 670.000 euros a la promoci\u00f3n de los productos agroalimentarios de calidad en diferentes ferias y mercados, tanto nacionales como internaciones. Estos fondos financiar\u00e1n tanto las actividades que prev\u00e9 realizar la propia consejer\u00eda como","canonical_url":"https:\/\/candas365.es\/noticias\/desarrollo-rural-destina-670-000-euros-este-ano-a-promocionar-los-alimentos-de-calidad-asturianos\/","robots":"max-image-preview:large","keywords":"asturias","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/desarrollo-rural-destina-670-000-euros-este-ano-a-promocionar-los-alimentos-de-calidad-asturianos\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","name":"Asturias"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","position":2,"name":"Asturias","item":"https:\/\/candas365.es\/noticias\/category\/asturias\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/desarrollo-rural-destina-670-000-euros-este-ano-a-promocionar-los-alimentos-de-calidad-asturianos\/#listItem","name":"Desarrollo Rural destina 670.000 euros este a\u00f1o a promocionar los alimentos de calidad asturianos"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/desarrollo-rural-destina-670-000-euros-este-ano-a-promocionar-los-alimentos-de-calidad-asturianos\/#listItem","position":3,"name":"Desarrollo Rural destina 670.000 euros este a\u00f1o a promocionar los alimentos de calidad asturianos","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","name":"Asturias"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/desarrollo-rural-destina-670-000-euros-este-ano-a-promocionar-los-alimentos-de-calidad-asturianos\/#newsarticle","name":"Desarrollo Rural destina 670.000 euros este a\u00f1o a promocionar los alimentos de calidad asturianos | Cand\u00e1s 365","headline":"Desarrollo Rural destina 670.000 euros este a\u00f1o a promocionar los alimentos de calidad asturianos","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/2018_03_03-Consejera-feria-Gustoko.jpg","width":1280,"height":960},"datePublished":"2018-03-05T13:09:06+01:00","dateModified":"2018-03-05T13:09:06+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/desarrollo-rural-destina-670-000-euros-este-ano-a-promocionar-los-alimentos-de-calidad-asturianos\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/desarrollo-rural-destina-670-000-euros-este-ano-a-promocionar-los-alimentos-de-calidad-asturianos\/#webpage"},"articleSection":"Asturias","dateline":"Publicado el marzo 5, 2018."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/desarrollo-rural-destina-670-000-euros-este-ano-a-promocionar-los-alimentos-de-calidad-asturianos\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/desarrollo-rural-destina-670-000-euros-este-ano-a-promocionar-los-alimentos-de-calidad-asturianos\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/desarrollo-rural-destina-670-000-euros-este-ano-a-promocionar-los-alimentos-de-calidad-asturianos\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/desarrollo-rural-destina-670-000-euros-este-ano-a-promocionar-los-alimentos-de-calidad-asturianos\/#webpage","url":"https:\/\/candas365.es\/noticias\/desarrollo-rural-destina-670-000-euros-este-ano-a-promocionar-los-alimentos-de-calidad-asturianos\/","name":"Desarrollo Rural destina 670.000 euros este a\u00f1o a promocionar los alimentos de calidad asturianos | Cand\u00e1s 365","description":"La consejera de Desarrollo Rural y Recursos Naturales, Mar\u00eda Jes\u00fas \u00c1lvarez, ha manifestado que su departamento dedicar\u00e1 este a\u00f1o un total de 670.000 euros a la promoci\u00f3n de los productos agroalimentarios de calidad en diferentes ferias y mercados, tanto nacionales como internaciones. Estos fondos financiar\u00e1n tanto las actividades que prev\u00e9 realizar la propia consejer\u00eda como","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/desarrollo-rural-destina-670-000-euros-este-ano-a-promocionar-los-alimentos-de-calidad-asturianos\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/2018_03_03-Consejera-feria-Gustoko.jpg","@id":"https:\/\/candas365.es\/noticias\/desarrollo-rural-destina-670-000-euros-este-ano-a-promocionar-los-alimentos-de-calidad-asturianos\/#mainImage","width":1280,"height":960},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/desarrollo-rural-destina-670-000-euros-este-ano-a-promocionar-los-alimentos-de-calidad-asturianos\/#mainImage"},"datePublished":"2018-03-05T13:09:06+01:00","dateModified":"2018-03-05T13:09:06+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Desarrollo Rural destina 670.000 euros este a\u00f1o a promocionar los alimentos de calidad asturianos | Cand\u00e1s 365","og:description":"La consejera de Desarrollo Rural y Recursos Naturales, Mar\u00eda Jes\u00fas \u00c1lvarez, ha manifestado que su departamento dedicar\u00e1 este a\u00f1o un total de 670.000 euros a la promoci\u00f3n de los productos agroalimentarios de calidad en diferentes ferias y mercados, tanto nacionales como internaciones. Estos fondos financiar\u00e1n tanto las actividades que prev\u00e9 realizar la propia consejer\u00eda como","og:url":"https:\/\/candas365.es\/noticias\/desarrollo-rural-destina-670-000-euros-este-ano-a-promocionar-los-alimentos-de-calidad-asturianos\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/2018_03_03-Consejera-feria-Gustoko.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/2018_03_03-Consejera-feria-Gustoko.jpg","og:image:width":1280,"og:image:height":960,"article:published_time":"2018-03-05T13:09:06+00:00","article:modified_time":"2018-03-05T13:09:06+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Desarrollo Rural destina 670.000 euros este a\u00f1o a promocionar los alimentos de calidad asturianos | Cand\u00e1s 365","twitter:description":"La consejera de Desarrollo Rural y Recursos Naturales, Mar\u00eda Jes\u00fas \u00c1lvarez, ha manifestado que su departamento dedicar\u00e1 este a\u00f1o un total de 670.000 euros a la promoci\u00f3n de los productos agroalimentarios de calidad en diferentes ferias y mercados, tanto nacionales como internaciones. Estos fondos financiar\u00e1n tanto las actividades que prev\u00e9 realizar la propia consejer\u00eda como","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/2018_03_03-Consejera-feria-Gustoko.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"91128","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-20 07:09:09","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 11:55:15","updated":"2026-05-20 07:09:09"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/asturias\/\" title=\"Asturias\">Asturias<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tDesarrollo Rural destina 670.000 euros este a\u00f1o a promocionar los alimentos de calidad asturianos\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Asturias","link":"https:\/\/candas365.es\/noticias\/category\/asturias\/"},{"label":"Desarrollo Rural destina 670.000 euros este a\u00f1o a promocionar los alimentos de calidad asturianos","link":"https:\/\/candas365.es\/noticias\/desarrollo-rural-destina-670-000-euros-este-ano-a-promocionar-los-alimentos-de-calidad-asturianos\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/91128","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=91128"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/91128\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/91129"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=91128"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=91128"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=91128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}