{"id":91113,"date":"2018-03-05T08:59:06","date_gmt":"2018-03-05T08:59:06","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=91113"},"modified":"2018-03-05T08:59:06","modified_gmt":"2018-03-05T08:59:06","slug":"ciudadanos-preocupado-por-el-incremento-del-desempleo-en-las-personas-mayores-de-55-anos-en-gijon","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/ciudadanos-preocupado-por-el-incremento-del-desempleo-en-las-personas-mayores-de-55-anos-en-gijon\/","title":{"rendered":"Ciudadanos preocupado por el incremento del desempleo en las personas mayores de 55 a\u00f1os en Gij\u00f3n"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-36778\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/gijon-ayto-360x198.jpg\" alt=\"\" width=\"360\" height=\"198\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/gijon-ayto-360x198.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/gijon-ayto-650x357.jpg 650w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/gijon-ayto-150x82.jpg 150w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/gijon-ayto-450x247.jpg 450w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/gijon-ayto.jpg 655w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>El Grupo Municipal de Ciudadanos reclamar\u00e1 en la pr\u00f3xima comisi\u00f3n de Empleo que se pongan en marcha medidas a nivel local para combatir el desempleo entre las personas mayores de 55 a\u00f1os, tras conocer esta semana los datos de desempleo correspondientes al mes de febrero.<\/p>\n<p>En este sentido, la formaci\u00f3n naranja ha destacado que uno de cada cuatro desempleados inscritos como demandantes de empleo en la ciudad se encuentran en esta franja de edad, y que adem\u00e1s ha sido el \u00fanico tramo de edad en el que se ha incrementado el desempleo en el \u00faltimo a\u00f1o. As\u00ed, mientras el conjunto de desempleados en la ciudad se redujo entre febrero de 2017 y febrero de 2018 en 1.653 personas, el de los mayores de 55 a\u00f1os se increment\u00f3 en 43. \u201cNo es que sea un incremento importante pero s\u00ed muestra una tendencia completamente diferente a la del resto de edades\u201d, explic\u00f3 Fern\u00e1ndez Sarasola.<\/p>\n<p>A juicio de Ciudadanos, esta tendencia muestra un problema social que empieza a ser ya preocupante en nuestra ciudad. \u201cNo cabe duda de los especiales problemas que tiene este colectivo para reinsertarse en el mercado laboral, lo que hace que muchas veces su situaci\u00f3n de desempleo sea ya permanente hasta la jubilaci\u00f3n, lo que repercute muy negativamente en sus pensiones, y puede terminar por arrastrar a buena parte de estas personas hacia los l\u00edmites de la pobreza o de la exclusi\u00f3n social\u201d, explic\u00f3 Fern\u00e1ndez Sarasola.<\/p>\n<p>Por ello, consider\u00f3 necesario que a nivel local se pongan en marcha acciones para ayudar espec\u00edficamente a este colectivo que ahora mismo adolece de medidas dise\u00f1adas espec\u00edficamente para ellos, \u201cno s\u00f3lo no les est\u00e1 ayudando de forma espec\u00edfica sino que cada vez se les est\u00e1 poniendo m\u00e1s dif\u00edcil\u201d, se lament\u00f3 Sarasola criticando que el Gobierno del Partido Popular hubiera endurecido los requisitos para acceder al subsidio para mayores de 55 a\u00f1os y cuya cuant\u00eda es escasa de apenas 426 euros mensuales.<\/p>\n<p>Para Ciudadanos, los trabajadores m\u00e1s mayores junto a los j\u00f3venes han sido los grandes damnificados por la crisis en Gij\u00f3n. \u201cS\u00f3lo que los j\u00f3venes han podido recurrir a otras v\u00e1lvulas de escape como emigrar o seguir form\u00e1ndose\u201d, concluy\u00f3 reclamando que las pol\u00edticas de empleo deber\u00edan centrarse principalmente en estos dos colectivos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Grupo Municipal de Ciudadanos reclamar\u00e1 en la pr\u00f3xima comisi\u00f3n de Empleo que se pongan en marcha medidas a nivel local para combatir el desempleo entre las personas mayores de 55 a\u00f1os, tras conocer esta semana los datos de desempleo correspondientes al mes de febrero. En este sentido, la formaci\u00f3n naranja ha destacado que uno<\/p>\n","protected":false},"author":1,"featured_media":36778,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-91113","post","type-post","status-publish","format-standard","has-post-thumbnail","category-asturias"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"El Grupo Municipal de Ciudadanos reclamar\u00e1 en la pr\u00f3xima comisi\u00f3n de Empleo que se pongan en marcha medidas a nivel local para combatir el desempleo entre las personas mayores de 55 a\u00f1os, tras conocer esta semana los datos de desempleo correspondientes al mes de febrero. En este sentido, la formaci\u00f3n naranja ha destacado que uno\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"asturias\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/ciudadanos-preocupado-por-el-incremento-del-desempleo-en-las-personas-mayores-de-55-anos-en-gijon\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Ciudadanos preocupado por el incremento del desempleo en las personas mayores de 55 a\u00f1os en Gij\u00f3n | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"El Grupo Municipal de Ciudadanos reclamar\u00e1 en la pr\u00f3xima comisi\u00f3n de Empleo que se pongan en marcha medidas a nivel local para combatir el desempleo entre las personas mayores de 55 a\u00f1os, tras conocer esta semana los datos de desempleo correspondientes al mes de febrero. En este sentido, la formaci\u00f3n naranja ha destacado que uno\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/ciudadanos-preocupado-por-el-incremento-del-desempleo-en-las-personas-mayores-de-55-anos-en-gijon\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/gijon-ayto.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/gijon-ayto.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"655\" \/>\n\t\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-03-05T08:59:06+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-03-05T08:59:06+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Ciudadanos preocupado por el incremento del desempleo en las personas mayores de 55 a\u00f1os en Gij\u00f3n | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El Grupo Municipal de Ciudadanos reclamar\u00e1 en la pr\u00f3xima comisi\u00f3n de Empleo que se pongan en marcha medidas a nivel local para combatir el desempleo entre las personas mayores de 55 a\u00f1os, tras conocer esta semana los datos de desempleo correspondientes al mes de febrero. En este sentido, la formaci\u00f3n naranja ha destacado que uno\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/gijon-ayto.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ciudadanos-preocupado-por-el-incremento-del-desempleo-en-las-personas-mayores-de-55-anos-en-gijon\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"name\":\"Asturias\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"position\":2,\"name\":\"Asturias\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ciudadanos-preocupado-por-el-incremento-del-desempleo-en-las-personas-mayores-de-55-anos-en-gijon\\\/#listItem\",\"name\":\"Ciudadanos preocupado por el incremento del desempleo en las personas mayores de 55 a\\u00f1os en Gij\\u00f3n\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ciudadanos-preocupado-por-el-incremento-del-desempleo-en-las-personas-mayores-de-55-anos-en-gijon\\\/#listItem\",\"position\":3,\"name\":\"Ciudadanos preocupado por el incremento del desempleo en las personas mayores de 55 a\\u00f1os en Gij\\u00f3n\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"name\":\"Asturias\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ciudadanos-preocupado-por-el-incremento-del-desempleo-en-las-personas-mayores-de-55-anos-en-gijon\\\/#newsarticle\",\"name\":\"Ciudadanos preocupado por el incremento del desempleo en las personas mayores de 55 a\\u00f1os en Gij\\u00f3n | Cand\\u00e1s 365\",\"headline\":\"Ciudadanos preocupado por el incremento del desempleo en las personas mayores de 55 a\\u00f1os en Gij\\u00f3n\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/gijon-ayto.jpg\",\"width\":655,\"height\":360},\"datePublished\":\"2018-03-05T08:59:06+01:00\",\"dateModified\":\"2018-03-05T08:59:06+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ciudadanos-preocupado-por-el-incremento-del-desempleo-en-las-personas-mayores-de-55-anos-en-gijon\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ciudadanos-preocupado-por-el-incremento-del-desempleo-en-las-personas-mayores-de-55-anos-en-gijon\\\/#webpage\"},\"articleSection\":\"Asturias\",\"dateline\":\"Publicado el marzo 5, 2018.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ciudadanos-preocupado-por-el-incremento-del-desempleo-en-las-personas-mayores-de-55-anos-en-gijon\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ciudadanos-preocupado-por-el-incremento-del-desempleo-en-las-personas-mayores-de-55-anos-en-gijon\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ciudadanos-preocupado-por-el-incremento-del-desempleo-en-las-personas-mayores-de-55-anos-en-gijon\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ciudadanos-preocupado-por-el-incremento-del-desempleo-en-las-personas-mayores-de-55-anos-en-gijon\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ciudadanos-preocupado-por-el-incremento-del-desempleo-en-las-personas-mayores-de-55-anos-en-gijon\\\/\",\"name\":\"Ciudadanos preocupado por el incremento del desempleo en las personas mayores de 55 a\\u00f1os en Gij\\u00f3n | Cand\\u00e1s 365\",\"description\":\"El Grupo Municipal de Ciudadanos reclamar\\u00e1 en la pr\\u00f3xima comisi\\u00f3n de Empleo que se pongan en marcha medidas a nivel local para combatir el desempleo entre las personas mayores de 55 a\\u00f1os, tras conocer esta semana los datos de desempleo correspondientes al mes de febrero. En este sentido, la formaci\\u00f3n naranja ha destacado que uno\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ciudadanos-preocupado-por-el-incremento-del-desempleo-en-las-personas-mayores-de-55-anos-en-gijon\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/gijon-ayto.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ciudadanos-preocupado-por-el-incremento-del-desempleo-en-las-personas-mayores-de-55-anos-en-gijon\\\/#mainImage\",\"width\":655,\"height\":360},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ciudadanos-preocupado-por-el-incremento-del-desempleo-en-las-personas-mayores-de-55-anos-en-gijon\\\/#mainImage\"},\"datePublished\":\"2018-03-05T08:59:06+01:00\",\"dateModified\":\"2018-03-05T08:59:06+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Ciudadanos preocupado por el incremento del desempleo en las personas mayores de 55 a\u00f1os en Gij\u00f3n | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Ciudadanos preocupado por el incremento del desempleo en las personas mayores de 55 a\u00f1os en Gij\u00f3n | Cand\u00e1s 365","description":"El Grupo Municipal de Ciudadanos reclamar\u00e1 en la pr\u00f3xima comisi\u00f3n de Empleo que se pongan en marcha medidas a nivel local para combatir el desempleo entre las personas mayores de 55 a\u00f1os, tras conocer esta semana los datos de desempleo correspondientes al mes de febrero. En este sentido, la formaci\u00f3n naranja ha destacado que uno","canonical_url":"https:\/\/candas365.es\/noticias\/ciudadanos-preocupado-por-el-incremento-del-desempleo-en-las-personas-mayores-de-55-anos-en-gijon\/","robots":"max-image-preview:large","keywords":"asturias","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/ciudadanos-preocupado-por-el-incremento-del-desempleo-en-las-personas-mayores-de-55-anos-en-gijon\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","name":"Asturias"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","position":2,"name":"Asturias","item":"https:\/\/candas365.es\/noticias\/category\/asturias\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/ciudadanos-preocupado-por-el-incremento-del-desempleo-en-las-personas-mayores-de-55-anos-en-gijon\/#listItem","name":"Ciudadanos preocupado por el incremento del desempleo en las personas mayores de 55 a\u00f1os en Gij\u00f3n"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/ciudadanos-preocupado-por-el-incremento-del-desempleo-en-las-personas-mayores-de-55-anos-en-gijon\/#listItem","position":3,"name":"Ciudadanos preocupado por el incremento del desempleo en las personas mayores de 55 a\u00f1os en Gij\u00f3n","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","name":"Asturias"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/ciudadanos-preocupado-por-el-incremento-del-desempleo-en-las-personas-mayores-de-55-anos-en-gijon\/#newsarticle","name":"Ciudadanos preocupado por el incremento del desempleo en las personas mayores de 55 a\u00f1os en Gij\u00f3n | Cand\u00e1s 365","headline":"Ciudadanos preocupado por el incremento del desempleo en las personas mayores de 55 a\u00f1os en Gij\u00f3n","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/gijon-ayto.jpg","width":655,"height":360},"datePublished":"2018-03-05T08:59:06+01:00","dateModified":"2018-03-05T08:59:06+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/ciudadanos-preocupado-por-el-incremento-del-desempleo-en-las-personas-mayores-de-55-anos-en-gijon\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/ciudadanos-preocupado-por-el-incremento-del-desempleo-en-las-personas-mayores-de-55-anos-en-gijon\/#webpage"},"articleSection":"Asturias","dateline":"Publicado el marzo 5, 2018."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/ciudadanos-preocupado-por-el-incremento-del-desempleo-en-las-personas-mayores-de-55-anos-en-gijon\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/ciudadanos-preocupado-por-el-incremento-del-desempleo-en-las-personas-mayores-de-55-anos-en-gijon\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/ciudadanos-preocupado-por-el-incremento-del-desempleo-en-las-personas-mayores-de-55-anos-en-gijon\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/ciudadanos-preocupado-por-el-incremento-del-desempleo-en-las-personas-mayores-de-55-anos-en-gijon\/#webpage","url":"https:\/\/candas365.es\/noticias\/ciudadanos-preocupado-por-el-incremento-del-desempleo-en-las-personas-mayores-de-55-anos-en-gijon\/","name":"Ciudadanos preocupado por el incremento del desempleo en las personas mayores de 55 a\u00f1os en Gij\u00f3n | Cand\u00e1s 365","description":"El Grupo Municipal de Ciudadanos reclamar\u00e1 en la pr\u00f3xima comisi\u00f3n de Empleo que se pongan en marcha medidas a nivel local para combatir el desempleo entre las personas mayores de 55 a\u00f1os, tras conocer esta semana los datos de desempleo correspondientes al mes de febrero. En este sentido, la formaci\u00f3n naranja ha destacado que uno","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/ciudadanos-preocupado-por-el-incremento-del-desempleo-en-las-personas-mayores-de-55-anos-en-gijon\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/gijon-ayto.jpg","@id":"https:\/\/candas365.es\/noticias\/ciudadanos-preocupado-por-el-incremento-del-desempleo-en-las-personas-mayores-de-55-anos-en-gijon\/#mainImage","width":655,"height":360},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/ciudadanos-preocupado-por-el-incremento-del-desempleo-en-las-personas-mayores-de-55-anos-en-gijon\/#mainImage"},"datePublished":"2018-03-05T08:59:06+01:00","dateModified":"2018-03-05T08:59:06+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Ciudadanos preocupado por el incremento del desempleo en las personas mayores de 55 a\u00f1os en Gij\u00f3n | Cand\u00e1s 365","og:description":"El Grupo Municipal de Ciudadanos reclamar\u00e1 en la pr\u00f3xima comisi\u00f3n de Empleo que se pongan en marcha medidas a nivel local para combatir el desempleo entre las personas mayores de 55 a\u00f1os, tras conocer esta semana los datos de desempleo correspondientes al mes de febrero. En este sentido, la formaci\u00f3n naranja ha destacado que uno","og:url":"https:\/\/candas365.es\/noticias\/ciudadanos-preocupado-por-el-incremento-del-desempleo-en-las-personas-mayores-de-55-anos-en-gijon\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/gijon-ayto.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/gijon-ayto.jpg","og:image:width":655,"og:image:height":360,"article:published_time":"2018-03-05T08:59:06+00:00","article:modified_time":"2018-03-05T08:59:06+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Ciudadanos preocupado por el incremento del desempleo en las personas mayores de 55 a\u00f1os en Gij\u00f3n | Cand\u00e1s 365","twitter:description":"El Grupo Municipal de Ciudadanos reclamar\u00e1 en la pr\u00f3xima comisi\u00f3n de Empleo que se pongan en marcha medidas a nivel local para combatir el desempleo entre las personas mayores de 55 a\u00f1os, tras conocer esta semana los datos de desempleo correspondientes al mes de febrero. En este sentido, la formaci\u00f3n naranja ha destacado que uno","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/gijon-ayto.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"91113","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-20 07:05:38","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 11:55:15","updated":"2026-05-20 07:05:38"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/asturias\/\" title=\"Asturias\">Asturias<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tCiudadanos preocupado por el incremento del desempleo en las personas mayores de 55 a\u00f1os en Gij\u00f3n\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Asturias","link":"https:\/\/candas365.es\/noticias\/category\/asturias\/"},{"label":"Ciudadanos preocupado por el incremento del desempleo en las personas mayores de 55 a\u00f1os en Gij\u00f3n","link":"https:\/\/candas365.es\/noticias\/ciudadanos-preocupado-por-el-incremento-del-desempleo-en-las-personas-mayores-de-55-anos-en-gijon\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/91113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=91113"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/91113\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/36778"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=91113"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=91113"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=91113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}