{"id":91103,"date":"2018-03-04T22:37:30","date_gmt":"2018-03-04T22:37:30","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=91103"},"modified":"2018-03-04T22:37:30","modified_gmt":"2018-03-04T22:37:30","slug":"amenaza-de-trump-de-aranceles-a-coches-de-la-ue-preocupa-a-alemania","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/amenaza-de-trump-de-aranceles-a-coches-de-la-ue-preocupa-a-alemania\/","title":{"rendered":"Amenaza de Trump de aranceles a coches de la UE preocupa a Alemania"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-35806\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/D.Trump-655x360-360x198.jpg\" alt=\"\" width=\"360\" height=\"198\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/D.Trump-655x360-360x198.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/D.Trump-655x360-650x357.jpg 650w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/D.Trump-655x360-150x82.jpg 150w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/D.Trump-655x360-450x247.jpg 450w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/D.Trump-655x360.jpg 655w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Berl\u00edn, 4 mar (dpa) &#8211; La ministra de econom\u00eda alemana, Brigitte Zypries, pidi\u00f3 hoy moderaci\u00f3n despu\u00e9s de que el presidente de Estados Unidos, Donald Trump, amenazara con imponer aranceles a los veh\u00edculos fabricados en la Uni\u00f3n Europea (UE).<\/p>\n<p>\u00abEspero que el presidente de Estados Unidos escuche a las numerosas voces sensibles de su pa\u00eds y cambie de opini\u00f3n\u00bb, dijo Zypries, miembro del Partido Socialdem\u00f3crata.<\/p>\n<p>\u00abEl presidente Trump quiere jugar a un juego que nadie puede ganar\u00bb, destac\u00f3 Zypries y a\u00f1adi\u00f3 que imponer cada vez m\u00e1s tasas a cada vez m\u00e1s productos podr\u00eda poner en peligro el comercio libre y la prosperidad.<\/p>\n<p>Bernhard Mattes, presidente de la asociaci\u00f3n alemana de la industria automotriz (VDA), dijo que se debe evitar a toda costa una guerra comercial entre Estados Unidos y Europa.<\/p>\n<p>\u00abEn este tipo de guerra comercial solo hay perdedores, en todos los bandos\u00bb, dijo hoy Mattes a dpa y agreg\u00f3 que la industria est\u00e1 observando la disputa con preocupaci\u00f3n.<\/p>\n<p>Mattes explic\u00f3 que los fabricantes alemanes de coches han expandido su producci\u00f3n en Estados Unidos durante a\u00f1os, han dado trabajo a mucha m\u00e1s gente all\u00ed y han reducido las exportaciones a Estados Unidos.<\/p>\n<p>El a\u00f1o pasado se exportaron desde Alemania al pa\u00eds norteamericano unos 494.000 autom\u00f3viles, m\u00e1s de un cuarto menos que en 2013, indic\u00f3 Mattes. En 2017, se vendieron en Estados Unidos unos 1,35 millones de coches alemanes nuevos, un incremento de alrededor del uno por ciento, seg\u00fan la VDA.<\/p>\n<p>Trump amenaz\u00f3 el s\u00e1bado a la UE con aplicar aranceles a los coches si el bloque aumentaba las tasas para las empresas de su pa\u00eds. \u00abHacen que sea imposible vender all\u00ed nuestros coches (y m\u00e1s). \u00a1Un gran desequilibrio comercial\u00bb, escribi\u00f3 en Twitter acusando al bloque europeo.<\/p>\n<p>\u00abThe Washington Post\u00bb inform\u00f3 el s\u00e1bado que el principal objetivo de los ataques del presidente era Alemania. Uno de los principales consejeros de comercio de Trump, Peter Navarro, cree que los fabricantes alemanes han robado cuotas de mercado en Estados Unidos al importar veh\u00edculos en masa y que han limitado la venta de autom\u00f3viles estadounidenses en Alemania.<\/p>\n<p>Sin embargo, el experto Stefan Bratzel, del instituto de automoci\u00f3n de la escuela superior de econom\u00eda de Bergisch Gladbach, considera que esas acusaciones son \u00abun aut\u00e9ntico disparate\u00bb. Aunque el mercado alem\u00e1n es complicado por la gran variedad t\u00e9cnica disponible, las empresas estadounidenses est\u00e1n m\u00e1s bien dificultadas por un problema de dise\u00f1o, explica a dpa.<\/p>\n<p>\u00abLos fabricantes estadounidenses no tienen, por ejemplo, productos premium\u00bb, cuenta. Adem\u00e1s, es muy dif\u00edcil imponerse a los fuertes fabricantes alemanes.<\/p>\n<p>Trump ya anunci\u00f3 el jueves sus planes de aplicar aranceles del 25 por ciento al acero importado y del diez por ciento al aluminio, lo que provoc\u00f3 que los socios comerciales amenazaran con represalias.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Berl\u00edn, 4 mar (dpa) &#8211; La ministra de econom\u00eda alemana, Brigitte Zypries, pidi\u00f3 hoy moderaci\u00f3n despu\u00e9s de que el presidente de Estados Unidos, Donald Trump, amenazara con imponer aranceles a los veh\u00edculos fabricados en la Uni\u00f3n Europea (UE). \u00abEspero que el presidente de Estados Unidos escuche a las numerosas voces sensibles de su pa\u00eds y<\/p>\n","protected":false},"author":1,"featured_media":35806,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343],"tags":[],"class_list":["post-91103","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Berl\u00edn, 4 mar (dpa) - La ministra de econom\u00eda alemana, Brigitte Zypries, pidi\u00f3 hoy moderaci\u00f3n despu\u00e9s de que el presidente de Estados Unidos, Donald Trump, amenazara con imponer aranceles a los veh\u00edculos fabricados en la Uni\u00f3n Europea (UE). &quot;Espero que el presidente de Estados Unidos escuche a las numerosas voces sensibles de su pa\u00eds y\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/amenaza-de-trump-de-aranceles-a-coches-de-la-ue-preocupa-a-alemania\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Amenaza de Trump de aranceles a coches de la UE preocupa a Alemania | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Berl\u00edn, 4 mar (dpa) - La ministra de econom\u00eda alemana, Brigitte Zypries, pidi\u00f3 hoy moderaci\u00f3n despu\u00e9s de que el presidente de Estados Unidos, Donald Trump, amenazara con imponer aranceles a los veh\u00edculos fabricados en la Uni\u00f3n Europea (UE). &quot;Espero que el presidente de Estados Unidos escuche a las numerosas voces sensibles de su pa\u00eds y\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/amenaza-de-trump-de-aranceles-a-coches-de-la-ue-preocupa-a-alemania\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/D.Trump-655x360.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/D.Trump-655x360.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"655\" \/>\n\t\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-03-04T22:37:30+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-03-04T22:37:30+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Amenaza de Trump de aranceles a coches de la UE preocupa a Alemania | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Berl\u00edn, 4 mar (dpa) - La ministra de econom\u00eda alemana, Brigitte Zypries, pidi\u00f3 hoy moderaci\u00f3n despu\u00e9s de que el presidente de Estados Unidos, Donald Trump, amenazara con imponer aranceles a los veh\u00edculos fabricados en la Uni\u00f3n Europea (UE). &quot;Espero que el presidente de Estados Unidos escuche a las numerosas voces sensibles de su pa\u00eds y\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/D.Trump-655x360.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/amenaza-de-trump-de-aranceles-a-coches-de-la-ue-preocupa-a-alemania\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/amenaza-de-trump-de-aranceles-a-coches-de-la-ue-preocupa-a-alemania\\\/#listItem\",\"name\":\"Amenaza de Trump de aranceles a coches de la UE preocupa a Alemania\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/amenaza-de-trump-de-aranceles-a-coches-de-la-ue-preocupa-a-alemania\\\/#listItem\",\"position\":3,\"name\":\"Amenaza de Trump de aranceles a coches de la UE preocupa a Alemania\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/amenaza-de-trump-de-aranceles-a-coches-de-la-ue-preocupa-a-alemania\\\/#newsarticle\",\"name\":\"Amenaza de Trump de aranceles a coches de la UE preocupa a Alemania | Cand\\u00e1s 365\",\"headline\":\"Amenaza de Trump de aranceles a coches de la UE preocupa a Alemania\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/D.Trump-655x360.jpg\",\"width\":655,\"height\":360},\"datePublished\":\"2018-03-04T22:37:30+01:00\",\"dateModified\":\"2018-03-04T22:37:30+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/amenaza-de-trump-de-aranceles-a-coches-de-la-ue-preocupa-a-alemania\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/amenaza-de-trump-de-aranceles-a-coches-de-la-ue-preocupa-a-alemania\\\/#webpage\"},\"articleSection\":\"Actualidad\",\"dateline\":\"Publicado el marzo 4, 2018.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/amenaza-de-trump-de-aranceles-a-coches-de-la-ue-preocupa-a-alemania\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/amenaza-de-trump-de-aranceles-a-coches-de-la-ue-preocupa-a-alemania\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/amenaza-de-trump-de-aranceles-a-coches-de-la-ue-preocupa-a-alemania\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/amenaza-de-trump-de-aranceles-a-coches-de-la-ue-preocupa-a-alemania\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/amenaza-de-trump-de-aranceles-a-coches-de-la-ue-preocupa-a-alemania\\\/\",\"name\":\"Amenaza de Trump de aranceles a coches de la UE preocupa a Alemania | Cand\\u00e1s 365\",\"description\":\"Berl\\u00edn, 4 mar (dpa) - La ministra de econom\\u00eda alemana, Brigitte Zypries, pidi\\u00f3 hoy moderaci\\u00f3n despu\\u00e9s de que el presidente de Estados Unidos, Donald Trump, amenazara con imponer aranceles a los veh\\u00edculos fabricados en la Uni\\u00f3n Europea (UE). \\\"Espero que el presidente de Estados Unidos escuche a las numerosas voces sensibles de su pa\\u00eds y\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/amenaza-de-trump-de-aranceles-a-coches-de-la-ue-preocupa-a-alemania\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/D.Trump-655x360.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/amenaza-de-trump-de-aranceles-a-coches-de-la-ue-preocupa-a-alemania\\\/#mainImage\",\"width\":655,\"height\":360},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/amenaza-de-trump-de-aranceles-a-coches-de-la-ue-preocupa-a-alemania\\\/#mainImage\"},\"datePublished\":\"2018-03-04T22:37:30+01:00\",\"dateModified\":\"2018-03-04T22:37:30+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Amenaza de Trump de aranceles a coches de la UE preocupa a Alemania | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Amenaza de Trump de aranceles a coches de la UE preocupa a Alemania | Cand\u00e1s 365","description":"Berl\u00edn, 4 mar (dpa) - La ministra de econom\u00eda alemana, Brigitte Zypries, pidi\u00f3 hoy moderaci\u00f3n despu\u00e9s de que el presidente de Estados Unidos, Donald Trump, amenazara con imponer aranceles a los veh\u00edculos fabricados en la Uni\u00f3n Europea (UE). \"Espero que el presidente de Estados Unidos escuche a las numerosas voces sensibles de su pa\u00eds y","canonical_url":"https:\/\/candas365.es\/noticias\/amenaza-de-trump-de-aranceles-a-coches-de-la-ue-preocupa-a-alemania\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/amenaza-de-trump-de-aranceles-a-coches-de-la-ue-preocupa-a-alemania\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/candas365.es\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/amenaza-de-trump-de-aranceles-a-coches-de-la-ue-preocupa-a-alemania\/#listItem","name":"Amenaza de Trump de aranceles a coches de la UE preocupa a Alemania"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/amenaza-de-trump-de-aranceles-a-coches-de-la-ue-preocupa-a-alemania\/#listItem","position":3,"name":"Amenaza de Trump de aranceles a coches de la UE preocupa a Alemania","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/amenaza-de-trump-de-aranceles-a-coches-de-la-ue-preocupa-a-alemania\/#newsarticle","name":"Amenaza de Trump de aranceles a coches de la UE preocupa a Alemania | Cand\u00e1s 365","headline":"Amenaza de Trump de aranceles a coches de la UE preocupa a Alemania","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/D.Trump-655x360.jpg","width":655,"height":360},"datePublished":"2018-03-04T22:37:30+01:00","dateModified":"2018-03-04T22:37:30+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/amenaza-de-trump-de-aranceles-a-coches-de-la-ue-preocupa-a-alemania\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/amenaza-de-trump-de-aranceles-a-coches-de-la-ue-preocupa-a-alemania\/#webpage"},"articleSection":"Actualidad","dateline":"Publicado el marzo 4, 2018."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/amenaza-de-trump-de-aranceles-a-coches-de-la-ue-preocupa-a-alemania\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/amenaza-de-trump-de-aranceles-a-coches-de-la-ue-preocupa-a-alemania\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/amenaza-de-trump-de-aranceles-a-coches-de-la-ue-preocupa-a-alemania\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/amenaza-de-trump-de-aranceles-a-coches-de-la-ue-preocupa-a-alemania\/#webpage","url":"https:\/\/candas365.es\/noticias\/amenaza-de-trump-de-aranceles-a-coches-de-la-ue-preocupa-a-alemania\/","name":"Amenaza de Trump de aranceles a coches de la UE preocupa a Alemania | Cand\u00e1s 365","description":"Berl\u00edn, 4 mar (dpa) - La ministra de econom\u00eda alemana, Brigitte Zypries, pidi\u00f3 hoy moderaci\u00f3n despu\u00e9s de que el presidente de Estados Unidos, Donald Trump, amenazara con imponer aranceles a los veh\u00edculos fabricados en la Uni\u00f3n Europea (UE). \"Espero que el presidente de Estados Unidos escuche a las numerosas voces sensibles de su pa\u00eds y","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/amenaza-de-trump-de-aranceles-a-coches-de-la-ue-preocupa-a-alemania\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/D.Trump-655x360.jpg","@id":"https:\/\/candas365.es\/noticias\/amenaza-de-trump-de-aranceles-a-coches-de-la-ue-preocupa-a-alemania\/#mainImage","width":655,"height":360},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/amenaza-de-trump-de-aranceles-a-coches-de-la-ue-preocupa-a-alemania\/#mainImage"},"datePublished":"2018-03-04T22:37:30+01:00","dateModified":"2018-03-04T22:37:30+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Amenaza de Trump de aranceles a coches de la UE preocupa a Alemania | Cand\u00e1s 365","og:description":"Berl\u00edn, 4 mar (dpa) - La ministra de econom\u00eda alemana, Brigitte Zypries, pidi\u00f3 hoy moderaci\u00f3n despu\u00e9s de que el presidente de Estados Unidos, Donald Trump, amenazara con imponer aranceles a los veh\u00edculos fabricados en la Uni\u00f3n Europea (UE). &quot;Espero que el presidente de Estados Unidos escuche a las numerosas voces sensibles de su pa\u00eds y","og:url":"https:\/\/candas365.es\/noticias\/amenaza-de-trump-de-aranceles-a-coches-de-la-ue-preocupa-a-alemania\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/D.Trump-655x360.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/D.Trump-655x360.jpg","og:image:width":655,"og:image:height":360,"article:published_time":"2018-03-04T22:37:30+00:00","article:modified_time":"2018-03-04T22:37:30+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Amenaza de Trump de aranceles a coches de la UE preocupa a Alemania | Cand\u00e1s 365","twitter:description":"Berl\u00edn, 4 mar (dpa) - La ministra de econom\u00eda alemana, Brigitte Zypries, pidi\u00f3 hoy moderaci\u00f3n despu\u00e9s de que el presidente de Estados Unidos, Donald Trump, amenazara con imponer aranceles a los veh\u00edculos fabricados en la Uni\u00f3n Europea (UE). &quot;Espero que el presidente de Estados Unidos escuche a las numerosas voces sensibles de su pa\u00eds y","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/D.Trump-655x360.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"91103","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-20 07:05:32","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 11:55:15","updated":"2026-05-20 07:05:32"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tAmenaza de Trump de aranceles a coches de la UE preocupa a Alemania\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Actualidad","link":"https:\/\/candas365.es\/noticias\/category\/actualidad\/"},{"label":"Amenaza de Trump de aranceles a coches de la UE preocupa a Alemania","link":"https:\/\/candas365.es\/noticias\/amenaza-de-trump-de-aranceles-a-coches-de-la-ue-preocupa-a-alemania\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/91103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=91103"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/91103\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/35806"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=91103"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=91103"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=91103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}