{"id":90998,"date":"2018-03-03T01:22:07","date_gmt":"2018-03-03T01:22:07","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=90998"},"modified":"2018-03-03T01:22:07","modified_gmt":"2018-03-03T01:22:07","slug":"merkel-y-trump-preocupados-por-anuncios-armamentistas-de-putin","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/merkel-y-trump-preocupados-por-anuncios-armamentistas-de-putin\/","title":{"rendered":"Merkel y Trump, preocupados por anuncios armamentistas de Putin"},"content":{"rendered":"<p>Berl\u00edn, 2 mar (dpa) &#8211; La canciller alemana, Angela Merkel, y el presidente de Estados Unidos, Donald Trump, se mostraron preocupados por los recientes anuncios de planes armamentistas del presidente ruso, Vladimir Putin, comunic\u00f3 hoy el Gobierno alem\u00e1n.<\/p>\n<p>El jefe de Estado ruso acus\u00f3 el jueves a Estados Unidos de incumplir el tratado START de reducci\u00f3n de armas nucleares y present\u00f3 nuevos tipos de armas con capacidad nuclear en respuesta al escudo antimisiles de Estados Unidos.<\/p>\n<p>Los l\u00edderes de Alemania y Estados Unidos manifestaron su preocupaci\u00f3n \u00absobre las recientes declaraciones del presidente ruso Putin sobre el desarrollo armamentista y sus efectos negativos en los esfuerzos internacionales para el control de armas\u00bb, se\u00f1al\u00f3 el comunicado.<\/p>\n<p>Merkel y Trump mantuvieron en la noche del jueves una conversaci\u00f3n telef\u00f3nica en la que llamaron a Rusia a dejar de participar en los bombardeos a la localidad siria de Guta Oriental y a llamar al r\u00e9gimen de Bashar al Assad a que frene la ofensiva contra la poblaci\u00f3n civil.<\/p>\n<p>Los mandatarios coincidieron que Siria y sus aliados de Rusia e Ir\u00e1n deben ser urgidos a aplicar de forma inmediata e integral la resoluci\u00f3n 2401 (2018) del Consejo de Seguridad de Naciones Unidas que demanda el cese inmediato de hostilidades en Siria. Adem\u00e1s demandaron que el Gobierno sirio sea responsabilizado por el deterioro de la situaci\u00f3n humanitaria en Guta Oriental.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Berl\u00edn, 2 mar (dpa) &#8211; La canciller alemana, Angela Merkel, y el presidente de Estados Unidos, Donald Trump, se mostraron preocupados por los recientes anuncios de planes armamentistas del presidente ruso, Vladimir Putin, comunic\u00f3 hoy el Gobierno alem\u00e1n. El jefe de Estado ruso acus\u00f3 el jueves a Estados Unidos de incumplir el tratado START de<\/p>\n","protected":false},"author":1,"featured_media":35806,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343],"tags":[],"class_list":["post-90998","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Berl\u00edn, 2 mar (dpa) - La canciller alemana, Angela Merkel, y el presidente de Estados Unidos, Donald Trump, se mostraron preocupados por los recientes anuncios de planes armamentistas del presidente ruso, Vladimir Putin, comunic\u00f3 hoy el Gobierno alem\u00e1n. El jefe de Estado ruso acus\u00f3 el jueves a Estados Unidos de incumplir el tratado START de\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/merkel-y-trump-preocupados-por-anuncios-armamentistas-de-putin\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Merkel y Trump, preocupados por anuncios armamentistas de Putin | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Berl\u00edn, 2 mar (dpa) - La canciller alemana, Angela Merkel, y el presidente de Estados Unidos, Donald Trump, se mostraron preocupados por los recientes anuncios de planes armamentistas del presidente ruso, Vladimir Putin, comunic\u00f3 hoy el Gobierno alem\u00e1n. El jefe de Estado ruso acus\u00f3 el jueves a Estados Unidos de incumplir el tratado START de\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/merkel-y-trump-preocupados-por-anuncios-armamentistas-de-putin\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/D.Trump-655x360.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/D.Trump-655x360.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"655\" \/>\n\t\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-03-03T01:22:07+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-03-03T01:22:07+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Merkel y Trump, preocupados por anuncios armamentistas de Putin | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Berl\u00edn, 2 mar (dpa) - La canciller alemana, Angela Merkel, y el presidente de Estados Unidos, Donald Trump, se mostraron preocupados por los recientes anuncios de planes armamentistas del presidente ruso, Vladimir Putin, comunic\u00f3 hoy el Gobierno alem\u00e1n. El jefe de Estado ruso acus\u00f3 el jueves a Estados Unidos de incumplir el tratado START de\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/D.Trump-655x360.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merkel-y-trump-preocupados-por-anuncios-armamentistas-de-putin\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merkel-y-trump-preocupados-por-anuncios-armamentistas-de-putin\\\/#listItem\",\"name\":\"Merkel y Trump, preocupados por anuncios armamentistas de Putin\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merkel-y-trump-preocupados-por-anuncios-armamentistas-de-putin\\\/#listItem\",\"position\":3,\"name\":\"Merkel y Trump, preocupados por anuncios armamentistas de Putin\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merkel-y-trump-preocupados-por-anuncios-armamentistas-de-putin\\\/#newsarticle\",\"name\":\"Merkel y Trump, preocupados por anuncios armamentistas de Putin | Cand\\u00e1s 365\",\"headline\":\"Merkel y Trump, preocupados por anuncios armamentistas de Putin\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/D.Trump-655x360.jpg\",\"width\":655,\"height\":360},\"datePublished\":\"2018-03-03T01:22:07+01:00\",\"dateModified\":\"2018-03-03T01:22:07+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merkel-y-trump-preocupados-por-anuncios-armamentistas-de-putin\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merkel-y-trump-preocupados-por-anuncios-armamentistas-de-putin\\\/#webpage\"},\"articleSection\":\"Actualidad\",\"dateline\":\"Publicado el marzo 3, 2018.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merkel-y-trump-preocupados-por-anuncios-armamentistas-de-putin\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merkel-y-trump-preocupados-por-anuncios-armamentistas-de-putin\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merkel-y-trump-preocupados-por-anuncios-armamentistas-de-putin\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merkel-y-trump-preocupados-por-anuncios-armamentistas-de-putin\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merkel-y-trump-preocupados-por-anuncios-armamentistas-de-putin\\\/\",\"name\":\"Merkel y Trump, preocupados por anuncios armamentistas de Putin | Cand\\u00e1s 365\",\"description\":\"Berl\\u00edn, 2 mar (dpa) - La canciller alemana, Angela Merkel, y el presidente de Estados Unidos, Donald Trump, se mostraron preocupados por los recientes anuncios de planes armamentistas del presidente ruso, Vladimir Putin, comunic\\u00f3 hoy el Gobierno alem\\u00e1n. El jefe de Estado ruso acus\\u00f3 el jueves a Estados Unidos de incumplir el tratado START de\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merkel-y-trump-preocupados-por-anuncios-armamentistas-de-putin\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/D.Trump-655x360.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merkel-y-trump-preocupados-por-anuncios-armamentistas-de-putin\\\/#mainImage\",\"width\":655,\"height\":360},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merkel-y-trump-preocupados-por-anuncios-armamentistas-de-putin\\\/#mainImage\"},\"datePublished\":\"2018-03-03T01:22:07+01:00\",\"dateModified\":\"2018-03-03T01:22:07+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Merkel y Trump, preocupados por anuncios armamentistas de Putin | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Merkel y Trump, preocupados por anuncios armamentistas de Putin | Cand\u00e1s 365","description":"Berl\u00edn, 2 mar (dpa) - La canciller alemana, Angela Merkel, y el presidente de Estados Unidos, Donald Trump, se mostraron preocupados por los recientes anuncios de planes armamentistas del presidente ruso, Vladimir Putin, comunic\u00f3 hoy el Gobierno alem\u00e1n. El jefe de Estado ruso acus\u00f3 el jueves a Estados Unidos de incumplir el tratado START de","canonical_url":"https:\/\/candas365.es\/noticias\/merkel-y-trump-preocupados-por-anuncios-armamentistas-de-putin\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/merkel-y-trump-preocupados-por-anuncios-armamentistas-de-putin\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/candas365.es\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/merkel-y-trump-preocupados-por-anuncios-armamentistas-de-putin\/#listItem","name":"Merkel y Trump, preocupados por anuncios armamentistas de Putin"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/merkel-y-trump-preocupados-por-anuncios-armamentistas-de-putin\/#listItem","position":3,"name":"Merkel y Trump, preocupados por anuncios armamentistas de Putin","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/merkel-y-trump-preocupados-por-anuncios-armamentistas-de-putin\/#newsarticle","name":"Merkel y Trump, preocupados por anuncios armamentistas de Putin | Cand\u00e1s 365","headline":"Merkel y Trump, preocupados por anuncios armamentistas de Putin","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/D.Trump-655x360.jpg","width":655,"height":360},"datePublished":"2018-03-03T01:22:07+01:00","dateModified":"2018-03-03T01:22:07+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/merkel-y-trump-preocupados-por-anuncios-armamentistas-de-putin\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/merkel-y-trump-preocupados-por-anuncios-armamentistas-de-putin\/#webpage"},"articleSection":"Actualidad","dateline":"Publicado el marzo 3, 2018."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/merkel-y-trump-preocupados-por-anuncios-armamentistas-de-putin\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/merkel-y-trump-preocupados-por-anuncios-armamentistas-de-putin\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/merkel-y-trump-preocupados-por-anuncios-armamentistas-de-putin\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/merkel-y-trump-preocupados-por-anuncios-armamentistas-de-putin\/#webpage","url":"https:\/\/candas365.es\/noticias\/merkel-y-trump-preocupados-por-anuncios-armamentistas-de-putin\/","name":"Merkel y Trump, preocupados por anuncios armamentistas de Putin | Cand\u00e1s 365","description":"Berl\u00edn, 2 mar (dpa) - La canciller alemana, Angela Merkel, y el presidente de Estados Unidos, Donald Trump, se mostraron preocupados por los recientes anuncios de planes armamentistas del presidente ruso, Vladimir Putin, comunic\u00f3 hoy el Gobierno alem\u00e1n. El jefe de Estado ruso acus\u00f3 el jueves a Estados Unidos de incumplir el tratado START de","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/merkel-y-trump-preocupados-por-anuncios-armamentistas-de-putin\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/D.Trump-655x360.jpg","@id":"https:\/\/candas365.es\/noticias\/merkel-y-trump-preocupados-por-anuncios-armamentistas-de-putin\/#mainImage","width":655,"height":360},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/merkel-y-trump-preocupados-por-anuncios-armamentistas-de-putin\/#mainImage"},"datePublished":"2018-03-03T01:22:07+01:00","dateModified":"2018-03-03T01:22:07+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Merkel y Trump, preocupados por anuncios armamentistas de Putin | Cand\u00e1s 365","og:description":"Berl\u00edn, 2 mar (dpa) - La canciller alemana, Angela Merkel, y el presidente de Estados Unidos, Donald Trump, se mostraron preocupados por los recientes anuncios de planes armamentistas del presidente ruso, Vladimir Putin, comunic\u00f3 hoy el Gobierno alem\u00e1n. El jefe de Estado ruso acus\u00f3 el jueves a Estados Unidos de incumplir el tratado START de","og:url":"https:\/\/candas365.es\/noticias\/merkel-y-trump-preocupados-por-anuncios-armamentistas-de-putin\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/D.Trump-655x360.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/D.Trump-655x360.jpg","og:image:width":655,"og:image:height":360,"article:published_time":"2018-03-03T01:22:07+00:00","article:modified_time":"2018-03-03T01:22:07+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Merkel y Trump, preocupados por anuncios armamentistas de Putin | Cand\u00e1s 365","twitter:description":"Berl\u00edn, 2 mar (dpa) - La canciller alemana, Angela Merkel, y el presidente de Estados Unidos, Donald Trump, se mostraron preocupados por los recientes anuncios de planes armamentistas del presidente ruso, Vladimir Putin, comunic\u00f3 hoy el Gobierno alem\u00e1n. El jefe de Estado ruso acus\u00f3 el jueves a Estados Unidos de incumplir el tratado START de","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/D.Trump-655x360.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"1 minuto"},"aioseo_meta_data":{"post_id":"90998","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-20 06:47:29","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 11:55:22","updated":"2026-05-20 06:47:29"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tMerkel y Trump, preocupados por anuncios armamentistas de Putin\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Actualidad","link":"https:\/\/candas365.es\/noticias\/category\/actualidad\/"},{"label":"Merkel y Trump, preocupados por anuncios armamentistas de Putin","link":"https:\/\/candas365.es\/noticias\/merkel-y-trump-preocupados-por-anuncios-armamentistas-de-putin\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/90998","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=90998"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/90998\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/35806"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=90998"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=90998"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=90998"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}