{"id":90920,"date":"2018-03-01T19:50:30","date_gmt":"2018-03-01T19:50:30","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=90920"},"modified":"2018-03-01T19:50:30","modified_gmt":"2018-03-01T19:50:30","slug":"aida-cruises-amplia-su-flota-de-barcos-de-cruceros","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/aida-cruises-amplia-su-flota-de-barcos-de-cruceros\/","title":{"rendered":"Aida Cruises ampl\u00eda su flota de barcos de cruceros"},"content":{"rendered":"<p>Papenburgo\/Rostock (Alemania), 1 mar (dpa) &#8211; La compa\u00f1\u00eda naviera Aida Cruises ampl\u00eda su flota de barcos de cruceros y encarga una nueva embarcaci\u00f3n a la empresa alemana de construcci\u00f3n naval Meyer Werft.<\/p>\n<p>La nave, que ser\u00e1 propulsada a gas natural licuado (GNL), deber\u00eda entrar en servicio en 2023. El volumen del pedido ascender\u00eda a los mil millones de euros, aproximadamente.<\/p>\n<p>\u00abReaccionamos as\u00ed al constante crecimiento que experimenta el mercado de los viajes en crucero\u00bb, se\u00f1al\u00f3 este martes Felix Eichhorn, presidente de Aida Cruises a la agencia dpa.<\/p>\n<p>Con este nuevo encargo, la flota del l\u00edder en cruceros en el mercado alem\u00e1n -propietario de 12 naves actualmente- pasar\u00e1 a contar con un total de 15 embarcaciones en 2023. Dos buques gemelos, tambi\u00e9n constru\u00eddos por Meyer Werft, ser\u00e1n entregados y puestos en funci\u00f3n en el \u00faltimo trimestre de este a\u00f1o y en 2021 respectivamente.<\/p>\n<p>La nueva nave encargada ser\u00e1 la d\u00e9cima que la alemana Meyer Werft construye para la compa\u00f1\u00eda de cruceros que pertenece al grupo Carnival Corporation y tiene su sede en la ciudad de Rostock, en el estado federado de Mecklemburgo-Pomerania Occidental, y la tercera propulsada exclusivamente con GNL.<\/p>\n<p>\u00abEn este sentido realizamos una labor pionera a nivel mundial para la navegaci\u00f3n\u00bb, destac\u00f3 Eichhorn. Aunque la infraestructura en algunos puertos dejen a\u00fan mucho que desear, GNL es actualmente el camino a seguir a fin de reducir considerablemente las emisiones, agreg\u00f3.<\/p>\n<p>Seg\u00fan datos de la asociaci\u00f3n internacional de l\u00edneas de cruceros CLIA, dos millones de turistas alemanes compraron en 2016 un viaje en crucero. Aida super\u00f3 en 2017 por primera vez la cifra de un mill\u00f3n de pasajeros. \u00abLa demanda es mucho mayor que la oferta. La mayor parte de nuestros viajes est\u00e1n vendidos\u00bb, afirma el jefe de la compa\u00f1\u00eda naviera.<\/p>\n<p>Con los tres nuevos barcos, Aida Cruises invierte m\u00e1s de tres mil millones de euros en los pr\u00f3ximos a\u00f1os, inform\u00f3 la compa\u00f1\u00eda. Adem\u00e1s, con cada barco nuevo se crean alrededor de 2.000 nuevos puestos de trabajo -a bordo y en tierra firme-. La empresa cuenta en total con 11.400 empleados provenientes de 40 pa\u00edses diferentes, 10.000 de ellos trabajan a bordo de las naves.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Papenburgo\/Rostock (Alemania), 1 mar (dpa) &#8211; La compa\u00f1\u00eda naviera Aida Cruises ampl\u00eda su flota de barcos de cruceros y encarga una nueva embarcaci\u00f3n a la empresa alemana de construcci\u00f3n naval Meyer Werft. La nave, que ser\u00e1 propulsada a gas natural licuado (GNL), deber\u00eda entrar en servicio en 2023. El volumen del pedido ascender\u00eda a los<\/p>\n","protected":false},"author":1,"featured_media":90921,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[151],"tags":[],"class_list":{"0":"post-90920","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-canal-empresas"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7 - aioseo.com -->\n\t<meta name=\"description\" content=\"Papenburgo\/Rostock (Alemania), 1 mar (dpa) - La compa\u00f1\u00eda naviera Aida Cruises ampl\u00eda su flota de barcos de cruceros y encarga una nueva embarcaci\u00f3n a la empresa alemana de construcci\u00f3n naval Meyer Werft. La nave, que ser\u00e1 propulsada a gas natural licuado (GNL), deber\u00eda entrar en servicio en 2023. El volumen del pedido ascender\u00eda a los\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"canal empresas\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/aida-cruises-amplia-su-flota-de-barcos-de-cruceros\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Aida Cruises ampl\u00eda su flota de barcos de cruceros | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Papenburgo\/Rostock (Alemania), 1 mar (dpa) - La compa\u00f1\u00eda naviera Aida Cruises ampl\u00eda su flota de barcos de cruceros y encarga una nueva embarcaci\u00f3n a la empresa alemana de construcci\u00f3n naval Meyer Werft. La nave, que ser\u00e1 propulsada a gas natural licuado (GNL), deber\u00eda entrar en servicio en 2023. El volumen del pedido ascender\u00eda a los\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/aida-cruises-amplia-su-flota-de-barcos-de-cruceros\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/2947877_1280.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/2947877_1280.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t\t<meta property=\"og:image:height\" content=\"719\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-03-01T19:50:30+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-03-01T19:50:30+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Aida Cruises ampl\u00eda su flota de barcos de cruceros | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Papenburgo\/Rostock (Alemania), 1 mar (dpa) - La compa\u00f1\u00eda naviera Aida Cruises ampl\u00eda su flota de barcos de cruceros y encarga una nueva embarcaci\u00f3n a la empresa alemana de construcci\u00f3n naval Meyer Werft. La nave, que ser\u00e1 propulsada a gas natural licuado (GNL), deber\u00eda entrar en servicio en 2023. El volumen del pedido ascender\u00eda a los\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/2947877_1280.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/aida-cruises-amplia-su-flota-de-barcos-de-cruceros\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"name\":\"Canal Empresas\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"position\":2,\"name\":\"Canal Empresas\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/aida-cruises-amplia-su-flota-de-barcos-de-cruceros\\\/#listItem\",\"name\":\"Aida Cruises ampl\\u00eda su flota de barcos de cruceros\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/aida-cruises-amplia-su-flota-de-barcos-de-cruceros\\\/#listItem\",\"position\":3,\"name\":\"Aida Cruises ampl\\u00eda su flota de barcos de cruceros\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"name\":\"Canal Empresas\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/aida-cruises-amplia-su-flota-de-barcos-de-cruceros\\\/#newsarticle\",\"name\":\"Aida Cruises ampl\\u00eda su flota de barcos de cruceros | Cand\\u00e1s 365\",\"headline\":\"Aida Cruises ampl\\u00eda su flota de barcos de cruceros\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/2947877_1280.jpg\",\"width\":1280,\"height\":719},\"datePublished\":\"2018-03-01T19:50:30+01:00\",\"dateModified\":\"2018-03-01T19:50:30+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/aida-cruises-amplia-su-flota-de-barcos-de-cruceros\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/aida-cruises-amplia-su-flota-de-barcos-de-cruceros\\\/#webpage\"},\"articleSection\":\"Canal Empresas\",\"dateline\":\"Publicado el marzo 1, 2018.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/aida-cruises-amplia-su-flota-de-barcos-de-cruceros\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/aida-cruises-amplia-su-flota-de-barcos-de-cruceros\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/aida-cruises-amplia-su-flota-de-barcos-de-cruceros\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/aida-cruises-amplia-su-flota-de-barcos-de-cruceros\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/aida-cruises-amplia-su-flota-de-barcos-de-cruceros\\\/\",\"name\":\"Aida Cruises ampl\\u00eda su flota de barcos de cruceros | Cand\\u00e1s 365\",\"description\":\"Papenburgo\\\/Rostock (Alemania), 1 mar (dpa) - La compa\\u00f1\\u00eda naviera Aida Cruises ampl\\u00eda su flota de barcos de cruceros y encarga una nueva embarcaci\\u00f3n a la empresa alemana de construcci\\u00f3n naval Meyer Werft. La nave, que ser\\u00e1 propulsada a gas natural licuado (GNL), deber\\u00eda entrar en servicio en 2023. El volumen del pedido ascender\\u00eda a los\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/aida-cruises-amplia-su-flota-de-barcos-de-cruceros\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/2947877_1280.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/aida-cruises-amplia-su-flota-de-barcos-de-cruceros\\\/#mainImage\",\"width\":1280,\"height\":719},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/aida-cruises-amplia-su-flota-de-barcos-de-cruceros\\\/#mainImage\"},\"datePublished\":\"2018-03-01T19:50:30+01:00\",\"dateModified\":\"2018-03-01T19:50:30+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Aida Cruises ampl\u00eda su flota de barcos de cruceros | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Aida Cruises ampl\u00eda su flota de barcos de cruceros | Cand\u00e1s 365","description":"Papenburgo\/Rostock (Alemania), 1 mar (dpa) - La compa\u00f1\u00eda naviera Aida Cruises ampl\u00eda su flota de barcos de cruceros y encarga una nueva embarcaci\u00f3n a la empresa alemana de construcci\u00f3n naval Meyer Werft. La nave, que ser\u00e1 propulsada a gas natural licuado (GNL), deber\u00eda entrar en servicio en 2023. El volumen del pedido ascender\u00eda a los","canonical_url":"https:\/\/candas365.es\/noticias\/aida-cruises-amplia-su-flota-de-barcos-de-cruceros\/","robots":"max-image-preview:large","keywords":"canal empresas","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/aida-cruises-amplia-su-flota-de-barcos-de-cruceros\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","name":"Canal Empresas"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","position":2,"name":"Canal Empresas","item":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/aida-cruises-amplia-su-flota-de-barcos-de-cruceros\/#listItem","name":"Aida Cruises ampl\u00eda su flota de barcos de cruceros"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/aida-cruises-amplia-su-flota-de-barcos-de-cruceros\/#listItem","position":3,"name":"Aida Cruises ampl\u00eda su flota de barcos de cruceros","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","name":"Canal Empresas"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/aida-cruises-amplia-su-flota-de-barcos-de-cruceros\/#newsarticle","name":"Aida Cruises ampl\u00eda su flota de barcos de cruceros | Cand\u00e1s 365","headline":"Aida Cruises ampl\u00eda su flota de barcos de cruceros","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/2947877_1280.jpg","width":1280,"height":719},"datePublished":"2018-03-01T19:50:30+01:00","dateModified":"2018-03-01T19:50:30+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/aida-cruises-amplia-su-flota-de-barcos-de-cruceros\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/aida-cruises-amplia-su-flota-de-barcos-de-cruceros\/#webpage"},"articleSection":"Canal Empresas","dateline":"Publicado el marzo 1, 2018."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/aida-cruises-amplia-su-flota-de-barcos-de-cruceros\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/aida-cruises-amplia-su-flota-de-barcos-de-cruceros\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/aida-cruises-amplia-su-flota-de-barcos-de-cruceros\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/aida-cruises-amplia-su-flota-de-barcos-de-cruceros\/#webpage","url":"https:\/\/candas365.es\/noticias\/aida-cruises-amplia-su-flota-de-barcos-de-cruceros\/","name":"Aida Cruises ampl\u00eda su flota de barcos de cruceros | Cand\u00e1s 365","description":"Papenburgo\/Rostock (Alemania), 1 mar (dpa) - La compa\u00f1\u00eda naviera Aida Cruises ampl\u00eda su flota de barcos de cruceros y encarga una nueva embarcaci\u00f3n a la empresa alemana de construcci\u00f3n naval Meyer Werft. La nave, que ser\u00e1 propulsada a gas natural licuado (GNL), deber\u00eda entrar en servicio en 2023. El volumen del pedido ascender\u00eda a los","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/aida-cruises-amplia-su-flota-de-barcos-de-cruceros\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/2947877_1280.jpg","@id":"https:\/\/candas365.es\/noticias\/aida-cruises-amplia-su-flota-de-barcos-de-cruceros\/#mainImage","width":1280,"height":719},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/aida-cruises-amplia-su-flota-de-barcos-de-cruceros\/#mainImage"},"datePublished":"2018-03-01T19:50:30+01:00","dateModified":"2018-03-01T19:50:30+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Aida Cruises ampl\u00eda su flota de barcos de cruceros | Cand\u00e1s 365","og:description":"Papenburgo\/Rostock (Alemania), 1 mar (dpa) - La compa\u00f1\u00eda naviera Aida Cruises ampl\u00eda su flota de barcos de cruceros y encarga una nueva embarcaci\u00f3n a la empresa alemana de construcci\u00f3n naval Meyer Werft. La nave, que ser\u00e1 propulsada a gas natural licuado (GNL), deber\u00eda entrar en servicio en 2023. El volumen del pedido ascender\u00eda a los","og:url":"https:\/\/candas365.es\/noticias\/aida-cruises-amplia-su-flota-de-barcos-de-cruceros\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/2947877_1280.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/2947877_1280.jpg","og:image:width":1280,"og:image:height":719,"article:published_time":"2018-03-01T19:50:30+00:00","article:modified_time":"2018-03-01T19:50:30+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Aida Cruises ampl\u00eda su flota de barcos de cruceros | Cand\u00e1s 365","twitter:description":"Papenburgo\/Rostock (Alemania), 1 mar (dpa) - La compa\u00f1\u00eda naviera Aida Cruises ampl\u00eda su flota de barcos de cruceros y encarga una nueva embarcaci\u00f3n a la empresa alemana de construcci\u00f3n naval Meyer Werft. La nave, que ser\u00e1 propulsada a gas natural licuado (GNL), deber\u00eda entrar en servicio en 2023. El volumen del pedido ascender\u00eda a los","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/2947877_1280.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"90920","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-26 14:13:10","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 11:55:22","updated":"2025-08-26 14:13:10"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/\" title=\"Canal Empresas\">Canal Empresas<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tAida Cruises ampl\u00eda su flota de barcos de cruceros\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Canal Empresas","link":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/"},{"label":"Aida Cruises ampl\u00eda su flota de barcos de cruceros","link":"https:\/\/candas365.es\/noticias\/aida-cruises-amplia-su-flota-de-barcos-de-cruceros\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/90920","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=90920"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/90920\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/90921"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=90920"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=90920"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=90920"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}