{"id":90464,"date":"2018-02-22T10:56:29","date_gmt":"2018-02-22T10:56:29","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=90464"},"modified":"2018-02-22T10:56:29","modified_gmt":"2018-02-22T10:56:29","slug":"vajilla-prehistorica-y-adn-cierran-un-debate-arqueologico-centenario","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/vajilla-prehistorica-y-adn-cierran-un-debate-arqueologico-centenario\/","title":{"rendered":"Vajilla prehist\u00f3rica y ADN cierran un debate arqueol\u00f3gico centenario"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-90465\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/kitcampan-360x242.jpg\" alt=\"\" width=\"360\" height=\"242\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/kitcampan-360x242.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/kitcampan-625x420.jpg 625w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/kitcampan-655x440.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/kitcampan.jpg 671w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Hace entre 4.750 y 4.500 a\u00f1os, un tipo de cer\u00e1mica muy decorada, conocida como vaso campaniforme por su forma de campana invertida, se extendi\u00f3 por el oeste y centro de Europa, marcando un periodo clave de la prehistoria del continente. Desde hace un siglo los cient\u00edficos debaten intensamente si su difusi\u00f3n se debi\u00f3 a un proceso migratorio a gran escala, a la expansi\u00f3n de pr\u00e1cticas sociales o una combinaci\u00f3n de ambos factores.<\/p>\n<p>Ahora, el mayor estudio de ADN antiguo realizado hasta la fecha revela que tanto la transmisi\u00f3n cultural como la migraci\u00f3n humana tuvieron un papel importante en la difusi\u00f3n del fen\u00f3meno campaniforme en Europa, aunque con distinto peso seg\u00fan la regi\u00f3n. Para llegar a esta conclusi\u00f3n se han analizado los restos de 400 esqueletos prehist\u00f3ricos de numerosos yacimientos europeos (11 en la pen\u00ednsula ib\u00e9rica), de los que 226 fueron enterrados junto a objetos campaniformes.<\/p>\n<p>El estudio se ha publicado en Nature y ha contado con la participaci\u00f3n de investigadores de las universidades Aut\u00f3noma de Barcelona, Valladolid, Complutense y Aut\u00f3noma de Madrid, Alcal\u00e1, Murcia, Santiago de Compostela y el Instituto de Biolog\u00eda Evolutiva (CSIC-UPF), entre otras instituciones nacionales.<\/p>\n<p>Seg\u00fan los resultados, la expansi\u00f3n del fen\u00f3meno campaniforme desde Iberia \u2013donde se ha obtenido el registro m\u00e1s antiguo de este estilo cer\u00e1mico\u2013 hasta el centro de Europa se debi\u00f3 a intercambios culturales y no por un movimiento migratorio de poblaci\u00f3n. I\u00f1igo Olalde, genetista de la Harvard Medical School en Boston (EE UU), primer autor del art\u00edculo, se\u00f1ala que el ADN de los esqueletos de las tumbas campaniformes ib\u00e9ricas no ten\u00eda una relaci\u00f3n de proximidad con los del centro del continente.<\/p>\n<p>Por su parte, el tambi\u00e9n coautor David Reich, investigador del Howard Hughes Medical Institute y del Broad Institute del MIT y Harvard, destaca: \u201cSe trata del primer claro ejemplo, a partir de ADN antiguo, de que las cer\u00e1micas no siempre iban de la mano de la poblaci\u00f3n\u201d.<\/p>\n<p><strong>Aislamiento gen\u00e9tico entre Iberia y Europa central<\/strong><\/p>\n<p>\u201cEs muy interesante observar c\u00f3mo Iberia, por una parte, y Europa central, por otra, mantuvieron un aislamiento gen\u00e9tico al final del Neol\u00edtico, hace unos 5.000 a\u00f1os, a pesar de las numerosas evidencias arqueol\u00f3gicas de interacciones y contactos entre ambas regiones\u201d, subraya Roberto Risch, profesor del departamento de Prehistoria de la Universidad Aut\u00f3noma de Barcelona (UAB).<\/p>\n<blockquote><p><strong><em>El vaso campaniforme pas\u00f3 de ser un objeto colectivo a s\u00edmbolo de poder: de las clases populares a las \u00e9lites, \u201ccomo sucedi\u00f3 con el jazz\u201d, explica Risch<\/em><\/strong><\/p><\/blockquote>\n<p>\u201cEl estudio muestra que la introducci\u00f3n del vaso campaniforme en Europa central hace 4.500 a\u00f1os no tuvo nada que ver con la llegada de poblaciones de la pen\u00ednsula ib\u00e9rica, como se hab\u00eda defendido durante mucho tiempo. La r\u00e1pida adopci\u00f3n de una vajilla, que deb\u00eda estar unida a unas pr\u00e1cticas de consumo muy concretas (alojar bebida o comida en rituales o fiestas), expresa el desarrollo de unas nuevas formas de comunicaci\u00f3n entre el sudoeste y el centro de Europa\u201d, a\u00f1ade Risch.<\/p>\n<p>Sorprendentemente, el vaso campaniforme fue adoptado en el centro de Europa por unas poblaciones que acababan de llegar del este. \u201cEn 2015 realizamos otro gran estudio internacional que mostr\u00f3 que hace unos 4.500 a\u00f1os al menos el 70% de la poblaci\u00f3n del centro y norte de Europa fue sustituida por una masiva migraci\u00f3n de grupos del este procedentes de la estepa. Y este nuevo trabajo revela c\u00f3mo este movimiento sigui\u00f3 avanzando hacia el oeste\u201d, destaca Wolfgang Haak, del Max Planck Institute for the Science of Human History (Alemania), otro de los autores.<\/p>\n<p><strong>Movimiento campaniforme hacia el oeste<\/strong><\/p>\n<p>\u201cPero, en este movimiento hacia el oeste, el vaso campaniforme ya no es expresi\u00f3n de unas pr\u00e1cticas de consumo colectivas, como lo fue en la pen\u00ednsula ib\u00e9rica, sino que se incorpora a tumbas individuales, en las que los hombres suelen aparecer con armas distintivas y distinguidas, como pu\u00f1ales de cobre, arco y flechas\u201d, puntualiza Risch.<\/p>\n<p>El profesor aclara a Sinc: \u201cEl significado social del vaso campaniforme cambi\u00f3 en ese recorrido desde la Pen\u00ednsula hasta Europa central, y de all\u00ed a las islas brit\u00e1nicas. De un objeto colectivo pas\u00f3 a ser un s\u00edmbolo de individuos poderosos. Es un caso claro de manipulaci\u00f3n del significado de las cosas en funci\u00f3n de los intereses de grupos de poder, algo que ha seguido ocurriendo hasta la actualidad. Un ejemplo paradigm\u00e1tico es el jazz, que pas\u00f3 de ser una m\u00fasica marginal y rompedora con la tradici\u00f3n cl\u00e1sica, a ser, sobre todo en Europa, una m\u00fasica de las \u00e9lites\u201d.<\/p>\n<p>En Reino Unido e Irlanda se han estudiado 155 muestras fechadas entre hace 6.000 y 3.000 a\u00f1os. Seg\u00fan el genetista Ian Barnes, del Museo de Historia Natural de Londres, \u201cesos ancestros brit\u00e1nicos ten\u00edan un perfil gen\u00e9tico diferente de los que vivieron poco tiempo despu\u00e9s que ellos y al menos el 90% fue reemplazado por la llegada del campaniforme desde el continente. Tras la llegada de esta nueva poblaci\u00f3n, empezaron a existir en la isla brit\u00e1nica habitantes con antepasados que ten\u00edan caracter\u00edsticas, color de piel y ojos similares a la mayor\u00eda de los brit\u00e1nicos actuales\u201d.<\/p>\n<p><strong>El &#8216;kit&#8217; campaniforme aparece en la Pen\u00ednsula<\/strong><\/p>\n<p>Barnes agrega que, curiosamente, hace unos 4.500 a\u00f1os, en la pen\u00ednsula ib\u00e9rica tambi\u00e9n comienza a introducirse entre la gente local el ritual funerario individual, con su ajuar de vasos campaniformes, pu\u00f1ales de metal y adornos como botones y brazales, un autentico &#8216;kit&#8217; campaniforme.<\/p>\n<p>\u00abAqu\u00ed, al contrario de lo que ocurri\u00f3 en las islas brit\u00e1nicas, no se aprecia un cambio gen\u00e9tico\u201d, comenta el profesor Ignacio Soriano de la UAB. \u201cEsta vez los cambios proced\u00edan del norte y provocaron una ruptura social importante cuyas consecuencias se ver\u00e1n en la Edad del Bronce, hace unos 4.200 a\u00f1os\u201d. En el caso de la pen\u00ednsula ib\u00e9rica, se ha observado una continuidad gen\u00e9tica directa entre las poblaciones neol\u00edticas previas y las posteriores de la Edad del Cobre y campaniformes.<\/p>\n<p>El tambi\u00e9n coautor Manuel Rojo Guerra, de la Universidad de Valladolid, coincide: \u00abDesde un punto de vista gen\u00e9tico, los pobladores de la Pen\u00ednsula en esa \u00e9poca son los descendientes de las poblaciones calcol\u00edticas. Es decir, son gentes que ya estaban aqu\u00ed y que en un momento determinado adoptan el kit campaniforme\u00bb, que aparece en distintas regiones de Europa casi de forma simultanea.<\/p>\n<p>En Centroeuropea se produce una situaci\u00f3n similar. El fen\u00f3meno campaniforme tambi\u00e9n aparece en el seno de poblaciones previamente establecidas que se hab\u00edan instalado en el solar europeo procedentes de las estepas euroasi\u00e1ticas.<\/p>\n<p><strong>La misteriosa llegada desde las estepas europeas<\/strong><\/p>\n<p>\u201cEn la prehistoria peninsular, las primeras comunidades que fabricaban armas de metal (como las que aparecen en los kits) segu\u00edan teniendo una configuraci\u00f3n gen\u00e9tica muy diferente a las sociedades actuales de la pen\u00ednsula ib\u00e9rica\u00bb, comenta Risch, \u00aby nuestro siguiente reto es determinar c\u00f3mo y cu\u00e1ndo se dieron los movimientos poblaciones que introducen el componente estepario en la Pen\u00ednsula y que vemos en la actualidad\u201d.<\/p>\n<p>El an\u00e1lisis exitoso de tantas muestras utilizadas en el estudio ha sido posible gracias a nuevos enfoques metodol\u00f3gicas que han reducido enormemente el coste por muestra de an\u00e1lisis de ADN antiguo. Uno se basa en un tratamiento qu\u00edmico que permite a los investigadores fijar su secuencia sobre la peque\u00f1a parte del genoma de m\u00e1s utilidad para el an\u00e1lisis. Tambi\u00e9n se ha tenido en cuenta que la cantidad de ADN extra\u00edda de la porci\u00f3n petrosa del hueso temporal es mucho mayor que la de cualquier otra parte del esqueleto.<\/p>\n<p>SINC<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hace entre 4.750 y 4.500 a\u00f1os, un tipo de cer\u00e1mica muy decorada, conocida como vaso campaniforme por su forma de campana invertida, se extendi\u00f3 por el oeste y centro de Europa, marcando un periodo clave de la prehistoria del continente. Desde hace un siglo los cient\u00edficos debaten intensamente si su difusi\u00f3n se debi\u00f3 a un<\/p>\n","protected":false},"author":1,"featured_media":90465,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[143],"tags":[],"class_list":["post-90464","post","type-post","status-publish","format-standard","has-post-thumbnail","category-sociedad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Hace entre 4.750 y 4.500 a\u00f1os, un tipo de cer\u00e1mica muy decorada, conocida como vaso campaniforme por su forma de campana invertida, se extendi\u00f3 por el oeste y centro de Europa, marcando un periodo clave de la prehistoria del continente. Desde hace un siglo los cient\u00edficos debaten intensamente si su difusi\u00f3n se debi\u00f3 a un\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"sociedad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/vajilla-prehistorica-y-adn-cierran-un-debate-arqueologico-centenario\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Vajilla prehist\u00f3rica y ADN cierran un debate arqueol\u00f3gico centenario | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Hace entre 4.750 y 4.500 a\u00f1os, un tipo de cer\u00e1mica muy decorada, conocida como vaso campaniforme por su forma de campana invertida, se extendi\u00f3 por el oeste y centro de Europa, marcando un periodo clave de la prehistoria del continente. Desde hace un siglo los cient\u00edficos debaten intensamente si su difusi\u00f3n se debi\u00f3 a un\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/vajilla-prehistorica-y-adn-cierran-un-debate-arqueologico-centenario\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/kitcampan.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/kitcampan.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"671\" \/>\n\t\t<meta property=\"og:image:height\" content=\"451\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-02-22T10:56:29+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-02-22T10:56:29+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Vajilla prehist\u00f3rica y ADN cierran un debate arqueol\u00f3gico centenario | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Hace entre 4.750 y 4.500 a\u00f1os, un tipo de cer\u00e1mica muy decorada, conocida como vaso campaniforme por su forma de campana invertida, se extendi\u00f3 por el oeste y centro de Europa, marcando un periodo clave de la prehistoria del continente. Desde hace un siglo los cient\u00edficos debaten intensamente si su difusi\u00f3n se debi\u00f3 a un\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/kitcampan.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/vajilla-prehistorica-y-adn-cierran-un-debate-arqueologico-centenario\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/sociedad\\\/#listItem\",\"name\":\"Sociedad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/sociedad\\\/#listItem\",\"position\":2,\"name\":\"Sociedad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/sociedad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/vajilla-prehistorica-y-adn-cierran-un-debate-arqueologico-centenario\\\/#listItem\",\"name\":\"Vajilla prehist\\u00f3rica y ADN cierran un debate arqueol\\u00f3gico centenario\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/vajilla-prehistorica-y-adn-cierran-un-debate-arqueologico-centenario\\\/#listItem\",\"position\":3,\"name\":\"Vajilla prehist\\u00f3rica y ADN cierran un debate arqueol\\u00f3gico centenario\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/sociedad\\\/#listItem\",\"name\":\"Sociedad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/vajilla-prehistorica-y-adn-cierran-un-debate-arqueologico-centenario\\\/#newsarticle\",\"name\":\"Vajilla prehist\\u00f3rica y ADN cierran un debate arqueol\\u00f3gico centenario | Cand\\u00e1s 365\",\"headline\":\"Vajilla prehist\\u00f3rica y ADN cierran un debate arqueol\\u00f3gico centenario\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/kitcampan.jpg\",\"width\":671,\"height\":451},\"datePublished\":\"2018-02-22T10:56:29+01:00\",\"dateModified\":\"2018-02-22T10:56:29+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/vajilla-prehistorica-y-adn-cierran-un-debate-arqueologico-centenario\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/vajilla-prehistorica-y-adn-cierran-un-debate-arqueologico-centenario\\\/#webpage\"},\"articleSection\":\"Sociedad\",\"dateline\":\"Publicado el febrero 22, 2018.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/vajilla-prehistorica-y-adn-cierran-un-debate-arqueologico-centenario\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/vajilla-prehistorica-y-adn-cierran-un-debate-arqueologico-centenario\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/vajilla-prehistorica-y-adn-cierran-un-debate-arqueologico-centenario\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/vajilla-prehistorica-y-adn-cierran-un-debate-arqueologico-centenario\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/vajilla-prehistorica-y-adn-cierran-un-debate-arqueologico-centenario\\\/\",\"name\":\"Vajilla prehist\\u00f3rica y ADN cierran un debate arqueol\\u00f3gico centenario | Cand\\u00e1s 365\",\"description\":\"Hace entre 4.750 y 4.500 a\\u00f1os, un tipo de cer\\u00e1mica muy decorada, conocida como vaso campaniforme por su forma de campana invertida, se extendi\\u00f3 por el oeste y centro de Europa, marcando un periodo clave de la prehistoria del continente. Desde hace un siglo los cient\\u00edficos debaten intensamente si su difusi\\u00f3n se debi\\u00f3 a un\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/vajilla-prehistorica-y-adn-cierran-un-debate-arqueologico-centenario\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/kitcampan.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/vajilla-prehistorica-y-adn-cierran-un-debate-arqueologico-centenario\\\/#mainImage\",\"width\":671,\"height\":451},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/vajilla-prehistorica-y-adn-cierran-un-debate-arqueologico-centenario\\\/#mainImage\"},\"datePublished\":\"2018-02-22T10:56:29+01:00\",\"dateModified\":\"2018-02-22T10:56:29+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Vajilla prehist\u00f3rica y ADN cierran un debate arqueol\u00f3gico centenario | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Vajilla prehist\u00f3rica y ADN cierran un debate arqueol\u00f3gico centenario | Cand\u00e1s 365","description":"Hace entre 4.750 y 4.500 a\u00f1os, un tipo de cer\u00e1mica muy decorada, conocida como vaso campaniforme por su forma de campana invertida, se extendi\u00f3 por el oeste y centro de Europa, marcando un periodo clave de la prehistoria del continente. Desde hace un siglo los cient\u00edficos debaten intensamente si su difusi\u00f3n se debi\u00f3 a un","canonical_url":"https:\/\/candas365.es\/noticias\/vajilla-prehistorica-y-adn-cierran-un-debate-arqueologico-centenario\/","robots":"max-image-preview:large","keywords":"sociedad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/vajilla-prehistorica-y-adn-cierran-un-debate-arqueologico-centenario\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/sociedad\/#listItem","name":"Sociedad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/sociedad\/#listItem","position":2,"name":"Sociedad","item":"https:\/\/candas365.es\/noticias\/category\/sociedad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/vajilla-prehistorica-y-adn-cierran-un-debate-arqueologico-centenario\/#listItem","name":"Vajilla prehist\u00f3rica y ADN cierran un debate arqueol\u00f3gico centenario"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/vajilla-prehistorica-y-adn-cierran-un-debate-arqueologico-centenario\/#listItem","position":3,"name":"Vajilla prehist\u00f3rica y ADN cierran un debate arqueol\u00f3gico centenario","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/sociedad\/#listItem","name":"Sociedad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/vajilla-prehistorica-y-adn-cierran-un-debate-arqueologico-centenario\/#newsarticle","name":"Vajilla prehist\u00f3rica y ADN cierran un debate arqueol\u00f3gico centenario | Cand\u00e1s 365","headline":"Vajilla prehist\u00f3rica y ADN cierran un debate arqueol\u00f3gico centenario","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/kitcampan.jpg","width":671,"height":451},"datePublished":"2018-02-22T10:56:29+01:00","dateModified":"2018-02-22T10:56:29+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/vajilla-prehistorica-y-adn-cierran-un-debate-arqueologico-centenario\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/vajilla-prehistorica-y-adn-cierran-un-debate-arqueologico-centenario\/#webpage"},"articleSection":"Sociedad","dateline":"Publicado el febrero 22, 2018."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/vajilla-prehistorica-y-adn-cierran-un-debate-arqueologico-centenario\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/vajilla-prehistorica-y-adn-cierran-un-debate-arqueologico-centenario\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/vajilla-prehistorica-y-adn-cierran-un-debate-arqueologico-centenario\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/vajilla-prehistorica-y-adn-cierran-un-debate-arqueologico-centenario\/#webpage","url":"https:\/\/candas365.es\/noticias\/vajilla-prehistorica-y-adn-cierran-un-debate-arqueologico-centenario\/","name":"Vajilla prehist\u00f3rica y ADN cierran un debate arqueol\u00f3gico centenario | Cand\u00e1s 365","description":"Hace entre 4.750 y 4.500 a\u00f1os, un tipo de cer\u00e1mica muy decorada, conocida como vaso campaniforme por su forma de campana invertida, se extendi\u00f3 por el oeste y centro de Europa, marcando un periodo clave de la prehistoria del continente. Desde hace un siglo los cient\u00edficos debaten intensamente si su difusi\u00f3n se debi\u00f3 a un","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/vajilla-prehistorica-y-adn-cierran-un-debate-arqueologico-centenario\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/kitcampan.jpg","@id":"https:\/\/candas365.es\/noticias\/vajilla-prehistorica-y-adn-cierran-un-debate-arqueologico-centenario\/#mainImage","width":671,"height":451},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/vajilla-prehistorica-y-adn-cierran-un-debate-arqueologico-centenario\/#mainImage"},"datePublished":"2018-02-22T10:56:29+01:00","dateModified":"2018-02-22T10:56:29+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Vajilla prehist\u00f3rica y ADN cierran un debate arqueol\u00f3gico centenario | Cand\u00e1s 365","og:description":"Hace entre 4.750 y 4.500 a\u00f1os, un tipo de cer\u00e1mica muy decorada, conocida como vaso campaniforme por su forma de campana invertida, se extendi\u00f3 por el oeste y centro de Europa, marcando un periodo clave de la prehistoria del continente. Desde hace un siglo los cient\u00edficos debaten intensamente si su difusi\u00f3n se debi\u00f3 a un","og:url":"https:\/\/candas365.es\/noticias\/vajilla-prehistorica-y-adn-cierran-un-debate-arqueologico-centenario\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/kitcampan.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/kitcampan.jpg","og:image:width":671,"og:image:height":451,"article:published_time":"2018-02-22T10:56:29+00:00","article:modified_time":"2018-02-22T10:56:29+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Vajilla prehist\u00f3rica y ADN cierran un debate arqueol\u00f3gico centenario | Cand\u00e1s 365","twitter:description":"Hace entre 4.750 y 4.500 a\u00f1os, un tipo de cer\u00e1mica muy decorada, conocida como vaso campaniforme por su forma de campana invertida, se extendi\u00f3 por el oeste y centro de Europa, marcando un periodo clave de la prehistoria del continente. Desde hace un siglo los cient\u00edficos debaten intensamente si su difusi\u00f3n se debi\u00f3 a un","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/kitcampan.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"7 minutos"},"aioseo_meta_data":{"post_id":"90464","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-20 05:14:28","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 11:55:46","updated":"2026-05-20 05:14:28"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/sociedad\/\" title=\"Sociedad\">Sociedad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tVajilla prehist\u00f3rica y ADN cierran un debate arqueol\u00f3gico centenario\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Sociedad","link":"https:\/\/candas365.es\/noticias\/category\/sociedad\/"},{"label":"Vajilla prehist\u00f3rica y ADN cierran un debate arqueol\u00f3gico centenario","link":"https:\/\/candas365.es\/noticias\/vajilla-prehistorica-y-adn-cierran-un-debate-arqueologico-centenario\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/90464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=90464"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/90464\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/90465"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=90464"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=90464"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=90464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}