{"id":90022,"date":"2018-02-16T20:23:37","date_gmt":"2018-02-16T20:23:37","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=90022"},"modified":"2018-02-16T20:23:37","modified_gmt":"2018-02-16T20:23:37","slug":"el-tiempo-sabado-17-de-febrero-de-2018","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/el-tiempo-sabado-17-de-febrero-de-2018\/","title":{"rendered":"El tiempo, s\u00e1bado 17 de febrero de 2018"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-6582\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/02\/nieve-360x240.jpg\" alt=\"\" width=\"360\" height=\"240\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/02\/nieve-360x240.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/02\/nieve-650x433.jpg 650w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/02\/nieve-768x512.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/02\/nieve-150x100.jpg 150w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/02\/nieve-450x300.jpg 450w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/02\/nieve-655x436.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/02\/nieve-696x464.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/02\/nieve-630x420.jpg 630w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/02\/nieve-84x55.jpg 84w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/02\/nieve.jpg 800w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>En Galicia, comunidades cant\u00e1bricas y norte de Navarra estar\u00e1 nuboso o cubierto con precipitaciones, tendiendo a remitir en Galicia a lo largo del d\u00eda y a extenderse al Pirineo, Catalu\u00f1a, Levante y Baleares. Afectar\u00e1n tambi\u00e9n, de forma m\u00e1s d\u00e9bil y dispersa a puntos dispersos del resto del tercio norte peninsular y a los sistemas monta\u00f1osos de la mitad norte. Por la tarde, se producir\u00e1n tambi\u00e9n algunos chubascos en Baleares y, probablemente, en la Comunidad Valenciana. En el resto del pa\u00eds tiempo estable.<\/p>\n<p>Cota de nieve: en Pirineos 2200\/2300 m bajando a 1000\/1400 m, en la Cant\u00e1brica 1400\/1800 m bajando a 900\/1200 m, en la Ib\u00e9rica 2200\/2400 m bajando a 700\/900 m y en el sistema central 1800\/2000 m bajando a 900\/1200 m.<\/p>\n<p>Temperaturas diurnas en descenso en la mitad norte y cuadrante suroeste peninsular. En algunas localidades de la mitad norte el descenso puede ser notable. Heladas d\u00e9biles en zonas de monta\u00f1a de la mitad norte.<\/p>\n<p>Viento de componente norte en la mitad norte de la Pen\u00ednsula y Canarias, de componente este en Baleares, y de Poniente en el Estrecho y Melilla. Algunas rachas fuertes de cierzo en el valle del Ebro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En Galicia, comunidades cant\u00e1bricas y norte de Navarra estar\u00e1 nuboso o cubierto con precipitaciones, tendiendo a remitir en Galicia a lo largo del d\u00eda y a extenderse al Pirineo, Catalu\u00f1a, Levante y Baleares. Afectar\u00e1n tambi\u00e9n, de forma m\u00e1s d\u00e9bil y dispersa a puntos dispersos del resto del tercio norte peninsular y a los sistemas monta\u00f1osos<\/p>\n","protected":false},"author":1,"featured_media":6582,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-90022","post","type-post","status-publish","format-standard","has-post-thumbnail","category-agenda"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"En Galicia, comunidades cant\u00e1bricas y norte de Navarra estar\u00e1 nuboso o cubierto con precipitaciones, tendiendo a remitir en Galicia a lo largo del d\u00eda y a extenderse al Pirineo, Catalu\u00f1a, Levante y Baleares. Afectar\u00e1n tambi\u00e9n, de forma m\u00e1s d\u00e9bil y dispersa a puntos dispersos del resto del tercio norte peninsular y a los sistemas monta\u00f1osos\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"agenda\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/el-tiempo-sabado-17-de-febrero-de-2018\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El tiempo, s\u00e1bado 17 de febrero de 2018 | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"En Galicia, comunidades cant\u00e1bricas y norte de Navarra estar\u00e1 nuboso o cubierto con precipitaciones, tendiendo a remitir en Galicia a lo largo del d\u00eda y a extenderse al Pirineo, Catalu\u00f1a, Levante y Baleares. Afectar\u00e1n tambi\u00e9n, de forma m\u00e1s d\u00e9bil y dispersa a puntos dispersos del resto del tercio norte peninsular y a los sistemas monta\u00f1osos\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/el-tiempo-sabado-17-de-febrero-de-2018\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/02\/nieve.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/02\/nieve.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-02-16T20:23:37+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-02-16T20:23:37+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El tiempo, s\u00e1bado 17 de febrero de 2018 | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"En Galicia, comunidades cant\u00e1bricas y norte de Navarra estar\u00e1 nuboso o cubierto con precipitaciones, tendiendo a remitir en Galicia a lo largo del d\u00eda y a extenderse al Pirineo, Catalu\u00f1a, Levante y Baleares. Afectar\u00e1n tambi\u00e9n, de forma m\u00e1s d\u00e9bil y dispersa a puntos dispersos del resto del tercio norte peninsular y a los sistemas monta\u00f1osos\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/02\/nieve.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-tiempo-sabado-17-de-febrero-de-2018\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/agenda\\\/#listItem\",\"name\":\"Agenda\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/agenda\\\/#listItem\",\"position\":2,\"name\":\"Agenda\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/agenda\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-tiempo-sabado-17-de-febrero-de-2018\\\/#listItem\",\"name\":\"El tiempo, s\\u00e1bado 17 de febrero de 2018\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-tiempo-sabado-17-de-febrero-de-2018\\\/#listItem\",\"position\":3,\"name\":\"El tiempo, s\\u00e1bado 17 de febrero de 2018\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/agenda\\\/#listItem\",\"name\":\"Agenda\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-tiempo-sabado-17-de-febrero-de-2018\\\/#newsarticle\",\"name\":\"El tiempo, s\\u00e1bado 17 de febrero de 2018 | Cand\\u00e1s 365\",\"headline\":\"El tiempo, s\\u00e1bado 17 de febrero de 2018\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/nieve.jpg\",\"width\":800,\"height\":533,\"caption\":\"nieve\"},\"datePublished\":\"2018-02-16T20:23:37+01:00\",\"dateModified\":\"2018-02-16T20:23:37+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-tiempo-sabado-17-de-febrero-de-2018\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-tiempo-sabado-17-de-febrero-de-2018\\\/#webpage\"},\"articleSection\":\"Agenda\",\"dateline\":\"Publicado el febrero 16, 2018.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-tiempo-sabado-17-de-febrero-de-2018\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-tiempo-sabado-17-de-febrero-de-2018\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-tiempo-sabado-17-de-febrero-de-2018\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-tiempo-sabado-17-de-febrero-de-2018\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-tiempo-sabado-17-de-febrero-de-2018\\\/\",\"name\":\"El tiempo, s\\u00e1bado 17 de febrero de 2018 | Cand\\u00e1s 365\",\"description\":\"En Galicia, comunidades cant\\u00e1bricas y norte de Navarra estar\\u00e1 nuboso o cubierto con precipitaciones, tendiendo a remitir en Galicia a lo largo del d\\u00eda y a extenderse al Pirineo, Catalu\\u00f1a, Levante y Baleares. Afectar\\u00e1n tambi\\u00e9n, de forma m\\u00e1s d\\u00e9bil y dispersa a puntos dispersos del resto del tercio norte peninsular y a los sistemas monta\\u00f1osos\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-tiempo-sabado-17-de-febrero-de-2018\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/nieve.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-tiempo-sabado-17-de-febrero-de-2018\\\/#mainImage\",\"width\":800,\"height\":533,\"caption\":\"nieve\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-tiempo-sabado-17-de-febrero-de-2018\\\/#mainImage\"},\"datePublished\":\"2018-02-16T20:23:37+01:00\",\"dateModified\":\"2018-02-16T20:23:37+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>El tiempo, s\u00e1bado 17 de febrero de 2018 | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"El tiempo, s\u00e1bado 17 de febrero de 2018 | Cand\u00e1s 365","description":"En Galicia, comunidades cant\u00e1bricas y norte de Navarra estar\u00e1 nuboso o cubierto con precipitaciones, tendiendo a remitir en Galicia a lo largo del d\u00eda y a extenderse al Pirineo, Catalu\u00f1a, Levante y Baleares. Afectar\u00e1n tambi\u00e9n, de forma m\u00e1s d\u00e9bil y dispersa a puntos dispersos del resto del tercio norte peninsular y a los sistemas monta\u00f1osos","canonical_url":"https:\/\/candas365.es\/noticias\/el-tiempo-sabado-17-de-febrero-de-2018\/","robots":"max-image-preview:large","keywords":"agenda","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/el-tiempo-sabado-17-de-febrero-de-2018\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/agenda\/#listItem","name":"Agenda"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/agenda\/#listItem","position":2,"name":"Agenda","item":"https:\/\/candas365.es\/noticias\/category\/agenda\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/el-tiempo-sabado-17-de-febrero-de-2018\/#listItem","name":"El tiempo, s\u00e1bado 17 de febrero de 2018"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/el-tiempo-sabado-17-de-febrero-de-2018\/#listItem","position":3,"name":"El tiempo, s\u00e1bado 17 de febrero de 2018","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/agenda\/#listItem","name":"Agenda"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/el-tiempo-sabado-17-de-febrero-de-2018\/#newsarticle","name":"El tiempo, s\u00e1bado 17 de febrero de 2018 | Cand\u00e1s 365","headline":"El tiempo, s\u00e1bado 17 de febrero de 2018","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/02\/nieve.jpg","width":800,"height":533,"caption":"nieve"},"datePublished":"2018-02-16T20:23:37+01:00","dateModified":"2018-02-16T20:23:37+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/el-tiempo-sabado-17-de-febrero-de-2018\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/el-tiempo-sabado-17-de-febrero-de-2018\/#webpage"},"articleSection":"Agenda","dateline":"Publicado el febrero 16, 2018."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/el-tiempo-sabado-17-de-febrero-de-2018\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/el-tiempo-sabado-17-de-febrero-de-2018\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/el-tiempo-sabado-17-de-febrero-de-2018\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/el-tiempo-sabado-17-de-febrero-de-2018\/#webpage","url":"https:\/\/candas365.es\/noticias\/el-tiempo-sabado-17-de-febrero-de-2018\/","name":"El tiempo, s\u00e1bado 17 de febrero de 2018 | Cand\u00e1s 365","description":"En Galicia, comunidades cant\u00e1bricas y norte de Navarra estar\u00e1 nuboso o cubierto con precipitaciones, tendiendo a remitir en Galicia a lo largo del d\u00eda y a extenderse al Pirineo, Catalu\u00f1a, Levante y Baleares. Afectar\u00e1n tambi\u00e9n, de forma m\u00e1s d\u00e9bil y dispersa a puntos dispersos del resto del tercio norte peninsular y a los sistemas monta\u00f1osos","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/el-tiempo-sabado-17-de-febrero-de-2018\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/02\/nieve.jpg","@id":"https:\/\/candas365.es\/noticias\/el-tiempo-sabado-17-de-febrero-de-2018\/#mainImage","width":800,"height":533,"caption":"nieve"},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/el-tiempo-sabado-17-de-febrero-de-2018\/#mainImage"},"datePublished":"2018-02-16T20:23:37+01:00","dateModified":"2018-02-16T20:23:37+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"El tiempo, s\u00e1bado 17 de febrero de 2018 | Cand\u00e1s 365","og:description":"En Galicia, comunidades cant\u00e1bricas y norte de Navarra estar\u00e1 nuboso o cubierto con precipitaciones, tendiendo a remitir en Galicia a lo largo del d\u00eda y a extenderse al Pirineo, Catalu\u00f1a, Levante y Baleares. Afectar\u00e1n tambi\u00e9n, de forma m\u00e1s d\u00e9bil y dispersa a puntos dispersos del resto del tercio norte peninsular y a los sistemas monta\u00f1osos","og:url":"https:\/\/candas365.es\/noticias\/el-tiempo-sabado-17-de-febrero-de-2018\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/02\/nieve.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/02\/nieve.jpg","og:image:width":800,"og:image:height":533,"article:published_time":"2018-02-16T20:23:37+00:00","article:modified_time":"2018-02-16T20:23:37+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"El tiempo, s\u00e1bado 17 de febrero de 2018 | Cand\u00e1s 365","twitter:description":"En Galicia, comunidades cant\u00e1bricas y norte de Navarra estar\u00e1 nuboso o cubierto con precipitaciones, tendiendo a remitir en Galicia a lo largo del d\u00eda y a extenderse al Pirineo, Catalu\u00f1a, Levante y Baleares. Afectar\u00e1n tambi\u00e9n, de forma m\u00e1s d\u00e9bil y dispersa a puntos dispersos del resto del tercio norte peninsular y a los sistemas monta\u00f1osos","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/02\/nieve.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"1 minuto"},"aioseo_meta_data":{"post_id":"90022","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-20 03:58:12","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 11:56:01","updated":"2026-05-20 03:58:12"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/agenda\/\" title=\"Agenda\">Agenda<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tEl tiempo, s\u00e1bado 17 de febrero de 2018\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Agenda","link":"https:\/\/candas365.es\/noticias\/category\/agenda\/"},{"label":"El tiempo, s\u00e1bado 17 de febrero de 2018","link":"https:\/\/candas365.es\/noticias\/el-tiempo-sabado-17-de-febrero-de-2018\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/90022","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=90022"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/90022\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/6582"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=90022"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=90022"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=90022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}