{"id":89985,"date":"2018-02-15T18:42:56","date_gmt":"2018-02-15T18:42:56","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=89985"},"modified":"2018-02-15T18:42:56","modified_gmt":"2018-02-15T18:42:56","slug":"el-ayuntamiento-de-oviedo-incorporara-diez-nuevos-policias-locales","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/el-ayuntamiento-de-oviedo-incorporara-diez-nuevos-policias-locales\/","title":{"rendered":"El Ayuntamiento de Oviedo incorporar\u00e1 diez nuevos polic\u00edas locales"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-89986\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/IMG_0079-Oviedo-360x240.jpg\" alt=\"\" width=\"360\" height=\"240\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/IMG_0079-Oviedo-360x240.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/IMG_0079-Oviedo-696x464.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/IMG_0079-Oviedo-1068x712.jpg 1068w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/IMG_0079-Oviedo-630x420.jpg 630w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/IMG_0079-Oviedo-768x512.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/IMG_0079-Oviedo-655x436.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/IMG_0079-Oviedo.jpg 1280w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>El Ayuntamiento de Oviedo incorporar\u00e1 esta primavera a diez nuevos agentes de Polic\u00eda Local. Los futuros funcionarios municipales se han sometido esta ma\u00f1ana a las pruebas f\u00edsicas, en las instalaciones deportivas de San L\u00e1zaro, tras haber superado, el mes pasado, las te\u00f3ricas.<\/p>\n<p>\u201cCon estas nuevas incorporaciones, previstas para esta primavera, se completar\u00eda la plantilla y la tasa de reposici\u00f3n. Pero aun as\u00ed, por poblaci\u00f3n, tendr\u00edamos que tener 320 polic\u00edas y no llegamos a los 300. Es insuficiente\u201d, ha asegurado el concejal de Seguridad Ciudadana, Ricardo Fern\u00e1ndez. \u201cCon \u00e9stos 10 llevaremos 22 nuevos agentes incorporados. Se cumple as\u00ed el objetivo de no perder empleo p\u00fablico. Llevamos desde 2007 con todo pr\u00e1cticamente paralizado y lo ideal ser\u00eda poder convocar en funci\u00f3n de las necesidades y no en funci\u00f3n de la gente que se jubila. Ahora incorporamos 10 porque se han jubilado 10\u201d, ha subrayado Fern\u00e1ndez<\/p>\n<p>Tambi\u00e9n a juicio del concejal de Personal, Iv\u00e1n \u00c1lvarez, \u201chay necesidad de m\u00e1s agentes. La tasa de reposici\u00f3n es del cien por cien pero estamos a la espera de que desaparezca para poder incrementar la plantilla. Ahora mismo estamos llevando a cabo, adem\u00e1s de estas pruebas para la Polic\u00eda Local, otros procesos de selecci\u00f3n como los de animador sociocultural, para que la oferta p\u00fablica de empleo \u2013hay plazas paralizadas desde 2007- consiga dotar a la Administraci\u00f3n de los medios que necesita\u201d. El edil de Personal ha adelantado que \u201cal final del primer semestre de este a\u00f1o tenemos pensado sacar otras 11 nuevas plazas de Bomberos\u201d.<\/p>\n<p>El servicio de Bomberos, ha a\u00f1adido el responsable municipal de Seguridad Ciudadana, Ricardo Fern\u00e1ndez, \u201cse ha debilitado con el paso de los a\u00f1os, algo que se evidencia en la edad media de la plantilla, en torno a los 50 a\u00f1os. El n\u00famero de efectivos es muy justo lo que obliga, en ocasiones, a llevar a cabo horas extraordinarias. Con la convocatoria estas 11 plazas de Bomberos que saldr\u00e1n en breve esperamos tener culminado el proceso en este servicio a mediados de a\u00f1o\u201d. Los aspirantes a estas plazas de Bombero \u201ctendr\u00e1n que superar conocimientos te\u00f3ricos, pruebas de resistencia f\u00edsica y, en lugar del psicot\u00e9cnico, una prueba de claustrofobia que creemos que est\u00e1 mejor orientada a lo que luego va a ser la tarea profesional de ese colectivo de trabajadores\u201d<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Ayuntamiento de Oviedo incorporar\u00e1 esta primavera a diez nuevos agentes de Polic\u00eda Local. Los futuros funcionarios municipales se han sometido esta ma\u00f1ana a las pruebas f\u00edsicas, en las instalaciones deportivas de San L\u00e1zaro, tras haber superado, el mes pasado, las te\u00f3ricas. \u201cCon estas nuevas incorporaciones, previstas para esta primavera, se completar\u00eda la plantilla y<\/p>\n","protected":false},"author":1,"featured_media":89986,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-89985","post","type-post","status-publish","format-standard","has-post-thumbnail","category-asturias"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"El Ayuntamiento de Oviedo incorporar\u00e1 esta primavera a diez nuevos agentes de Polic\u00eda Local. Los futuros funcionarios municipales se han sometido esta ma\u00f1ana a las pruebas f\u00edsicas, en las instalaciones deportivas de San L\u00e1zaro, tras haber superado, el mes pasado, las te\u00f3ricas. \u201cCon estas nuevas incorporaciones, previstas para esta primavera, se completar\u00eda la plantilla y\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"asturias\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/el-ayuntamiento-de-oviedo-incorporara-diez-nuevos-policias-locales\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El Ayuntamiento de Oviedo incorporar\u00e1 diez nuevos polic\u00edas locales | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"El Ayuntamiento de Oviedo incorporar\u00e1 esta primavera a diez nuevos agentes de Polic\u00eda Local. Los futuros funcionarios municipales se han sometido esta ma\u00f1ana a las pruebas f\u00edsicas, en las instalaciones deportivas de San L\u00e1zaro, tras haber superado, el mes pasado, las te\u00f3ricas. \u201cCon estas nuevas incorporaciones, previstas para esta primavera, se completar\u00eda la plantilla y\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/el-ayuntamiento-de-oviedo-incorporara-diez-nuevos-policias-locales\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/IMG_0079-Oviedo.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/IMG_0079-Oviedo.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-02-15T18:42:56+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-02-15T18:42:56+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El Ayuntamiento de Oviedo incorporar\u00e1 diez nuevos polic\u00edas locales | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El Ayuntamiento de Oviedo incorporar\u00e1 esta primavera a diez nuevos agentes de Polic\u00eda Local. Los futuros funcionarios municipales se han sometido esta ma\u00f1ana a las pruebas f\u00edsicas, en las instalaciones deportivas de San L\u00e1zaro, tras haber superado, el mes pasado, las te\u00f3ricas. \u201cCon estas nuevas incorporaciones, previstas para esta primavera, se completar\u00eda la plantilla y\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/IMG_0079-Oviedo.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-ayuntamiento-de-oviedo-incorporara-diez-nuevos-policias-locales\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"name\":\"Asturias\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"position\":2,\"name\":\"Asturias\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-ayuntamiento-de-oviedo-incorporara-diez-nuevos-policias-locales\\\/#listItem\",\"name\":\"El Ayuntamiento de Oviedo incorporar\\u00e1 diez nuevos polic\\u00edas locales\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-ayuntamiento-de-oviedo-incorporara-diez-nuevos-policias-locales\\\/#listItem\",\"position\":3,\"name\":\"El Ayuntamiento de Oviedo incorporar\\u00e1 diez nuevos polic\\u00edas locales\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"name\":\"Asturias\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-ayuntamiento-de-oviedo-incorporara-diez-nuevos-policias-locales\\\/#newsarticle\",\"name\":\"El Ayuntamiento de Oviedo incorporar\\u00e1 diez nuevos polic\\u00edas locales | Cand\\u00e1s 365\",\"headline\":\"El Ayuntamiento de Oviedo incorporar\\u00e1 diez nuevos polic\\u00edas locales\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/IMG_0079-Oviedo.jpg\",\"width\":1280,\"height\":853},\"datePublished\":\"2018-02-15T18:42:56+01:00\",\"dateModified\":\"2018-02-15T18:42:56+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-ayuntamiento-de-oviedo-incorporara-diez-nuevos-policias-locales\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-ayuntamiento-de-oviedo-incorporara-diez-nuevos-policias-locales\\\/#webpage\"},\"articleSection\":\"Asturias\",\"dateline\":\"Publicado el febrero 15, 2018.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-ayuntamiento-de-oviedo-incorporara-diez-nuevos-policias-locales\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-ayuntamiento-de-oviedo-incorporara-diez-nuevos-policias-locales\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-ayuntamiento-de-oviedo-incorporara-diez-nuevos-policias-locales\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-ayuntamiento-de-oviedo-incorporara-diez-nuevos-policias-locales\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-ayuntamiento-de-oviedo-incorporara-diez-nuevos-policias-locales\\\/\",\"name\":\"El Ayuntamiento de Oviedo incorporar\\u00e1 diez nuevos polic\\u00edas locales | Cand\\u00e1s 365\",\"description\":\"El Ayuntamiento de Oviedo incorporar\\u00e1 esta primavera a diez nuevos agentes de Polic\\u00eda Local. Los futuros funcionarios municipales se han sometido esta ma\\u00f1ana a las pruebas f\\u00edsicas, en las instalaciones deportivas de San L\\u00e1zaro, tras haber superado, el mes pasado, las te\\u00f3ricas. \\u201cCon estas nuevas incorporaciones, previstas para esta primavera, se completar\\u00eda la plantilla y\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-ayuntamiento-de-oviedo-incorporara-diez-nuevos-policias-locales\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/IMG_0079-Oviedo.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-ayuntamiento-de-oviedo-incorporara-diez-nuevos-policias-locales\\\/#mainImage\",\"width\":1280,\"height\":853},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-ayuntamiento-de-oviedo-incorporara-diez-nuevos-policias-locales\\\/#mainImage\"},\"datePublished\":\"2018-02-15T18:42:56+01:00\",\"dateModified\":\"2018-02-15T18:42:56+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>El Ayuntamiento de Oviedo incorporar\u00e1 diez nuevos polic\u00edas locales | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"El Ayuntamiento de Oviedo incorporar\u00e1 diez nuevos polic\u00edas locales | Cand\u00e1s 365","description":"El Ayuntamiento de Oviedo incorporar\u00e1 esta primavera a diez nuevos agentes de Polic\u00eda Local. Los futuros funcionarios municipales se han sometido esta ma\u00f1ana a las pruebas f\u00edsicas, en las instalaciones deportivas de San L\u00e1zaro, tras haber superado, el mes pasado, las te\u00f3ricas. \u201cCon estas nuevas incorporaciones, previstas para esta primavera, se completar\u00eda la plantilla y","canonical_url":"https:\/\/candas365.es\/noticias\/el-ayuntamiento-de-oviedo-incorporara-diez-nuevos-policias-locales\/","robots":"max-image-preview:large","keywords":"asturias","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/el-ayuntamiento-de-oviedo-incorporara-diez-nuevos-policias-locales\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","name":"Asturias"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","position":2,"name":"Asturias","item":"https:\/\/candas365.es\/noticias\/category\/asturias\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/el-ayuntamiento-de-oviedo-incorporara-diez-nuevos-policias-locales\/#listItem","name":"El Ayuntamiento de Oviedo incorporar\u00e1 diez nuevos polic\u00edas locales"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/el-ayuntamiento-de-oviedo-incorporara-diez-nuevos-policias-locales\/#listItem","position":3,"name":"El Ayuntamiento de Oviedo incorporar\u00e1 diez nuevos polic\u00edas locales","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","name":"Asturias"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/el-ayuntamiento-de-oviedo-incorporara-diez-nuevos-policias-locales\/#newsarticle","name":"El Ayuntamiento de Oviedo incorporar\u00e1 diez nuevos polic\u00edas locales | Cand\u00e1s 365","headline":"El Ayuntamiento de Oviedo incorporar\u00e1 diez nuevos polic\u00edas locales","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/IMG_0079-Oviedo.jpg","width":1280,"height":853},"datePublished":"2018-02-15T18:42:56+01:00","dateModified":"2018-02-15T18:42:56+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/el-ayuntamiento-de-oviedo-incorporara-diez-nuevos-policias-locales\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/el-ayuntamiento-de-oviedo-incorporara-diez-nuevos-policias-locales\/#webpage"},"articleSection":"Asturias","dateline":"Publicado el febrero 15, 2018."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/el-ayuntamiento-de-oviedo-incorporara-diez-nuevos-policias-locales\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/el-ayuntamiento-de-oviedo-incorporara-diez-nuevos-policias-locales\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/el-ayuntamiento-de-oviedo-incorporara-diez-nuevos-policias-locales\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/el-ayuntamiento-de-oviedo-incorporara-diez-nuevos-policias-locales\/#webpage","url":"https:\/\/candas365.es\/noticias\/el-ayuntamiento-de-oviedo-incorporara-diez-nuevos-policias-locales\/","name":"El Ayuntamiento de Oviedo incorporar\u00e1 diez nuevos polic\u00edas locales | Cand\u00e1s 365","description":"El Ayuntamiento de Oviedo incorporar\u00e1 esta primavera a diez nuevos agentes de Polic\u00eda Local. Los futuros funcionarios municipales se han sometido esta ma\u00f1ana a las pruebas f\u00edsicas, en las instalaciones deportivas de San L\u00e1zaro, tras haber superado, el mes pasado, las te\u00f3ricas. \u201cCon estas nuevas incorporaciones, previstas para esta primavera, se completar\u00eda la plantilla y","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/el-ayuntamiento-de-oviedo-incorporara-diez-nuevos-policias-locales\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/IMG_0079-Oviedo.jpg","@id":"https:\/\/candas365.es\/noticias\/el-ayuntamiento-de-oviedo-incorporara-diez-nuevos-policias-locales\/#mainImage","width":1280,"height":853},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/el-ayuntamiento-de-oviedo-incorporara-diez-nuevos-policias-locales\/#mainImage"},"datePublished":"2018-02-15T18:42:56+01:00","dateModified":"2018-02-15T18:42:56+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"El Ayuntamiento de Oviedo incorporar\u00e1 diez nuevos polic\u00edas locales | Cand\u00e1s 365","og:description":"El Ayuntamiento de Oviedo incorporar\u00e1 esta primavera a diez nuevos agentes de Polic\u00eda Local. Los futuros funcionarios municipales se han sometido esta ma\u00f1ana a las pruebas f\u00edsicas, en las instalaciones deportivas de San L\u00e1zaro, tras haber superado, el mes pasado, las te\u00f3ricas. \u201cCon estas nuevas incorporaciones, previstas para esta primavera, se completar\u00eda la plantilla y","og:url":"https:\/\/candas365.es\/noticias\/el-ayuntamiento-de-oviedo-incorporara-diez-nuevos-policias-locales\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/IMG_0079-Oviedo.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/IMG_0079-Oviedo.jpg","og:image:width":1280,"og:image:height":853,"article:published_time":"2018-02-15T18:42:56+00:00","article:modified_time":"2018-02-15T18:42:56+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"El Ayuntamiento de Oviedo incorporar\u00e1 diez nuevos polic\u00edas locales | Cand\u00e1s 365","twitter:description":"El Ayuntamiento de Oviedo incorporar\u00e1 esta primavera a diez nuevos agentes de Polic\u00eda Local. Los futuros funcionarios municipales se han sometido esta ma\u00f1ana a las pruebas f\u00edsicas, en las instalaciones deportivas de San L\u00e1zaro, tras haber superado, el mes pasado, las te\u00f3ricas. \u201cCon estas nuevas incorporaciones, previstas para esta primavera, se completar\u00eda la plantilla y","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/IMG_0079-Oviedo.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"89985","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-20 03:50:59","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 11:56:02","updated":"2026-05-20 03:50:59"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/asturias\/\" title=\"Asturias\">Asturias<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tEl Ayuntamiento de Oviedo incorporar\u00e1 diez nuevos polic\u00edas locales\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Asturias","link":"https:\/\/candas365.es\/noticias\/category\/asturias\/"},{"label":"El Ayuntamiento de Oviedo incorporar\u00e1 diez nuevos polic\u00edas locales","link":"https:\/\/candas365.es\/noticias\/el-ayuntamiento-de-oviedo-incorporara-diez-nuevos-policias-locales\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/89985","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=89985"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/89985\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/89986"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=89985"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=89985"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=89985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}