{"id":89091,"date":"2018-02-02T14:39:02","date_gmt":"2018-02-02T14:39:02","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=89091"},"modified":"2018-02-02T14:39:02","modified_gmt":"2018-02-02T14:39:02","slug":"information-builders-incorpora-a-frank-j-vella-como-director-de-operaciones","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/information-builders-incorpora-a-frank-j-vella-como-director-de-operaciones\/","title":{"rendered":"Information Builders incorpora a Frank J. Vella como director de Operaciones"},"content":{"rendered":"<p><a href=\"http:\/\/www.informationbuilders.es\/\" target=\"_blank\" rel=\"nofollow noopener\"><span style=\"color: #ff0000;\"><strong><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-89092\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/1517565005_IB_Frank_Vella-326x300.jpg\" alt=\"\" width=\"326\" height=\"300\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/1517565005_IB_Frank_Vella-326x300.jpg 326w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/1517565005_IB_Frank_Vella-456x420.jpg 456w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/1517565005_IB_Frank_Vella-522x480.jpg 522w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/1517565005_IB_Frank_Vella.jpg 677w\" sizes=\"(max-width: 326px) 100vw, 326px\" \/>Information Builders<\/strong><\/span><\/a>, compa\u00f1\u00eda l\u00edder en el mercado BI (Business Intelligence), anal\u00edtica y gesti\u00f3n de datos incorpora a Frank J. Vella como director de Operaciones. Vella trabajar\u00e1 estrechamente con el equipo ejecutivo de Information Builders para desarrollar estrategias de crecimiento, identificar nuevas oportunidades de mercado e impulsar los planes de expansi\u00f3n de la compa\u00f1\u00eda.<\/p>\n<p>El nombramiento de Vella se enmarca en un periodo de crecimiento y transformaci\u00f3n de la compa\u00f1\u00eda que, el pasado a\u00f1o, recibi\u00f3 una fuerte inversi\u00f3n de capital del grupo Private Capital Investing de Goldman Sachs; inversi\u00f3n que se ha destinado a continuar promoviendo la innovaci\u00f3n de productos y soluciones para sus clientes. Es por ello que Vella, bajo estos objetivos, se incorpora a la compa\u00f1\u00eda para aportar su visi\u00f3n empresarial y an\u00e1lisis estrat\u00e9gico, de cara a investigar las nuevas necesidades del mercado y adaptar las soluciones de la compa\u00f1\u00eda a las mismas.<\/p>\n<p>Anteriormente, Vella desempe\u00f1aba las funciones de Chief Revenue en la compa\u00f1\u00eda BlueJeans Network, donde supervis\u00f3 la estrategia de expansi\u00f3n y crecimiento de la compa\u00f1\u00eda. Adem\u00e1s, ha sido vicepresidente de Ventas y Operaciones de Hewlett-Packard Enterprise (HPE) y ha desarrollado puestos de liderazgo en otras tecnol\u00f3gicas como Virtustream, Quest Software y Microsoft Corporation. Por ello, la amplia experiencia de Vella en software empresarial y su capacidad estrat\u00e9gica para aumentar la cuota de mercado han sido las principales razones por las que Information Builders ha querido incorporarle en el equipo, en una etapa crucial para el crecimiento de la compa\u00f1\u00eda.<\/p>\n<p><strong>Gerald Cohen, presidente y CEO de Information Builders<\/strong>, ha querido resaltar la importancia de la incorporaci\u00f3n de Fran J. Vella al equipo. \u00abGracias a la incorporaci\u00f3n de Frank y a la inversi\u00f3n de Goldman Sachs vamos a poner el foco en nuestra estrategia de expansi\u00f3n. Queremos dar a nuestros clientes nuevos servicios y soluciones para continuar creciendo\u00bb.<\/p>\n<p>Por su parte,\u00a0<strong>Frank J. Vella<\/strong>\u00a0apunta que \u00abInformation Builders es un l\u00edder comprobado de la industria que siempre se ha distinguido por su compromiso con los clientes y su enfoque singular en la anticipaci\u00f3n de las necesidades anal\u00edticas de todas las comunidades de usuarios. Esta es la raz\u00f3n principal por la que me entusiasma la oportunidad de unirme a la compa\u00f1\u00eda. Espero colaborar con la compa\u00f1\u00eda en todos sus casos de \u00e9xito y llevar a Information Builders a su siguiente fase de crecimiento\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Information Builders, compa\u00f1\u00eda l\u00edder en el mercado BI (Business Intelligence), anal\u00edtica y gesti\u00f3n de datos incorpora a Frank J. Vella como director de Operaciones. Vella trabajar\u00e1 estrechamente con el equipo ejecutivo de Information Builders para desarrollar estrategias de crecimiento, identificar nuevas oportunidades de mercado e impulsar los planes de expansi\u00f3n de la compa\u00f1\u00eda. El nombramiento<\/p>\n","protected":false},"author":1,"featured_media":89092,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[151],"tags":[],"class_list":{"0":"post-89091","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-canal-empresas"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7 - aioseo.com -->\n\t<meta name=\"description\" content=\"Information Builders, compa\u00f1\u00eda l\u00edder en el mercado BI (Business Intelligence), anal\u00edtica y gesti\u00f3n de datos incorpora a Frank J. Vella como director de Operaciones. Vella trabajar\u00e1 estrechamente con el equipo ejecutivo de Information Builders para desarrollar estrategias de crecimiento, identificar nuevas oportunidades de mercado e impulsar los planes de expansi\u00f3n de la compa\u00f1\u00eda. El nombramiento\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"canal empresas\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/information-builders-incorpora-a-frank-j-vella-como-director-de-operaciones\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Information Builders incorpora a Frank J. Vella como director de Operaciones | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Information Builders, compa\u00f1\u00eda l\u00edder en el mercado BI (Business Intelligence), anal\u00edtica y gesti\u00f3n de datos incorpora a Frank J. Vella como director de Operaciones. Vella trabajar\u00e1 estrechamente con el equipo ejecutivo de Information Builders para desarrollar estrategias de crecimiento, identificar nuevas oportunidades de mercado e impulsar los planes de expansi\u00f3n de la compa\u00f1\u00eda. El nombramiento\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/information-builders-incorpora-a-frank-j-vella-como-director-de-operaciones\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/1517565005_IB_Frank_Vella.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/1517565005_IB_Frank_Vella.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"677\" \/>\n\t\t<meta property=\"og:image:height\" content=\"623\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-02-02T14:39:02+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-02-02T14:39:02+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Information Builders incorpora a Frank J. Vella como director de Operaciones | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Information Builders, compa\u00f1\u00eda l\u00edder en el mercado BI (Business Intelligence), anal\u00edtica y gesti\u00f3n de datos incorpora a Frank J. Vella como director de Operaciones. Vella trabajar\u00e1 estrechamente con el equipo ejecutivo de Information Builders para desarrollar estrategias de crecimiento, identificar nuevas oportunidades de mercado e impulsar los planes de expansi\u00f3n de la compa\u00f1\u00eda. El nombramiento\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/1517565005_IB_Frank_Vella.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/information-builders-incorpora-a-frank-j-vella-como-director-de-operaciones\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"name\":\"Canal Empresas\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"position\":2,\"name\":\"Canal Empresas\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/information-builders-incorpora-a-frank-j-vella-como-director-de-operaciones\\\/#listItem\",\"name\":\"Information Builders incorpora a Frank J. Vella como director de Operaciones\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/information-builders-incorpora-a-frank-j-vella-como-director-de-operaciones\\\/#listItem\",\"position\":3,\"name\":\"Information Builders incorpora a Frank J. Vella como director de Operaciones\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"name\":\"Canal Empresas\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/information-builders-incorpora-a-frank-j-vella-como-director-de-operaciones\\\/#newsarticle\",\"name\":\"Information Builders incorpora a Frank J. Vella como director de Operaciones | Cand\\u00e1s 365\",\"headline\":\"Information Builders incorpora a Frank J. Vella como director de Operaciones\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/1517565005_IB_Frank_Vella.jpg\",\"width\":677,\"height\":623},\"datePublished\":\"2018-02-02T14:39:02+01:00\",\"dateModified\":\"2018-02-02T14:39:02+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/information-builders-incorpora-a-frank-j-vella-como-director-de-operaciones\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/information-builders-incorpora-a-frank-j-vella-como-director-de-operaciones\\\/#webpage\"},\"articleSection\":\"Canal Empresas\",\"dateline\":\"Publicado el febrero 2, 2018.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/information-builders-incorpora-a-frank-j-vella-como-director-de-operaciones\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/information-builders-incorpora-a-frank-j-vella-como-director-de-operaciones\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/information-builders-incorpora-a-frank-j-vella-como-director-de-operaciones\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/information-builders-incorpora-a-frank-j-vella-como-director-de-operaciones\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/information-builders-incorpora-a-frank-j-vella-como-director-de-operaciones\\\/\",\"name\":\"Information Builders incorpora a Frank J. Vella como director de Operaciones | Cand\\u00e1s 365\",\"description\":\"Information Builders, compa\\u00f1\\u00eda l\\u00edder en el mercado BI (Business Intelligence), anal\\u00edtica y gesti\\u00f3n de datos incorpora a Frank J. Vella como director de Operaciones. Vella trabajar\\u00e1 estrechamente con el equipo ejecutivo de Information Builders para desarrollar estrategias de crecimiento, identificar nuevas oportunidades de mercado e impulsar los planes de expansi\\u00f3n de la compa\\u00f1\\u00eda. El nombramiento\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/information-builders-incorpora-a-frank-j-vella-como-director-de-operaciones\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/1517565005_IB_Frank_Vella.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/information-builders-incorpora-a-frank-j-vella-como-director-de-operaciones\\\/#mainImage\",\"width\":677,\"height\":623},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/information-builders-incorpora-a-frank-j-vella-como-director-de-operaciones\\\/#mainImage\"},\"datePublished\":\"2018-02-02T14:39:02+01:00\",\"dateModified\":\"2018-02-02T14:39:02+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Information Builders incorpora a Frank J. Vella como director de Operaciones | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Information Builders incorpora a Frank J. Vella como director de Operaciones | Cand\u00e1s 365","description":"Information Builders, compa\u00f1\u00eda l\u00edder en el mercado BI (Business Intelligence), anal\u00edtica y gesti\u00f3n de datos incorpora a Frank J. Vella como director de Operaciones. Vella trabajar\u00e1 estrechamente con el equipo ejecutivo de Information Builders para desarrollar estrategias de crecimiento, identificar nuevas oportunidades de mercado e impulsar los planes de expansi\u00f3n de la compa\u00f1\u00eda. El nombramiento","canonical_url":"https:\/\/candas365.es\/noticias\/information-builders-incorpora-a-frank-j-vella-como-director-de-operaciones\/","robots":"max-image-preview:large","keywords":"canal empresas","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/information-builders-incorpora-a-frank-j-vella-como-director-de-operaciones\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","name":"Canal Empresas"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","position":2,"name":"Canal Empresas","item":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/information-builders-incorpora-a-frank-j-vella-como-director-de-operaciones\/#listItem","name":"Information Builders incorpora a Frank J. Vella como director de Operaciones"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/information-builders-incorpora-a-frank-j-vella-como-director-de-operaciones\/#listItem","position":3,"name":"Information Builders incorpora a Frank J. Vella como director de Operaciones","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","name":"Canal Empresas"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/information-builders-incorpora-a-frank-j-vella-como-director-de-operaciones\/#newsarticle","name":"Information Builders incorpora a Frank J. Vella como director de Operaciones | Cand\u00e1s 365","headline":"Information Builders incorpora a Frank J. Vella como director de Operaciones","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/1517565005_IB_Frank_Vella.jpg","width":677,"height":623},"datePublished":"2018-02-02T14:39:02+01:00","dateModified":"2018-02-02T14:39:02+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/information-builders-incorpora-a-frank-j-vella-como-director-de-operaciones\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/information-builders-incorpora-a-frank-j-vella-como-director-de-operaciones\/#webpage"},"articleSection":"Canal Empresas","dateline":"Publicado el febrero 2, 2018."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/information-builders-incorpora-a-frank-j-vella-como-director-de-operaciones\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/information-builders-incorpora-a-frank-j-vella-como-director-de-operaciones\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/information-builders-incorpora-a-frank-j-vella-como-director-de-operaciones\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/information-builders-incorpora-a-frank-j-vella-como-director-de-operaciones\/#webpage","url":"https:\/\/candas365.es\/noticias\/information-builders-incorpora-a-frank-j-vella-como-director-de-operaciones\/","name":"Information Builders incorpora a Frank J. Vella como director de Operaciones | Cand\u00e1s 365","description":"Information Builders, compa\u00f1\u00eda l\u00edder en el mercado BI (Business Intelligence), anal\u00edtica y gesti\u00f3n de datos incorpora a Frank J. Vella como director de Operaciones. Vella trabajar\u00e1 estrechamente con el equipo ejecutivo de Information Builders para desarrollar estrategias de crecimiento, identificar nuevas oportunidades de mercado e impulsar los planes de expansi\u00f3n de la compa\u00f1\u00eda. El nombramiento","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/information-builders-incorpora-a-frank-j-vella-como-director-de-operaciones\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/1517565005_IB_Frank_Vella.jpg","@id":"https:\/\/candas365.es\/noticias\/information-builders-incorpora-a-frank-j-vella-como-director-de-operaciones\/#mainImage","width":677,"height":623},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/information-builders-incorpora-a-frank-j-vella-como-director-de-operaciones\/#mainImage"},"datePublished":"2018-02-02T14:39:02+01:00","dateModified":"2018-02-02T14:39:02+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Information Builders incorpora a Frank J. Vella como director de Operaciones | Cand\u00e1s 365","og:description":"Information Builders, compa\u00f1\u00eda l\u00edder en el mercado BI (Business Intelligence), anal\u00edtica y gesti\u00f3n de datos incorpora a Frank J. Vella como director de Operaciones. Vella trabajar\u00e1 estrechamente con el equipo ejecutivo de Information Builders para desarrollar estrategias de crecimiento, identificar nuevas oportunidades de mercado e impulsar los planes de expansi\u00f3n de la compa\u00f1\u00eda. El nombramiento","og:url":"https:\/\/candas365.es\/noticias\/information-builders-incorpora-a-frank-j-vella-como-director-de-operaciones\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/1517565005_IB_Frank_Vella.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/1517565005_IB_Frank_Vella.jpg","og:image:width":677,"og:image:height":623,"article:published_time":"2018-02-02T14:39:02+00:00","article:modified_time":"2018-02-02T14:39:02+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Information Builders incorpora a Frank J. Vella como director de Operaciones | Cand\u00e1s 365","twitter:description":"Information Builders, compa\u00f1\u00eda l\u00edder en el mercado BI (Business Intelligence), anal\u00edtica y gesti\u00f3n de datos incorpora a Frank J. Vella como director de Operaciones. Vella trabajar\u00e1 estrechamente con el equipo ejecutivo de Information Builders para desarrollar estrategias de crecimiento, identificar nuevas oportunidades de mercado e impulsar los planes de expansi\u00f3n de la compa\u00f1\u00eda. El nombramiento","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/02\/1517565005_IB_Frank_Vella.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"89091","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-26 11:37:20","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 12:00:57","updated":"2025-08-26 11:37:20"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/\" title=\"Canal Empresas\">Canal Empresas<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tInformation Builders incorpora a Frank J. Vella como director de Operaciones\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Canal Empresas","link":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/"},{"label":"Information Builders incorpora a Frank J. Vella como director de Operaciones","link":"https:\/\/candas365.es\/noticias\/information-builders-incorpora-a-frank-j-vella-como-director-de-operaciones\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/89091","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=89091"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/89091\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/89092"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=89091"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=89091"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=89091"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}