{"id":84096,"date":"2017-11-10T19:50:27","date_gmt":"2017-11-10T19:50:27","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=84096"},"modified":"2017-11-10T19:50:27","modified_gmt":"2017-11-10T19:50:27","slug":"amil-asociados-estrena-pagina-web","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/amil-asociados-estrena-pagina-web\/","title":{"rendered":"Amil &#038; Asociados estrena p\u00e1gina web"},"content":{"rendered":"<p><strong><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-84097\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/1510318055_2017_IMAGEN_POST_NOVIEMBRE-360x188.png\" alt=\"\" width=\"360\" height=\"188\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/1510318055_2017_IMAGEN_POST_NOVIEMBRE-360x188.png 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/1510318055_2017_IMAGEN_POST_NOVIEMBRE-768x402.png 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/1510318055_2017_IMAGEN_POST_NOVIEMBRE-655x343.png 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/1510318055_2017_IMAGEN_POST_NOVIEMBRE-696x364.png 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/1510318055_2017_IMAGEN_POST_NOVIEMBRE-1068x559.png 1068w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/1510318055_2017_IMAGEN_POST_NOVIEMBRE-803x420.png 803w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/1510318055_2017_IMAGEN_POST_NOVIEMBRE.png 1200w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Amil &amp; Asociados<\/strong> es un despacho jur\u00eddico ubicado en el municipio de Carmona, que ofrece servicios relacionados con el \u00e1mbito del Derecho Civil, Penal, Laboral y Administrativo.<\/p>\n<p>\u201cNuestros principios b\u00e1sicos son la \u00e9tica profesional y el compromiso total con el cliente\u201d, explica Alejandro Amil G\u00f3mez, titulado en Derecho Privado y P\u00fablico y con m\u00e1s de 10 a\u00f1os de dilatada experiencia en sectores bancarios, de seguridad y jur\u00eddico.<\/p>\n<p>El equipo lo completa Cristina Alonso Bellido, quien ha trabajado para prestigiosos despachos as\u00ed como para la Junta de Andaluc\u00eda; adem\u00e1s, est\u00e1 especializada en Derecho Administrativo, Penal y Familia. \u201cNuestra formaci\u00f3n nos permite ofrecer servicios muy personalizados\u201d, cuenta Alonso.<\/p>\n<p><strong>La importancia de estar en la red<\/strong><\/p>\n<p>No cabe duda de que el \u00e9xito de un negocio depende hoy, en buena parte, de su presencia en Internet. Por este motivo, el bufete <strong>Amil &amp; Asociados<\/strong> ha decidido crear su carta de presentaci\u00f3n en forma de <strong><a href=\"http:\/\/www.amilasociados.com\/\" target=\"_blank\" rel=\"nofollow noopener\"><span style=\"color: #ff0000;\">web<\/span> <span style=\"color: #ff0000;\">propia<\/span><\/a><\/strong>.<\/p>\n<p>Se trata de un espacio online de dise\u00f1o elegante y f\u00e1cil navegaci\u00f3n, lo cual se traduce en un mayor tiempo en la p\u00e1gina por parte del usuario. En \u00e9l, pueden consultarse los distintos servicios que ofrecen e informaci\u00f3n acerca del equipo y la empresa. Destacan las im\u00e1genes de alta calidad y el color granate sobre blanco.<\/p>\n<p>Sin embargo, el apartado m\u00e1s interesante es el denominado <em>BLOG<\/em>, un lugar donde se publicar\u00e1n textos relacionados con el sector y que mantendr\u00e1n la web actualizada. \u201cQueremos acercar el Derecho a todo el mundo, incluso a aquellos que creen no entenderlo\u201d, explica Alejandro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Amil &amp; Asociados es un despacho jur\u00eddico ubicado en el municipio de Carmona, que ofrece servicios relacionados con el \u00e1mbito del Derecho Civil, Penal, Laboral y Administrativo. \u201cNuestros principios b\u00e1sicos son la \u00e9tica profesional y el compromiso total con el cliente\u201d, explica Alejandro Amil G\u00f3mez, titulado en Derecho Privado y P\u00fablico y con m\u00e1s de<\/p>\n","protected":false},"author":1,"featured_media":84097,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[151],"tags":[],"class_list":{"0":"post-84096","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-canal-empresas"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7 - aioseo.com -->\n\t<meta name=\"description\" content=\"Amil &amp; Asociados es un despacho jur\u00eddico ubicado en el municipio de Carmona, que ofrece servicios relacionados con el \u00e1mbito del Derecho Civil, Penal, Laboral y Administrativo. \u201cNuestros principios b\u00e1sicos son la \u00e9tica profesional y el compromiso total con el cliente\u201d, explica Alejandro Amil G\u00f3mez, titulado en Derecho Privado y P\u00fablico y con m\u00e1s de\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"canal empresas\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/amil-asociados-estrena-pagina-web\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Amil &amp; Asociados estrena p\u00e1gina web | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Amil &amp; Asociados es un despacho jur\u00eddico ubicado en el municipio de Carmona, que ofrece servicios relacionados con el \u00e1mbito del Derecho Civil, Penal, Laboral y Administrativo. \u201cNuestros principios b\u00e1sicos son la \u00e9tica profesional y el compromiso total con el cliente\u201d, explica Alejandro Amil G\u00f3mez, titulado en Derecho Privado y P\u00fablico y con m\u00e1s de\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/amil-asociados-estrena-pagina-web\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/1510318055_2017_IMAGEN_POST_NOVIEMBRE.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/1510318055_2017_IMAGEN_POST_NOVIEMBRE.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2017-11-10T19:50:27+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2017-11-10T19:50:27+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Amil &amp; Asociados estrena p\u00e1gina web | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Amil &amp; Asociados es un despacho jur\u00eddico ubicado en el municipio de Carmona, que ofrece servicios relacionados con el \u00e1mbito del Derecho Civil, Penal, Laboral y Administrativo. \u201cNuestros principios b\u00e1sicos son la \u00e9tica profesional y el compromiso total con el cliente\u201d, explica Alejandro Amil G\u00f3mez, titulado en Derecho Privado y P\u00fablico y con m\u00e1s de\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/1510318055_2017_IMAGEN_POST_NOVIEMBRE.png\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/amil-asociados-estrena-pagina-web\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"name\":\"Canal Empresas\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"position\":2,\"name\":\"Canal Empresas\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/amil-asociados-estrena-pagina-web\\\/#listItem\",\"name\":\"Amil &#038; Asociados estrena p\\u00e1gina web\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/amil-asociados-estrena-pagina-web\\\/#listItem\",\"position\":3,\"name\":\"Amil &#038; Asociados estrena p\\u00e1gina web\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"name\":\"Canal Empresas\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/amil-asociados-estrena-pagina-web\\\/#newsarticle\",\"name\":\"Amil & Asociados estrena p\\u00e1gina web | Cand\\u00e1s 365\",\"headline\":\"Amil &#038; Asociados estrena p\\u00e1gina web\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/1510318055_2017_IMAGEN_POST_NOVIEMBRE.png\",\"width\":1200,\"height\":628},\"datePublished\":\"2017-11-10T19:50:27+01:00\",\"dateModified\":\"2017-11-10T19:50:27+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/amil-asociados-estrena-pagina-web\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/amil-asociados-estrena-pagina-web\\\/#webpage\"},\"articleSection\":\"Canal Empresas\",\"dateline\":\"Publicado el noviembre 10, 2017.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/amil-asociados-estrena-pagina-web\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/amil-asociados-estrena-pagina-web\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/amil-asociados-estrena-pagina-web\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/amil-asociados-estrena-pagina-web\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/amil-asociados-estrena-pagina-web\\\/\",\"name\":\"Amil & Asociados estrena p\\u00e1gina web | Cand\\u00e1s 365\",\"description\":\"Amil & Asociados es un despacho jur\\u00eddico ubicado en el municipio de Carmona, que ofrece servicios relacionados con el \\u00e1mbito del Derecho Civil, Penal, Laboral y Administrativo. \\u201cNuestros principios b\\u00e1sicos son la \\u00e9tica profesional y el compromiso total con el cliente\\u201d, explica Alejandro Amil G\\u00f3mez, titulado en Derecho Privado y P\\u00fablico y con m\\u00e1s de\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/amil-asociados-estrena-pagina-web\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/1510318055_2017_IMAGEN_POST_NOVIEMBRE.png\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/amil-asociados-estrena-pagina-web\\\/#mainImage\",\"width\":1200,\"height\":628},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/amil-asociados-estrena-pagina-web\\\/#mainImage\"},\"datePublished\":\"2017-11-10T19:50:27+01:00\",\"dateModified\":\"2017-11-10T19:50:27+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Amil &amp; Asociados estrena p\u00e1gina web | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Amil & Asociados estrena p\u00e1gina web | Cand\u00e1s 365","description":"Amil & Asociados es un despacho jur\u00eddico ubicado en el municipio de Carmona, que ofrece servicios relacionados con el \u00e1mbito del Derecho Civil, Penal, Laboral y Administrativo. \u201cNuestros principios b\u00e1sicos son la \u00e9tica profesional y el compromiso total con el cliente\u201d, explica Alejandro Amil G\u00f3mez, titulado en Derecho Privado y P\u00fablico y con m\u00e1s de","canonical_url":"https:\/\/candas365.es\/noticias\/amil-asociados-estrena-pagina-web\/","robots":"max-image-preview:large","keywords":"canal empresas","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/amil-asociados-estrena-pagina-web\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","name":"Canal Empresas"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","position":2,"name":"Canal Empresas","item":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/amil-asociados-estrena-pagina-web\/#listItem","name":"Amil &#038; Asociados estrena p\u00e1gina web"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/amil-asociados-estrena-pagina-web\/#listItem","position":3,"name":"Amil &#038; Asociados estrena p\u00e1gina web","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","name":"Canal Empresas"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/amil-asociados-estrena-pagina-web\/#newsarticle","name":"Amil & Asociados estrena p\u00e1gina web | Cand\u00e1s 365","headline":"Amil &#038; Asociados estrena p\u00e1gina web","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/1510318055_2017_IMAGEN_POST_NOVIEMBRE.png","width":1200,"height":628},"datePublished":"2017-11-10T19:50:27+01:00","dateModified":"2017-11-10T19:50:27+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/amil-asociados-estrena-pagina-web\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/amil-asociados-estrena-pagina-web\/#webpage"},"articleSection":"Canal Empresas","dateline":"Publicado el noviembre 10, 2017."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/amil-asociados-estrena-pagina-web\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/amil-asociados-estrena-pagina-web\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/amil-asociados-estrena-pagina-web\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/amil-asociados-estrena-pagina-web\/#webpage","url":"https:\/\/candas365.es\/noticias\/amil-asociados-estrena-pagina-web\/","name":"Amil & Asociados estrena p\u00e1gina web | Cand\u00e1s 365","description":"Amil & Asociados es un despacho jur\u00eddico ubicado en el municipio de Carmona, que ofrece servicios relacionados con el \u00e1mbito del Derecho Civil, Penal, Laboral y Administrativo. \u201cNuestros principios b\u00e1sicos son la \u00e9tica profesional y el compromiso total con el cliente\u201d, explica Alejandro Amil G\u00f3mez, titulado en Derecho Privado y P\u00fablico y con m\u00e1s de","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/amil-asociados-estrena-pagina-web\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/1510318055_2017_IMAGEN_POST_NOVIEMBRE.png","@id":"https:\/\/candas365.es\/noticias\/amil-asociados-estrena-pagina-web\/#mainImage","width":1200,"height":628},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/amil-asociados-estrena-pagina-web\/#mainImage"},"datePublished":"2017-11-10T19:50:27+01:00","dateModified":"2017-11-10T19:50:27+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Amil &amp; Asociados estrena p\u00e1gina web | Cand\u00e1s 365","og:description":"Amil &amp; Asociados es un despacho jur\u00eddico ubicado en el municipio de Carmona, que ofrece servicios relacionados con el \u00e1mbito del Derecho Civil, Penal, Laboral y Administrativo. \u201cNuestros principios b\u00e1sicos son la \u00e9tica profesional y el compromiso total con el cliente\u201d, explica Alejandro Amil G\u00f3mez, titulado en Derecho Privado y P\u00fablico y con m\u00e1s de","og:url":"https:\/\/candas365.es\/noticias\/amil-asociados-estrena-pagina-web\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/1510318055_2017_IMAGEN_POST_NOVIEMBRE.png","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/1510318055_2017_IMAGEN_POST_NOVIEMBRE.png","og:image:width":1200,"og:image:height":628,"article:published_time":"2017-11-10T19:50:27+00:00","article:modified_time":"2017-11-10T19:50:27+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Amil &amp; Asociados estrena p\u00e1gina web | Cand\u00e1s 365","twitter:description":"Amil &amp; Asociados es un despacho jur\u00eddico ubicado en el municipio de Carmona, que ofrece servicios relacionados con el \u00e1mbito del Derecho Civil, Penal, Laboral y Administrativo. \u201cNuestros principios b\u00e1sicos son la \u00e9tica profesional y el compromiso total con el cliente\u201d, explica Alejandro Amil G\u00f3mez, titulado en Derecho Privado y P\u00fablico y con m\u00e1s de","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/1510318055_2017_IMAGEN_POST_NOVIEMBRE.png","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"1 minuto"},"aioseo_meta_data":{"post_id":"84096","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-26 05:10:25","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 12:27:58","updated":"2025-08-26 05:10:25"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/\" title=\"Canal Empresas\">Canal Empresas<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tAmil &amp; Asociados estrena p\u00e1gina web\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Canal Empresas","link":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/"},{"label":"Amil &#038; Asociados estrena p\u00e1gina web","link":"https:\/\/candas365.es\/noticias\/amil-asociados-estrena-pagina-web\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/84096","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=84096"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/84096\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/84097"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=84096"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=84096"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=84096"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}