{"id":81925,"date":"2017-10-10T16:36:30","date_gmt":"2017-10-10T16:36:30","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=81925"},"modified":"2017-10-10T16:36:30","modified_gmt":"2017-10-10T16:36:30","slug":"espana-lamenta-la-destruccion-causada-por-la-tormenta-tropical-nate-en-centroamerica","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/espana-lamenta-la-destruccion-causada-por-la-tormenta-tropical-nate-en-centroamerica\/","title":{"rendered":"Espa\u00f1a lamenta la destrucci\u00f3n causada por la tormenta tropical \u00abNate\u00bb en Centroam\u00e9rica"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-81926\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/10\/09032017_SedeMinisterio-360x239.jpg\" alt=\"\" width=\"360\" height=\"239\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/10\/09032017_SedeMinisterio-360x239.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/10\/09032017_SedeMinisterio-84x55.jpg 84w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/10\/09032017_SedeMinisterio.jpg 496w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Espa\u00f1a expresa su dolor por la terrible destrucci\u00f3n provocada por el paso de la tormenta tropical \u00abNate\u00bb por Centroam\u00e9rica con efectos devastadores, en particular en Costa Rica y Nicaragua, donde ha provocado p\u00e9rdida de vidas humanas y graves da\u00f1os materiales, y en El Salvador, Honduras, Guatemala y Belice que se han visto, tambi\u00e9n, gravemente afectados.<\/p>\n<p>\u200bEl Gobierno de Espa\u00f1a expresa sus condolencias a las familias de las v\u00edctimas y desea el pronto restablecimiento de los heridos y traslada su solidaridad y apoyo al pueblo y a las autoridades de dichos pa\u00edses. Espa\u00f1a va a realizar una contribuci\u00f3n al Fondo de Emergencias de Respuesta ante Desastres que la Federaci\u00f3n Internacional de la Cruz Roja ha constituido tras el paso del hurac\u00e1n \u00abNate\u00bb en Nicaragua que permitir\u00e1 proporcionar elementos de cobijo y art\u00edculos no alimentarios a numerosas familias afectadas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Espa\u00f1a expresa su dolor por la terrible destrucci\u00f3n provocada por el paso de la tormenta tropical \u00abNate\u00bb por Centroam\u00e9rica con efectos devastadores, en particular en Costa Rica y Nicaragua, donde ha provocado p\u00e9rdida de vidas humanas y graves da\u00f1os materiales, y en El Salvador, Honduras, Guatemala y Belice que se han visto, tambi\u00e9n, gravemente afectados.<\/p>\n","protected":false},"author":1,"featured_media":81926,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343],"tags":[],"class_list":{"0":"post-81925","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-actualidad"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Espa\u00f1a expresa su dolor por la terrible destrucci\u00f3n provocada por el paso de la tormenta tropical &quot;Nate&quot; por Centroam\u00e9rica con efectos devastadores, en particular en Costa Rica y Nicaragua, donde ha provocado p\u00e9rdida de vidas humanas y graves da\u00f1os materiales, y en El Salvador, Honduras, Guatemala y Belice que se han visto, tambi\u00e9n, gravemente afectados.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/espana-lamenta-la-destruccion-causada-por-la-tormenta-tropical-nate-en-centroamerica\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Espa\u00f1a lamenta la destrucci\u00f3n causada por la tormenta tropical \u00abNate\u00bb en Centroam\u00e9rica | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Espa\u00f1a expresa su dolor por la terrible destrucci\u00f3n provocada por el paso de la tormenta tropical &quot;Nate&quot; por Centroam\u00e9rica con efectos devastadores, en particular en Costa Rica y Nicaragua, donde ha provocado p\u00e9rdida de vidas humanas y graves da\u00f1os materiales, y en El Salvador, Honduras, Guatemala y Belice que se han visto, tambi\u00e9n, gravemente afectados.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/espana-lamenta-la-destruccion-causada-por-la-tormenta-tropical-nate-en-centroamerica\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/10\/09032017_SedeMinisterio.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/10\/09032017_SedeMinisterio.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"496\" \/>\n\t\t<meta property=\"og:image:height\" content=\"329\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2017-10-10T16:36:30+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2017-10-10T16:36:30+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Espa\u00f1a lamenta la destrucci\u00f3n causada por la tormenta tropical \u00abNate\u00bb en Centroam\u00e9rica | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Espa\u00f1a expresa su dolor por la terrible destrucci\u00f3n provocada por el paso de la tormenta tropical &quot;Nate&quot; por Centroam\u00e9rica con efectos devastadores, en particular en Costa Rica y Nicaragua, donde ha provocado p\u00e9rdida de vidas humanas y graves da\u00f1os materiales, y en El Salvador, Honduras, Guatemala y Belice que se han visto, tambi\u00e9n, gravemente afectados.\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/10\/09032017_SedeMinisterio.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/espana-lamenta-la-destruccion-causada-por-la-tormenta-tropical-nate-en-centroamerica\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/espana-lamenta-la-destruccion-causada-por-la-tormenta-tropical-nate-en-centroamerica\\\/#listItem\",\"name\":\"Espa\\u00f1a lamenta la destrucci\\u00f3n causada por la tormenta tropical \\u00abNate\\u00bb en Centroam\\u00e9rica\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/espana-lamenta-la-destruccion-causada-por-la-tormenta-tropical-nate-en-centroamerica\\\/#listItem\",\"position\":3,\"name\":\"Espa\\u00f1a lamenta la destrucci\\u00f3n causada por la tormenta tropical \\u00abNate\\u00bb en Centroam\\u00e9rica\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/espana-lamenta-la-destruccion-causada-por-la-tormenta-tropical-nate-en-centroamerica\\\/#newsarticle\",\"name\":\"Espa\\u00f1a lamenta la destrucci\\u00f3n causada por la tormenta tropical \\u00abNate\\u00bb en Centroam\\u00e9rica | Cand\\u00e1s 365\",\"headline\":\"Espa\\u00f1a lamenta la destrucci\\u00f3n causada por la tormenta tropical \\u00abNate\\u00bb en Centroam\\u00e9rica\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/09032017_SedeMinisterio.jpg\",\"width\":496,\"height\":329},\"datePublished\":\"2017-10-10T16:36:30+02:00\",\"dateModified\":\"2017-10-10T16:36:30+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/espana-lamenta-la-destruccion-causada-por-la-tormenta-tropical-nate-en-centroamerica\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/espana-lamenta-la-destruccion-causada-por-la-tormenta-tropical-nate-en-centroamerica\\\/#webpage\"},\"articleSection\":\"Actualidad\",\"dateline\":\"Publicado el octubre 10, 2017.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/espana-lamenta-la-destruccion-causada-por-la-tormenta-tropical-nate-en-centroamerica\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/espana-lamenta-la-destruccion-causada-por-la-tormenta-tropical-nate-en-centroamerica\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/espana-lamenta-la-destruccion-causada-por-la-tormenta-tropical-nate-en-centroamerica\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/espana-lamenta-la-destruccion-causada-por-la-tormenta-tropical-nate-en-centroamerica\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/espana-lamenta-la-destruccion-causada-por-la-tormenta-tropical-nate-en-centroamerica\\\/\",\"name\":\"Espa\\u00f1a lamenta la destrucci\\u00f3n causada por la tormenta tropical \\u00abNate\\u00bb en Centroam\\u00e9rica | Cand\\u00e1s 365\",\"description\":\"Espa\\u00f1a expresa su dolor por la terrible destrucci\\u00f3n provocada por el paso de la tormenta tropical \\\"Nate\\\" por Centroam\\u00e9rica con efectos devastadores, en particular en Costa Rica y Nicaragua, donde ha provocado p\\u00e9rdida de vidas humanas y graves da\\u00f1os materiales, y en El Salvador, Honduras, Guatemala y Belice que se han visto, tambi\\u00e9n, gravemente afectados.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/espana-lamenta-la-destruccion-causada-por-la-tormenta-tropical-nate-en-centroamerica\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/09032017_SedeMinisterio.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/espana-lamenta-la-destruccion-causada-por-la-tormenta-tropical-nate-en-centroamerica\\\/#mainImage\",\"width\":496,\"height\":329},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/espana-lamenta-la-destruccion-causada-por-la-tormenta-tropical-nate-en-centroamerica\\\/#mainImage\"},\"datePublished\":\"2017-10-10T16:36:30+02:00\",\"dateModified\":\"2017-10-10T16:36:30+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Espa\u00f1a lamenta la destrucci\u00f3n causada por la tormenta tropical \u00abNate\u00bb en Centroam\u00e9rica | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Espa\u00f1a lamenta la destrucci\u00f3n causada por la tormenta tropical \u00abNate\u00bb en Centroam\u00e9rica | Cand\u00e1s 365","description":"Espa\u00f1a expresa su dolor por la terrible destrucci\u00f3n provocada por el paso de la tormenta tropical \"Nate\" por Centroam\u00e9rica con efectos devastadores, en particular en Costa Rica y Nicaragua, donde ha provocado p\u00e9rdida de vidas humanas y graves da\u00f1os materiales, y en El Salvador, Honduras, Guatemala y Belice que se han visto, tambi\u00e9n, gravemente afectados.","canonical_url":"https:\/\/candas365.es\/noticias\/espana-lamenta-la-destruccion-causada-por-la-tormenta-tropical-nate-en-centroamerica\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/espana-lamenta-la-destruccion-causada-por-la-tormenta-tropical-nate-en-centroamerica\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/candas365.es\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/espana-lamenta-la-destruccion-causada-por-la-tormenta-tropical-nate-en-centroamerica\/#listItem","name":"Espa\u00f1a lamenta la destrucci\u00f3n causada por la tormenta tropical \u00abNate\u00bb en Centroam\u00e9rica"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/espana-lamenta-la-destruccion-causada-por-la-tormenta-tropical-nate-en-centroamerica\/#listItem","position":3,"name":"Espa\u00f1a lamenta la destrucci\u00f3n causada por la tormenta tropical \u00abNate\u00bb en Centroam\u00e9rica","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/espana-lamenta-la-destruccion-causada-por-la-tormenta-tropical-nate-en-centroamerica\/#newsarticle","name":"Espa\u00f1a lamenta la destrucci\u00f3n causada por la tormenta tropical \u00abNate\u00bb en Centroam\u00e9rica | Cand\u00e1s 365","headline":"Espa\u00f1a lamenta la destrucci\u00f3n causada por la tormenta tropical \u00abNate\u00bb en Centroam\u00e9rica","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/10\/09032017_SedeMinisterio.jpg","width":496,"height":329},"datePublished":"2017-10-10T16:36:30+02:00","dateModified":"2017-10-10T16:36:30+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/espana-lamenta-la-destruccion-causada-por-la-tormenta-tropical-nate-en-centroamerica\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/espana-lamenta-la-destruccion-causada-por-la-tormenta-tropical-nate-en-centroamerica\/#webpage"},"articleSection":"Actualidad","dateline":"Publicado el octubre 10, 2017."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/espana-lamenta-la-destruccion-causada-por-la-tormenta-tropical-nate-en-centroamerica\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/espana-lamenta-la-destruccion-causada-por-la-tormenta-tropical-nate-en-centroamerica\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/espana-lamenta-la-destruccion-causada-por-la-tormenta-tropical-nate-en-centroamerica\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/espana-lamenta-la-destruccion-causada-por-la-tormenta-tropical-nate-en-centroamerica\/#webpage","url":"https:\/\/candas365.es\/noticias\/espana-lamenta-la-destruccion-causada-por-la-tormenta-tropical-nate-en-centroamerica\/","name":"Espa\u00f1a lamenta la destrucci\u00f3n causada por la tormenta tropical \u00abNate\u00bb en Centroam\u00e9rica | Cand\u00e1s 365","description":"Espa\u00f1a expresa su dolor por la terrible destrucci\u00f3n provocada por el paso de la tormenta tropical \"Nate\" por Centroam\u00e9rica con efectos devastadores, en particular en Costa Rica y Nicaragua, donde ha provocado p\u00e9rdida de vidas humanas y graves da\u00f1os materiales, y en El Salvador, Honduras, Guatemala y Belice que se han visto, tambi\u00e9n, gravemente afectados.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/espana-lamenta-la-destruccion-causada-por-la-tormenta-tropical-nate-en-centroamerica\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/10\/09032017_SedeMinisterio.jpg","@id":"https:\/\/candas365.es\/noticias\/espana-lamenta-la-destruccion-causada-por-la-tormenta-tropical-nate-en-centroamerica\/#mainImage","width":496,"height":329},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/espana-lamenta-la-destruccion-causada-por-la-tormenta-tropical-nate-en-centroamerica\/#mainImage"},"datePublished":"2017-10-10T16:36:30+02:00","dateModified":"2017-10-10T16:36:30+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Espa\u00f1a lamenta la destrucci\u00f3n causada por la tormenta tropical \u00abNate\u00bb en Centroam\u00e9rica | Cand\u00e1s 365","og:description":"Espa\u00f1a expresa su dolor por la terrible destrucci\u00f3n provocada por el paso de la tormenta tropical &quot;Nate&quot; por Centroam\u00e9rica con efectos devastadores, en particular en Costa Rica y Nicaragua, donde ha provocado p\u00e9rdida de vidas humanas y graves da\u00f1os materiales, y en El Salvador, Honduras, Guatemala y Belice que se han visto, tambi\u00e9n, gravemente afectados.","og:url":"https:\/\/candas365.es\/noticias\/espana-lamenta-la-destruccion-causada-por-la-tormenta-tropical-nate-en-centroamerica\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/10\/09032017_SedeMinisterio.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/10\/09032017_SedeMinisterio.jpg","og:image:width":496,"og:image:height":329,"article:published_time":"2017-10-10T16:36:30+00:00","article:modified_time":"2017-10-10T16:36:30+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Espa\u00f1a lamenta la destrucci\u00f3n causada por la tormenta tropical \u00abNate\u00bb en Centroam\u00e9rica | Cand\u00e1s 365","twitter:description":"Espa\u00f1a expresa su dolor por la terrible destrucci\u00f3n provocada por el paso de la tormenta tropical &quot;Nate&quot; por Centroam\u00e9rica con efectos devastadores, en particular en Costa Rica y Nicaragua, donde ha provocado p\u00e9rdida de vidas humanas y graves da\u00f1os materiales, y en El Salvador, Honduras, Guatemala y Belice que se han visto, tambi\u00e9n, gravemente afectados.","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/10\/09032017_SedeMinisterio.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"1 minuto"},"aioseo_meta_data":{"post_id":"81925","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-26 02:26:14","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 12:38:57","updated":"2025-08-26 02:26:14"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tEspa\u00f1a lamenta la destrucci\u00f3n causada por la tormenta tropical \u00abNate\u00bb en Centroam\u00e9rica\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Actualidad","link":"https:\/\/candas365.es\/noticias\/category\/actualidad\/"},{"label":"Espa\u00f1a lamenta la destrucci\u00f3n causada por la tormenta tropical \u00abNate\u00bb en Centroam\u00e9rica","link":"https:\/\/candas365.es\/noticias\/espana-lamenta-la-destruccion-causada-por-la-tormenta-tropical-nate-en-centroamerica\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/81925","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=81925"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/81925\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/81926"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=81925"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=81925"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=81925"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}