{"id":81357,"date":"2017-10-02T21:39:19","date_gmt":"2017-10-02T21:39:19","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=81357"},"modified":"2017-10-02T21:39:19","modified_gmt":"2017-10-02T21:39:19","slug":"enrique-tomas-empresa-lider-en-la-venta-de-jamon-iberico-estrena-web","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/enrique-tomas-empresa-lider-en-la-venta-de-jamon-iberico-estrena-web\/","title":{"rendered":"Enrique Tom\u00e1s, empresa l\u00edder en la venta de jam\u00f3n ib\u00e9rico estrena web"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-81358\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/10\/1506938906_Tienda_online_comprar_jamon_iberico_001-360x240.jpg\" alt=\"\" width=\"360\" height=\"240\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/10\/1506938906_Tienda_online_comprar_jamon_iberico_001-360x240.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/10\/1506938906_Tienda_online_comprar_jamon_iberico_001.jpg 1920w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/10\/1506938906_Tienda_online_comprar_jamon_iberico_001-768x512.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/10\/1506938906_Tienda_online_comprar_jamon_iberico_001-655x436.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/10\/1506938906_Tienda_online_comprar_jamon_iberico_001-696x464.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/10\/1506938906_Tienda_online_comprar_jamon_iberico_001-1068x711.jpg 1068w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/10\/1506938906_Tienda_online_comprar_jamon_iberico_001-630x420.jpg 630w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/10\/1506938906_Tienda_online_comprar_jamon_iberico_001-84x55.jpg 84w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>El mejor portal de venta de <strong><a href=\"https:\/\/enriquetomas.com\/\" target=\"_blank\" rel=\"follow noopener\"><span style=\"color: #ff0000;\">jam\u00f3n<\/span> <span style=\"color: #ff0000;\">ib\u00e9rico<\/span><\/a><\/strong> est\u00e1 dise\u00f1ado en 3 idiomas (<strong>castellano<\/strong>, <strong>ingl\u00e9s<\/strong> y <strong>franc\u00e9s<\/strong>) y en las pr\u00f3ximas semanas incluir\u00e1 las versiones<strong> alemana<\/strong> e <strong>italiana<\/strong>. La expansi\u00f3n internacional de la empresa a nivel de tiendas tambi\u00e9n se est\u00e1 realizando paralelamente a nivel online<\/p>\n<p>El nuevo eCommerce mejora la experiencia de compra, el entorno visual, la categorizaci\u00f3n de productos y la navegaci\u00f3n tanto en m\u00f3vil como en escritorio. Adem\u00e1s, incorpora los \u00faltimos avances tecnol\u00f3gicos para que la experiencia de compra sea lo m\u00e1s c\u00f3moda y \u00e1gil posible.<\/p>\n<p>Entre las mejoras, cabe destacar que <strong><a href=\"https:\/\/www.enriquetomas.com\/\" target=\"_blank\" rel=\"follow noopener\"><span style=\"color: #ff0000;\">Enriquetomas.com<\/span><\/a><\/strong> incluye un novedoso chat para estar m\u00e1s cerca del cliente durante el proceso de compra. De tal manera que los mejores especialistas del sector podr\u00e1n asesorar a los clientes para que siempre compren exactamente lo que necesitan.<\/p>\n<p>Para llevar a cabo una iniciativa tan ambiciosa, <strong>Enrique Tom\u00e1s<\/strong> ha creado un equipo en el que hay traductores, periodistas, redactores, especialistas en atenci\u00f3n al cliente, profesionales del marqueting digital, programadores, dise\u00f1adores gr\u00e1ficos as\u00ed como expertos en SEO y SEM.<\/p>\n<p>Este equipo tiene como misi\u00f3n principal incrementar la visibilidad de un comercio electr\u00f3nico que ofrece todos los tipos de jam\u00f3n existentes, con un triple proceso de selecci\u00f3n que garantiza su calidad. Enrique Tom\u00e1s quiere ofrecer a sus clientes, la seguridad de siempre estar comprando el producto en su momento \u00f3ptimo de curaci\u00f3n y sobre todo asesorar en que la mejor opci\u00f3n, para muchos, es que uno de sus maestros cortadores haga el loncheado de la pieza y as\u00ed obtener un mejor rendimiento y que el cliente eleve su experiencia a otro nivel.<\/p>\n<p><em><strong>Su mayor objetivo: \u00a1Que disfrutes cada vez que comas jam\u00f3n!<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El mejor portal de venta de jam\u00f3n ib\u00e9rico est\u00e1 dise\u00f1ado en 3 idiomas (castellano, ingl\u00e9s y franc\u00e9s) y en las pr\u00f3ximas semanas incluir\u00e1 las versiones alemana e italiana. La expansi\u00f3n internacional de la empresa a nivel de tiendas tambi\u00e9n se est\u00e1 realizando paralelamente a nivel online El nuevo eCommerce mejora la experiencia de compra, el<\/p>\n","protected":false},"author":1,"featured_media":81358,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[151],"tags":[],"class_list":{"0":"post-81357","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-canal-empresas"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7 - aioseo.com -->\n\t<meta name=\"description\" content=\"El mejor portal de venta de jam\u00f3n ib\u00e9rico est\u00e1 dise\u00f1ado en 3 idiomas (castellano, ingl\u00e9s y franc\u00e9s) y en las pr\u00f3ximas semanas incluir\u00e1 las versiones alemana e italiana. La expansi\u00f3n internacional de la empresa a nivel de tiendas tambi\u00e9n se est\u00e1 realizando paralelamente a nivel online El nuevo eCommerce mejora la experiencia de compra, el\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"canal empresas\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/enrique-tomas-empresa-lider-en-la-venta-de-jamon-iberico-estrena-web\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Enrique Tom\u00e1s, empresa l\u00edder en la venta de jam\u00f3n ib\u00e9rico estrena web | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"El mejor portal de venta de jam\u00f3n ib\u00e9rico est\u00e1 dise\u00f1ado en 3 idiomas (castellano, ingl\u00e9s y franc\u00e9s) y en las pr\u00f3ximas semanas incluir\u00e1 las versiones alemana e italiana. La expansi\u00f3n internacional de la empresa a nivel de tiendas tambi\u00e9n se est\u00e1 realizando paralelamente a nivel online El nuevo eCommerce mejora la experiencia de compra, el\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/enrique-tomas-empresa-lider-en-la-venta-de-jamon-iberico-estrena-web\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/10\/1506938906_Tienda_online_comprar_jamon_iberico_001.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/10\/1506938906_Tienda_online_comprar_jamon_iberico_001.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1279\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2017-10-02T21:39:19+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2017-10-02T21:39:19+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Enrique Tom\u00e1s, empresa l\u00edder en la venta de jam\u00f3n ib\u00e9rico estrena web | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El mejor portal de venta de jam\u00f3n ib\u00e9rico est\u00e1 dise\u00f1ado en 3 idiomas (castellano, ingl\u00e9s y franc\u00e9s) y en las pr\u00f3ximas semanas incluir\u00e1 las versiones alemana e italiana. La expansi\u00f3n internacional de la empresa a nivel de tiendas tambi\u00e9n se est\u00e1 realizando paralelamente a nivel online El nuevo eCommerce mejora la experiencia de compra, el\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/10\/1506938906_Tienda_online_comprar_jamon_iberico_001.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/enrique-tomas-empresa-lider-en-la-venta-de-jamon-iberico-estrena-web\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"name\":\"Canal Empresas\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"position\":2,\"name\":\"Canal Empresas\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/enrique-tomas-empresa-lider-en-la-venta-de-jamon-iberico-estrena-web\\\/#listItem\",\"name\":\"Enrique Tom\\u00e1s, empresa l\\u00edder en la venta de jam\\u00f3n ib\\u00e9rico estrena web\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/enrique-tomas-empresa-lider-en-la-venta-de-jamon-iberico-estrena-web\\\/#listItem\",\"position\":3,\"name\":\"Enrique Tom\\u00e1s, empresa l\\u00edder en la venta de jam\\u00f3n ib\\u00e9rico estrena web\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"name\":\"Canal Empresas\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/enrique-tomas-empresa-lider-en-la-venta-de-jamon-iberico-estrena-web\\\/#newsarticle\",\"name\":\"Enrique Tom\\u00e1s, empresa l\\u00edder en la venta de jam\\u00f3n ib\\u00e9rico estrena web | Cand\\u00e1s 365\",\"headline\":\"Enrique Tom\\u00e1s, empresa l\\u00edder en la venta de jam\\u00f3n ib\\u00e9rico estrena web\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/1506938906_Tienda_online_comprar_jamon_iberico_001.jpg\",\"width\":1920,\"height\":1279},\"datePublished\":\"2017-10-02T21:39:19+02:00\",\"dateModified\":\"2017-10-02T21:39:19+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/enrique-tomas-empresa-lider-en-la-venta-de-jamon-iberico-estrena-web\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/enrique-tomas-empresa-lider-en-la-venta-de-jamon-iberico-estrena-web\\\/#webpage\"},\"articleSection\":\"Canal Empresas\",\"dateline\":\"Publicado el octubre 2, 2017.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/enrique-tomas-empresa-lider-en-la-venta-de-jamon-iberico-estrena-web\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/enrique-tomas-empresa-lider-en-la-venta-de-jamon-iberico-estrena-web\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/enrique-tomas-empresa-lider-en-la-venta-de-jamon-iberico-estrena-web\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/enrique-tomas-empresa-lider-en-la-venta-de-jamon-iberico-estrena-web\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/enrique-tomas-empresa-lider-en-la-venta-de-jamon-iberico-estrena-web\\\/\",\"name\":\"Enrique Tom\\u00e1s, empresa l\\u00edder en la venta de jam\\u00f3n ib\\u00e9rico estrena web | Cand\\u00e1s 365\",\"description\":\"El mejor portal de venta de jam\\u00f3n ib\\u00e9rico est\\u00e1 dise\\u00f1ado en 3 idiomas (castellano, ingl\\u00e9s y franc\\u00e9s) y en las pr\\u00f3ximas semanas incluir\\u00e1 las versiones alemana e italiana. La expansi\\u00f3n internacional de la empresa a nivel de tiendas tambi\\u00e9n se est\\u00e1 realizando paralelamente a nivel online El nuevo eCommerce mejora la experiencia de compra, el\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/enrique-tomas-empresa-lider-en-la-venta-de-jamon-iberico-estrena-web\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/1506938906_Tienda_online_comprar_jamon_iberico_001.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/enrique-tomas-empresa-lider-en-la-venta-de-jamon-iberico-estrena-web\\\/#mainImage\",\"width\":1920,\"height\":1279},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/enrique-tomas-empresa-lider-en-la-venta-de-jamon-iberico-estrena-web\\\/#mainImage\"},\"datePublished\":\"2017-10-02T21:39:19+02:00\",\"dateModified\":\"2017-10-02T21:39:19+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Enrique Tom\u00e1s, empresa l\u00edder en la venta de jam\u00f3n ib\u00e9rico estrena web | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Enrique Tom\u00e1s, empresa l\u00edder en la venta de jam\u00f3n ib\u00e9rico estrena web | Cand\u00e1s 365","description":"El mejor portal de venta de jam\u00f3n ib\u00e9rico est\u00e1 dise\u00f1ado en 3 idiomas (castellano, ingl\u00e9s y franc\u00e9s) y en las pr\u00f3ximas semanas incluir\u00e1 las versiones alemana e italiana. La expansi\u00f3n internacional de la empresa a nivel de tiendas tambi\u00e9n se est\u00e1 realizando paralelamente a nivel online El nuevo eCommerce mejora la experiencia de compra, el","canonical_url":"https:\/\/candas365.es\/noticias\/enrique-tomas-empresa-lider-en-la-venta-de-jamon-iberico-estrena-web\/","robots":"max-image-preview:large","keywords":"canal empresas","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/enrique-tomas-empresa-lider-en-la-venta-de-jamon-iberico-estrena-web\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","name":"Canal Empresas"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","position":2,"name":"Canal Empresas","item":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/enrique-tomas-empresa-lider-en-la-venta-de-jamon-iberico-estrena-web\/#listItem","name":"Enrique Tom\u00e1s, empresa l\u00edder en la venta de jam\u00f3n ib\u00e9rico estrena web"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/enrique-tomas-empresa-lider-en-la-venta-de-jamon-iberico-estrena-web\/#listItem","position":3,"name":"Enrique Tom\u00e1s, empresa l\u00edder en la venta de jam\u00f3n ib\u00e9rico estrena web","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","name":"Canal Empresas"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/enrique-tomas-empresa-lider-en-la-venta-de-jamon-iberico-estrena-web\/#newsarticle","name":"Enrique Tom\u00e1s, empresa l\u00edder en la venta de jam\u00f3n ib\u00e9rico estrena web | Cand\u00e1s 365","headline":"Enrique Tom\u00e1s, empresa l\u00edder en la venta de jam\u00f3n ib\u00e9rico estrena web","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/10\/1506938906_Tienda_online_comprar_jamon_iberico_001.jpg","width":1920,"height":1279},"datePublished":"2017-10-02T21:39:19+02:00","dateModified":"2017-10-02T21:39:19+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/enrique-tomas-empresa-lider-en-la-venta-de-jamon-iberico-estrena-web\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/enrique-tomas-empresa-lider-en-la-venta-de-jamon-iberico-estrena-web\/#webpage"},"articleSection":"Canal Empresas","dateline":"Publicado el octubre 2, 2017."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/enrique-tomas-empresa-lider-en-la-venta-de-jamon-iberico-estrena-web\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/enrique-tomas-empresa-lider-en-la-venta-de-jamon-iberico-estrena-web\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/enrique-tomas-empresa-lider-en-la-venta-de-jamon-iberico-estrena-web\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/enrique-tomas-empresa-lider-en-la-venta-de-jamon-iberico-estrena-web\/#webpage","url":"https:\/\/candas365.es\/noticias\/enrique-tomas-empresa-lider-en-la-venta-de-jamon-iberico-estrena-web\/","name":"Enrique Tom\u00e1s, empresa l\u00edder en la venta de jam\u00f3n ib\u00e9rico estrena web | Cand\u00e1s 365","description":"El mejor portal de venta de jam\u00f3n ib\u00e9rico est\u00e1 dise\u00f1ado en 3 idiomas (castellano, ingl\u00e9s y franc\u00e9s) y en las pr\u00f3ximas semanas incluir\u00e1 las versiones alemana e italiana. La expansi\u00f3n internacional de la empresa a nivel de tiendas tambi\u00e9n se est\u00e1 realizando paralelamente a nivel online El nuevo eCommerce mejora la experiencia de compra, el","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/enrique-tomas-empresa-lider-en-la-venta-de-jamon-iberico-estrena-web\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/10\/1506938906_Tienda_online_comprar_jamon_iberico_001.jpg","@id":"https:\/\/candas365.es\/noticias\/enrique-tomas-empresa-lider-en-la-venta-de-jamon-iberico-estrena-web\/#mainImage","width":1920,"height":1279},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/enrique-tomas-empresa-lider-en-la-venta-de-jamon-iberico-estrena-web\/#mainImage"},"datePublished":"2017-10-02T21:39:19+02:00","dateModified":"2017-10-02T21:39:19+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Enrique Tom\u00e1s, empresa l\u00edder en la venta de jam\u00f3n ib\u00e9rico estrena web | Cand\u00e1s 365","og:description":"El mejor portal de venta de jam\u00f3n ib\u00e9rico est\u00e1 dise\u00f1ado en 3 idiomas (castellano, ingl\u00e9s y franc\u00e9s) y en las pr\u00f3ximas semanas incluir\u00e1 las versiones alemana e italiana. La expansi\u00f3n internacional de la empresa a nivel de tiendas tambi\u00e9n se est\u00e1 realizando paralelamente a nivel online El nuevo eCommerce mejora la experiencia de compra, el","og:url":"https:\/\/candas365.es\/noticias\/enrique-tomas-empresa-lider-en-la-venta-de-jamon-iberico-estrena-web\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/10\/1506938906_Tienda_online_comprar_jamon_iberico_001.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/10\/1506938906_Tienda_online_comprar_jamon_iberico_001.jpg","og:image:width":1920,"og:image:height":1279,"article:published_time":"2017-10-02T21:39:19+00:00","article:modified_time":"2017-10-02T21:39:19+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Enrique Tom\u00e1s, empresa l\u00edder en la venta de jam\u00f3n ib\u00e9rico estrena web | Cand\u00e1s 365","twitter:description":"El mejor portal de venta de jam\u00f3n ib\u00e9rico est\u00e1 dise\u00f1ado en 3 idiomas (castellano, ingl\u00e9s y franc\u00e9s) y en las pr\u00f3ximas semanas incluir\u00e1 las versiones alemana e italiana. La expansi\u00f3n internacional de la empresa a nivel de tiendas tambi\u00e9n se est\u00e1 realizando paralelamente a nivel online El nuevo eCommerce mejora la experiencia de compra, el","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/10\/1506938906_Tienda_online_comprar_jamon_iberico_001.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"81357","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-26 01:44:44","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 12:42:55","updated":"2025-08-26 01:44:44"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/\" title=\"Canal Empresas\">Canal Empresas<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tEnrique Tom\u00e1s, empresa l\u00edder en la venta de jam\u00f3n ib\u00e9rico estrena web\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Canal Empresas","link":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/"},{"label":"Enrique Tom\u00e1s, empresa l\u00edder en la venta de jam\u00f3n ib\u00e9rico estrena web","link":"https:\/\/candas365.es\/noticias\/enrique-tomas-empresa-lider-en-la-venta-de-jamon-iberico-estrena-web\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/81357","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=81357"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/81357\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/81358"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=81357"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=81357"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=81357"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}