{"id":80693,"date":"2017-09-25T20:48:26","date_gmt":"2017-09-25T20:48:26","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=80693"},"modified":"2017-09-25T20:48:26","modified_gmt":"2017-09-25T20:48:26","slug":"el-centro-europeo-de-empresas-e-innovacion-del-principado-de-asturias-convoca-sus-premios-anuales","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/el-centro-europeo-de-empresas-e-innovacion-del-principado-de-asturias-convoca-sus-premios-anuales\/","title":{"rendered":"El Centro Europeo de Empresas e Innovaci\u00f3n del Principado de Asturias convoca sus premios anuales"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-80694\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/09\/premios-ceei-360x289.jpg\" alt=\"\" width=\"360\" height=\"289\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/09\/premios-ceei-360x289.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/09\/premios-ceei-768x617.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/09\/premios-ceei-598x480.jpg 598w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/09\/premios-ceei-696x559.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/09\/premios-ceei-1068x858.jpg 1068w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/09\/premios-ceei-523x420.jpg 523w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/09\/premios-ceei.jpg 1280w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>El Centro Europeo de Empresas e Innovaci\u00f3n del Principado de Asturias (CEEI) convoca sus premios anuales, con los que distingue las iniciativas de transferencia de conocimiento al mercado en forma de nuevos productos y servicios, ya sea a trav\u00e9s de la creaci\u00f3n de compa\u00f1\u00edas de base tecnol\u00f3gica o de la protecci\u00f3n de resultados de investigaci\u00f3n por parte de pymes y emprendedores.<\/p>\n<p>La convocatoria se realiza a trav\u00e9s de dos modalidades: el XII Premio al Mejor Proyecto Empresarial de Base Tecnol\u00f3gica y el XI Concurso de Patentes y Modelos de Utilidad de Asturias. El plazo de presentaci\u00f3n de candidaturas finaliza el 11 de octubre.<\/p>\n<p>El consejero de Empleo, Industria y Turismo, Isaac Pola, ha presentado hoy la nueva convocatoria de los premios, patrocinados por el Instituto de Desarrollo Econ\u00f3mico del Principado (Idepa), el Banco Sabadell, Caja Rural, La Caixa, Liberbank, Abanca, la Fundaci\u00f3n Prodintec y la empresa Garrigues.<\/p>\n<p>Estos galardones constituyen una de las iniciativas m\u00e1s consolidadas en la cartera de servicios del CEEI, han recibido m\u00e1s de 230 candidaturas y han permitido repartir 195.000 euros desde su primera edici\u00f3n.<\/p>\n<p><strong>XII Premio al Mejor Proyecto Empresarial de Base Tecnol\u00f3gica<\/strong><\/p>\n<p>Este premio, dotado con 10.000 euros, pretende potenciar la aparici\u00f3n y apoyar la maduraci\u00f3n y puesta en marcha de los mejores proyectos de firmas de base tecnol\u00f3gica (EBTs), con el fin de que Asturias desarrolle un nuevo tejido empresarial con mayor valor a\u00f1adido y empleo cualificado. Est\u00e1 dirigido a personas f\u00edsicas o jur\u00eddicas que hayan concebido un proyecto empresarial innovador as\u00ed como a EBTs ya constituidas, siempre que no se hayan puesto en marcha antes del 1 de septiembre de 2016 y tengan domicilio social o centro de trabajo en el Principado.<\/p>\n<p><strong>XI Concurso de Patentes y Modelos de Utilidad de Asturias<\/strong><\/p>\n<p>Esta convocatoria premia iniciativas de protecci\u00f3n de resultados de investigaci\u00f3n mediante patentes de invenci\u00f3n y modelos de utilidad, en la medida en que sirvan de elementos tractores y contribuyan al desarrollo de nuevas iniciativas empresariales. A este concurso pueden acceder los titulares de una solicitud de patente o modelo de utilidad concedido. El galard\u00f3n est\u00e1 valorado en 5.000 euros.<\/p>\n<p><strong>Centro de empresas<\/strong><\/p>\n<p>El CEEI es el instrumento de apoyo al emprendizaje innovador m\u00e1s potente del Gobierno de Asturias. Su trabajo y actividades se basan en un modelo de inspiraci\u00f3n europea y est\u00e1 apoyado a trav\u00e9s del Idepa. Desarrolla m\u00faltiples actividades en captaci\u00f3n, apoyo a la creaci\u00f3n, aceleraci\u00f3n y crecimiento de proyectos altamente innovadores y especialmente de base tecnol\u00f3gica.<\/p>\n<p>Desde el a\u00f1o 2000, ha apoyado la puesta en marcha de 332 empresas altamente innovadoras. Actualmente, el n\u00famero de EBTs que se crean anualmente ronda ya la quincena.<\/p>\n<p>En el caso de proyectos de base tecnol\u00f3gica, el centro ha apoyado ya a 131 nuevas empresas, de las que siguen en marcha un 77%, lo que representa un \u00edndice de supervivencia muy superior a la media nacional, con porcentajes que mejoran hasta en 25 puntos la supervivencia de compa\u00f1\u00edas sin este sesgo innovador.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Centro Europeo de Empresas e Innovaci\u00f3n del Principado de Asturias (CEEI) convoca sus premios anuales, con los que distingue las iniciativas de transferencia de conocimiento al mercado en forma de nuevos productos y servicios, ya sea a trav\u00e9s de la creaci\u00f3n de compa\u00f1\u00edas de base tecnol\u00f3gica o de la protecci\u00f3n de resultados de investigaci\u00f3n<\/p>\n","protected":false},"author":1,"featured_media":80694,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[151],"tags":[],"class_list":{"0":"post-80693","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-canal-empresas"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7 - aioseo.com -->\n\t<meta name=\"description\" content=\"El Centro Europeo de Empresas e Innovaci\u00f3n del Principado de Asturias (CEEI) convoca sus premios anuales, con los que distingue las iniciativas de transferencia de conocimiento al mercado en forma de nuevos productos y servicios, ya sea a trav\u00e9s de la creaci\u00f3n de compa\u00f1\u00edas de base tecnol\u00f3gica o de la protecci\u00f3n de resultados de investigaci\u00f3n\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"canal empresas\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/el-centro-europeo-de-empresas-e-innovacion-del-principado-de-asturias-convoca-sus-premios-anuales\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El Centro Europeo de Empresas e Innovaci\u00f3n del Principado de Asturias convoca sus premios anuales | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"El Centro Europeo de Empresas e Innovaci\u00f3n del Principado de Asturias (CEEI) convoca sus premios anuales, con los que distingue las iniciativas de transferencia de conocimiento al mercado en forma de nuevos productos y servicios, ya sea a trav\u00e9s de la creaci\u00f3n de compa\u00f1\u00edas de base tecnol\u00f3gica o de la protecci\u00f3n de resultados de investigaci\u00f3n\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/el-centro-europeo-de-empresas-e-innovacion-del-principado-de-asturias-convoca-sus-premios-anuales\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/09\/premios-ceei.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/09\/premios-ceei.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1028\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2017-09-25T20:48:26+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2017-09-25T20:48:26+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El Centro Europeo de Empresas e Innovaci\u00f3n del Principado de Asturias convoca sus premios anuales | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El Centro Europeo de Empresas e Innovaci\u00f3n del Principado de Asturias (CEEI) convoca sus premios anuales, con los que distingue las iniciativas de transferencia de conocimiento al mercado en forma de nuevos productos y servicios, ya sea a trav\u00e9s de la creaci\u00f3n de compa\u00f1\u00edas de base tecnol\u00f3gica o de la protecci\u00f3n de resultados de investigaci\u00f3n\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/09\/premios-ceei.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-centro-europeo-de-empresas-e-innovacion-del-principado-de-asturias-convoca-sus-premios-anuales\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"name\":\"Canal Empresas\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"position\":2,\"name\":\"Canal Empresas\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-centro-europeo-de-empresas-e-innovacion-del-principado-de-asturias-convoca-sus-premios-anuales\\\/#listItem\",\"name\":\"El Centro Europeo de Empresas e Innovaci\\u00f3n del Principado de Asturias convoca sus premios anuales\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-centro-europeo-de-empresas-e-innovacion-del-principado-de-asturias-convoca-sus-premios-anuales\\\/#listItem\",\"position\":3,\"name\":\"El Centro Europeo de Empresas e Innovaci\\u00f3n del Principado de Asturias convoca sus premios anuales\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"name\":\"Canal Empresas\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-centro-europeo-de-empresas-e-innovacion-del-principado-de-asturias-convoca-sus-premios-anuales\\\/#newsarticle\",\"name\":\"El Centro Europeo de Empresas e Innovaci\\u00f3n del Principado de Asturias convoca sus premios anuales | Cand\\u00e1s 365\",\"headline\":\"El Centro Europeo de Empresas e Innovaci\\u00f3n del Principado de Asturias convoca sus premios anuales\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/premios-ceei.jpg\",\"width\":1280,\"height\":1028},\"datePublished\":\"2017-09-25T20:48:26+02:00\",\"dateModified\":\"2017-09-25T20:48:26+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-centro-europeo-de-empresas-e-innovacion-del-principado-de-asturias-convoca-sus-premios-anuales\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-centro-europeo-de-empresas-e-innovacion-del-principado-de-asturias-convoca-sus-premios-anuales\\\/#webpage\"},\"articleSection\":\"Canal Empresas\",\"dateline\":\"Publicado el septiembre 25, 2017.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-centro-europeo-de-empresas-e-innovacion-del-principado-de-asturias-convoca-sus-premios-anuales\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-centro-europeo-de-empresas-e-innovacion-del-principado-de-asturias-convoca-sus-premios-anuales\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-centro-europeo-de-empresas-e-innovacion-del-principado-de-asturias-convoca-sus-premios-anuales\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-centro-europeo-de-empresas-e-innovacion-del-principado-de-asturias-convoca-sus-premios-anuales\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-centro-europeo-de-empresas-e-innovacion-del-principado-de-asturias-convoca-sus-premios-anuales\\\/\",\"name\":\"El Centro Europeo de Empresas e Innovaci\\u00f3n del Principado de Asturias convoca sus premios anuales | Cand\\u00e1s 365\",\"description\":\"El Centro Europeo de Empresas e Innovaci\\u00f3n del Principado de Asturias (CEEI) convoca sus premios anuales, con los que distingue las iniciativas de transferencia de conocimiento al mercado en forma de nuevos productos y servicios, ya sea a trav\\u00e9s de la creaci\\u00f3n de compa\\u00f1\\u00edas de base tecnol\\u00f3gica o de la protecci\\u00f3n de resultados de investigaci\\u00f3n\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-centro-europeo-de-empresas-e-innovacion-del-principado-de-asturias-convoca-sus-premios-anuales\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/premios-ceei.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-centro-europeo-de-empresas-e-innovacion-del-principado-de-asturias-convoca-sus-premios-anuales\\\/#mainImage\",\"width\":1280,\"height\":1028},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-centro-europeo-de-empresas-e-innovacion-del-principado-de-asturias-convoca-sus-premios-anuales\\\/#mainImage\"},\"datePublished\":\"2017-09-25T20:48:26+02:00\",\"dateModified\":\"2017-09-25T20:48:26+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>El Centro Europeo de Empresas e Innovaci\u00f3n del Principado de Asturias convoca sus premios anuales | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"El Centro Europeo de Empresas e Innovaci\u00f3n del Principado de Asturias convoca sus premios anuales | Cand\u00e1s 365","description":"El Centro Europeo de Empresas e Innovaci\u00f3n del Principado de Asturias (CEEI) convoca sus premios anuales, con los que distingue las iniciativas de transferencia de conocimiento al mercado en forma de nuevos productos y servicios, ya sea a trav\u00e9s de la creaci\u00f3n de compa\u00f1\u00edas de base tecnol\u00f3gica o de la protecci\u00f3n de resultados de investigaci\u00f3n","canonical_url":"https:\/\/candas365.es\/noticias\/el-centro-europeo-de-empresas-e-innovacion-del-principado-de-asturias-convoca-sus-premios-anuales\/","robots":"max-image-preview:large","keywords":"canal empresas","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/el-centro-europeo-de-empresas-e-innovacion-del-principado-de-asturias-convoca-sus-premios-anuales\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","name":"Canal Empresas"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","position":2,"name":"Canal Empresas","item":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/el-centro-europeo-de-empresas-e-innovacion-del-principado-de-asturias-convoca-sus-premios-anuales\/#listItem","name":"El Centro Europeo de Empresas e Innovaci\u00f3n del Principado de Asturias convoca sus premios anuales"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/el-centro-europeo-de-empresas-e-innovacion-del-principado-de-asturias-convoca-sus-premios-anuales\/#listItem","position":3,"name":"El Centro Europeo de Empresas e Innovaci\u00f3n del Principado de Asturias convoca sus premios anuales","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","name":"Canal Empresas"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/el-centro-europeo-de-empresas-e-innovacion-del-principado-de-asturias-convoca-sus-premios-anuales\/#newsarticle","name":"El Centro Europeo de Empresas e Innovaci\u00f3n del Principado de Asturias convoca sus premios anuales | Cand\u00e1s 365","headline":"El Centro Europeo de Empresas e Innovaci\u00f3n del Principado de Asturias convoca sus premios anuales","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/09\/premios-ceei.jpg","width":1280,"height":1028},"datePublished":"2017-09-25T20:48:26+02:00","dateModified":"2017-09-25T20:48:26+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/el-centro-europeo-de-empresas-e-innovacion-del-principado-de-asturias-convoca-sus-premios-anuales\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/el-centro-europeo-de-empresas-e-innovacion-del-principado-de-asturias-convoca-sus-premios-anuales\/#webpage"},"articleSection":"Canal Empresas","dateline":"Publicado el septiembre 25, 2017."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/el-centro-europeo-de-empresas-e-innovacion-del-principado-de-asturias-convoca-sus-premios-anuales\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/el-centro-europeo-de-empresas-e-innovacion-del-principado-de-asturias-convoca-sus-premios-anuales\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/el-centro-europeo-de-empresas-e-innovacion-del-principado-de-asturias-convoca-sus-premios-anuales\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/el-centro-europeo-de-empresas-e-innovacion-del-principado-de-asturias-convoca-sus-premios-anuales\/#webpage","url":"https:\/\/candas365.es\/noticias\/el-centro-europeo-de-empresas-e-innovacion-del-principado-de-asturias-convoca-sus-premios-anuales\/","name":"El Centro Europeo de Empresas e Innovaci\u00f3n del Principado de Asturias convoca sus premios anuales | Cand\u00e1s 365","description":"El Centro Europeo de Empresas e Innovaci\u00f3n del Principado de Asturias (CEEI) convoca sus premios anuales, con los que distingue las iniciativas de transferencia de conocimiento al mercado en forma de nuevos productos y servicios, ya sea a trav\u00e9s de la creaci\u00f3n de compa\u00f1\u00edas de base tecnol\u00f3gica o de la protecci\u00f3n de resultados de investigaci\u00f3n","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/el-centro-europeo-de-empresas-e-innovacion-del-principado-de-asturias-convoca-sus-premios-anuales\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/09\/premios-ceei.jpg","@id":"https:\/\/candas365.es\/noticias\/el-centro-europeo-de-empresas-e-innovacion-del-principado-de-asturias-convoca-sus-premios-anuales\/#mainImage","width":1280,"height":1028},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/el-centro-europeo-de-empresas-e-innovacion-del-principado-de-asturias-convoca-sus-premios-anuales\/#mainImage"},"datePublished":"2017-09-25T20:48:26+02:00","dateModified":"2017-09-25T20:48:26+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"El Centro Europeo de Empresas e Innovaci\u00f3n del Principado de Asturias convoca sus premios anuales | Cand\u00e1s 365","og:description":"El Centro Europeo de Empresas e Innovaci\u00f3n del Principado de Asturias (CEEI) convoca sus premios anuales, con los que distingue las iniciativas de transferencia de conocimiento al mercado en forma de nuevos productos y servicios, ya sea a trav\u00e9s de la creaci\u00f3n de compa\u00f1\u00edas de base tecnol\u00f3gica o de la protecci\u00f3n de resultados de investigaci\u00f3n","og:url":"https:\/\/candas365.es\/noticias\/el-centro-europeo-de-empresas-e-innovacion-del-principado-de-asturias-convoca-sus-premios-anuales\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/09\/premios-ceei.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/09\/premios-ceei.jpg","og:image:width":1280,"og:image:height":1028,"article:published_time":"2017-09-25T20:48:26+00:00","article:modified_time":"2017-09-25T20:48:26+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"El Centro Europeo de Empresas e Innovaci\u00f3n del Principado de Asturias convoca sus premios anuales | Cand\u00e1s 365","twitter:description":"El Centro Europeo de Empresas e Innovaci\u00f3n del Principado de Asturias (CEEI) convoca sus premios anuales, con los que distingue las iniciativas de transferencia de conocimiento al mercado en forma de nuevos productos y servicios, ya sea a trav\u00e9s de la creaci\u00f3n de compa\u00f1\u00edas de base tecnol\u00f3gica o de la protecci\u00f3n de resultados de investigaci\u00f3n","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/09\/premios-ceei.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"3 minutos"},"aioseo_meta_data":{"post_id":"80693","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-26 00:49:18","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 12:45:56","updated":"2025-08-26 00:49:18"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/\" title=\"Canal Empresas\">Canal Empresas<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tEl Centro Europeo de Empresas e Innovaci\u00f3n del Principado de Asturias convoca sus premios anuales\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Canal Empresas","link":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/"},{"label":"El Centro Europeo de Empresas e Innovaci\u00f3n del Principado de Asturias convoca sus premios anuales","link":"https:\/\/candas365.es\/noticias\/el-centro-europeo-de-empresas-e-innovacion-del-principado-de-asturias-convoca-sus-premios-anuales\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/80693","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=80693"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/80693\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/80694"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=80693"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=80693"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=80693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}