{"id":79137,"date":"2017-09-07T17:20:31","date_gmt":"2017-09-07T17:20:31","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=79137"},"modified":"2017-09-07T17:20:31","modified_gmt":"2017-09-07T17:20:31","slug":"industria-de-la-construccion-alemana-preve-mas-viviendas-para-2017","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/industria-de-la-construccion-alemana-preve-mas-viviendas-para-2017\/","title":{"rendered":"Industria de la construcci\u00f3n alemana prev\u00e9 m\u00e1s viviendas para 2017"},"content":{"rendered":"<p>(dpa) &#8211; La industria de la construcci\u00f3n en Alemania estima para 2017 un notable crecimiento del n\u00famero de viviendas listas para ser habitadas. La federaci\u00f3n de la industria de la construcci\u00f3n alemana prev\u00e9 que en el presente a\u00f1o ser\u00e1n entregadas unas 320.000 viviendas, se\u00f1al\u00f3 un portavoz de la entidad a dpa. Esta cifra incluye tanto viviendas a estrenar as\u00ed como apartamentos remodelados en edificios ya existentes.<\/p>\n<p>Seg\u00fan datos de la Oficina Federal de Estad\u00edsticas, en 2016 fueron terminadas un total de 278.000 unidades en todo el pa\u00eds. La federaci\u00f3n del ramo de la construcci\u00f3n registr\u00f3 un r\u00e9cord en el primer semestre de 2017, con un aumento de la facturaci\u00f3n de casi diez por ciento en comparaci\u00f3n con el mismo per\u00edodo del a\u00f1o anterior. Tambi\u00e9n el n\u00famero de pedidos subi\u00f3 en un cinco por ciento.<\/p>\n<p>El auge de la construcci\u00f3n impulsa adem\u00e1s la demanda de arena y grava. Seg\u00fan la Oficina Federal de Ciencias Geol\u00f3gicas y Materias Primas, este grupo de materiales es el m\u00e1s extra\u00eddo en Alemania en cuanto a volumen. Cada a\u00f1o son procesados en las obras unos 239 millones de toneladas de grava y arena. Ambas materias primas son elementos b\u00e1sicos para producir hormig\u00f3n.<\/p>\n<p>La arena y la grava de origen alem\u00e1n provienen de unas 2.000 canteras. Solo un peque\u00f1o porcentaje de la arena extra\u00edda en Alemania es de origen marino. Seg\u00fan el ge\u00f3logo Kay-Christian Emeis, del Instituto Helmholtz de Investigaci\u00f3n de Material y Costas en las cercan\u00edas de Hamburgo, en Alemania la arena del mar es usada casi exclusivamente para reforzar las zonas costeras, por ejemplo para evitar que se desmorone el acantilado de la isla de Sylt, en el mar del Norte, o para aumentar el volumen de arena de las playas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(dpa) &#8211; La industria de la construcci\u00f3n en Alemania estima para 2017 un notable crecimiento del n\u00famero de viviendas listas para ser habitadas. La federaci\u00f3n de la industria de la construcci\u00f3n alemana prev\u00e9 que en el presente a\u00f1o ser\u00e1n entregadas unas 320.000 viviendas, se\u00f1al\u00f3 un portavoz de la entidad a dpa. Esta cifra incluye tanto<\/p>\n","protected":false},"author":1,"featured_media":8123,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[151],"tags":[],"class_list":{"0":"post-79137","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-canal-empresas"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7 - aioseo.com -->\n\t<meta name=\"description\" content=\"(dpa) - La industria de la construcci\u00f3n en Alemania estima para 2017 un notable crecimiento del n\u00famero de viviendas listas para ser habitadas. La federaci\u00f3n de la industria de la construcci\u00f3n alemana prev\u00e9 que en el presente a\u00f1o ser\u00e1n entregadas unas 320.000 viviendas, se\u00f1al\u00f3 un portavoz de la entidad a dpa. Esta cifra incluye tanto\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"canal empresas\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/industria-de-la-construccion-alemana-preve-mas-viviendas-para-2017\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Industria de la construcci\u00f3n alemana prev\u00e9 m\u00e1s viviendas para 2017 | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"(dpa) - La industria de la construcci\u00f3n en Alemania estima para 2017 un notable crecimiento del n\u00famero de viviendas listas para ser habitadas. La federaci\u00f3n de la industria de la construcci\u00f3n alemana prev\u00e9 que en el presente a\u00f1o ser\u00e1n entregadas unas 320.000 viviendas, se\u00f1al\u00f3 un portavoz de la entidad a dpa. Esta cifra incluye tanto\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/industria-de-la-construccion-alemana-preve-mas-viviendas-para-2017\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/03\/euros.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/03\/euros.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"360\" \/>\n\t\t<meta property=\"og:image:height\" content=\"235\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2017-09-07T17:20:31+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2017-09-07T17:20:31+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Industria de la construcci\u00f3n alemana prev\u00e9 m\u00e1s viviendas para 2017 | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"(dpa) - La industria de la construcci\u00f3n en Alemania estima para 2017 un notable crecimiento del n\u00famero de viviendas listas para ser habitadas. La federaci\u00f3n de la industria de la construcci\u00f3n alemana prev\u00e9 que en el presente a\u00f1o ser\u00e1n entregadas unas 320.000 viviendas, se\u00f1al\u00f3 un portavoz de la entidad a dpa. Esta cifra incluye tanto\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/03\/euros.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/industria-de-la-construccion-alemana-preve-mas-viviendas-para-2017\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"name\":\"Canal Empresas\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"position\":2,\"name\":\"Canal Empresas\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/industria-de-la-construccion-alemana-preve-mas-viviendas-para-2017\\\/#listItem\",\"name\":\"Industria de la construcci\\u00f3n alemana prev\\u00e9 m\\u00e1s viviendas para 2017\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/industria-de-la-construccion-alemana-preve-mas-viviendas-para-2017\\\/#listItem\",\"position\":3,\"name\":\"Industria de la construcci\\u00f3n alemana prev\\u00e9 m\\u00e1s viviendas para 2017\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"name\":\"Canal Empresas\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/industria-de-la-construccion-alemana-preve-mas-viviendas-para-2017\\\/#newsarticle\",\"name\":\"Industria de la construcci\\u00f3n alemana prev\\u00e9 m\\u00e1s viviendas para 2017 | Cand\\u00e1s 365\",\"headline\":\"Industria de la construcci\\u00f3n alemana prev\\u00e9 m\\u00e1s viviendas para 2017\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/euros.jpg\",\"width\":360,\"height\":235},\"datePublished\":\"2017-09-07T17:20:31+02:00\",\"dateModified\":\"2017-09-07T17:20:31+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/industria-de-la-construccion-alemana-preve-mas-viviendas-para-2017\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/industria-de-la-construccion-alemana-preve-mas-viviendas-para-2017\\\/#webpage\"},\"articleSection\":\"Canal Empresas\",\"dateline\":\"Publicado el septiembre 7, 2017.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/industria-de-la-construccion-alemana-preve-mas-viviendas-para-2017\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/industria-de-la-construccion-alemana-preve-mas-viviendas-para-2017\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/industria-de-la-construccion-alemana-preve-mas-viviendas-para-2017\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/industria-de-la-construccion-alemana-preve-mas-viviendas-para-2017\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/industria-de-la-construccion-alemana-preve-mas-viviendas-para-2017\\\/\",\"name\":\"Industria de la construcci\\u00f3n alemana prev\\u00e9 m\\u00e1s viviendas para 2017 | Cand\\u00e1s 365\",\"description\":\"(dpa) - La industria de la construcci\\u00f3n en Alemania estima para 2017 un notable crecimiento del n\\u00famero de viviendas listas para ser habitadas. La federaci\\u00f3n de la industria de la construcci\\u00f3n alemana prev\\u00e9 que en el presente a\\u00f1o ser\\u00e1n entregadas unas 320.000 viviendas, se\\u00f1al\\u00f3 un portavoz de la entidad a dpa. Esta cifra incluye tanto\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/industria-de-la-construccion-alemana-preve-mas-viviendas-para-2017\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/euros.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/industria-de-la-construccion-alemana-preve-mas-viviendas-para-2017\\\/#mainImage\",\"width\":360,\"height\":235},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/industria-de-la-construccion-alemana-preve-mas-viviendas-para-2017\\\/#mainImage\"},\"datePublished\":\"2017-09-07T17:20:31+02:00\",\"dateModified\":\"2017-09-07T17:20:31+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Industria de la construcci\u00f3n alemana prev\u00e9 m\u00e1s viviendas para 2017 | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Industria de la construcci\u00f3n alemana prev\u00e9 m\u00e1s viviendas para 2017 | Cand\u00e1s 365","description":"(dpa) - La industria de la construcci\u00f3n en Alemania estima para 2017 un notable crecimiento del n\u00famero de viviendas listas para ser habitadas. La federaci\u00f3n de la industria de la construcci\u00f3n alemana prev\u00e9 que en el presente a\u00f1o ser\u00e1n entregadas unas 320.000 viviendas, se\u00f1al\u00f3 un portavoz de la entidad a dpa. Esta cifra incluye tanto","canonical_url":"https:\/\/candas365.es\/noticias\/industria-de-la-construccion-alemana-preve-mas-viviendas-para-2017\/","robots":"max-image-preview:large","keywords":"canal empresas","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/industria-de-la-construccion-alemana-preve-mas-viviendas-para-2017\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","name":"Canal Empresas"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","position":2,"name":"Canal Empresas","item":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/industria-de-la-construccion-alemana-preve-mas-viviendas-para-2017\/#listItem","name":"Industria de la construcci\u00f3n alemana prev\u00e9 m\u00e1s viviendas para 2017"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/industria-de-la-construccion-alemana-preve-mas-viviendas-para-2017\/#listItem","position":3,"name":"Industria de la construcci\u00f3n alemana prev\u00e9 m\u00e1s viviendas para 2017","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","name":"Canal Empresas"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/industria-de-la-construccion-alemana-preve-mas-viviendas-para-2017\/#newsarticle","name":"Industria de la construcci\u00f3n alemana prev\u00e9 m\u00e1s viviendas para 2017 | Cand\u00e1s 365","headline":"Industria de la construcci\u00f3n alemana prev\u00e9 m\u00e1s viviendas para 2017","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/03\/euros.jpg","width":360,"height":235},"datePublished":"2017-09-07T17:20:31+02:00","dateModified":"2017-09-07T17:20:31+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/industria-de-la-construccion-alemana-preve-mas-viviendas-para-2017\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/industria-de-la-construccion-alemana-preve-mas-viviendas-para-2017\/#webpage"},"articleSection":"Canal Empresas","dateline":"Publicado el septiembre 7, 2017."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/industria-de-la-construccion-alemana-preve-mas-viviendas-para-2017\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/industria-de-la-construccion-alemana-preve-mas-viviendas-para-2017\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/industria-de-la-construccion-alemana-preve-mas-viviendas-para-2017\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/industria-de-la-construccion-alemana-preve-mas-viviendas-para-2017\/#webpage","url":"https:\/\/candas365.es\/noticias\/industria-de-la-construccion-alemana-preve-mas-viviendas-para-2017\/","name":"Industria de la construcci\u00f3n alemana prev\u00e9 m\u00e1s viviendas para 2017 | Cand\u00e1s 365","description":"(dpa) - La industria de la construcci\u00f3n en Alemania estima para 2017 un notable crecimiento del n\u00famero de viviendas listas para ser habitadas. La federaci\u00f3n de la industria de la construcci\u00f3n alemana prev\u00e9 que en el presente a\u00f1o ser\u00e1n entregadas unas 320.000 viviendas, se\u00f1al\u00f3 un portavoz de la entidad a dpa. Esta cifra incluye tanto","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/industria-de-la-construccion-alemana-preve-mas-viviendas-para-2017\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/03\/euros.jpg","@id":"https:\/\/candas365.es\/noticias\/industria-de-la-construccion-alemana-preve-mas-viviendas-para-2017\/#mainImage","width":360,"height":235},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/industria-de-la-construccion-alemana-preve-mas-viviendas-para-2017\/#mainImage"},"datePublished":"2017-09-07T17:20:31+02:00","dateModified":"2017-09-07T17:20:31+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Industria de la construcci\u00f3n alemana prev\u00e9 m\u00e1s viviendas para 2017 | Cand\u00e1s 365","og:description":"(dpa) - La industria de la construcci\u00f3n en Alemania estima para 2017 un notable crecimiento del n\u00famero de viviendas listas para ser habitadas. La federaci\u00f3n de la industria de la construcci\u00f3n alemana prev\u00e9 que en el presente a\u00f1o ser\u00e1n entregadas unas 320.000 viviendas, se\u00f1al\u00f3 un portavoz de la entidad a dpa. Esta cifra incluye tanto","og:url":"https:\/\/candas365.es\/noticias\/industria-de-la-construccion-alemana-preve-mas-viviendas-para-2017\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/03\/euros.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/03\/euros.jpg","og:image:width":360,"og:image:height":235,"article:published_time":"2017-09-07T17:20:31+00:00","article:modified_time":"2017-09-07T17:20:31+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Industria de la construcci\u00f3n alemana prev\u00e9 m\u00e1s viviendas para 2017 | Cand\u00e1s 365","twitter:description":"(dpa) - La industria de la construcci\u00f3n en Alemania estima para 2017 un notable crecimiento del n\u00famero de viviendas listas para ser habitadas. La federaci\u00f3n de la industria de la construcci\u00f3n alemana prev\u00e9 que en el presente a\u00f1o ser\u00e1n entregadas unas 320.000 viviendas, se\u00f1al\u00f3 un portavoz de la entidad a dpa. Esta cifra incluye tanto","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/03\/euros.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"79137","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-25 22:45:04","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 12:54:01","updated":"2025-08-25 22:45:04"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/\" title=\"Canal Empresas\">Canal Empresas<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tIndustria de la construcci\u00f3n alemana prev\u00e9 m\u00e1s viviendas para 2017\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Canal Empresas","link":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/"},{"label":"Industria de la construcci\u00f3n alemana prev\u00e9 m\u00e1s viviendas para 2017","link":"https:\/\/candas365.es\/noticias\/industria-de-la-construccion-alemana-preve-mas-viviendas-para-2017\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/79137","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=79137"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/79137\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/8123"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=79137"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=79137"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=79137"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}