{"id":78125,"date":"2017-08-23T17:43:23","date_gmt":"2017-08-23T17:43:23","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=78125"},"modified":"2017-08-23T17:43:23","modified_gmt":"2017-08-23T17:43:23","slug":"el-principado-destaca-el-papel-innovador-de-valnalon","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/el-principado-destaca-el-papel-innovador-de-valnalon\/","title":{"rendered":"El Principado destaca el papel innovador de Valnal\u00f3n"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-78126\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/08\/Valnalon-360x195.jpg\" alt=\"\" width=\"360\" height=\"195\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/08\/Valnalon-360x195.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/08\/Valnalon-768x417.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/08\/Valnalon-655x356.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/08\/Valnalon-696x378.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/08\/Valnalon-1068x580.jpg 1068w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/08\/Valnalon-774x420.jpg 774w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/08\/Valnalon.jpg 1280w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>La directora general de Innovaci\u00f3n y Emprendimiento, Ana Concejo, ha destacado hoy el papel innovador de Valnal\u00f3n, as\u00ed como la importancia de los proyectos que ha desarrollado en los \u00faltimos 30 a\u00f1os, una trayectoria que ha convertido a la Ciudad Industrial del Valle del Nal\u00f3n en un modelo de referencia para otras comunidades.<\/p>\n<p>Ana Concejo ha realizado estas declaraciones durante la visita que ha realizado a las instalaciones de La Felguera una delegaci\u00f3n del Cabildo de Tenerife, interesada en conocer los proyectos de educaci\u00f3n y promoci\u00f3n emprendedora que promueve esta entidad, dependiente de la Consejer\u00eda de Empleo, Industria y Turismo. A juicio de la directora general, estos encuentros ponen en valor la labor de Valnal\u00f3n, que se ha exportado a otras autonom\u00edas como ejemplo de buenas pr\u00e1cticas.<\/p>\n<p>Entre los nuevos retos que afronta la Ciudad Industrial figura el de vincular los proyectos emprendedores a la innovaci\u00f3n para promover este concepto entre los m\u00e1s j\u00f3venes.<\/p>\n<p>La delegaci\u00f3n visitante, encabezada por el consejero insular de Empleo tinerfe\u00f1o, Leopoldo Benjumea, y el director insular de Cultura, Educaci\u00f3n y Unidades Art\u00edsticas, Jos\u00e9 Luis Rivero, analizar\u00e1 la posibilidad de trasladar a la isla canaria algunas de las iniciativas que desarrolla Valnal\u00f3n en Asturias.<\/p>\n<p>Con esta visita, se refuerzan las relaciones que la entidad mantiene con la comunidad aut\u00f3noma de Canarias, que se han plasmado en la transferencia de proyectos a la Universidad de La Laguna, el Cabildo de Gran Canaria y la Federaci\u00f3n Canaria de Desarrollo Rural.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La directora general de Innovaci\u00f3n y Emprendimiento, Ana Concejo, ha destacado hoy el papel innovador de Valnal\u00f3n, as\u00ed como la importancia de los proyectos que ha desarrollado en los \u00faltimos 30 a\u00f1os, una trayectoria que ha convertido a la Ciudad Industrial del Valle del Nal\u00f3n en un modelo de referencia para otras comunidades. Ana Concejo<\/p>\n","protected":false},"author":1,"featured_media":78126,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[151],"tags":[],"class_list":{"0":"post-78125","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-canal-empresas"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7 - aioseo.com -->\n\t<meta name=\"description\" content=\"La directora general de Innovaci\u00f3n y Emprendimiento, Ana Concejo, ha destacado hoy el papel innovador de Valnal\u00f3n, as\u00ed como la importancia de los proyectos que ha desarrollado en los \u00faltimos 30 a\u00f1os, una trayectoria que ha convertido a la Ciudad Industrial del Valle del Nal\u00f3n en un modelo de referencia para otras comunidades. Ana Concejo\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"canal empresas\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/el-principado-destaca-el-papel-innovador-de-valnalon\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El Principado destaca el papel innovador de Valnal\u00f3n | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"La directora general de Innovaci\u00f3n y Emprendimiento, Ana Concejo, ha destacado hoy el papel innovador de Valnal\u00f3n, as\u00ed como la importancia de los proyectos que ha desarrollado en los \u00faltimos 30 a\u00f1os, una trayectoria que ha convertido a la Ciudad Industrial del Valle del Nal\u00f3n en un modelo de referencia para otras comunidades. Ana Concejo\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/el-principado-destaca-el-papel-innovador-de-valnalon\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/08\/Valnalon.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/08\/Valnalon.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t\t<meta property=\"og:image:height\" content=\"695\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2017-08-23T17:43:23+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2017-08-23T17:43:23+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El Principado destaca el papel innovador de Valnal\u00f3n | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La directora general de Innovaci\u00f3n y Emprendimiento, Ana Concejo, ha destacado hoy el papel innovador de Valnal\u00f3n, as\u00ed como la importancia de los proyectos que ha desarrollado en los \u00faltimos 30 a\u00f1os, una trayectoria que ha convertido a la Ciudad Industrial del Valle del Nal\u00f3n en un modelo de referencia para otras comunidades. Ana Concejo\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/08\/Valnalon.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-destaca-el-papel-innovador-de-valnalon\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"name\":\"Canal Empresas\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"position\":2,\"name\":\"Canal Empresas\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-destaca-el-papel-innovador-de-valnalon\\\/#listItem\",\"name\":\"El Principado destaca el papel innovador de Valnal\\u00f3n\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-destaca-el-papel-innovador-de-valnalon\\\/#listItem\",\"position\":3,\"name\":\"El Principado destaca el papel innovador de Valnal\\u00f3n\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"name\":\"Canal Empresas\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-destaca-el-papel-innovador-de-valnalon\\\/#newsarticle\",\"name\":\"El Principado destaca el papel innovador de Valnal\\u00f3n | Cand\\u00e1s 365\",\"headline\":\"El Principado destaca el papel innovador de Valnal\\u00f3n\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/Valnalon.jpg\",\"width\":1280,\"height\":695},\"datePublished\":\"2017-08-23T17:43:23+02:00\",\"dateModified\":\"2017-08-23T17:43:23+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-destaca-el-papel-innovador-de-valnalon\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-destaca-el-papel-innovador-de-valnalon\\\/#webpage\"},\"articleSection\":\"Canal Empresas\",\"dateline\":\"Publicado el agosto 23, 2017.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-destaca-el-papel-innovador-de-valnalon\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-destaca-el-papel-innovador-de-valnalon\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-destaca-el-papel-innovador-de-valnalon\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-destaca-el-papel-innovador-de-valnalon\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-destaca-el-papel-innovador-de-valnalon\\\/\",\"name\":\"El Principado destaca el papel innovador de Valnal\\u00f3n | Cand\\u00e1s 365\",\"description\":\"La directora general de Innovaci\\u00f3n y Emprendimiento, Ana Concejo, ha destacado hoy el papel innovador de Valnal\\u00f3n, as\\u00ed como la importancia de los proyectos que ha desarrollado en los \\u00faltimos 30 a\\u00f1os, una trayectoria que ha convertido a la Ciudad Industrial del Valle del Nal\\u00f3n en un modelo de referencia para otras comunidades. Ana Concejo\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-destaca-el-papel-innovador-de-valnalon\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/Valnalon.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-destaca-el-papel-innovador-de-valnalon\\\/#mainImage\",\"width\":1280,\"height\":695},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-destaca-el-papel-innovador-de-valnalon\\\/#mainImage\"},\"datePublished\":\"2017-08-23T17:43:23+02:00\",\"dateModified\":\"2017-08-23T17:43:23+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>El Principado destaca el papel innovador de Valnal\u00f3n | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"El Principado destaca el papel innovador de Valnal\u00f3n | Cand\u00e1s 365","description":"La directora general de Innovaci\u00f3n y Emprendimiento, Ana Concejo, ha destacado hoy el papel innovador de Valnal\u00f3n, as\u00ed como la importancia de los proyectos que ha desarrollado en los \u00faltimos 30 a\u00f1os, una trayectoria que ha convertido a la Ciudad Industrial del Valle del Nal\u00f3n en un modelo de referencia para otras comunidades. Ana Concejo","canonical_url":"https:\/\/candas365.es\/noticias\/el-principado-destaca-el-papel-innovador-de-valnalon\/","robots":"max-image-preview:large","keywords":"canal empresas","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/el-principado-destaca-el-papel-innovador-de-valnalon\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","name":"Canal Empresas"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","position":2,"name":"Canal Empresas","item":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/el-principado-destaca-el-papel-innovador-de-valnalon\/#listItem","name":"El Principado destaca el papel innovador de Valnal\u00f3n"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/el-principado-destaca-el-papel-innovador-de-valnalon\/#listItem","position":3,"name":"El Principado destaca el papel innovador de Valnal\u00f3n","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","name":"Canal Empresas"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/el-principado-destaca-el-papel-innovador-de-valnalon\/#newsarticle","name":"El Principado destaca el papel innovador de Valnal\u00f3n | Cand\u00e1s 365","headline":"El Principado destaca el papel innovador de Valnal\u00f3n","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/08\/Valnalon.jpg","width":1280,"height":695},"datePublished":"2017-08-23T17:43:23+02:00","dateModified":"2017-08-23T17:43:23+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/el-principado-destaca-el-papel-innovador-de-valnalon\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/el-principado-destaca-el-papel-innovador-de-valnalon\/#webpage"},"articleSection":"Canal Empresas","dateline":"Publicado el agosto 23, 2017."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/el-principado-destaca-el-papel-innovador-de-valnalon\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/el-principado-destaca-el-papel-innovador-de-valnalon\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/el-principado-destaca-el-papel-innovador-de-valnalon\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/el-principado-destaca-el-papel-innovador-de-valnalon\/#webpage","url":"https:\/\/candas365.es\/noticias\/el-principado-destaca-el-papel-innovador-de-valnalon\/","name":"El Principado destaca el papel innovador de Valnal\u00f3n | Cand\u00e1s 365","description":"La directora general de Innovaci\u00f3n y Emprendimiento, Ana Concejo, ha destacado hoy el papel innovador de Valnal\u00f3n, as\u00ed como la importancia de los proyectos que ha desarrollado en los \u00faltimos 30 a\u00f1os, una trayectoria que ha convertido a la Ciudad Industrial del Valle del Nal\u00f3n en un modelo de referencia para otras comunidades. Ana Concejo","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/el-principado-destaca-el-papel-innovador-de-valnalon\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/08\/Valnalon.jpg","@id":"https:\/\/candas365.es\/noticias\/el-principado-destaca-el-papel-innovador-de-valnalon\/#mainImage","width":1280,"height":695},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/el-principado-destaca-el-papel-innovador-de-valnalon\/#mainImage"},"datePublished":"2017-08-23T17:43:23+02:00","dateModified":"2017-08-23T17:43:23+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"El Principado destaca el papel innovador de Valnal\u00f3n | Cand\u00e1s 365","og:description":"La directora general de Innovaci\u00f3n y Emprendimiento, Ana Concejo, ha destacado hoy el papel innovador de Valnal\u00f3n, as\u00ed como la importancia de los proyectos que ha desarrollado en los \u00faltimos 30 a\u00f1os, una trayectoria que ha convertido a la Ciudad Industrial del Valle del Nal\u00f3n en un modelo de referencia para otras comunidades. Ana Concejo","og:url":"https:\/\/candas365.es\/noticias\/el-principado-destaca-el-papel-innovador-de-valnalon\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/08\/Valnalon.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/08\/Valnalon.jpg","og:image:width":1280,"og:image:height":695,"article:published_time":"2017-08-23T17:43:23+00:00","article:modified_time":"2017-08-23T17:43:23+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"El Principado destaca el papel innovador de Valnal\u00f3n | Cand\u00e1s 365","twitter:description":"La directora general de Innovaci\u00f3n y Emprendimiento, Ana Concejo, ha destacado hoy el papel innovador de Valnal\u00f3n, as\u00ed como la importancia de los proyectos que ha desarrollado en los \u00faltimos 30 a\u00f1os, una trayectoria que ha convertido a la Ciudad Industrial del Valle del Nal\u00f3n en un modelo de referencia para otras comunidades. Ana Concejo","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/08\/Valnalon.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"1 minuto"},"aioseo_meta_data":{"post_id":"78125","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-25 21:26:12","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 12:54:48","updated":"2025-08-25 21:26:12"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/\" title=\"Canal Empresas\">Canal Empresas<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tEl Principado destaca el papel innovador de Valnal\u00f3n\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Canal Empresas","link":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/"},{"label":"El Principado destaca el papel innovador de Valnal\u00f3n","link":"https:\/\/candas365.es\/noticias\/el-principado-destaca-el-papel-innovador-de-valnalon\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/78125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=78125"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/78125\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/78126"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=78125"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=78125"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=78125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}