{"id":75841,"date":"2017-07-18T00:47:03","date_gmt":"2017-07-18T00:47:03","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=75841"},"modified":"2017-07-18T00:47:03","modified_gmt":"2017-07-18T00:47:03","slug":"ncr-celebra-el-50-aniversario-del-cajero-automatico","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/ncr-celebra-el-50-aniversario-del-cajero-automatico\/","title":{"rendered":"NCR celebra el 50 aniversario del cajero autom\u00e1tico"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-75842\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/07\/1499917696_NCR_CAjero-360x202.jpg\" alt=\"\" width=\"360\" height=\"202\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/07\/1499917696_NCR_CAjero-360x202.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/07\/1499917696_NCR_CAjero-655x368.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/07\/1499917696_NCR_CAjero-499x280.jpg 499w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/07\/1499917696_NCR_CAjero.jpg 660w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Hoy en d\u00eda, el Cajero Autom\u00e1tico es considerado como una conveniencia que antes de su debut en Inglaterra en 1967, se pensaba como inconcebible para el consumidor com\u00fan. Cinco d\u00e9cadas m\u00e1s tarde, el Cajero Autom\u00e1tico en una econom\u00eda conectada tiene interacciones m\u00f3viles, capacidades de v\u00eddeo incrustadas, y el poder de ofrecer experiencias m\u00e1s inteligentes e interactivas. <strong>NCR Corporation <\/strong>(NYSE:NCR), el l\u00edder mundial en soluciones omni-canal, celebra el 50 aniversario del cajero autom\u00e1tico, festeja lo lejos que ha llegado la industria del cajero autom\u00e1tico, y la evoluci\u00f3n de la tecnolog\u00eda que sigue siendo el centro de los esfuerzos de los bancos para reinventar la experiencia minorista y transformar sus sucursales.<\/p>\n<p>\u00abLo que comenz\u00f3 como un simple dispositivo de transacci\u00f3n en efectivo es ahora una plataforma indispensable que ayuda a los bancos a transformar la experiencia de la sucursal y el canal f\u00edsico\u00bb, dijo Bill Nuti, Presidente y CEO de NCR Corporation. \u00abHoy en d\u00eda, gracias a los esfuerzos de NCR y la industria en su conjunto, el Cajero Autom\u00e1tico se ha convertido en un puente, un medio para combinar canales digitales y f\u00edsicos y crear experiencias conectadas para los consumidores, es desde luego, una valiosa herramienta para promover la inclusi\u00f3n financiera y la oportunidad en todo el mundo\u00bb.<\/p>\n<p><strong><em>Aqu\u00ed est\u00e1n s\u00f3lo algunos momentos clave de su larga historia de innovaci\u00f3n:<\/em><\/strong><\/p>\n<p>1967 &#8211; Barclays en Londres instala el primer cajero autom\u00e1tico del mundo el 27 de junio<\/p>\n<p>1969 &#8211; El primer Cajero Autom\u00e1tico de EU hace su debut p\u00fablico en Rockville Centre, N.Y.<\/p>\n<p>1977 &#8211; NCR lanza su primer Cajero Automatico, el Modelo 770, un revolucionario terminal de autoservicio<\/p>\n<p>1980 &#8211; NCR presenta el modelo NCR 1780, su cajero autom\u00e1tico, en Baton Rouge, LA.<\/p>\n<p>1998 &#8211; NCR instala un cajero autom\u00e1tico en la Estaci\u00f3n McMurdo en la Ant\u00e1rtida, el Cajero Autom\u00e1tico m\u00e1s solitario del mundo<\/p>\n<p>2000 &#8211; La instalaci\u00f3n de cajeros autom\u00e1ticos a nivel mundial llega a 1 mill\u00f3n<\/p>\n<p>2014 &#8211; NCR tiene cajeros autom\u00e1ticos en m\u00e1s de 120 pa\u00edses<\/p>\n<p>2015 &#8211; NCR lanza <strong>Kalpana\u2122,<\/strong> una plataforma de software empresarial que mueve el software y las operaciones de Cajeros Autom\u00e1ticos a la nube<\/p>\n<p>2017 &#8211; NCR lanza el <strong>NCR SelfServ 80 Series<\/strong>, un cajero autom\u00e1tico preparado para redefinir la experiencia bancaria<\/p>\n<p>2017 &#8211; El presidente y consejero delegado de NCR, Bill Nuti, recibe el premio Lifetime Global Innovation Award de la Asociaci\u00f3n de la Industria de Cajeros Autom\u00e1ticos en Londres.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy en d\u00eda, el Cajero Autom\u00e1tico es considerado como una conveniencia que antes de su debut en Inglaterra en 1967, se pensaba como inconcebible para el consumidor com\u00fan. Cinco d\u00e9cadas m\u00e1s tarde, el Cajero Autom\u00e1tico en una econom\u00eda conectada tiene interacciones m\u00f3viles, capacidades de v\u00eddeo incrustadas, y el poder de ofrecer experiencias m\u00e1s inteligentes e<\/p>\n","protected":false},"author":1,"featured_media":75842,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[151],"tags":[],"class_list":["post-75841","post","type-post","status-publish","format-standard","has-post-thumbnail","category-canal-empresas"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Hoy en d\u00eda, el Cajero Autom\u00e1tico es considerado como una conveniencia que antes de su debut en Inglaterra en 1967, se pensaba como inconcebible para el consumidor com\u00fan. Cinco d\u00e9cadas m\u00e1s tarde, el Cajero Autom\u00e1tico en una econom\u00eda conectada tiene interacciones m\u00f3viles, capacidades de v\u00eddeo incrustadas, y el poder de ofrecer experiencias m\u00e1s inteligentes e\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"canal empresas\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/ncr-celebra-el-50-aniversario-del-cajero-automatico\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"NCR celebra el 50 aniversario del cajero autom\u00e1tico | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Hoy en d\u00eda, el Cajero Autom\u00e1tico es considerado como una conveniencia que antes de su debut en Inglaterra en 1967, se pensaba como inconcebible para el consumidor com\u00fan. Cinco d\u00e9cadas m\u00e1s tarde, el Cajero Autom\u00e1tico en una econom\u00eda conectada tiene interacciones m\u00f3viles, capacidades de v\u00eddeo incrustadas, y el poder de ofrecer experiencias m\u00e1s inteligentes e\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/ncr-celebra-el-50-aniversario-del-cajero-automatico\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/07\/1499917696_NCR_CAjero.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/07\/1499917696_NCR_CAjero.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"660\" \/>\n\t\t<meta property=\"og:image:height\" content=\"371\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2017-07-18T00:47:03+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2017-07-18T00:47:03+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"NCR celebra el 50 aniversario del cajero autom\u00e1tico | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Hoy en d\u00eda, el Cajero Autom\u00e1tico es considerado como una conveniencia que antes de su debut en Inglaterra en 1967, se pensaba como inconcebible para el consumidor com\u00fan. Cinco d\u00e9cadas m\u00e1s tarde, el Cajero Autom\u00e1tico en una econom\u00eda conectada tiene interacciones m\u00f3viles, capacidades de v\u00eddeo incrustadas, y el poder de ofrecer experiencias m\u00e1s inteligentes e\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/07\/1499917696_NCR_CAjero.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ncr-celebra-el-50-aniversario-del-cajero-automatico\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"name\":\"Canal Empresas\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"position\":2,\"name\":\"Canal Empresas\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ncr-celebra-el-50-aniversario-del-cajero-automatico\\\/#listItem\",\"name\":\"NCR celebra el 50 aniversario del cajero autom\\u00e1tico\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ncr-celebra-el-50-aniversario-del-cajero-automatico\\\/#listItem\",\"position\":3,\"name\":\"NCR celebra el 50 aniversario del cajero autom\\u00e1tico\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"name\":\"Canal Empresas\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ncr-celebra-el-50-aniversario-del-cajero-automatico\\\/#newsarticle\",\"name\":\"NCR celebra el 50 aniversario del cajero autom\\u00e1tico | Cand\\u00e1s 365\",\"headline\":\"NCR celebra el 50 aniversario del cajero autom\\u00e1tico\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/1499917696_NCR_CAjero.jpg\",\"width\":660,\"height\":371},\"datePublished\":\"2017-07-18T00:47:03+02:00\",\"dateModified\":\"2017-07-18T00:47:03+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ncr-celebra-el-50-aniversario-del-cajero-automatico\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ncr-celebra-el-50-aniversario-del-cajero-automatico\\\/#webpage\"},\"articleSection\":\"Canal Empresas\",\"dateline\":\"Publicado el julio 18, 2017.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ncr-celebra-el-50-aniversario-del-cajero-automatico\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ncr-celebra-el-50-aniversario-del-cajero-automatico\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ncr-celebra-el-50-aniversario-del-cajero-automatico\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ncr-celebra-el-50-aniversario-del-cajero-automatico\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ncr-celebra-el-50-aniversario-del-cajero-automatico\\\/\",\"name\":\"NCR celebra el 50 aniversario del cajero autom\\u00e1tico | Cand\\u00e1s 365\",\"description\":\"Hoy en d\\u00eda, el Cajero Autom\\u00e1tico es considerado como una conveniencia que antes de su debut en Inglaterra en 1967, se pensaba como inconcebible para el consumidor com\\u00fan. Cinco d\\u00e9cadas m\\u00e1s tarde, el Cajero Autom\\u00e1tico en una econom\\u00eda conectada tiene interacciones m\\u00f3viles, capacidades de v\\u00eddeo incrustadas, y el poder de ofrecer experiencias m\\u00e1s inteligentes e\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ncr-celebra-el-50-aniversario-del-cajero-automatico\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/1499917696_NCR_CAjero.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ncr-celebra-el-50-aniversario-del-cajero-automatico\\\/#mainImage\",\"width\":660,\"height\":371},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ncr-celebra-el-50-aniversario-del-cajero-automatico\\\/#mainImage\"},\"datePublished\":\"2017-07-18T00:47:03+02:00\",\"dateModified\":\"2017-07-18T00:47:03+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>NCR celebra el 50 aniversario del cajero autom\u00e1tico | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"NCR celebra el 50 aniversario del cajero autom\u00e1tico | Cand\u00e1s 365","description":"Hoy en d\u00eda, el Cajero Autom\u00e1tico es considerado como una conveniencia que antes de su debut en Inglaterra en 1967, se pensaba como inconcebible para el consumidor com\u00fan. Cinco d\u00e9cadas m\u00e1s tarde, el Cajero Autom\u00e1tico en una econom\u00eda conectada tiene interacciones m\u00f3viles, capacidades de v\u00eddeo incrustadas, y el poder de ofrecer experiencias m\u00e1s inteligentes e","canonical_url":"https:\/\/candas365.es\/noticias\/ncr-celebra-el-50-aniversario-del-cajero-automatico\/","robots":"max-image-preview:large","keywords":"canal empresas","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/ncr-celebra-el-50-aniversario-del-cajero-automatico\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","name":"Canal Empresas"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","position":2,"name":"Canal Empresas","item":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/ncr-celebra-el-50-aniversario-del-cajero-automatico\/#listItem","name":"NCR celebra el 50 aniversario del cajero autom\u00e1tico"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/ncr-celebra-el-50-aniversario-del-cajero-automatico\/#listItem","position":3,"name":"NCR celebra el 50 aniversario del cajero autom\u00e1tico","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","name":"Canal Empresas"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/ncr-celebra-el-50-aniversario-del-cajero-automatico\/#newsarticle","name":"NCR celebra el 50 aniversario del cajero autom\u00e1tico | Cand\u00e1s 365","headline":"NCR celebra el 50 aniversario del cajero autom\u00e1tico","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/07\/1499917696_NCR_CAjero.jpg","width":660,"height":371},"datePublished":"2017-07-18T00:47:03+02:00","dateModified":"2017-07-18T00:47:03+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/ncr-celebra-el-50-aniversario-del-cajero-automatico\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/ncr-celebra-el-50-aniversario-del-cajero-automatico\/#webpage"},"articleSection":"Canal Empresas","dateline":"Publicado el julio 18, 2017."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/ncr-celebra-el-50-aniversario-del-cajero-automatico\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/ncr-celebra-el-50-aniversario-del-cajero-automatico\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/ncr-celebra-el-50-aniversario-del-cajero-automatico\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/ncr-celebra-el-50-aniversario-del-cajero-automatico\/#webpage","url":"https:\/\/candas365.es\/noticias\/ncr-celebra-el-50-aniversario-del-cajero-automatico\/","name":"NCR celebra el 50 aniversario del cajero autom\u00e1tico | Cand\u00e1s 365","description":"Hoy en d\u00eda, el Cajero Autom\u00e1tico es considerado como una conveniencia que antes de su debut en Inglaterra en 1967, se pensaba como inconcebible para el consumidor com\u00fan. Cinco d\u00e9cadas m\u00e1s tarde, el Cajero Autom\u00e1tico en una econom\u00eda conectada tiene interacciones m\u00f3viles, capacidades de v\u00eddeo incrustadas, y el poder de ofrecer experiencias m\u00e1s inteligentes e","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/ncr-celebra-el-50-aniversario-del-cajero-automatico\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/07\/1499917696_NCR_CAjero.jpg","@id":"https:\/\/candas365.es\/noticias\/ncr-celebra-el-50-aniversario-del-cajero-automatico\/#mainImage","width":660,"height":371},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/ncr-celebra-el-50-aniversario-del-cajero-automatico\/#mainImage"},"datePublished":"2017-07-18T00:47:03+02:00","dateModified":"2017-07-18T00:47:03+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"NCR celebra el 50 aniversario del cajero autom\u00e1tico | Cand\u00e1s 365","og:description":"Hoy en d\u00eda, el Cajero Autom\u00e1tico es considerado como una conveniencia que antes de su debut en Inglaterra en 1967, se pensaba como inconcebible para el consumidor com\u00fan. Cinco d\u00e9cadas m\u00e1s tarde, el Cajero Autom\u00e1tico en una econom\u00eda conectada tiene interacciones m\u00f3viles, capacidades de v\u00eddeo incrustadas, y el poder de ofrecer experiencias m\u00e1s inteligentes e","og:url":"https:\/\/candas365.es\/noticias\/ncr-celebra-el-50-aniversario-del-cajero-automatico\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/07\/1499917696_NCR_CAjero.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/07\/1499917696_NCR_CAjero.jpg","og:image:width":660,"og:image:height":371,"article:published_time":"2017-07-18T00:47:03+00:00","article:modified_time":"2017-07-18T00:47:03+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"NCR celebra el 50 aniversario del cajero autom\u00e1tico | Cand\u00e1s 365","twitter:description":"Hoy en d\u00eda, el Cajero Autom\u00e1tico es considerado como una conveniencia que antes de su debut en Inglaterra en 1967, se pensaba como inconcebible para el consumidor com\u00fan. Cinco d\u00e9cadas m\u00e1s tarde, el Cajero Autom\u00e1tico en una econom\u00eda conectada tiene interacciones m\u00f3viles, capacidades de v\u00eddeo incrustadas, y el poder de ofrecer experiencias m\u00e1s inteligentes e","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/07\/1499917696_NCR_CAjero.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"75841","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-18 12:11:21","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 12:56:31","updated":"2026-05-18 12:11:21"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/\" title=\"Canal Empresas\">Canal Empresas<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tNCR celebra el 50 aniversario del cajero autom\u00e1tico\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Canal Empresas","link":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/"},{"label":"NCR celebra el 50 aniversario del cajero autom\u00e1tico","link":"https:\/\/candas365.es\/noticias\/ncr-celebra-el-50-aniversario-del-cajero-automatico\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/75841","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=75841"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/75841\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/75842"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=75841"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=75841"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=75841"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}