{"id":75618,"date":"2017-07-13T14:52:19","date_gmt":"2017-07-13T14:52:19","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=75618"},"modified":"2017-07-13T14:52:19","modified_gmt":"2017-07-13T14:52:19","slug":"secura-duplica-resultados-respecto-al-mismo-trimestre-de-2016","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/secura-duplica-resultados-respecto-al-mismo-trimestre-de-2016\/","title":{"rendered":"Secura duplica resultados respecto al mismo trimestre de 2016"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-75619\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/07\/1499850049_Crecimiento_Securapq-360x225.jpg\" alt=\"\" width=\"360\" height=\"225\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/07\/1499850049_Crecimiento_Securapq-360x225.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/07\/1499850049_Crecimiento_Securapq-655x410.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/07\/1499850049_Crecimiento_Securapq-696x435.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/07\/1499850049_Crecimiento_Securapq-672x420.jpg 672w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/07\/1499850049_Crecimiento_Securapq-279x173.jpg 279w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/07\/1499850049_Crecimiento_Securapq.jpg 710w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>El mundo de la seguridad premia a la estrategia de especializaci\u00f3n, saber hacer y magia del equipo de Secura, (www.secura.es), integrador especialista en ciberseguridad, que cierra un segundo trimestre redondo en el que duplica su facturaci\u00f3n respecto al mismo per\u00edodo del a\u00f1o anterior. Sin duda un merecido premio y gran satisfacci\u00f3n pero tambi\u00e9n mucha responsabilidad, no en vano grandes consultoras y empresas del IBEX-35 conf\u00edan en sus servicios.<\/p>\n<p>\u201cDuplicar resultados da un poco de v\u00e9rtigo, pero mucho orgullo\u2026 estos resultados son el fruto de a\u00f1os de trabajo, alta especializaci\u00f3n, dedicaci\u00f3n, orientaci\u00f3n al cliente y buen hacer. Gozamos de una amplia cartera de clientes, entre los que se encuentran cuatro firmas del IBEX-35, muy satisfechos y con un 100% de fidelizaci\u00f3n. En Secura, llevamos muchos a\u00f1os de crecimiento continuado, incluso en los a\u00f1os fuertes de crisis y ahora firmamos estas cifras r\u00e9cord, lo que pone de manifiesto que nuestra estrategia unida a la estela de marcado crecimiento del mercado, es garant\u00eda de \u00e9xito.\u201d afirma Arantxa Calvo Moyano, Account Manager de Secura. \u201cCon un panorama inestable por el aumento exponencial de ataques, cada vez son m\u00e1s las empresas que toman conciencia de la necesidad real de protecci\u00f3n e invierten proactivamente contra amenazas tanto conocidas como desconocidas y forman a su personal en este \u00e1rea. Seg\u00fan datos de IDC el gasto mundial en seguridad aument\u00f3 un 8,2% respecto 2016 y se acelerar\u00e1 durante los pr\u00f3ximos a\u00f1os. La seguridad se convierte en un TODO vital para la supervivencia de las empresas y est\u00e1n concienciadas que deben pagar por ello, lo que se traduce en m\u00e1s negocio para el canal.\u201d matiza Calvo.<\/p>\n<p>Y es que la seguridad es un desaf\u00edo en el que no se puede proteger todo por igual, es necesario herramientas dedicadas, algo que desde Secura tienen muy claro y es otro de sus factores de \u00e9xito: \u201cEn nuestra clara apuesta por la especializaci\u00f3n seguimos trabajando con fabricantes de nicho, que abordan distintas \u00e1reas de seguridad, con soluciones innovadoras y punteras, l\u00edderes en el cuadrante Gartner y t\u00e9cnicamente robustas como Palo Alto, Stormshield o ForeScout, firma con la que llevamos 7 a\u00f1os cosechando \u00e9xitos, siendo Secura el \u00fanico integrador espa\u00f1ol con el m\u00e1ximo grado de certificaci\u00f3n FSCE. Con ellos hemos cerrado grandes proyectos en corporaciones de empaque nacionales e internacionales. Al tiempo, hemos detectado un aumento de inversiones en el \u00e1mbito de la movilidad y en soluciones de seguridad de aplicaciones sobre todo en el sector educativo, realizando exitosos despliegues con Aerohive\u201d expone Arantxa Calvo, Account Manager de Secura.<\/p>\n<p>Para Secura, que se ha ganado un sitio con nombre propio en el canal, la demanda de soluciones de seguridad es una oportunidad, pero para aprovecharla es necesario continuar con su alta especializaci\u00f3n y ofrecer nuevos servicios de valor a sus clientes que, por otro lado, proporcionan importantes ingresos recurrentes m\u00e1s all\u00e1 de la mera venta de hardware. \u201cEsta es la filosof\u00eda con la pusimos en marcha nuestro Security Guardian, un servicio de atenci\u00f3n y seguimiento personalizado, muy valorado por nuestros clientes y que nos ha reportado muchas satisfacciones estos \u00faltimos tres a\u00f1os. Con \u00e9l pretendemos acercarnos a las personas, convirti\u00e9ndonos en su socio estrat\u00e9gico, controlando en todo momento el estado de su seguridad. Nuestras \u00e1reas comercial y t\u00e9cnica trabajan de manera alineada conformando soluciones globales a medida de las necesidades de cada cliente, aumentando su rentabilidad y manteniendo unos niveles de seguridad \u00f3ptimos. Este supone otro de los estandartes de Secura\u201d detalla Arantxa Calvo, Account Manager de Secura.<\/p>\n<p>Finalmente, Secura prev\u00e9 continuar con su exitosa estrategia e imparable crecimiento, especialmente de cara al pr\u00f3ximo a\u00f1o con la entrada en vigor de la normativa GDPR y la necesidad de las empresas al tener que cumplir con esta nueva regulaci\u00f3n europea. \u201dLa nueva normativa impactar\u00e1 de lleno en todas las empresas europeas, independientemente de su tama\u00f1o y sector, exponi\u00e9ndose a graves sanciones si no la cumplen. Es imperativo para ellas aumentar las inversiones en seguridad para proteger TODA la informaci\u00f3n que almacenen est\u00e9 donde est\u00e9. En este proceso Secura es su aliado estrat\u00e9gico\u201d finaliza la Directiva.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El mundo de la seguridad premia a la estrategia de especializaci\u00f3n, saber hacer y magia del equipo de Secura, (www.secura.es), integrador especialista en ciberseguridad, que cierra un segundo trimestre redondo en el que duplica su facturaci\u00f3n respecto al mismo per\u00edodo del a\u00f1o anterior. Sin duda un merecido premio y gran satisfacci\u00f3n pero tambi\u00e9n mucha responsabilidad,<\/p>\n","protected":false},"author":1,"featured_media":75619,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[151],"tags":[],"class_list":["post-75618","post","type-post","status-publish","format-standard","has-post-thumbnail","category-canal-empresas"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"El mundo de la seguridad premia a la estrategia de especializaci\u00f3n, saber hacer y magia del equipo de Secura, (www.secura.es), integrador especialista en ciberseguridad, que cierra un segundo trimestre redondo en el que duplica su facturaci\u00f3n respecto al mismo per\u00edodo del a\u00f1o anterior. Sin duda un merecido premio y gran satisfacci\u00f3n pero tambi\u00e9n mucha responsabilidad,\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"canal empresas\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/secura-duplica-resultados-respecto-al-mismo-trimestre-de-2016\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Secura duplica resultados respecto al mismo trimestre de 2016 | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"El mundo de la seguridad premia a la estrategia de especializaci\u00f3n, saber hacer y magia del equipo de Secura, (www.secura.es), integrador especialista en ciberseguridad, que cierra un segundo trimestre redondo en el que duplica su facturaci\u00f3n respecto al mismo per\u00edodo del a\u00f1o anterior. Sin duda un merecido premio y gran satisfacci\u00f3n pero tambi\u00e9n mucha responsabilidad,\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/secura-duplica-resultados-respecto-al-mismo-trimestre-de-2016\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/07\/1499850049_Crecimiento_Securapq.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/07\/1499850049_Crecimiento_Securapq.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"710\" \/>\n\t\t<meta property=\"og:image:height\" content=\"444\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2017-07-13T14:52:19+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2017-07-13T14:52:19+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Secura duplica resultados respecto al mismo trimestre de 2016 | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El mundo de la seguridad premia a la estrategia de especializaci\u00f3n, saber hacer y magia del equipo de Secura, (www.secura.es), integrador especialista en ciberseguridad, que cierra un segundo trimestre redondo en el que duplica su facturaci\u00f3n respecto al mismo per\u00edodo del a\u00f1o anterior. Sin duda un merecido premio y gran satisfacci\u00f3n pero tambi\u00e9n mucha responsabilidad,\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/07\/1499850049_Crecimiento_Securapq.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/secura-duplica-resultados-respecto-al-mismo-trimestre-de-2016\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"name\":\"Canal Empresas\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"position\":2,\"name\":\"Canal Empresas\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/secura-duplica-resultados-respecto-al-mismo-trimestre-de-2016\\\/#listItem\",\"name\":\"Secura duplica resultados respecto al mismo trimestre de 2016\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/secura-duplica-resultados-respecto-al-mismo-trimestre-de-2016\\\/#listItem\",\"position\":3,\"name\":\"Secura duplica resultados respecto al mismo trimestre de 2016\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"name\":\"Canal Empresas\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/secura-duplica-resultados-respecto-al-mismo-trimestre-de-2016\\\/#newsarticle\",\"name\":\"Secura duplica resultados respecto al mismo trimestre de 2016 | Cand\\u00e1s 365\",\"headline\":\"Secura duplica resultados respecto al mismo trimestre de 2016\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/1499850049_Crecimiento_Securapq.jpg\",\"width\":710,\"height\":444},\"datePublished\":\"2017-07-13T14:52:19+02:00\",\"dateModified\":\"2017-07-13T14:52:19+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/secura-duplica-resultados-respecto-al-mismo-trimestre-de-2016\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/secura-duplica-resultados-respecto-al-mismo-trimestre-de-2016\\\/#webpage\"},\"articleSection\":\"Canal Empresas\",\"dateline\":\"Publicado el julio 13, 2017.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/secura-duplica-resultados-respecto-al-mismo-trimestre-de-2016\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/secura-duplica-resultados-respecto-al-mismo-trimestre-de-2016\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/secura-duplica-resultados-respecto-al-mismo-trimestre-de-2016\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/secura-duplica-resultados-respecto-al-mismo-trimestre-de-2016\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/secura-duplica-resultados-respecto-al-mismo-trimestre-de-2016\\\/\",\"name\":\"Secura duplica resultados respecto al mismo trimestre de 2016 | Cand\\u00e1s 365\",\"description\":\"El mundo de la seguridad premia a la estrategia de especializaci\\u00f3n, saber hacer y magia del equipo de Secura, (www.secura.es), integrador especialista en ciberseguridad, que cierra un segundo trimestre redondo en el que duplica su facturaci\\u00f3n respecto al mismo per\\u00edodo del a\\u00f1o anterior. Sin duda un merecido premio y gran satisfacci\\u00f3n pero tambi\\u00e9n mucha responsabilidad,\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/secura-duplica-resultados-respecto-al-mismo-trimestre-de-2016\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/1499850049_Crecimiento_Securapq.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/secura-duplica-resultados-respecto-al-mismo-trimestre-de-2016\\\/#mainImage\",\"width\":710,\"height\":444},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/secura-duplica-resultados-respecto-al-mismo-trimestre-de-2016\\\/#mainImage\"},\"datePublished\":\"2017-07-13T14:52:19+02:00\",\"dateModified\":\"2017-07-13T14:52:19+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Secura duplica resultados respecto al mismo trimestre de 2016 | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Secura duplica resultados respecto al mismo trimestre de 2016 | Cand\u00e1s 365","description":"El mundo de la seguridad premia a la estrategia de especializaci\u00f3n, saber hacer y magia del equipo de Secura, (www.secura.es), integrador especialista en ciberseguridad, que cierra un segundo trimestre redondo en el que duplica su facturaci\u00f3n respecto al mismo per\u00edodo del a\u00f1o anterior. Sin duda un merecido premio y gran satisfacci\u00f3n pero tambi\u00e9n mucha responsabilidad,","canonical_url":"https:\/\/candas365.es\/noticias\/secura-duplica-resultados-respecto-al-mismo-trimestre-de-2016\/","robots":"max-image-preview:large","keywords":"canal empresas","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/secura-duplica-resultados-respecto-al-mismo-trimestre-de-2016\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","name":"Canal Empresas"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","position":2,"name":"Canal Empresas","item":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/secura-duplica-resultados-respecto-al-mismo-trimestre-de-2016\/#listItem","name":"Secura duplica resultados respecto al mismo trimestre de 2016"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/secura-duplica-resultados-respecto-al-mismo-trimestre-de-2016\/#listItem","position":3,"name":"Secura duplica resultados respecto al mismo trimestre de 2016","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","name":"Canal Empresas"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/secura-duplica-resultados-respecto-al-mismo-trimestre-de-2016\/#newsarticle","name":"Secura duplica resultados respecto al mismo trimestre de 2016 | Cand\u00e1s 365","headline":"Secura duplica resultados respecto al mismo trimestre de 2016","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/07\/1499850049_Crecimiento_Securapq.jpg","width":710,"height":444},"datePublished":"2017-07-13T14:52:19+02:00","dateModified":"2017-07-13T14:52:19+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/secura-duplica-resultados-respecto-al-mismo-trimestre-de-2016\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/secura-duplica-resultados-respecto-al-mismo-trimestre-de-2016\/#webpage"},"articleSection":"Canal Empresas","dateline":"Publicado el julio 13, 2017."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/secura-duplica-resultados-respecto-al-mismo-trimestre-de-2016\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/secura-duplica-resultados-respecto-al-mismo-trimestre-de-2016\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/secura-duplica-resultados-respecto-al-mismo-trimestre-de-2016\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/secura-duplica-resultados-respecto-al-mismo-trimestre-de-2016\/#webpage","url":"https:\/\/candas365.es\/noticias\/secura-duplica-resultados-respecto-al-mismo-trimestre-de-2016\/","name":"Secura duplica resultados respecto al mismo trimestre de 2016 | Cand\u00e1s 365","description":"El mundo de la seguridad premia a la estrategia de especializaci\u00f3n, saber hacer y magia del equipo de Secura, (www.secura.es), integrador especialista en ciberseguridad, que cierra un segundo trimestre redondo en el que duplica su facturaci\u00f3n respecto al mismo per\u00edodo del a\u00f1o anterior. Sin duda un merecido premio y gran satisfacci\u00f3n pero tambi\u00e9n mucha responsabilidad,","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/secura-duplica-resultados-respecto-al-mismo-trimestre-de-2016\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/07\/1499850049_Crecimiento_Securapq.jpg","@id":"https:\/\/candas365.es\/noticias\/secura-duplica-resultados-respecto-al-mismo-trimestre-de-2016\/#mainImage","width":710,"height":444},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/secura-duplica-resultados-respecto-al-mismo-trimestre-de-2016\/#mainImage"},"datePublished":"2017-07-13T14:52:19+02:00","dateModified":"2017-07-13T14:52:19+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Secura duplica resultados respecto al mismo trimestre de 2016 | Cand\u00e1s 365","og:description":"El mundo de la seguridad premia a la estrategia de especializaci\u00f3n, saber hacer y magia del equipo de Secura, (www.secura.es), integrador especialista en ciberseguridad, que cierra un segundo trimestre redondo en el que duplica su facturaci\u00f3n respecto al mismo per\u00edodo del a\u00f1o anterior. Sin duda un merecido premio y gran satisfacci\u00f3n pero tambi\u00e9n mucha responsabilidad,","og:url":"https:\/\/candas365.es\/noticias\/secura-duplica-resultados-respecto-al-mismo-trimestre-de-2016\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/07\/1499850049_Crecimiento_Securapq.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/07\/1499850049_Crecimiento_Securapq.jpg","og:image:width":710,"og:image:height":444,"article:published_time":"2017-07-13T14:52:19+00:00","article:modified_time":"2017-07-13T14:52:19+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Secura duplica resultados respecto al mismo trimestre de 2016 | Cand\u00e1s 365","twitter:description":"El mundo de la seguridad premia a la estrategia de especializaci\u00f3n, saber hacer y magia del equipo de Secura, (www.secura.es), integrador especialista en ciberseguridad, que cierra un segundo trimestre redondo en el que duplica su facturaci\u00f3n respecto al mismo per\u00edodo del a\u00f1o anterior. Sin duda un merecido premio y gran satisfacci\u00f3n pero tambi\u00e9n mucha responsabilidad,","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/07\/1499850049_Crecimiento_Securapq.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"4 minutos"},"aioseo_meta_data":{"post_id":"75618","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-18 11:26:35","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 12:56:38","updated":"2026-05-18 11:26:35"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/\" title=\"Canal Empresas\">Canal Empresas<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tSecura duplica resultados respecto al mismo trimestre de 2016\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Canal Empresas","link":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/"},{"label":"Secura duplica resultados respecto al mismo trimestre de 2016","link":"https:\/\/candas365.es\/noticias\/secura-duplica-resultados-respecto-al-mismo-trimestre-de-2016\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/75618","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=75618"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/75618\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/75619"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=75618"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=75618"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=75618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}