{"id":75371,"date":"2017-07-08T21:52:10","date_gmt":"2017-07-08T21:52:10","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=75371"},"modified":"2017-07-08T21:52:10","modified_gmt":"2017-07-08T21:52:10","slug":"barin-se-preocupa-por-las-condiciones-laborales-en-la-construccion","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/barin-se-preocupa-por-las-condiciones-laborales-en-la-construccion\/","title":{"rendered":"Barin se preocupa por las condiciones laborales en la construcci\u00f3n"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-75372\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/07\/1499412091_Captura-360x293.png\" alt=\"\" width=\"360\" height=\"293\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/07\/1499412091_Captura-360x293.png 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/07\/1499412091_Captura-516x420.png 516w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/07\/1499412091_Captura.png 525w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Mientras se elaboran y trabajan materiales en este tipo de talleres, se genera una alta cantidad de polvo suspendido en el aire. Es invisible al ojo humano y se corre peligro si se inhala ya que provoca enfermedades respiratorias. Por ello, es primordial una buena <a href=\"http:\/\/www.barin.es\/aspiracion\/paneles-frontales-aspiracion-filtracion-en-seco.asp\" target=\"_blank\" rel=\"nofollow noopener\"><span style=\"color: #ff0000;\">aspiraci\u00f3n industrial<\/span><\/a>.<\/p>\n<p><strong>\u00bfQu\u00e9 propone Barin? <\/strong><br \/>\nPaneles Frontales de Aspiraci\u00f3n y Filtraci\u00f3n en Seco. Estos paneles aspiran el polvo producido limpiando el ambiente. Se ofrecen para diversos tipos de trabajos con herramientas manuales. A t\u00edtulo de ejemplo, lijadoras, discos de corte, amoladoras, etc.<\/p>\n<p><strong>\u00bfCu\u00e1ndo se recomienda instalar un panel de aspiraci\u00f3n?<\/strong><\/p>\n<ul>\n<li>Cuando la aspiraci\u00f3n resulta imposible en este tipo de trabajo<\/li>\n<li>Cuando no se puede instalar otro sistema de aspiraci\u00f3n o resulta insuficiente<\/li>\n<li>En situaciones donde el polvo cambia seg\u00fan el proceso productivo llevado a cabo<\/li>\n<li>P\u00e9rdida del aire climatizado<\/li>\n<\/ul>\n<p><strong>\u00bfQu\u00e9 beneficios supondr\u00eda la instalaci\u00f3n de un panel de aspiraci\u00f3n?<\/strong><\/p>\n<ul>\n<li>Ahorro energ\u00e9tico y reducci\u00f3n de costes en calefacci\u00f3n y climatizaci\u00f3n<\/li>\n<li>No se precisan tuber\u00edas<\/li>\n<li>El mantenimiento es sencillo<\/li>\n<li>De acuerdo con los requerimientos de la producci\u00f3n, se puede variar el filtro<\/li>\n<li>El contenedor ayuda a recuperar el polvo<\/li>\n<li>Sencillo sistema de montaje; se precisa un enchufe para la conexi\u00f3n a la energ\u00eda el\u00e9ctrica y al aire comprimido<\/li>\n<li>Funcionamiento silencioso gracias a la eficiencia de los ventiladores y sus caracter\u00edsticas palas<\/li>\n<\/ul>\n<p><strong>Y\u2026 \u00bfC\u00f3mo funciona?<\/strong><\/p>\n<p>Las cabinas est\u00e1n fabricadas con paneles de chapa galvanizada. Mediante el aspirador centr\u00edfugo montado en el techo se crea una corriente forzada de aire que traslada el polvo a trav\u00e9s de unos filtros, librando as\u00ed el \u00e1rea de trabajo del polvo.<\/p>\n<p>Una vez depurado el aire, se expele a trav\u00e9s de aspirador centr\u00edfugo, cuyas caracter\u00edsticas t\u00e9cnicas garantizan eficacia y rapidez.<\/p>\n<p>La cabina se entrega al cliente con programador c\u00edclico de forma que beneficia la limpieza de forma autom\u00e1tica de los cartuchos que filtran el aire.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mientras se elaboran y trabajan materiales en este tipo de talleres, se genera una alta cantidad de polvo suspendido en el aire. Es invisible al ojo humano y se corre peligro si se inhala ya que provoca enfermedades respiratorias. Por ello, es primordial una buena aspiraci\u00f3n industrial. \u00bfQu\u00e9 propone Barin? Paneles Frontales de Aspiraci\u00f3n y<\/p>\n","protected":false},"author":1,"featured_media":75372,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[151],"tags":[],"class_list":{"0":"post-75371","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-canal-empresas"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7 - aioseo.com -->\n\t<meta name=\"description\" content=\"Mientras se elaboran y trabajan materiales en este tipo de talleres, se genera una alta cantidad de polvo suspendido en el aire. Es invisible al ojo humano y se corre peligro si se inhala ya que provoca enfermedades respiratorias. Por ello, es primordial una buena aspiraci\u00f3n industrial. \u00bfQu\u00e9 propone Barin? Paneles Frontales de Aspiraci\u00f3n y\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"canal empresas\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/barin-se-preocupa-por-las-condiciones-laborales-en-la-construccion\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Barin se preocupa por las condiciones laborales en la construcci\u00f3n | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Mientras se elaboran y trabajan materiales en este tipo de talleres, se genera una alta cantidad de polvo suspendido en el aire. Es invisible al ojo humano y se corre peligro si se inhala ya que provoca enfermedades respiratorias. Por ello, es primordial una buena aspiraci\u00f3n industrial. \u00bfQu\u00e9 propone Barin? Paneles Frontales de Aspiraci\u00f3n y\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/barin-se-preocupa-por-las-condiciones-laborales-en-la-construccion\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/07\/1499412091_Captura.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/07\/1499412091_Captura.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"525\" \/>\n\t\t<meta property=\"og:image:height\" content=\"427\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2017-07-08T21:52:10+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2017-07-08T21:52:10+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Barin se preocupa por las condiciones laborales en la construcci\u00f3n | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Mientras se elaboran y trabajan materiales en este tipo de talleres, se genera una alta cantidad de polvo suspendido en el aire. Es invisible al ojo humano y se corre peligro si se inhala ya que provoca enfermedades respiratorias. Por ello, es primordial una buena aspiraci\u00f3n industrial. \u00bfQu\u00e9 propone Barin? Paneles Frontales de Aspiraci\u00f3n y\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/07\/1499412091_Captura.png\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/barin-se-preocupa-por-las-condiciones-laborales-en-la-construccion\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"name\":\"Canal Empresas\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"position\":2,\"name\":\"Canal Empresas\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/barin-se-preocupa-por-las-condiciones-laborales-en-la-construccion\\\/#listItem\",\"name\":\"Barin se preocupa por las condiciones laborales en la construcci\\u00f3n\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/barin-se-preocupa-por-las-condiciones-laborales-en-la-construccion\\\/#listItem\",\"position\":3,\"name\":\"Barin se preocupa por las condiciones laborales en la construcci\\u00f3n\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"name\":\"Canal Empresas\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/barin-se-preocupa-por-las-condiciones-laborales-en-la-construccion\\\/#newsarticle\",\"name\":\"Barin se preocupa por las condiciones laborales en la construcci\\u00f3n | Cand\\u00e1s 365\",\"headline\":\"Barin se preocupa por las condiciones laborales en la construcci\\u00f3n\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/1499412091_Captura.png\",\"width\":525,\"height\":427},\"datePublished\":\"2017-07-08T21:52:10+02:00\",\"dateModified\":\"2017-07-08T21:52:10+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/barin-se-preocupa-por-las-condiciones-laborales-en-la-construccion\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/barin-se-preocupa-por-las-condiciones-laborales-en-la-construccion\\\/#webpage\"},\"articleSection\":\"Canal Empresas\",\"dateline\":\"Publicado el julio 8, 2017.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/barin-se-preocupa-por-las-condiciones-laborales-en-la-construccion\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/barin-se-preocupa-por-las-condiciones-laborales-en-la-construccion\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/barin-se-preocupa-por-las-condiciones-laborales-en-la-construccion\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/barin-se-preocupa-por-las-condiciones-laborales-en-la-construccion\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/barin-se-preocupa-por-las-condiciones-laborales-en-la-construccion\\\/\",\"name\":\"Barin se preocupa por las condiciones laborales en la construcci\\u00f3n | Cand\\u00e1s 365\",\"description\":\"Mientras se elaboran y trabajan materiales en este tipo de talleres, se genera una alta cantidad de polvo suspendido en el aire. Es invisible al ojo humano y se corre peligro si se inhala ya que provoca enfermedades respiratorias. Por ello, es primordial una buena aspiraci\\u00f3n industrial. \\u00bfQu\\u00e9 propone Barin? Paneles Frontales de Aspiraci\\u00f3n y\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/barin-se-preocupa-por-las-condiciones-laborales-en-la-construccion\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/1499412091_Captura.png\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/barin-se-preocupa-por-las-condiciones-laborales-en-la-construccion\\\/#mainImage\",\"width\":525,\"height\":427},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/barin-se-preocupa-por-las-condiciones-laborales-en-la-construccion\\\/#mainImage\"},\"datePublished\":\"2017-07-08T21:52:10+02:00\",\"dateModified\":\"2017-07-08T21:52:10+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Barin se preocupa por las condiciones laborales en la construcci\u00f3n | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Barin se preocupa por las condiciones laborales en la construcci\u00f3n | Cand\u00e1s 365","description":"Mientras se elaboran y trabajan materiales en este tipo de talleres, se genera una alta cantidad de polvo suspendido en el aire. Es invisible al ojo humano y se corre peligro si se inhala ya que provoca enfermedades respiratorias. Por ello, es primordial una buena aspiraci\u00f3n industrial. \u00bfQu\u00e9 propone Barin? Paneles Frontales de Aspiraci\u00f3n y","canonical_url":"https:\/\/candas365.es\/noticias\/barin-se-preocupa-por-las-condiciones-laborales-en-la-construccion\/","robots":"max-image-preview:large","keywords":"canal empresas","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/barin-se-preocupa-por-las-condiciones-laborales-en-la-construccion\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","name":"Canal Empresas"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","position":2,"name":"Canal Empresas","item":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/barin-se-preocupa-por-las-condiciones-laborales-en-la-construccion\/#listItem","name":"Barin se preocupa por las condiciones laborales en la construcci\u00f3n"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/barin-se-preocupa-por-las-condiciones-laborales-en-la-construccion\/#listItem","position":3,"name":"Barin se preocupa por las condiciones laborales en la construcci\u00f3n","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","name":"Canal Empresas"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/barin-se-preocupa-por-las-condiciones-laborales-en-la-construccion\/#newsarticle","name":"Barin se preocupa por las condiciones laborales en la construcci\u00f3n | Cand\u00e1s 365","headline":"Barin se preocupa por las condiciones laborales en la construcci\u00f3n","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/07\/1499412091_Captura.png","width":525,"height":427},"datePublished":"2017-07-08T21:52:10+02:00","dateModified":"2017-07-08T21:52:10+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/barin-se-preocupa-por-las-condiciones-laborales-en-la-construccion\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/barin-se-preocupa-por-las-condiciones-laborales-en-la-construccion\/#webpage"},"articleSection":"Canal Empresas","dateline":"Publicado el julio 8, 2017."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/barin-se-preocupa-por-las-condiciones-laborales-en-la-construccion\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/barin-se-preocupa-por-las-condiciones-laborales-en-la-construccion\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/barin-se-preocupa-por-las-condiciones-laborales-en-la-construccion\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/barin-se-preocupa-por-las-condiciones-laborales-en-la-construccion\/#webpage","url":"https:\/\/candas365.es\/noticias\/barin-se-preocupa-por-las-condiciones-laborales-en-la-construccion\/","name":"Barin se preocupa por las condiciones laborales en la construcci\u00f3n | Cand\u00e1s 365","description":"Mientras se elaboran y trabajan materiales en este tipo de talleres, se genera una alta cantidad de polvo suspendido en el aire. Es invisible al ojo humano y se corre peligro si se inhala ya que provoca enfermedades respiratorias. Por ello, es primordial una buena aspiraci\u00f3n industrial. \u00bfQu\u00e9 propone Barin? Paneles Frontales de Aspiraci\u00f3n y","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/barin-se-preocupa-por-las-condiciones-laborales-en-la-construccion\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/07\/1499412091_Captura.png","@id":"https:\/\/candas365.es\/noticias\/barin-se-preocupa-por-las-condiciones-laborales-en-la-construccion\/#mainImage","width":525,"height":427},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/barin-se-preocupa-por-las-condiciones-laborales-en-la-construccion\/#mainImage"},"datePublished":"2017-07-08T21:52:10+02:00","dateModified":"2017-07-08T21:52:10+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Barin se preocupa por las condiciones laborales en la construcci\u00f3n | Cand\u00e1s 365","og:description":"Mientras se elaboran y trabajan materiales en este tipo de talleres, se genera una alta cantidad de polvo suspendido en el aire. Es invisible al ojo humano y se corre peligro si se inhala ya que provoca enfermedades respiratorias. Por ello, es primordial una buena aspiraci\u00f3n industrial. \u00bfQu\u00e9 propone Barin? Paneles Frontales de Aspiraci\u00f3n y","og:url":"https:\/\/candas365.es\/noticias\/barin-se-preocupa-por-las-condiciones-laborales-en-la-construccion\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/07\/1499412091_Captura.png","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/07\/1499412091_Captura.png","og:image:width":525,"og:image:height":427,"article:published_time":"2017-07-08T21:52:10+00:00","article:modified_time":"2017-07-08T21:52:10+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Barin se preocupa por las condiciones laborales en la construcci\u00f3n | Cand\u00e1s 365","twitter:description":"Mientras se elaboran y trabajan materiales en este tipo de talleres, se genera una alta cantidad de polvo suspendido en el aire. Es invisible al ojo humano y se corre peligro si se inhala ya que provoca enfermedades respiratorias. Por ello, es primordial una buena aspiraci\u00f3n industrial. \u00bfQu\u00e9 propone Barin? Paneles Frontales de Aspiraci\u00f3n y","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/07\/1499412091_Captura.png","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"75371","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-25 17:58:39","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 12:56:47","updated":"2025-08-25 17:58:39"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/\" title=\"Canal Empresas\">Canal Empresas<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tBarin se preocupa por las condiciones laborales en la construcci\u00f3n\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Canal Empresas","link":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/"},{"label":"Barin se preocupa por las condiciones laborales en la construcci\u00f3n","link":"https:\/\/candas365.es\/noticias\/barin-se-preocupa-por-las-condiciones-laborales-en-la-construccion\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/75371","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=75371"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/75371\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/75372"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=75371"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=75371"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=75371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}