{"id":75185,"date":"2017-07-05T20:20:33","date_gmt":"2017-07-05T20:20:33","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=75185"},"modified":"2017-07-05T20:20:33","modified_gmt":"2017-07-05T20:20:33","slug":"el-grupo-dekra-celebra-el-global-dekra-partner-day","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/el-grupo-dekra-celebra-el-global-dekra-partner-day\/","title":{"rendered":"El grupo DEKRA celebra el Global DEKRA Partner Day"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-75186\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/07\/1499170174-360x252.png\" alt=\"\" width=\"360\" height=\"252\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/07\/1499170174-360x252.png 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/07\/1499170174-655x459.png 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/07\/1499170174-100x70.png 100w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/07\/1499170174-600x420.png 600w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/07\/1499170174.png 690w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Los 39.000 empleados del grupo <a href=\"http:\/\/www.dekra.es\/es\/home\" target=\"_blank\" rel=\"nofollow noopener\"><strong><span style=\"color: #ff0000;\">DEK<\/span><\/strong><span style=\"color: #ff0000;\">RA<\/span><\/a> tuvieron la oportunidad de participar en unas jornadas centradas en los partners internos y externos de la compa\u00f1\u00eda, elemento de vital importancia dentro de su Visi\u00f3n 2025 \u201cSeremos el partner global para un mundo seguro\u201d. Bajo el lema de &#8216;connecting the dots&#8217;\u00a0las jornadas ten\u00edan principalmente dos claros objetivos: identificar qui\u00e9nes son sus partners y desarrollar y fortalecer las relaciones con ellos. \u201cEsta tarea es sin duda un elemento clave en nuestro trabajo diario. Estas jornadas adem\u00e1s de perseguir estos objetivos, \u201cfortalecen nuestro trabajo en equipo, elemento de \u00e9xito para cualquier empresa que pretenda tener \u00e9xito y ofrecer servicios de calidad\u201d, afirma Yvonne Rauh, Directora General de DEKRA Espa\u00f1a.<\/p>\n<p>En Espa\u00f1a donde DEKRA cuenta con m\u00e1s de 500 empleados repartidos principalmente por sus delegaciones de Madrid, Barcelona y M\u00e1laga se celebraron varias jornadas acogidas con gran expectaci\u00f3n y compromiso.<\/p>\n<p>En palabras de Yvonne Rauh \u201cesta experiencia nos ha servido para dar un paso adelante hacia nuestra Visi\u00f3n 2025. Atar los cabos para y con nuestros clientes, partners y stakeholders y hacer de nuestro mundo un mundo m\u00e1s conectado y seguro.\u201d<\/p>\n<p><strong>Sobre DEKRA<\/strong><\/p>\n<p>DEKRA ha estado activa en el campo de la seguridad durante m\u00e1s de 90 a\u00f1os. Fundada en 1925 en Berl\u00edn, es hoy una de las organizaciones de expertos l\u00edderes en el mundo. DEKRA SE es una filial de DEKRA e.V. y gestiona los negocios de explotaci\u00f3n del Grupo. Sus servicios van desde la inspecci\u00f3n de veh\u00edculos y expertos de evaluaciones a los servicios de reclamaciones, inspecciones industriales y de construcci\u00f3n, consultor\u00eda de seguridad, pruebas y certificaci\u00f3n de productos y sistemas, as\u00ed como cursos de formaci\u00f3n y trabajo temporal.<\/p>\n<p><strong>DEKRA en Espa\u00f1a <\/strong>cerr\u00f3 en 2016 con una facturaci\u00f3n de 57 millones de euros, con un crecimiento del 10% frente al a\u00f1o anterior y con 531 empleados. Presente en sus 3 unidades de negocio principales, Automoci\u00f3n, Industria y Personal, prev\u00e9 un crecimiento importante de acuerdo con las nuevas oportunidades del mercado para los a\u00f1os venideros.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los 39.000 empleados del grupo DEKRA tuvieron la oportunidad de participar en unas jornadas centradas en los partners internos y externos de la compa\u00f1\u00eda, elemento de vital importancia dentro de su Visi\u00f3n 2025 \u201cSeremos el partner global para un mundo seguro\u201d. Bajo el lema de &#8216;connecting the dots&#8217;\u00a0las jornadas ten\u00edan principalmente dos claros objetivos: identificar<\/p>\n","protected":false},"author":1,"featured_media":75186,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[151],"tags":[],"class_list":{"0":"post-75185","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-canal-empresas"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7 - aioseo.com -->\n\t<meta name=\"description\" content=\"Los 39.000 empleados del grupo DEKRA tuvieron la oportunidad de participar en unas jornadas centradas en los partners internos y externos de la compa\u00f1\u00eda, elemento de vital importancia dentro de su Visi\u00f3n 2025 \u201cSeremos el partner global para un mundo seguro\u201d. Bajo el lema de &#039;connecting the dots&#039; las jornadas ten\u00edan principalmente dos claros objetivos: identificar\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"canal empresas\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/el-grupo-dekra-celebra-el-global-dekra-partner-day\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El grupo DEKRA celebra el Global DEKRA Partner Day | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Los 39.000 empleados del grupo DEKRA tuvieron la oportunidad de participar en unas jornadas centradas en los partners internos y externos de la compa\u00f1\u00eda, elemento de vital importancia dentro de su Visi\u00f3n 2025 \u201cSeremos el partner global para un mundo seguro\u201d. Bajo el lema de &#039;connecting the dots&#039; las jornadas ten\u00edan principalmente dos claros objetivos: identificar\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/el-grupo-dekra-celebra-el-global-dekra-partner-day\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/07\/1499170174.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/07\/1499170174.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"690\" \/>\n\t\t<meta property=\"og:image:height\" content=\"483\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2017-07-05T20:20:33+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2017-07-05T20:20:33+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El grupo DEKRA celebra el Global DEKRA Partner Day | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Los 39.000 empleados del grupo DEKRA tuvieron la oportunidad de participar en unas jornadas centradas en los partners internos y externos de la compa\u00f1\u00eda, elemento de vital importancia dentro de su Visi\u00f3n 2025 \u201cSeremos el partner global para un mundo seguro\u201d. Bajo el lema de &#039;connecting the dots&#039; las jornadas ten\u00edan principalmente dos claros objetivos: identificar\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/07\/1499170174.png\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-grupo-dekra-celebra-el-global-dekra-partner-day\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"name\":\"Canal Empresas\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"position\":2,\"name\":\"Canal Empresas\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-grupo-dekra-celebra-el-global-dekra-partner-day\\\/#listItem\",\"name\":\"El grupo DEKRA celebra el Global DEKRA Partner Day\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-grupo-dekra-celebra-el-global-dekra-partner-day\\\/#listItem\",\"position\":3,\"name\":\"El grupo DEKRA celebra el Global DEKRA Partner Day\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"name\":\"Canal Empresas\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-grupo-dekra-celebra-el-global-dekra-partner-day\\\/#newsarticle\",\"name\":\"El grupo DEKRA celebra el Global DEKRA Partner Day | Cand\\u00e1s 365\",\"headline\":\"El grupo DEKRA celebra el Global DEKRA Partner Day\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/1499170174.png\",\"width\":690,\"height\":483},\"datePublished\":\"2017-07-05T20:20:33+02:00\",\"dateModified\":\"2017-07-05T20:20:33+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-grupo-dekra-celebra-el-global-dekra-partner-day\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-grupo-dekra-celebra-el-global-dekra-partner-day\\\/#webpage\"},\"articleSection\":\"Canal Empresas\",\"dateline\":\"Publicado el julio 5, 2017.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-grupo-dekra-celebra-el-global-dekra-partner-day\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-grupo-dekra-celebra-el-global-dekra-partner-day\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-grupo-dekra-celebra-el-global-dekra-partner-day\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-grupo-dekra-celebra-el-global-dekra-partner-day\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-grupo-dekra-celebra-el-global-dekra-partner-day\\\/\",\"name\":\"El grupo DEKRA celebra el Global DEKRA Partner Day | Cand\\u00e1s 365\",\"description\":\"Los 39.000 empleados del grupo DEKRA tuvieron la oportunidad de participar en unas jornadas centradas en los partners internos y externos de la compa\\u00f1\\u00eda, elemento de vital importancia dentro de su Visi\\u00f3n 2025 \\u201cSeremos el partner global para un mundo seguro\\u201d. Bajo el lema de 'connecting the dots' las jornadas ten\\u00edan principalmente dos claros objetivos: identificar\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-grupo-dekra-celebra-el-global-dekra-partner-day\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/1499170174.png\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-grupo-dekra-celebra-el-global-dekra-partner-day\\\/#mainImage\",\"width\":690,\"height\":483},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-grupo-dekra-celebra-el-global-dekra-partner-day\\\/#mainImage\"},\"datePublished\":\"2017-07-05T20:20:33+02:00\",\"dateModified\":\"2017-07-05T20:20:33+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>El grupo DEKRA celebra el Global DEKRA Partner Day | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"El grupo DEKRA celebra el Global DEKRA Partner Day | Cand\u00e1s 365","description":"Los 39.000 empleados del grupo DEKRA tuvieron la oportunidad de participar en unas jornadas centradas en los partners internos y externos de la compa\u00f1\u00eda, elemento de vital importancia dentro de su Visi\u00f3n 2025 \u201cSeremos el partner global para un mundo seguro\u201d. Bajo el lema de 'connecting the dots' las jornadas ten\u00edan principalmente dos claros objetivos: identificar","canonical_url":"https:\/\/candas365.es\/noticias\/el-grupo-dekra-celebra-el-global-dekra-partner-day\/","robots":"max-image-preview:large","keywords":"canal empresas","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/el-grupo-dekra-celebra-el-global-dekra-partner-day\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","name":"Canal Empresas"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","position":2,"name":"Canal Empresas","item":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/el-grupo-dekra-celebra-el-global-dekra-partner-day\/#listItem","name":"El grupo DEKRA celebra el Global DEKRA Partner Day"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/el-grupo-dekra-celebra-el-global-dekra-partner-day\/#listItem","position":3,"name":"El grupo DEKRA celebra el Global DEKRA Partner Day","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","name":"Canal Empresas"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/el-grupo-dekra-celebra-el-global-dekra-partner-day\/#newsarticle","name":"El grupo DEKRA celebra el Global DEKRA Partner Day | Cand\u00e1s 365","headline":"El grupo DEKRA celebra el Global DEKRA Partner Day","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/07\/1499170174.png","width":690,"height":483},"datePublished":"2017-07-05T20:20:33+02:00","dateModified":"2017-07-05T20:20:33+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/el-grupo-dekra-celebra-el-global-dekra-partner-day\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/el-grupo-dekra-celebra-el-global-dekra-partner-day\/#webpage"},"articleSection":"Canal Empresas","dateline":"Publicado el julio 5, 2017."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/el-grupo-dekra-celebra-el-global-dekra-partner-day\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/el-grupo-dekra-celebra-el-global-dekra-partner-day\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/el-grupo-dekra-celebra-el-global-dekra-partner-day\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/el-grupo-dekra-celebra-el-global-dekra-partner-day\/#webpage","url":"https:\/\/candas365.es\/noticias\/el-grupo-dekra-celebra-el-global-dekra-partner-day\/","name":"El grupo DEKRA celebra el Global DEKRA Partner Day | Cand\u00e1s 365","description":"Los 39.000 empleados del grupo DEKRA tuvieron la oportunidad de participar en unas jornadas centradas en los partners internos y externos de la compa\u00f1\u00eda, elemento de vital importancia dentro de su Visi\u00f3n 2025 \u201cSeremos el partner global para un mundo seguro\u201d. Bajo el lema de 'connecting the dots' las jornadas ten\u00edan principalmente dos claros objetivos: identificar","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/el-grupo-dekra-celebra-el-global-dekra-partner-day\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/07\/1499170174.png","@id":"https:\/\/candas365.es\/noticias\/el-grupo-dekra-celebra-el-global-dekra-partner-day\/#mainImage","width":690,"height":483},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/el-grupo-dekra-celebra-el-global-dekra-partner-day\/#mainImage"},"datePublished":"2017-07-05T20:20:33+02:00","dateModified":"2017-07-05T20:20:33+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"El grupo DEKRA celebra el Global DEKRA Partner Day | Cand\u00e1s 365","og:description":"Los 39.000 empleados del grupo DEKRA tuvieron la oportunidad de participar en unas jornadas centradas en los partners internos y externos de la compa\u00f1\u00eda, elemento de vital importancia dentro de su Visi\u00f3n 2025 \u201cSeremos el partner global para un mundo seguro\u201d. Bajo el lema de 'connecting the dots' las jornadas ten\u00edan principalmente dos claros objetivos: identificar","og:url":"https:\/\/candas365.es\/noticias\/el-grupo-dekra-celebra-el-global-dekra-partner-day\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/07\/1499170174.png","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/07\/1499170174.png","og:image:width":690,"og:image:height":483,"article:published_time":"2017-07-05T20:20:33+00:00","article:modified_time":"2017-07-05T20:20:33+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"El grupo DEKRA celebra el Global DEKRA Partner Day | Cand\u00e1s 365","twitter:description":"Los 39.000 empleados del grupo DEKRA tuvieron la oportunidad de participar en unas jornadas centradas en los partners internos y externos de la compa\u00f1\u00eda, elemento de vital importancia dentro de su Visi\u00f3n 2025 \u201cSeremos el partner global para un mundo seguro\u201d. Bajo el lema de 'connecting the dots' las jornadas ten\u00edan principalmente dos claros objetivos: identificar","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/07\/1499170174.png","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"75185","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-25 17:44:25","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 11:18:14","updated":"2025-08-25 17:44:25"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/\" title=\"Canal Empresas\">Canal Empresas<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tEl grupo DEKRA celebra el Global DEKRA Partner Day\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Canal Empresas","link":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/"},{"label":"El grupo DEKRA celebra el Global DEKRA Partner Day","link":"https:\/\/candas365.es\/noticias\/el-grupo-dekra-celebra-el-global-dekra-partner-day\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/75185","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=75185"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/75185\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/75186"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=75185"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=75185"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=75185"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}