{"id":74915,"date":"2017-06-30T12:56:48","date_gmt":"2017-06-30T12:56:48","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=74915"},"modified":"2017-06-30T12:56:48","modified_gmt":"2017-06-30T12:56:48","slug":"la-nueva-ley-de-salud-amplia-las-garantias-de-los-pacientes-asturianos","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/la-nueva-ley-de-salud-amplia-las-garantias-de-los-pacientes-asturianos\/","title":{"rendered":"La nueva Ley de Salud ampl\u00eda las garant\u00edas de los pacientes asturianos"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-74916\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/Sanidad-Asturias-360x224.jpg\" alt=\"\" width=\"360\" height=\"224\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/Sanidad-Asturias-360x224.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/Sanidad-Asturias-768x478.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/Sanidad-Asturias-655x407.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/Sanidad-Asturias-696x433.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/Sanidad-Asturias-1068x664.jpg 1068w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/Sanidad-Asturias-675x420.jpg 675w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/Sanidad-Asturias-279x173.jpg 279w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/Sanidad-Asturias.jpg 1280w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>El anteproyecto de Ley de Salud del Principado de Asturias, que en los pr\u00f3ximos meses comenzar\u00e1 su tramitaci\u00f3n, consolida el derecho universal a la sanidad para todos los residentes en el Principado y ampl\u00eda sus garant\u00edas en cuanto a informaci\u00f3n, transparencia, acceso a los servicios y prestaciones y autonom\u00eda de decisi\u00f3n sobre sus necesidades de atenci\u00f3n.<\/p>\n<p>El consejero de Sanidad, Francisco del Busto, ha presentado hoy este documento a la Federaci\u00f3n Asturiana de Concejos de Asturias (FACC). Ha explicado que se trata de un anteproyecto legislativo con un enfoque integral, orientado no s\u00f3lo a la atenci\u00f3n sanitaria, sino tambi\u00e9n a la prevenci\u00f3n de la enfermedad, la protecci\u00f3n de la salud y la promoci\u00f3n de h\u00e1bitos saludables.<\/p>\n<p>Del Busto ha asegurado que su objetivo fundamental es \u201cmantener y consolidar el desarrollo de un modelo sanitario universal, de calidad, equitativo y sostenible, con la mayor capacidad de prestaciones y servicios, que mantiene a los ciudadanos como centro de referencia y que requiere de una gran implicaci\u00f3n de los profesionales y una \u00f3ptima gesti\u00f3n de los recursos humanos y materiales\u201d.<\/p>\n<p>La norma tambi\u00e9n pretende fortalecer la confianza de los usuarios en la sanidad. \u201cLa exigencia de transparencia en los servicios p\u00fablicos es tambi\u00e9n trasladable a los servicios sanitarios y al d\u00eda a d\u00eda de la tarea asistencial\u201d, ha asegurado el consejero. Ha destacado, adem\u00e1s, que \u201cuna informaci\u00f3n ajustada a las expectativas de la ciudadan\u00eda ayuda a fortalecer la confianza, mientras que la desinformaci\u00f3n y las dudas generan desconfianza y debilitan la credibilidad\u201d.<\/p>\n<p>Del Busto se ha referido a algunas de las amenazas que tendr\u00e1 que afrontar la sanidad p\u00fablica espa\u00f1ola en el futuro, entre ellas, la disponibilidad de tecnolog\u00edas diagn\u00f3sticas y terap\u00e9uticas de alto coste de adquisici\u00f3n y mantenimiento, as\u00ed como la dificultad para disponer de facultativos en numerosas especialidades, derivada de una incorrecta planificaci\u00f3n de la formaci\u00f3n especializada desde hace a\u00f1os. Sin embargo, el consejero se ha mostrado optimista sobre el futuro, ya que \u201ca pesar de que todo esto puede parecer una tormenta perfecta, el Sistema Nacional de Salud tiene recursos e imaginaci\u00f3n para superar estas dificultades gracias a la fuerza del aprecio de los ciudadanos y el empuje de los profesionales; eso es una garant\u00eda para que cualquier Gobierno pueda tomar las medidas necesarias\u201d.<\/p>\n<p>El anteproyecto de ley no contempla la toma de decisiones sobre el mapa sanitario asturiano, por lo que no incluye propuestas de modificaci\u00f3n del dise\u00f1o actual. La consejer\u00eda ha decidido omitir este asunto para evitar fricciones y posicionamientos pol\u00edticos que podr\u00edan impedir un objetivo mucho m\u00e1s amplio y m\u00e1s importante para la ciudadan\u00eda. \u201cSer\u00eda bueno para Asturias que esta altura de miras sea denominador com\u00fan a la hora de valorar y de realizar al texto que ahora presentamos\u201d, ha explicado el consejero.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El anteproyecto de Ley de Salud del Principado de Asturias, que en los pr\u00f3ximos meses comenzar\u00e1 su tramitaci\u00f3n, consolida el derecho universal a la sanidad para todos los residentes en el Principado y ampl\u00eda sus garant\u00edas en cuanto a informaci\u00f3n, transparencia, acceso a los servicios y prestaciones y autonom\u00eda de decisi\u00f3n sobre sus necesidades de<\/p>\n","protected":false},"author":1,"featured_media":74916,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[143],"tags":[],"class_list":{"0":"post-74915","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-sociedad"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7 - aioseo.com -->\n\t<meta name=\"description\" content=\"El anteproyecto de Ley de Salud del Principado de Asturias, que en los pr\u00f3ximos meses comenzar\u00e1 su tramitaci\u00f3n, consolida el derecho universal a la sanidad para todos los residentes en el Principado y ampl\u00eda sus garant\u00edas en cuanto a informaci\u00f3n, transparencia, acceso a los servicios y prestaciones y autonom\u00eda de decisi\u00f3n sobre sus necesidades de\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"sociedad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/la-nueva-ley-de-salud-amplia-las-garantias-de-los-pacientes-asturianos\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"La nueva Ley de Salud ampl\u00eda las garant\u00edas de los pacientes asturianos | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"El anteproyecto de Ley de Salud del Principado de Asturias, que en los pr\u00f3ximos meses comenzar\u00e1 su tramitaci\u00f3n, consolida el derecho universal a la sanidad para todos los residentes en el Principado y ampl\u00eda sus garant\u00edas en cuanto a informaci\u00f3n, transparencia, acceso a los servicios y prestaciones y autonom\u00eda de decisi\u00f3n sobre sus necesidades de\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/la-nueva-ley-de-salud-amplia-las-garantias-de-los-pacientes-asturianos\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/Sanidad-Asturias.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/Sanidad-Asturias.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t\t<meta property=\"og:image:height\" content=\"796\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2017-06-30T12:56:48+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2017-06-30T12:56:48+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"La nueva Ley de Salud ampl\u00eda las garant\u00edas de los pacientes asturianos | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El anteproyecto de Ley de Salud del Principado de Asturias, que en los pr\u00f3ximos meses comenzar\u00e1 su tramitaci\u00f3n, consolida el derecho universal a la sanidad para todos los residentes en el Principado y ampl\u00eda sus garant\u00edas en cuanto a informaci\u00f3n, transparencia, acceso a los servicios y prestaciones y autonom\u00eda de decisi\u00f3n sobre sus necesidades de\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/Sanidad-Asturias.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-nueva-ley-de-salud-amplia-las-garantias-de-los-pacientes-asturianos\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/sociedad\\\/#listItem\",\"name\":\"Sociedad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/sociedad\\\/#listItem\",\"position\":2,\"name\":\"Sociedad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/sociedad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-nueva-ley-de-salud-amplia-las-garantias-de-los-pacientes-asturianos\\\/#listItem\",\"name\":\"La nueva Ley de Salud ampl\\u00eda las garant\\u00edas de los pacientes asturianos\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-nueva-ley-de-salud-amplia-las-garantias-de-los-pacientes-asturianos\\\/#listItem\",\"position\":3,\"name\":\"La nueva Ley de Salud ampl\\u00eda las garant\\u00edas de los pacientes asturianos\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/sociedad\\\/#listItem\",\"name\":\"Sociedad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-nueva-ley-de-salud-amplia-las-garantias-de-los-pacientes-asturianos\\\/#newsarticle\",\"name\":\"La nueva Ley de Salud ampl\\u00eda las garant\\u00edas de los pacientes asturianos | Cand\\u00e1s 365\",\"headline\":\"La nueva Ley de Salud ampl\\u00eda las garant\\u00edas de los pacientes asturianos\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/Sanidad-Asturias.jpg\",\"width\":1280,\"height\":796},\"datePublished\":\"2017-06-30T12:56:48+02:00\",\"dateModified\":\"2017-06-30T12:56:48+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-nueva-ley-de-salud-amplia-las-garantias-de-los-pacientes-asturianos\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-nueva-ley-de-salud-amplia-las-garantias-de-los-pacientes-asturianos\\\/#webpage\"},\"articleSection\":\"Sociedad\",\"dateline\":\"Publicado el junio 30, 2017.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-nueva-ley-de-salud-amplia-las-garantias-de-los-pacientes-asturianos\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-nueva-ley-de-salud-amplia-las-garantias-de-los-pacientes-asturianos\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-nueva-ley-de-salud-amplia-las-garantias-de-los-pacientes-asturianos\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-nueva-ley-de-salud-amplia-las-garantias-de-los-pacientes-asturianos\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-nueva-ley-de-salud-amplia-las-garantias-de-los-pacientes-asturianos\\\/\",\"name\":\"La nueva Ley de Salud ampl\\u00eda las garant\\u00edas de los pacientes asturianos | Cand\\u00e1s 365\",\"description\":\"El anteproyecto de Ley de Salud del Principado de Asturias, que en los pr\\u00f3ximos meses comenzar\\u00e1 su tramitaci\\u00f3n, consolida el derecho universal a la sanidad para todos los residentes en el Principado y ampl\\u00eda sus garant\\u00edas en cuanto a informaci\\u00f3n, transparencia, acceso a los servicios y prestaciones y autonom\\u00eda de decisi\\u00f3n sobre sus necesidades de\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-nueva-ley-de-salud-amplia-las-garantias-de-los-pacientes-asturianos\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/Sanidad-Asturias.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-nueva-ley-de-salud-amplia-las-garantias-de-los-pacientes-asturianos\\\/#mainImage\",\"width\":1280,\"height\":796},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-nueva-ley-de-salud-amplia-las-garantias-de-los-pacientes-asturianos\\\/#mainImage\"},\"datePublished\":\"2017-06-30T12:56:48+02:00\",\"dateModified\":\"2017-06-30T12:56:48+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>La nueva Ley de Salud ampl\u00eda las garant\u00edas de los pacientes asturianos | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"La nueva Ley de Salud ampl\u00eda las garant\u00edas de los pacientes asturianos | Cand\u00e1s 365","description":"El anteproyecto de Ley de Salud del Principado de Asturias, que en los pr\u00f3ximos meses comenzar\u00e1 su tramitaci\u00f3n, consolida el derecho universal a la sanidad para todos los residentes en el Principado y ampl\u00eda sus garant\u00edas en cuanto a informaci\u00f3n, transparencia, acceso a los servicios y prestaciones y autonom\u00eda de decisi\u00f3n sobre sus necesidades de","canonical_url":"https:\/\/candas365.es\/noticias\/la-nueva-ley-de-salud-amplia-las-garantias-de-los-pacientes-asturianos\/","robots":"max-image-preview:large","keywords":"sociedad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/la-nueva-ley-de-salud-amplia-las-garantias-de-los-pacientes-asturianos\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/sociedad\/#listItem","name":"Sociedad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/sociedad\/#listItem","position":2,"name":"Sociedad","item":"https:\/\/candas365.es\/noticias\/category\/sociedad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/la-nueva-ley-de-salud-amplia-las-garantias-de-los-pacientes-asturianos\/#listItem","name":"La nueva Ley de Salud ampl\u00eda las garant\u00edas de los pacientes asturianos"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/la-nueva-ley-de-salud-amplia-las-garantias-de-los-pacientes-asturianos\/#listItem","position":3,"name":"La nueva Ley de Salud ampl\u00eda las garant\u00edas de los pacientes asturianos","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/sociedad\/#listItem","name":"Sociedad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/la-nueva-ley-de-salud-amplia-las-garantias-de-los-pacientes-asturianos\/#newsarticle","name":"La nueva Ley de Salud ampl\u00eda las garant\u00edas de los pacientes asturianos | Cand\u00e1s 365","headline":"La nueva Ley de Salud ampl\u00eda las garant\u00edas de los pacientes asturianos","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/Sanidad-Asturias.jpg","width":1280,"height":796},"datePublished":"2017-06-30T12:56:48+02:00","dateModified":"2017-06-30T12:56:48+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/la-nueva-ley-de-salud-amplia-las-garantias-de-los-pacientes-asturianos\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/la-nueva-ley-de-salud-amplia-las-garantias-de-los-pacientes-asturianos\/#webpage"},"articleSection":"Sociedad","dateline":"Publicado el junio 30, 2017."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/la-nueva-ley-de-salud-amplia-las-garantias-de-los-pacientes-asturianos\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/la-nueva-ley-de-salud-amplia-las-garantias-de-los-pacientes-asturianos\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/la-nueva-ley-de-salud-amplia-las-garantias-de-los-pacientes-asturianos\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/la-nueva-ley-de-salud-amplia-las-garantias-de-los-pacientes-asturianos\/#webpage","url":"https:\/\/candas365.es\/noticias\/la-nueva-ley-de-salud-amplia-las-garantias-de-los-pacientes-asturianos\/","name":"La nueva Ley de Salud ampl\u00eda las garant\u00edas de los pacientes asturianos | Cand\u00e1s 365","description":"El anteproyecto de Ley de Salud del Principado de Asturias, que en los pr\u00f3ximos meses comenzar\u00e1 su tramitaci\u00f3n, consolida el derecho universal a la sanidad para todos los residentes en el Principado y ampl\u00eda sus garant\u00edas en cuanto a informaci\u00f3n, transparencia, acceso a los servicios y prestaciones y autonom\u00eda de decisi\u00f3n sobre sus necesidades de","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/la-nueva-ley-de-salud-amplia-las-garantias-de-los-pacientes-asturianos\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/Sanidad-Asturias.jpg","@id":"https:\/\/candas365.es\/noticias\/la-nueva-ley-de-salud-amplia-las-garantias-de-los-pacientes-asturianos\/#mainImage","width":1280,"height":796},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/la-nueva-ley-de-salud-amplia-las-garantias-de-los-pacientes-asturianos\/#mainImage"},"datePublished":"2017-06-30T12:56:48+02:00","dateModified":"2017-06-30T12:56:48+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"La nueva Ley de Salud ampl\u00eda las garant\u00edas de los pacientes asturianos | Cand\u00e1s 365","og:description":"El anteproyecto de Ley de Salud del Principado de Asturias, que en los pr\u00f3ximos meses comenzar\u00e1 su tramitaci\u00f3n, consolida el derecho universal a la sanidad para todos los residentes en el Principado y ampl\u00eda sus garant\u00edas en cuanto a informaci\u00f3n, transparencia, acceso a los servicios y prestaciones y autonom\u00eda de decisi\u00f3n sobre sus necesidades de","og:url":"https:\/\/candas365.es\/noticias\/la-nueva-ley-de-salud-amplia-las-garantias-de-los-pacientes-asturianos\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/Sanidad-Asturias.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/Sanidad-Asturias.jpg","og:image:width":1280,"og:image:height":796,"article:published_time":"2017-06-30T12:56:48+00:00","article:modified_time":"2017-06-30T12:56:48+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"La nueva Ley de Salud ampl\u00eda las garant\u00edas de los pacientes asturianos | Cand\u00e1s 365","twitter:description":"El anteproyecto de Ley de Salud del Principado de Asturias, que en los pr\u00f3ximos meses comenzar\u00e1 su tramitaci\u00f3n, consolida el derecho universal a la sanidad para todos los residentes en el Principado y ampl\u00eda sus garant\u00edas en cuanto a informaci\u00f3n, transparencia, acceso a los servicios y prestaciones y autonom\u00eda de decisi\u00f3n sobre sus necesidades de","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/Sanidad-Asturias.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"3 minutos"},"aioseo_meta_data":{"post_id":"74915","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-25 17:24:15","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 12:57:59","updated":"2025-08-25 17:24:15"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/sociedad\/\" title=\"Sociedad\">Sociedad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tLa nueva Ley de Salud ampl\u00eda las garant\u00edas de los pacientes asturianos\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Sociedad","link":"https:\/\/candas365.es\/noticias\/category\/sociedad\/"},{"label":"La nueva Ley de Salud ampl\u00eda las garant\u00edas de los pacientes asturianos","link":"https:\/\/candas365.es\/noticias\/la-nueva-ley-de-salud-amplia-las-garantias-de-los-pacientes-asturianos\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/74915","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=74915"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/74915\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/74916"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=74915"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=74915"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=74915"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}