{"id":74896,"date":"2017-06-30T01:10:45","date_gmt":"2017-06-30T01:10:45","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=74896"},"modified":"2017-06-30T01:10:45","modified_gmt":"2017-06-30T01:10:45","slug":"varela-reconoce-a-iu-la-necesidad-de-mejorar-las-relaciones-laborales-en-fasad","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/varela-reconoce-a-iu-la-necesidad-de-mejorar-las-relaciones-laborales-en-fasad\/","title":{"rendered":"Varela reconoce a IU la necesidad de mejorar las relaciones laborales en Fasad"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-37837\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/12\/P-Varela-360x198.jpg\" alt=\"\" width=\"360\" height=\"198\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/12\/P-Varela-360x198.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/12\/P-Varela-650x357.jpg 650w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/12\/P-Varela-150x82.jpg 150w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/12\/P-Varela-450x247.jpg 450w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/12\/P-Varela.jpg 655w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>La Consejera de Derechos Sociales, Pilar Varela, reconoci\u00f3 esta ma\u00f1ana la necesidad de mejorar las relaciones laborales en la Fundaci\u00f3n Fasad ante la pregunta de la diputada de IU, Marta Pulgar, sobre qu\u00e9 medidas piensa tomar ante el deterioro de la situaci\u00f3n laboral en la Fundaci\u00f3n Asturiana de Atenci\u00f3n y Protecci\u00f3n a Personas con Discapacidades y\/o Dependencias. Varela asegur\u00f3 que su prioridad es establecer una relaci\u00f3n de puestos de trabajo clara, dado que a la anterior negociada tiene \u201cflecos sueltos\u201d y que el patronato ya ha decidido la contrataci\u00f3n de un director de recursos humanos, adem\u00e1s de abrir una nueva bolsa de empleo. La consejera puso como fecha tope de las negociaciones el 30 de septiembre.<\/p>\n<p>Marta Pulgar demand\u00f3 que este proceso llegue a buen t\u00e9rmino, pero record\u00f3 la manifestaci\u00f3n de 80 trabajadores el d\u00eda 23 de junio que reivindicaban una fundaci\u00f3n transparente, por unas mejores condiciones de trabajo, por unas retribuciones justas y por la estabilidad en el empleo \u2026 \u201creivindicaciones m\u00e1s que acertadas porque desgraciadamente en esta fundaci\u00f3n p\u00fablica no se da\u201d. Es m\u00e1s, dijo Pulgar, unas reivindicaciones que \u201ctienen moho\u201d porque llevan dos a\u00f1os aparcadas.<\/p>\n<p>Pulgar record\u00f3 que bolsa de empleo tiene una regulaci\u00f3n, un reglamento de 2016, que en Fasad no se aplica y que el comit\u00e9 de empresa lleva a\u00f1os pidiendo su cumplimiento. \u201cEsos visos de entrada arbitraria deben desaparecer de una vez\u201d, demand\u00f3 la diputada de IU, al igual que las contrataciones en fraude de ley. Tambi\u00e9n denunci\u00f3 que es \u201csangrente\u201d el tema de las retribuciones, ya que muchos trabajadores cobran el 50% menos que otras que hacen las mismas funciones en otras instituciones p\u00fablicas.<\/p>\n<p>Pulgar reconoci\u00f3 que la paciencia para que la Consejer\u00eda lleve a cabo estas cuestiones \u201cse agota\u201d por lo que pidi\u00f3 poner encima de la mesa el punto final y soluciones concretas. Demand\u00f3 un calendario concreto para poner \u201cpatas arriba la pol\u00edtica de personal aunque no sea sencillo y para que se firme un convenio colectivo propio\u201d. \u201cSin prisa pero sin pausa\u201d, exigi\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Consejera de Derechos Sociales, Pilar Varela, reconoci\u00f3 esta ma\u00f1ana la necesidad de mejorar las relaciones laborales en la Fundaci\u00f3n Fasad ante la pregunta de la diputada de IU, Marta Pulgar, sobre qu\u00e9 medidas piensa tomar ante el deterioro de la situaci\u00f3n laboral en la Fundaci\u00f3n Asturiana de Atenci\u00f3n y Protecci\u00f3n a Personas con Discapacidades<\/p>\n","protected":false},"author":1,"featured_media":37837,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":{"0":"post-74896","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-asturias"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"La Consejera de Derechos Sociales, Pilar Varela, reconoci\u00f3 esta ma\u00f1ana la necesidad de mejorar las relaciones laborales en la Fundaci\u00f3n Fasad ante la pregunta de la diputada de IU, Marta Pulgar, sobre qu\u00e9 medidas piensa tomar ante el deterioro de la situaci\u00f3n laboral en la Fundaci\u00f3n Asturiana de Atenci\u00f3n y Protecci\u00f3n a Personas con Discapacidades\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"asturias\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/varela-reconoce-a-iu-la-necesidad-de-mejorar-las-relaciones-laborales-en-fasad\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Varela reconoce a IU la necesidad de mejorar las relaciones laborales en Fasad | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"La Consejera de Derechos Sociales, Pilar Varela, reconoci\u00f3 esta ma\u00f1ana la necesidad de mejorar las relaciones laborales en la Fundaci\u00f3n Fasad ante la pregunta de la diputada de IU, Marta Pulgar, sobre qu\u00e9 medidas piensa tomar ante el deterioro de la situaci\u00f3n laboral en la Fundaci\u00f3n Asturiana de Atenci\u00f3n y Protecci\u00f3n a Personas con Discapacidades\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/varela-reconoce-a-iu-la-necesidad-de-mejorar-las-relaciones-laborales-en-fasad\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/12\/P-Varela.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/12\/P-Varela.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"655\" \/>\n\t\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2017-06-30T01:10:45+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2017-06-30T01:10:45+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Varela reconoce a IU la necesidad de mejorar las relaciones laborales en Fasad | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La Consejera de Derechos Sociales, Pilar Varela, reconoci\u00f3 esta ma\u00f1ana la necesidad de mejorar las relaciones laborales en la Fundaci\u00f3n Fasad ante la pregunta de la diputada de IU, Marta Pulgar, sobre qu\u00e9 medidas piensa tomar ante el deterioro de la situaci\u00f3n laboral en la Fundaci\u00f3n Asturiana de Atenci\u00f3n y Protecci\u00f3n a Personas con Discapacidades\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/12\/P-Varela.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/varela-reconoce-a-iu-la-necesidad-de-mejorar-las-relaciones-laborales-en-fasad\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"name\":\"Asturias\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"position\":2,\"name\":\"Asturias\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/varela-reconoce-a-iu-la-necesidad-de-mejorar-las-relaciones-laborales-en-fasad\\\/#listItem\",\"name\":\"Varela reconoce a IU la necesidad de mejorar las relaciones laborales en Fasad\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/varela-reconoce-a-iu-la-necesidad-de-mejorar-las-relaciones-laborales-en-fasad\\\/#listItem\",\"position\":3,\"name\":\"Varela reconoce a IU la necesidad de mejorar las relaciones laborales en Fasad\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"name\":\"Asturias\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/varela-reconoce-a-iu-la-necesidad-de-mejorar-las-relaciones-laborales-en-fasad\\\/#newsarticle\",\"name\":\"Varela reconoce a IU la necesidad de mejorar las relaciones laborales en Fasad | Cand\\u00e1s 365\",\"headline\":\"Varela reconoce a IU la necesidad de mejorar las relaciones laborales en Fasad\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/P-Varela.jpg\",\"width\":655,\"height\":360},\"datePublished\":\"2017-06-30T01:10:45+02:00\",\"dateModified\":\"2017-06-30T01:10:45+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/varela-reconoce-a-iu-la-necesidad-de-mejorar-las-relaciones-laborales-en-fasad\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/varela-reconoce-a-iu-la-necesidad-de-mejorar-las-relaciones-laborales-en-fasad\\\/#webpage\"},\"articleSection\":\"Asturias\",\"dateline\":\"Publicado el junio 30, 2017.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/varela-reconoce-a-iu-la-necesidad-de-mejorar-las-relaciones-laborales-en-fasad\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/varela-reconoce-a-iu-la-necesidad-de-mejorar-las-relaciones-laborales-en-fasad\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/varela-reconoce-a-iu-la-necesidad-de-mejorar-las-relaciones-laborales-en-fasad\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/varela-reconoce-a-iu-la-necesidad-de-mejorar-las-relaciones-laborales-en-fasad\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/varela-reconoce-a-iu-la-necesidad-de-mejorar-las-relaciones-laborales-en-fasad\\\/\",\"name\":\"Varela reconoce a IU la necesidad de mejorar las relaciones laborales en Fasad | Cand\\u00e1s 365\",\"description\":\"La Consejera de Derechos Sociales, Pilar Varela, reconoci\\u00f3 esta ma\\u00f1ana la necesidad de mejorar las relaciones laborales en la Fundaci\\u00f3n Fasad ante la pregunta de la diputada de IU, Marta Pulgar, sobre qu\\u00e9 medidas piensa tomar ante el deterioro de la situaci\\u00f3n laboral en la Fundaci\\u00f3n Asturiana de Atenci\\u00f3n y Protecci\\u00f3n a Personas con Discapacidades\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/varela-reconoce-a-iu-la-necesidad-de-mejorar-las-relaciones-laborales-en-fasad\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/P-Varela.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/varela-reconoce-a-iu-la-necesidad-de-mejorar-las-relaciones-laborales-en-fasad\\\/#mainImage\",\"width\":655,\"height\":360},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/varela-reconoce-a-iu-la-necesidad-de-mejorar-las-relaciones-laborales-en-fasad\\\/#mainImage\"},\"datePublished\":\"2017-06-30T01:10:45+02:00\",\"dateModified\":\"2017-06-30T01:10:45+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Varela reconoce a IU la necesidad de mejorar las relaciones laborales en Fasad | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Varela reconoce a IU la necesidad de mejorar las relaciones laborales en Fasad | Cand\u00e1s 365","description":"La Consejera de Derechos Sociales, Pilar Varela, reconoci\u00f3 esta ma\u00f1ana la necesidad de mejorar las relaciones laborales en la Fundaci\u00f3n Fasad ante la pregunta de la diputada de IU, Marta Pulgar, sobre qu\u00e9 medidas piensa tomar ante el deterioro de la situaci\u00f3n laboral en la Fundaci\u00f3n Asturiana de Atenci\u00f3n y Protecci\u00f3n a Personas con Discapacidades","canonical_url":"https:\/\/candas365.es\/noticias\/varela-reconoce-a-iu-la-necesidad-de-mejorar-las-relaciones-laborales-en-fasad\/","robots":"max-image-preview:large","keywords":"asturias","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/varela-reconoce-a-iu-la-necesidad-de-mejorar-las-relaciones-laborales-en-fasad\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","name":"Asturias"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","position":2,"name":"Asturias","item":"https:\/\/candas365.es\/noticias\/category\/asturias\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/varela-reconoce-a-iu-la-necesidad-de-mejorar-las-relaciones-laborales-en-fasad\/#listItem","name":"Varela reconoce a IU la necesidad de mejorar las relaciones laborales en Fasad"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/varela-reconoce-a-iu-la-necesidad-de-mejorar-las-relaciones-laborales-en-fasad\/#listItem","position":3,"name":"Varela reconoce a IU la necesidad de mejorar las relaciones laborales en Fasad","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","name":"Asturias"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/varela-reconoce-a-iu-la-necesidad-de-mejorar-las-relaciones-laborales-en-fasad\/#newsarticle","name":"Varela reconoce a IU la necesidad de mejorar las relaciones laborales en Fasad | Cand\u00e1s 365","headline":"Varela reconoce a IU la necesidad de mejorar las relaciones laborales en Fasad","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/12\/P-Varela.jpg","width":655,"height":360},"datePublished":"2017-06-30T01:10:45+02:00","dateModified":"2017-06-30T01:10:45+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/varela-reconoce-a-iu-la-necesidad-de-mejorar-las-relaciones-laborales-en-fasad\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/varela-reconoce-a-iu-la-necesidad-de-mejorar-las-relaciones-laborales-en-fasad\/#webpage"},"articleSection":"Asturias","dateline":"Publicado el junio 30, 2017."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/varela-reconoce-a-iu-la-necesidad-de-mejorar-las-relaciones-laborales-en-fasad\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/varela-reconoce-a-iu-la-necesidad-de-mejorar-las-relaciones-laborales-en-fasad\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/varela-reconoce-a-iu-la-necesidad-de-mejorar-las-relaciones-laborales-en-fasad\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/varela-reconoce-a-iu-la-necesidad-de-mejorar-las-relaciones-laborales-en-fasad\/#webpage","url":"https:\/\/candas365.es\/noticias\/varela-reconoce-a-iu-la-necesidad-de-mejorar-las-relaciones-laborales-en-fasad\/","name":"Varela reconoce a IU la necesidad de mejorar las relaciones laborales en Fasad | Cand\u00e1s 365","description":"La Consejera de Derechos Sociales, Pilar Varela, reconoci\u00f3 esta ma\u00f1ana la necesidad de mejorar las relaciones laborales en la Fundaci\u00f3n Fasad ante la pregunta de la diputada de IU, Marta Pulgar, sobre qu\u00e9 medidas piensa tomar ante el deterioro de la situaci\u00f3n laboral en la Fundaci\u00f3n Asturiana de Atenci\u00f3n y Protecci\u00f3n a Personas con Discapacidades","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/varela-reconoce-a-iu-la-necesidad-de-mejorar-las-relaciones-laborales-en-fasad\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/12\/P-Varela.jpg","@id":"https:\/\/candas365.es\/noticias\/varela-reconoce-a-iu-la-necesidad-de-mejorar-las-relaciones-laborales-en-fasad\/#mainImage","width":655,"height":360},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/varela-reconoce-a-iu-la-necesidad-de-mejorar-las-relaciones-laborales-en-fasad\/#mainImage"},"datePublished":"2017-06-30T01:10:45+02:00","dateModified":"2017-06-30T01:10:45+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Varela reconoce a IU la necesidad de mejorar las relaciones laborales en Fasad | Cand\u00e1s 365","og:description":"La Consejera de Derechos Sociales, Pilar Varela, reconoci\u00f3 esta ma\u00f1ana la necesidad de mejorar las relaciones laborales en la Fundaci\u00f3n Fasad ante la pregunta de la diputada de IU, Marta Pulgar, sobre qu\u00e9 medidas piensa tomar ante el deterioro de la situaci\u00f3n laboral en la Fundaci\u00f3n Asturiana de Atenci\u00f3n y Protecci\u00f3n a Personas con Discapacidades","og:url":"https:\/\/candas365.es\/noticias\/varela-reconoce-a-iu-la-necesidad-de-mejorar-las-relaciones-laborales-en-fasad\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/12\/P-Varela.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/12\/P-Varela.jpg","og:image:width":655,"og:image:height":360,"article:published_time":"2017-06-30T01:10:45+00:00","article:modified_time":"2017-06-30T01:10:45+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Varela reconoce a IU la necesidad de mejorar las relaciones laborales en Fasad | Cand\u00e1s 365","twitter:description":"La Consejera de Derechos Sociales, Pilar Varela, reconoci\u00f3 esta ma\u00f1ana la necesidad de mejorar las relaciones laborales en la Fundaci\u00f3n Fasad ante la pregunta de la diputada de IU, Marta Pulgar, sobre qu\u00e9 medidas piensa tomar ante el deterioro de la situaci\u00f3n laboral en la Fundaci\u00f3n Asturiana de Atenci\u00f3n y Protecci\u00f3n a Personas con Discapacidades","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/12\/P-Varela.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"74896","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-25 17:22:25","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 12:57:59","updated":"2025-08-25 17:22:25"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/asturias\/\" title=\"Asturias\">Asturias<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tVarela reconoce a IU la necesidad de mejorar las relaciones laborales en Fasad\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Asturias","link":"https:\/\/candas365.es\/noticias\/category\/asturias\/"},{"label":"Varela reconoce a IU la necesidad de mejorar las relaciones laborales en Fasad","link":"https:\/\/candas365.es\/noticias\/varela-reconoce-a-iu-la-necesidad-de-mejorar-las-relaciones-laborales-en-fasad\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/74896","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=74896"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/74896\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/37837"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=74896"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=74896"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=74896"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}